{"id":1473364,"date":"2026-04-21T08:03:41","date_gmt":"2026-04-21T15:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/"},"modified":"2026-04-21T08:03:41","modified_gmt":"2026-04-21T15:03:41","slug":"detenidaos-ataque-judia-londres-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/","title":{"rendered":"Hay siete personas detenidas por un frustrado ataque incendiario contra una comunidad jud\u00eda en Londres"},"content":{"rendered":"<p>La polic\u00eda antiterrorista brit\u00e1nica detuvo a ocho personas en relaci\u00f3n con una investigaci\u00f3n sobre presuntos ataques incendiarios en Londres, incluyendo un complot frustrado para atacar un lugar vinculado a la comunidad jud\u00eda, inform\u00f3 la polic\u00eda este martes.<\/p>\n<p>Siete de las detenciones, realizadas en las \u00faltimas 48 horas, forman parte de lo que la polic\u00eda denomin\u00f3 \u201cuna investigaci\u00f3n proactiva sobre una presunta conspiraci\u00f3n para cometer incendios provocados\u201d.<\/p>\n<p>\u201cEn este momento, si bien se cree que el objetivo de esta conspiraci\u00f3n es un lugar vinculado a la comunidad jud\u00eda, se desconoce el objetivo o lugar espec\u00edfico\u201d, declar\u00f3 la Polic\u00eda Metropolitana de Londres en un comunicado.<\/p>\n<p>Las detenciones se llevaron a cabo en las ciudades inglesas de Harpenden y Stevenage, cerca de Birmingham, as\u00ed como en el suburbio londinense de Ealing.<\/p>\n<p>La polic\u00eda inform\u00f3 que, desde el ataque incendiario del 23 de marzo en el barrio londinense de Golders Green, donde varias ambulancias pertenecientes a una organizaci\u00f3n jud\u00eda de rescate voluntario fueron incendiadas frente a una sinagoga, ocho personas han sido acusadas de delitos relacionados con incendios provocados y trece permanecen bajo custodia policial o en libertad bajo fianza mientras se lleva a cabo la investigaci\u00f3n.<\/p>\n<p>\u201cNuestro mensaje es claro: no toleraremos esta intimidaci\u00f3n contra nuestras comunidades y perseguiremos a los responsables\u201d, declar\u00f3 Vicki Evans, coordinadora nacional s\u00e9nior de la polic\u00eda para la lucha antiterrorista.<\/p>\n<p>\u201cUna de nuestras l\u00edneas de investigaci\u00f3n clave es si se est\u00e1 utilizando a personas que reciben dinero a cambio de cometer delitos para perpetrar alguno de estos incendios provocados\u201d, a\u00f1adi\u00f3 Evans.<\/p>\n<p>Esto ocurre mientras el rabino jefe del Reino Unido, Ephraim Mirvis, advirti\u00f3 el domingo que una \u201ccampa\u00f1a sostenida de violencia e intimidaci\u00f3n contra la comunidad jud\u00eda del Reino Unido est\u00e1 cobrando fuerza\u201d, se\u00f1alando una serie de incendios provocados e intentos de incendio dirigidos contra la comunidad.<\/p>\n<p>Mirvis afirm\u00f3 que una sinagoga en Kenton, al noroeste de Londres, fue blanco de un \u201ccobarde ataque incendiario\u201d. Tambi\u00e9n mencion\u00f3 un ataque contra una sinagoga en el barrio londinense de Finchley el mi\u00e9rcoles pasado y un intento de ataque contra otro edificio en Hendon, al noroeste de Londres, el viernes pasado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La polic\u00eda antiterrorista brit\u00e1nica detuvo a ocho personas en relaci\u00f3n con una investigaci\u00f3n sobre presuntos ataques incendiarios en Londres, incluyendo un complot frustrado para atacar un lugar vinculado a la comunidad jud\u00eda, inform\u00f3 la polic\u00eda este martes. Siete de las detenciones, realizadas en las \u00faltimas 48 horas, forman parte de lo que la polic\u00eda denomin\u00f3 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473364","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hay siete personas detenidas por un frustrado ataque incendiario contra una comunidad jud\u00eda en Londres - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hay siete personas detenidas por un frustrado ataque incendiario contra una comunidad jud\u00eda en Londres - Noticias\" \/>\n<meta property=\"og:description\" content=\"La polic\u00eda antiterrorista brit\u00e1nica detuvo a ocho personas en relaci\u00f3n con una investigaci\u00f3n sobre presuntos ataques incendiarios en Londres, incluyendo un complot frustrado para atacar un lugar vinculado a la comunidad jud\u00eda, inform\u00f3 la polic\u00eda este martes. Siete de las detenciones, realizadas en las \u00faltimas 48 horas, forman parte de lo que la polic\u00eda denomin\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-21T15:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hay siete personas detenidas por un frustrado ataque incendiario contra una comunidad jud\u00eda en Londres\",\"datePublished\":\"2026-04-21T15:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/\"},\"wordCount\":409,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/\",\"name\":\"Hay siete personas detenidas por un frustrado ataque incendiario contra una comunidad jud\u00eda en Londres - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-21T15:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hay siete personas detenidas por un frustrado ataque incendiario contra una comunidad jud\u00eda en Londres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hay siete personas detenidas por un frustrado ataque incendiario contra una comunidad jud\u00eda en Londres - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Hay siete personas detenidas por un frustrado ataque incendiario contra una comunidad jud\u00eda en Londres - Noticias","og_description":"La polic\u00eda antiterrorista brit\u00e1nica detuvo a ocho personas en relaci\u00f3n con una investigaci\u00f3n sobre presuntos ataques incendiarios en Londres, incluyendo un complot frustrado para atacar un lugar vinculado a la comunidad jud\u00eda, inform\u00f3 la polic\u00eda este martes. Siete de las detenciones, realizadas en las \u00faltimas 48 horas, forman parte de lo que la polic\u00eda denomin\u00f3 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-21T15:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/"},"author":{"name":"","@id":""},"headline":"Hay siete personas detenidas por un frustrado ataque incendiario contra una comunidad jud\u00eda en Londres","datePublished":"2026-04-21T15:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/"},"wordCount":409,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/","name":"Hay siete personas detenidas por un frustrado ataque incendiario contra una comunidad jud\u00eda en Londres - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-21T15:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Hay siete personas detenidas por un frustrado ataque incendiario contra una comunidad jud\u00eda en Londres"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Hay siete personas detenidas por un frustrado ataque incendiario contra una comunidad jud\u00eda en Londres","url":"http:\/\/noticiasya.com\/kansas\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2026\/04\/21\/detenidaos-ataque-judia-londres-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-21T15:03:41Z","datePublished":"2026-04-21T15:03:41Z","dateModified":"2026-04-21T15:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Hay siete personas detenidas por un frustrado ataque incendiario contra una comunidad jud\\u00eda en Londres\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/21\\\/detenidaos-ataque-judia-londres-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/21\\\/detenidaos-ataque-judia-londres-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-21T15:03:41Z\",\"datePublished\":\"2026-04-21T15:03:41Z\",\"dateModified\":\"2026-04-21T15:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472457,"url":"https:\/\/noticiasya.com\/kansas\/2026\/03\/23\/ambulancias-voluntarios-judios-incendiada-sinagoga-londres-trax\/","url_meta":{"origin":1473364,"position":0},"title":"Incendian ambulancias de voluntarios jud\u00edos frente a una sinagoga de Londres en un ataque antisemita","author":"","date":"marzo 23, 2026","format":false,"excerpt":"Varias ambulancias pertenecientes a una organizaci\u00f3n jud\u00eda de rescate voluntario fueron incendiadas a primera hora de este lunes frente a una sinagoga en un barrio que alberga a la mayor comunidad jud\u00eda de Londres, en lo que la Polic\u00eda est\u00e1 investigando como un ataque antisemita.Las llamas iluminaron el cielo nocturno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473629,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/29\/apunalan-personas-londres-ataques-recientes-trax\/","url_meta":{"origin":1473364,"position":1},"title":"Apu\u00f1alan a dos personas en el norte de Londres, seg\u00fan inform\u00f3 un grupo de seguridad jud\u00edo, tras serie de ataques recientes","author":"","date":"abril 29, 2026","format":false,"excerpt":"Dos personas jud\u00edas fueron apu\u00f1aladas el mi\u00e9rcoles en el norte de Londres, seg\u00fan relataron testigos a CNN, en un incidente que se produce en el contexto de una serie de ataques antisemitas en la capital brit\u00e1nica.Un hombre fue detenido y varios veh\u00edculos de los servicios de emergencia, incluyendo una ambulancia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463078,"url":"https:\/\/noticiasya.com\/kansas\/2025\/06\/01\/fbi-investiga-ataque-terrorista-colorado-trax\/","url_meta":{"origin":1473364,"position":2},"title":"Atacan a varias personas durante una marcha en proisrael\u00ed en Colorado seg\u00fan la polic\u00eda","author":"","date":"junio 1, 2025","format":false,"excerpt":"Un hombre prendi\u00f3 fuego a personas en Boulder, Colorado, dejando a varias heridas, inform\u00f3 el jefe de polic\u00eda de la ciudad, durante un evento en apoyo a Israel.Un sospechoso est\u00e1 detenido y la polic\u00eda investigar\u00e1 lo que los funcionarios del FBI calificaron inmediatamente de \u201cataque terrorista selectivo\u201d, aunque las autoridades\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456907,"url":"https:\/\/noticiasya.com\/kansas\/2024\/12\/23\/comunidad-judia-guatemala-secta-delitos-menores-orix\/","url_meta":{"origin":1473364,"position":3},"title":"La Asociaci\u00f3n Comunidad Jud\u00eda de Guatemala se deslinda de secta Lev Tahor tras denuncias por presuntos delitos contra menores","author":"","date":"diciembre 23, 2024","format":false,"excerpt":"La Asociaci\u00f3n Comunidad Jud\u00eda de Guatemala afirm\u00f3 que la secta Lev Tahor \u201cno representa al juda\u00edsmo ni a nuestra comunidad\u201d luego de que el Ministerio P\u00fablico de ese pa\u00eds anunciara el viernes que se \u201crescat\u00f3\u201d a \u201c85 menores de edad\u201d del grupo, tras denuncias de presuntos delitos de trata de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468392,"url":"https:\/\/noticiasya.com\/kansas\/2025\/11\/16\/detenciones-complot-isis-estados-unidos-trax\/","url_meta":{"origin":1473364,"position":4},"title":"Las detenciones por complot terrorista revelan una v\u00eda en l\u00ednea &#171;m\u00e1s peligrosa&#187; hacia la radicalizaci\u00f3n por el ISIS en EE.UU.","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"Viven en Nueva Jersey, Michigan y el estado de Washington: seis j\u00f3venes arrestados en las \u00faltimas semanas y acusados \u200b\u200bde participar en un presunto complot terrorista inspirado por el ISIS.Los sospechosos, entre otros, est\u00e1n acusados \u200b\u200bde utilizar aplicaciones de mensajer\u00eda encriptada y redes sociales \u201cpara compartir material extremista y relacionado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472184,"url":"https:\/\/noticiasya.com\/kansas\/2026\/03\/14\/explosion-escuela-judia-amsterdam-ataque-comunidad-judia-trax\/","url_meta":{"origin":1473364,"position":5},"title":"Explosi\u00f3n sacude una escuela jud\u00eda de \u00c1msterdam en lo que el alcalde califica de &#171;ataque selectivo&#187; contra la comunidad jud\u00eda","author":"","date":"marzo 14, 2026","format":false,"excerpt":"Una explosi\u00f3n sacudi\u00f3 durante la noche una escuela jud\u00eda en \u00c1msterdam, en lo que el alcalde de la ciudad calific\u00f3 de \u201cataque selectivo contra la comunidad jud\u00eda\u201d.La explosi\u00f3n impact\u00f3 en el muro exterior de la escuela, ubicada en Buitenveldert, considerado el barrio jud\u00edo moderno de la ciudad y hogar de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1473364"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473364\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1473364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1473364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1473364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}