{"id":1473379,"date":"2026-04-21T14:03:53","date_gmt":"2026-04-21T21:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/"},"modified":"2026-04-21T14:03:53","modified_gmt":"2026-04-21T21:03:53","slug":"nuevo-secretario-general-onu-potencias-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/","title":{"rendered":"C\u00f3mo se elige al nuevo secretario general de la ONU y a qui\u00e9nes apoyan las potencias mundiales"},"content":{"rendered":"<p>La carrera para suceder a Ant\u00f3nio Guterres como secretario general de la ONU comienza formalmente esta semana, con la presentaci\u00f3n de los candidatos en audiencias p\u00fablicas ante los miembros de la Asamblea General, una etapa que puede arrojar luz sobre los apoyos con los que cuenta cada uno, aunque la decisi\u00f3n pasar\u00e1 en los pr\u00f3ximos meses por los pa\u00edses con asiento en el Consejo de Seguridad.<\/p>\n<p>Una regla no escrita es la rotaci\u00f3n de las regiones y ser\u00eda el turno de Am\u00e9rica Latina, que solo tuvo el cargo una vez, con el peruano <a href=\"https:\/\/www.un.org\/sg\/es\/former-sg\/javier-perez-de-cuellar\">Javier P\u00e9rez de Cu\u00e9llar<\/a> hace m\u00e1s de tres d\u00e9cadas. Adem\u00e1s, crece el consenso de que ser\u00eda el momento de elegir por primera vez a una mujer.<\/p>\n<p>Hasta el momento hay cuatro candidatos, pero no se trata de una lista cerrada: alguno m\u00e1s podr\u00eda incorporarse m\u00e1s adelante. Los aspirantes pasar\u00e1n desde este martes por encuentros abiertos para recibir preguntas sobre su postulaci\u00f3n.<\/p>\n<p><strong>Michelle Bachelet<\/strong>. La expresidenta de Chile es una de las aspirantes m\u00e1s voceadas y tambi\u00e9n m\u00e1s criticadas. Fue presentada por el entonces mandatario, Gabriel Boric, el a\u00f1o pasado, pero cuando asumi\u00f3 Jos\u00e9 Antonio Kast, su pa\u00eds le retir\u00f3 el apoyo. Sin embargo, M\u00e9xico y Brasil, con l\u00edderes progresistas, sostuvieron su candidatura. Cuenta con amplia experiencia en organismos internacionales como ONU Mujeres y el Alto Comisionado para Derechos Humanos.<\/p>\n<p><strong>Rafael Grossi<\/strong>. El Gobierno de Argentina, cercano a Estados Unidos, present\u00f3 en noviembre al actual director general de la Agencia Internacional de la Energ\u00eda At\u00f3mica (AIEA), quien ya hab\u00eda manifestado sus aspiraciones al cargo. En <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/22\/mundo\/rafael-grossi-onu-entrevista-orix\">entrevista con CNN<\/a>, dijo que la ONU \u201colvid\u00f3 la premisa inicial sobre la cual fue creada: velar por la paz y la seguridad internacionales\u201d.<\/p>\n<p><strong>Rebeca Grynspan<\/strong>. La economista y exvicepresidente de Costa Rica fue nominada por el mandatario Rodrigo Chaves. Actualmente es secretaria general de la Conferencia de las Naciones Unidas sobre Comercio y Desarrollo de la ONU y anteriormente fue la titular de la Secretar\u00eda General Iberoamericana (Segib).<\/p>\n<p><strong>Macky Sall<\/strong>. El expresidente senegal\u00e9s es el \u00fanico candidato fuera de Am\u00e9rica Latina. Su candidatura fue respaldada por Burundi, aunque no cuenta con el apoyo de su propio pa\u00eds.<\/p>\n<p>Bachelet y Grossi se presentan este martes, mientras que Grynspan y Sall lo har\u00e1n el jueves, con un mensaje inicial de 10 minutos y luego hasta tres horas de preguntas.<\/p>\n<p>Los candidatos ya enviaron sus hojas de vida y una declaraci\u00f3n de intenciones. Una vez que se realicen los di\u00e1logos interactivos convocados por la presidencia de la Asamblea General, no hay una fecha prevista para las votaciones del Consejo de Seguridad, ya que todo depende de los di\u00e1logos diplom\u00e1ticos.<\/p>\n<p>\u201cLos candidatos van delineando cu\u00e1les son sus objetivos y pol\u00edticas, en un momento particularmente complejo para los organismos multilaterales\u201d, dijo a CNN el historiador Gilberto Aranda, acad\u00e9mico del Instituto de Estudios Internacionales de la Universidad de Chile. \u201cLe presto atenci\u00f3n a lo que viene despu\u00e9s, c\u00f3mo se van posicionando los miembros del Consejo de Seguridad, que hacen la decisi\u00f3n inicial. Ser\u00e1n meses en los que se realizar\u00e1n votaciones informales para conocer cu\u00e1nto apoyo tiene candidato y, sobre todo, ver si alguno est\u00e1 vetado por las potencias\u201d, apunt\u00f3.<\/p>\n<p>Para el caso de Guterres (2016) y de Ban Ki Moon (2006), las rondas informales comenzaron en julio y finalmente fueron elegidos en octubre.<\/p>\n<p>Los miembros no permanentes que participan de la selecci\u00f3n, sin derecho a veto, son Argelia, Guyana, Sierra Leona, Corea del Sur, Eslovenia, Jap\u00f3n, Malta, Mozambique, Suiza y Ecuador.<\/p>\n<p>Una vez que el Consejo de Seguridad presenta a un candidato, debe ser aprobado por la Asamblea General, que hasta ahora nunca rechaz\u00f3 una propuesta.<\/p>\n<p>Aranda indic\u00f3 que durante este proceso las votaciones en paralelo que ocurren en la Asamblea General \u201cpueden lastrar o potenciar ciertas candidaturas\u201d. Como ejemplo, mencion\u00f3 que el voto en contra de Estados Unidos, Israel y Argentina para una resoluci\u00f3n que tilda la esclavitud africana del \u201ccrimen m\u00e1s grave contra la humanidad\u201d puede haber \u201ccomplicado\u201d las aspiraciones de Grossi entre los miembros africanos.<\/p>\n<p>En ese sentido, no descart\u00f3 que sea Grynspan quien termine emergiendo como \u201cla candidata, si hay muchas diferencias, que teja el consenso\u201d.<\/p>\n<p>Hasta ahora, los miembros permanentes del Consejo de Seguridad no han dicho abiertamente a qui\u00e9n apoyan, pero en el caso de EE.UU. y Rusia s\u00ed enviaron algunas se\u00f1ales.<\/p>\n<p>La semana pasada, Mike Waltz, embajador de Washington ante la ONU, dijo ante el Senado de su pa\u00eds que \u201ccomparte las preocupaciones\u201d sobre la candidatura de Michelle Bachelet.<\/p>\n<p>En marzo, un grupo de legisladores republicanos <a href=\"https:\/\/chrissmith.house.gov\/uploadedfiles\/2026-03-25_-_bicameral_letter_opposing_michelle_bachelet_as_unsg_w_signatures_final.pdf\">solicit\u00f3 en una carta<\/a> al Gobierno que vetara a la diplom\u00e1tica chilena por su postura a favor del derecho al aborto y por no haber calificado como \u201cgenocidio\u201d las <a href=\"https:\/\/cnnespanol.cnn.com\/2022\/09\/01\/china-crimenes-humanidad-xinjiang-informe-onu-trax\">violaciones de derechos humanos en China a la minor\u00eda uigur<\/a>.<\/p>\n<p>Sin embargo, aunque se especula con un apoyo t\u00e1cito de Washington a Grossi, Waltz no mencion\u00f3 al argentino y record\u00f3 que hay una \u201copini\u00f3n generalizada\u201d de que se deber\u00eda elegir a una mujer latinoamericana. \u201cNo estoy en posici\u00f3n de decir a qui\u00e9n apoyaremos (\u2026). Nosotros hemos adoptado la postura de que solo necesitamos a los mejores, y esta instituci\u00f3n necesita desesperadamente liderazgo efectivo y fuerte\u201d, agreg\u00f3. Consultado por un posible veto a Bachelet, expres\u00f3: \u201cCreo que EE.UU. estar\u00e1 absolutamente preparado para asegurar que el pr\u00f3ximo secretario general est\u00e9 alineado con los valores e intereses estadounidenses\u201d.<\/p>\n<p>Para Aranda, la gran pregunta es si los reparos de Washington hacia la expresidenta chilena se plasmar\u00e1n finalmente en un veto o si permitir\u00e1 que su candidatura siga en pie. \u201cBachelet hizo gala de tener capacidad de negociaci\u00f3n y lograr entenderse con pol\u00edticos que no pensaban como ella. El \u00e1nimo de Estados Unidos no es conforme al mundo del que proviene la expresidenta, un mundo progresista, cree que es crucial la acci\u00f3n de los organismos, en un momento en que EE.UU. se retira de ellos. Ella no se ajusta a ese perfil\u201d, analiz\u00f3.<\/p>\n<p>Ese mismo reporte de la oficina de Bachelet sobre los uigures criticado por los republicanos tambi\u00e9n despert\u00f3 enojo en el gigante asi\u00e1tico, que lo describi\u00f3 como \u201cuna farsa planeada por Estados Unidos, los pa\u00edses occidentales y las fuerzas contra China\u201d. De todos modos, Beijing no se ha pronunciado puntualmente sobre los candidatos.<\/p>\n<p>Por su parte, Rusia dio este martes la se\u00f1al m\u00e1s clara hasta el momento en apoyo a Grossi. El portavoz del Kremlin, Dmitri Peskov, dijo en rueda de prensa: \u201cConocemos a muchos de los candidatos potenciales. Tenemos una buena opini\u00f3n de Grossi\u201d. El argentino est\u00e1 en permanente contacto con Mosc\u00fa para abordar la situaci\u00f3n de las centrales nucleares ucranianas, en especial la de Zaporiyia, que est\u00e1 bajo control de las fuerzas rusas desde 2022.<\/p>\n<p>Aranda explic\u00f3 que es habitual que las potencias no se pronuncien tan abiertamente sobre sus preferencias. \u201cEl camino es ser cauteloso hasta tener claro que hay un candidato que re\u00fana la mayor\u00eda y no tenga vetos. Hoy hay m\u00e1s dosis de suspenso, en un momento complejo. La cautela es una actitud hist\u00f3rica\u201d, remarc\u00f3.<\/p>\n<p>Seg\u00fan analiz\u00f3, Inglaterra y Francia son muy atendidos y referidos en la esfera europea, mientras que Rusia busca defender su visi\u00f3n diplom\u00e1tica. \u201cIntentaron siempre tener una Secretar\u00eda General que no sea lesiva a sus intereses\u201d, repas\u00f3.<\/p>\n<p>De todos modos, el analista afirm\u00f3 que pese a la situaci\u00f3n de conflictos, un escenario que eleva el papel del hard power y reduce el multilateralismo, todav\u00eda hay margen para que el Sur global juegue un rol.<\/p>\n<p>\u201cHoy el mundo es m\u00e1s diverso. Claramente las candidaturas tienen que, adem\u00e1s de no representar un peligro para los cinco (miembros permanentes), saber trabajar con otras potencias regionales y atender otros pilares de la ONU\u201d, dijo.<\/p>\n<p>Aunque hay menos candidatos que en 2016, cuando fueron 13, todav\u00eda no est\u00e1 cerca un consenso en Am\u00e9rica Latina sobre los candidatos. Susana Malcorra, excanciller de Argentina y presidenta y fundadora de GWL Voices, un grupo de defensa del multilateralismo y la igualdad de g\u00e9nero, record\u00f3 que hace una d\u00e9cada el lugar le correspond\u00eda al Viejo Continente, pero m\u00e1s espec\u00edficamente a Europa del Este, lo que no sucedi\u00f3. \u201cCon esto quiero graficar que, aunque prevalece la noci\u00f3n de que naturalmente debiera ser una persona procedente de Latinoam\u00e9rica y el Caribe, no hay ning\u00fan mecanismo institucional que garantice que as\u00ed vaya a ser\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/02\/mundo\/onu-eleccion-secretario-general-latinoamericano-orix\">dijo a CNN.<\/a><\/p>\n<p>Sin embargo, Aranda conf\u00eda en que el puesto ser\u00e1 ocupado por alguien de la regi\u00f3n. \u201cAm\u00e9rica Latina tiene todav\u00eda la chance de hacerse con la secretar\u00eda general. Vamos a ver c\u00f3mo se llega a aquello. No dir\u00eda que hay una hiperfragmentaci\u00f3n; en un contexto de polaridad, se ir\u00e1n delineando\u201d, coment\u00f3.<\/p>\n<p>El historiador destac\u00f3 el rol de l\u00edder de Brasil en la regi\u00f3n, algo que, seg\u00fan dijo, podr\u00eda resonar tambi\u00e9n en otras latitudes, como en China y el Grupo de los 77. \u201c(El expresidente de EE.UU. Richard) Nixon dijo que por donde camine Brasil, ir\u00e1 el resto de Sudam\u00e9rica. Eso tiene bemoles, estamos en un giro, en algunos casos hacia el conservadurismo. Para muchos Brasil es un referente, otros lo mirar\u00e1n con m\u00e1s distancia en un momento de polarizaci\u00f3n\u201d, afirm\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La carrera para suceder a Ant\u00f3nio Guterres como secretario general de la ONU comienza formalmente esta semana, con la presentaci\u00f3n de los candidatos en audiencias p\u00fablicas ante los miembros de la Asamblea General, una etapa que puede arrojar luz sobre los apoyos con los que cuenta cada uno, aunque la decisi\u00f3n pasar\u00e1 en los pr\u00f3ximos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473379","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo se elige al nuevo secretario general de la ONU y a qui\u00e9nes apoyan las potencias mundiales - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo se elige al nuevo secretario general de la ONU y a qui\u00e9nes apoyan las potencias mundiales - Noticias\" \/>\n<meta property=\"og:description\" content=\"La carrera para suceder a Ant\u00f3nio Guterres como secretario general de la ONU comienza formalmente esta semana, con la presentaci\u00f3n de los candidatos en audiencias p\u00fablicas ante los miembros de la Asamblea General, una etapa que puede arrojar luz sobre los apoyos con los que cuenta cada uno, aunque la decisi\u00f3n pasar\u00e1 en los pr\u00f3ximos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-21T21:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"C\u00f3mo se elige al nuevo secretario general de la ONU y a qui\u00e9nes apoyan las potencias mundiales\",\"datePublished\":\"2026-04-21T21:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/\"},\"wordCount\":1641,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/\",\"name\":\"C\u00f3mo se elige al nuevo secretario general de la ONU y a qui\u00e9nes apoyan las potencias mundiales - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-21T21:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo se elige al nuevo secretario general de la ONU y a qui\u00e9nes apoyan las potencias mundiales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo se elige al nuevo secretario general de la ONU y a qui\u00e9nes apoyan las potencias mundiales - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo se elige al nuevo secretario general de la ONU y a qui\u00e9nes apoyan las potencias mundiales - Noticias","og_description":"La carrera para suceder a Ant\u00f3nio Guterres como secretario general de la ONU comienza formalmente esta semana, con la presentaci\u00f3n de los candidatos en audiencias p\u00fablicas ante los miembros de la Asamblea General, una etapa que puede arrojar luz sobre los apoyos con los que cuenta cada uno, aunque la decisi\u00f3n pasar\u00e1 en los pr\u00f3ximos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-21T21:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/"},"author":{"name":"","@id":""},"headline":"C\u00f3mo se elige al nuevo secretario general de la ONU y a qui\u00e9nes apoyan las potencias mundiales","datePublished":"2026-04-21T21:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/"},"wordCount":1641,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/","name":"C\u00f3mo se elige al nuevo secretario general de la ONU y a qui\u00e9nes apoyan las potencias mundiales - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-21T21:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo se elige al nuevo secretario general de la ONU y a qui\u00e9nes apoyan las potencias mundiales"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"C\u00f3mo se elige al nuevo secretario general de la ONU y a qui\u00e9nes apoyan las potencias mundiales","url":"http:\/\/noticiasya.com\/kansas\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2026\/04\/21\/nuevo-secretario-general-onu-potencias-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-21T21:03:53Z","datePublished":"2026-04-21T21:03:53Z","dateModified":"2026-04-21T21:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"C\\u00f3mo se elige al nuevo secretario general de la ONU y a qui\\u00e9nes apoyan las potencias mundiales\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/21\\\/nuevo-secretario-general-onu-potencias-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/21\\\/nuevo-secretario-general-onu-potencias-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-21T21:03:53Z\",\"datePublished\":\"2026-04-21T21:03:53Z\",\"dateModified\":\"2026-04-21T21:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472799,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/02\/onu-eleccion-secretario-general-latinoamericano-orix\/","url_meta":{"origin":1473379,"position":0},"title":"La ONU es cada vez m\u00e1s cuestionada. \u00bfPuede salvarla un latinoamericano?","author":"","date":"abril 2, 2026","format":false,"excerpt":"Aumento de la militarizaci\u00f3n, resoluci\u00f3n bilateral de conflictos, liderazgos cada vez m\u00e1s poderosos y ret\u00f3ricas incendiarias son apenas una pincelada de una actualidad cada vez m\u00e1s normalizada. Para las Naciones Unidas, el organismo que en el Art\u00edculo 1 de su carta establece el prop\u00f3sito \u201cmantener la paz y la seguridad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473358,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/21\/onu-cuestionada-latinoamericano-secretaria-general-orix\/","url_meta":{"origin":1473379,"position":1},"title":"La ONU es cada vez m\u00e1s cuestionada. \u00bfPuede salvarla un latinoamericano?","author":"","date":"abril 21, 2026","format":false,"excerpt":"Aumento de la militarizaci\u00f3n, resoluci\u00f3n bilateral de conflictos, liderazgos cada vez m\u00e1s poderosos y ret\u00f3ricas incendiarias son apenas una pincelada de una actualidad cada vez m\u00e1s normalizada. Para las Naciones Unidas, el organismo que en el Art\u00edculo 1 de su carta establece el prop\u00f3sito de \u201cmantener la paz y la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473415,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/22\/propuestas-candidatos-latinoamericanos-onu-orix\/","url_meta":{"origin":1473379,"position":2},"title":"Reformas y m\u00e1s acci\u00f3n: esto proponen los candidatos latinoamericanos a dirigir la ONU","author":"","date":"abril 22, 2026","format":false,"excerpt":"Los tres candidatos latinoamericanos a la Secretar\u00eda General de la ONU presentaron este martes y mi\u00e9rcoles sus propuestas para el organismo, en las que coincidieron en se\u00f1alar una cr\u00edtica al sistema multilateral de gobernanza, con diferentes estilos para liderar la instituci\u00f3n en un momento dif\u00edcil para las relaciones internacionales.La rotaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461858,"url":"https:\/\/noticiasya.com\/kansas\/2025\/05\/01\/trump-waltz-embajador-onu-rubio-asesor-seguridad-nacional-trax\/","url_meta":{"origin":1473379,"position":3},"title":"Trump nombra a Waltz embajador en la ONU y anuncia a Rubio como asesor interino de Seguridad Nacional","author":"","date":"mayo 1, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump anunci\u00f3 este jueves que designar\u00e1 a Mike Waltz para servir como embajador de la ONU, un cambio a su papel como asesor de Seguridad Nacional.Marco Rubio ahora servir\u00e1 como secretario de Estado y asesor de seguridad nacional interino, dijo Trump.\u201cMike Waltz ha trabajado duro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469502,"url":"https:\/\/noticiasya.com\/kansas\/2025\/12\/22\/rafael-grossi-onu-entrevista-orix\/","url_meta":{"origin":1473379,"position":4},"title":"&#171;La ONU olvid\u00f3 su premisa inicial&#187;, dice el argentino Rafael Grossi, quien busca ser su pr\u00f3ximo secretario general","author":"","date":"diciembre 22, 2025","format":false,"excerpt":"El argentino Rafael Grossi, director general de Organismo Internacional de Energ\u00eda At\u00f3mica (OIEA), quiere ser el pr\u00f3ximo secretario general de las Naciones Unidas \u201cporque es muy importante rescatar el papel del organismo en un mundo afectado por fragmentaci\u00f3n, guerras, conflictos y graves peligros\u201d, seg\u00fan dijo este lunes en una entrevista\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451859,"url":"https:\/\/noticiasya.com\/kansas\/2024\/08\/14\/informe-elecciones-venezuela-expertos-onu-orix\/","url_meta":{"origin":1473379,"position":5},"title":"Esto dice el informe preliminar sobre las elecciones en Venezuela que elabor\u00f3 el panel de expertos de la ONU","author":"","date":"agosto 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Un panel de expertos de la ONU que estuvo en Venezuela desde finales de junio hasta el 2 de agosto public\u00f3 un informe preliminar que critica el proceso electoral en el pa\u00eds, en el que Consejo Nacional Electoral (CNE) dio como ganador de la presidencia a Nicol\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1473379"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473379\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1473379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1473379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1473379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}