{"id":1473423,"date":"2026-04-22T23:03:51","date_gmt":"2026-04-23T06:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/"},"modified":"2026-04-22T23:03:51","modified_gmt":"2026-04-23T06:03:51","slug":"trump-afirma-regimen-irani-fracturado-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/","title":{"rendered":"Trump afirma que el r\u00e9gimen iran\u00ed est\u00e1 fracturado. La realidad es m\u00e1s compleja"},"content":{"rendered":"<p>El presidente Donald Trump describi\u00f3 al Gobierno iran\u00ed como \u201cgravemente fracturado\u201d cuando decidi\u00f3 <a href=\"https:\/\/www.cnn.com\/2026\/04\/21\/politics\/iran-trump-negotiations-peace-ceasefire\">extender el alto el fuego<\/a> para darle tiempo a presentar una propuesta \u201cunificada\u201d.<\/p>\n<p>La Casa Blanca argument\u00f3 que la ausencia de Ir\u00e1n en Pakist\u00e1n para una segunda ronda de conversaciones con el vicepresidente J.D. Vance demostraba el grado de desarticulaci\u00f3n del liderazgo iran\u00ed.<\/p>\n<p>Los observadores de Ir\u00e1n tienen una visi\u00f3n diferente. Ir\u00e1n ha insistido en que Estados Unidos debe poner fin al bloqueo de sus puertos antes de que se reanuden las conversaciones, y muchos analistas afirman que el liderazgo es m\u00e1s cohesionado de lo que se muestra.<\/p>\n<p>\u201cCreo que se trata de una interpretaci\u00f3n err\u00f3nea del liderazgo iran\u00ed\u201d, declar\u00f3 Mehrat Kamrava, profesor de ciencias pol\u00edticas en la Universidad de Georgetown en Qatar, a Becky Anderson de CNN. \u201cEl liderazgo ha sido bastante cohesionado, y lo hemos visto tanto en la conducci\u00f3n de la guerra como en las negociaciones\u201d.<\/p>\n<p>La gobernanza en Ir\u00e1n se ha vuelto mucho m\u00e1s compleja desde que Estados Unidos e Israel eliminaron a la mayor\u00eda de los altos mandos militares y pol\u00edticos del r\u00e9gimen, incluido el l\u00edder supremo de Ir\u00e1n, <a href=\"https:\/\/www.cnn.com\/2026\/02\/28\/middleeast\/obituary-ayatollah-ali-khamenei-hnk-intl\">el ayatola Ali Jamenei<\/a>.<\/p>\n<p>Un grupo de funcionarios que antes compet\u00edan entre s\u00ed y que representan a todo el espectro pol\u00edtico de la Rep\u00fablica Isl\u00e1mica ahora decide el futuro del pa\u00eds bajo la amenaza de una guerra existencial y en medio de la <a href=\"https:\/\/www.cnn.com\/2026\/04\/21\/middleeast\/iran-supreme-leader-intl\">notable ausencia<\/a> del m\u00e1ximo responsable de la toma de decisiones, Mojtaba Jamenei, quien sucedi\u00f3 a su difunto padre como nuevo l\u00edder supremo.<\/p>\n<p>Estos funcionarios tambi\u00e9n se ven obligados a equilibrar su visi\u00f3n del futuro de Ir\u00e1n con la presi\u00f3n interna de los grupos de l\u00ednea dura que se niegan a declarar la derrota y la presi\u00f3n externa del empe\u00f1o de Trump por declarar la victoria.<\/p>\n<p>Sin embargo, a pesar de sus diferencias pol\u00edticas, este grupo de funcionarios parece decidido a proyectar cohesi\u00f3n p\u00fablicamente, incluso si discrepan sobre c\u00f3mo afrontar la guerra y llevar a cabo la diplomacia con Estados Unidos, seg\u00fan los expertos.<\/p>\n<p>\u201cLas distintas facciones del liderazgo iran\u00ed est\u00e1n ahora m\u00e1s alineadas que antes de la guerra\u201d, declar\u00f3 a CNN Trita Parsi, vicepresidente ejecutivo del Instituto Quincy para la Gobernanza Responsable. \u201cDebido a que se trata de un c\u00edrculo mucho m\u00e1s reducido\u2026 este c\u00edrculo est\u00e1 m\u00e1s unido en cuanto a la estrategia que emplean en la guerra\u201d, en comparaci\u00f3n con las restricciones impuestas anteriormente bajo el mandato de Ali Jamenei.<\/p>\n<p>En medio de la intensa especulaci\u00f3n sobre la posible asistencia de Ir\u00e1n a las conversaciones de esta semana, Teher\u00e1n mantuvo una postura p\u00fablica coherente: sus negociadores no participar\u00edan. Acus\u00f3 a Washington de violar el alto el fuego y de falta de seriedad en la b\u00fasqueda de una soluci\u00f3n diplom\u00e1tica.<\/p>\n<p>Incluso antes de la guerra, la Rep\u00fablica Isl\u00e1mica, bajo el mandato de Ali Jamenei, manten\u00eda una lista clara de \u201cl\u00edneas rojas\u201d, entre las que se inclu\u00edan el derecho a enriquecer uranio, el desarrollo continuado de misiles y el apoyo a sus grupos afines.<\/p>\n<p>Todas esas exigencias se mantienen en las negociaciones actuales con la administraci\u00f3n Trump.<\/p>\n<p>La c\u00fapula pol\u00edtica iran\u00ed se ha esforzado por desmentir los rumores de luchas internas y por proyectar una imagen unificada de los objetivos militares y la estrategia de negociaci\u00f3n del pa\u00eds.<\/p>\n<p>\u201cHablar de divisiones entre los altos funcionarios es una manida t\u00e1ctica pol\u00edtica y propagand\u00edstica de los adversarios de Ir\u00e1n\u201d, escribi\u00f3 el mi\u00e9rcoles en X Mehdi Tabatabai, portavoz adjunto del presidente iran\u00ed. \u201cLa unidad y el consenso entre el campo de batalla, la ciudadan\u00eda y los diplom\u00e1ticos en estos momentos han sido excepcionales y dignos de menci\u00f3n\u201d.<\/p>\n<p>El r\u00e9gimen ha elevado a un funcionario a la categor\u00eda de figura representativa de esa unidad.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2026\/03\/24\/world\/iran-trump-talks-us-mohammad-bagher-ghalibaf-intl\">Mohammad Bagher Ghalibaf<\/a>, veterano presidente del parlamento del pa\u00eds y excomandante de la Guardia Revolucionaria, lider\u00f3 la primera ronda de negociaciones con Estados Unidos en Islamabad y ahora es considerado una de las principales figuras que representan a la Rep\u00fablica Isl\u00e1mica.<\/p>\n<p>Sin embargo, incluso cuando Ghalibaf aterriz\u00f3 en Islamabad para la primera ronda de conversaciones, estuvo acompa\u00f1ado por un equipo sin precedentes de funcionarios iran\u00edes que representaban un espectro pol\u00edtico diverso, en lo que parec\u00eda ser un intento deliberado de demostrar cohesi\u00f3n.<\/p>\n<p>\u201c\u00bfHay diferencias? Por supuesto que las hay\u201d, coment\u00f3 Parsi. Pero afirmar que la raz\u00f3n por la que ambas partes no pueden llegar a un acuerdo no se debe a los mensajes contradictorios de Trump, sino a la fragmentaci\u00f3n del liderazgo iran\u00ed, es \u201cun error alejado de la realidad\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Durante el fin de semana, Estados Unidos e Ir\u00e1n parec\u00edan estar cerca de un acuerdo para poner fin a la <a href=\"https:\/\/www.cnn.com\/2026\/04\/20\/world\/live-news\/iran-war-us-trump-israel\">guerra de siete semanas<\/a>, seg\u00fan inform\u00f3 CNN. Posteriormente, Trump comenz\u00f3 a publicar en redes sociales sobre las conversaciones en curso y a hablar por tel\u00e9fono con varios periodistas el viernes por la ma\u00f1ana, mientras intermediarios pakistan\u00edes lo manten\u00edan al tanto de las negociaciones con funcionarios iran\u00edes en Teher\u00e1n.<\/p>\n<p>Algunos funcionarios de la administraci\u00f3n Trump <a href=\"https:\/\/www.cnn.com\/2026\/04\/20\/politics\/social-media-posts-trump-iran-deal\">reconocieron en privado a CNN<\/a> que los comentarios p\u00fablicos del presidente han sido perjudiciales para las conversaciones, se\u00f1alando la delicadeza de las negociaciones y la profunda desconfianza de los iran\u00edes hacia Estados Unidos.<\/p>\n<p>Ante la amenaza de la aniquilaci\u00f3n, el r\u00e9gimen iran\u00ed ha desmantelado su sistema tradicional de centros de poder rivales que compitieron durante casi cinco d\u00e9cadas.<\/p>\n<p>En su lugar, una nueva estructura b\u00e9lica ha consolidado a negociadores y operadores pol\u00edticos bajo un mismo paraguas militar, con el objetivo de guiar a la Rep\u00fablica Isl\u00e1mica fuera de la crisis sin admitir la derrota.<\/p>\n<p>En las calles, grandes multitudes que representan a las facciones m\u00e1s radicales del pa\u00eds se han manifestado diariamente en apoyo del r\u00e9gimen y en contra de cualquier acuerdo con Washington que coloque a Ir\u00e1n en una posici\u00f3n de derrota.<\/p>\n<p>Estas <a href=\"https:\/\/www.cnn.com\/2026\/04\/03\/middleeast\/trump-claims-iran-regime-change-intl\">posturas intransigentes<\/a> dominan el parlamento y los medios estatales, donde cualquier aparente disposici\u00f3n de los funcionarios iran\u00edes a permitir que Trump declare la victoria suscita feroces cr\u00edticas.<\/p>\n<p>Cuando el ministro de Asuntos Exteriores, Abbas Araghchi, se\u00f1al\u00f3 la semana pasada que el estrecho de Ormuz estaba abierto al tr\u00e1fico mar\u00edtimo comercial, fue duramente atacado por los sectores m\u00e1s intransigentes del r\u00e9gimen, lo que oblig\u00f3 a otros funcionarios a emitir aclaraciones de inmediato.<\/p>\n<p>Esta estructura instaurada en tiempos de guerra difiere notablemente de la forma en que la Rep\u00fablica Isl\u00e1mica fue gobernada durante 37 a\u00f1os bajo el l\u00edder supremo Al\u00ed Jamenei.<\/p>\n<p>Su hijo, Mojtaba, ha sido designado para dirigir el pa\u00eds, pero permanece oculto.<\/p>\n<p> Seg\u00fan los informes, est\u00e1 herido o gravemente incapacitado, lo que aumenta la incertidumbre sobre si est\u00e1 dando instrucciones claras a sus subordinados o si estos simplemente tienen que adivinar lo que quiere sin instrucciones espec\u00edficas.<\/p>\n<p>\u201cEl sistema ahora funciona de manera diferente. Antes ten\u00edamos instituciones\u2026 que se supon\u00eda que deb\u00edan debatir asuntos estrat\u00e9gicos y presentar al l\u00edder supremo notas consultivas para que \u00e9l tomara la decisi\u00f3n final\u201d, declar\u00f3 Hamidreza Azizi, investigador visitante del Instituto Alem\u00e1n de Asuntos Internacionales y de Seguridad.<\/p>\n<p>\u201cEl acceso al l\u00edder supremo no puede ser tan regular como deber\u00eda\u201d, afirm\u00f3. \u201cEso implica autom\u00e1ticamente que otros funcionarios tienen m\u00e1s margen de maniobra a la hora de decidir las medidas que deben adoptarse en materia de guerra y paz\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump describi\u00f3 al Gobierno iran\u00ed como \u201cgravemente fracturado\u201d cuando decidi\u00f3 extender el alto el fuego para darle tiempo a presentar una propuesta \u201cunificada\u201d. La Casa Blanca argument\u00f3 que la ausencia de Ir\u00e1n en Pakist\u00e1n para una segunda ronda de conversaciones con el vicepresidente J.D. Vance demostraba el grado de desarticulaci\u00f3n del liderazgo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473423","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump afirma que el r\u00e9gimen iran\u00ed est\u00e1 fracturado. La realidad es m\u00e1s compleja - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump afirma que el r\u00e9gimen iran\u00ed est\u00e1 fracturado. La realidad es m\u00e1s compleja - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump describi\u00f3 al Gobierno iran\u00ed como \u201cgravemente fracturado\u201d cuando decidi\u00f3 extender el alto el fuego para darle tiempo a presentar una propuesta \u201cunificada\u201d. La Casa Blanca argument\u00f3 que la ausencia de Ir\u00e1n en Pakist\u00e1n para una segunda ronda de conversaciones con el vicepresidente J.D. Vance demostraba el grado de desarticulaci\u00f3n del liderazgo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-23T06:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump afirma que el r\u00e9gimen iran\u00ed est\u00e1 fracturado. La realidad es m\u00e1s compleja\",\"datePublished\":\"2026-04-23T06:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/\"},\"wordCount\":1346,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/\",\"name\":\"Trump afirma que el r\u00e9gimen iran\u00ed est\u00e1 fracturado. La realidad es m\u00e1s compleja - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-23T06:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump afirma que el r\u00e9gimen iran\u00ed est\u00e1 fracturado. La realidad es m\u00e1s compleja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump afirma que el r\u00e9gimen iran\u00ed est\u00e1 fracturado. La realidad es m\u00e1s compleja - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump afirma que el r\u00e9gimen iran\u00ed est\u00e1 fracturado. La realidad es m\u00e1s compleja - Noticias","og_description":"El presidente Donald Trump describi\u00f3 al Gobierno iran\u00ed como \u201cgravemente fracturado\u201d cuando decidi\u00f3 extender el alto el fuego para darle tiempo a presentar una propuesta \u201cunificada\u201d. La Casa Blanca argument\u00f3 que la ausencia de Ir\u00e1n en Pakist\u00e1n para una segunda ronda de conversaciones con el vicepresidente J.D. Vance demostraba el grado de desarticulaci\u00f3n del liderazgo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-23T06:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/"},"author":{"name":"","@id":""},"headline":"Trump afirma que el r\u00e9gimen iran\u00ed est\u00e1 fracturado. La realidad es m\u00e1s compleja","datePublished":"2026-04-23T06:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/"},"wordCount":1346,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/","name":"Trump afirma que el r\u00e9gimen iran\u00ed est\u00e1 fracturado. La realidad es m\u00e1s compleja - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-23T06:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump afirma que el r\u00e9gimen iran\u00ed est\u00e1 fracturado. La realidad es m\u00e1s compleja"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump afirma que el r\u00e9gimen iran\u00ed est\u00e1 fracturado. La realidad es m\u00e1s compleja","url":"http:\/\/noticiasya.com\/kansas\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2026\/04\/22\/trump-afirma-regimen-irani-fracturado-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-23T06:03:51Z","datePublished":"2026-04-23T06:03:51Z","dateModified":"2026-04-23T06:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump afirma que el r\\u00e9gimen iran\\u00ed est\\u00e1 fracturado. La realidad es m\\u00e1s compleja\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/22\\\/trump-afirma-regimen-irani-fracturado-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/22\\\/trump-afirma-regimen-irani-fracturado-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-23T06:03:51Z\",\"datePublished\":\"2026-04-23T06:03:51Z\",\"dateModified\":\"2026-04-23T06:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473390,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/21\/ultimo-cambio-trump-iran-taco-trax\/","url_meta":{"origin":1473423,"position":0},"title":"Por qu\u00e9 el \u00faltimo cambio de postura de Trump sobre Ir\u00e1n podr\u00eda ser m\u00e1s que un simple TACO","author":"","date":"abril 21, 2026","format":false,"excerpt":"El presidente Donald Trump volvi\u00f3 a ceder y extendi\u00f3 el alto el fuego con Ir\u00e1n.Sus cr\u00edticos se burlan de otro TACO (\u201cTrump siempre se acobarda\u201d) este martes despu\u00e9s de que el presidente cediera en otra l\u00ednea roja personal d\u00edas despu\u00e9s de advertir que \u201cno habr\u00eda m\u00e1s Sr. Buen Tipo\u201d si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473454,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/23\/quien-cedera-guerra-iran-economia-trax\/","url_meta":{"origin":1473423,"position":1},"title":"\u00bfQui\u00e9n ceder\u00e1 primero mientras la guerra con Ir\u00e1n golpea a la econom\u00eda mundial?","author":"","date":"abril 23, 2026","format":false,"excerpt":"Con las conversaciones de paz estancadas y el presidente de Estados Unidos, Donald Trump, sin ofrecer un calendario para poner fin a la guerra con Ir\u00e1n, la pregunta en boca de todos es qui\u00e9n puede soportar por m\u00e1s tiempo el costo de este conflicto. Hay indicios crecientes de que podr\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472482,"url":"https:\/\/noticiasya.com\/kansas\/2026\/03\/24\/que-pasa-dia-25-guerra-estados-unidos-israel-iran-trax\/","url_meta":{"origin":1473423,"position":2},"title":"\u00bfQu\u00e9 est\u00e1 pasando al d\u00eda 25 de la guerra entre Estados Unidos e Israel e Ir\u00e1n?","author":"","date":"marzo 24, 2026","format":false,"excerpt":"El cambio de postura del presidente Donald Trump respecto a su ultim\u00e1tum a Ir\u00e1n ha aliviado la presi\u00f3n sobre los precios del petr\u00f3leo, incluso cuando Teher\u00e1n neg\u00f3 sus afirmaciones de que los dos pa\u00edses hab\u00edan hablado.La pausa de cinco d\u00edas en la amenaza de ataque de Trump ha dado un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471878,"url":"https:\/\/noticiasya.com\/kansas\/2026\/03\/04\/inteligencia-irani-mensaje-posible-fin-guerra-trax\/","url_meta":{"origin":1473423,"position":3},"title":"Inteligencia iran\u00ed env\u00eda mensaje a EE.UU. sobre posible fin de la guerra, pero Washington niega negociaciones activas","author":"","date":"marzo 4, 2026","format":false,"excerpt":"La inteligencia iran\u00ed envi\u00f3 un mensaje a Estados Unidos indicando que podr\u00eda estar preparada para abrir conversaciones sobre c\u00f3mo poner fin a la guerra, seg\u00fan personas familiarizadas con los mensajes indirectos, pero funcionarios estadounidenses afirman que no hay negociaciones en marcha y que es poco probable que se materialicen posibles\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461662,"url":"https:\/\/noticiasya.com\/kansas\/2025\/04\/26\/eeuu-e-iran-optimistas-cautela-conversaciones-nucleares-trax\/","url_meta":{"origin":1473423,"position":4},"title":"EE.UU. e Ir\u00e1n se muestran cautelosamente optimistas tras la tercera ronda de conversaciones nucleares","author":"","date":"abril 26, 2025","format":false,"excerpt":"Los l\u00edderes de Estados Unidos e Ir\u00e1n presentaron el s\u00e1bado un panorama optimista \u2014aunque cauteloso\u2014 de las conversaciones entre ambos pa\u00edses sobre el programa nuclear iran\u00ed, tras la conclusi\u00f3n de la tercera fase de las negociaciones en Om\u00e1n.El ministro de Asuntos Exteriores iran\u00ed, Abbas Araghchi, y el enviado estadounidense para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462213,"url":"https:\/\/noticiasya.com\/kansas\/2025\/05\/10\/eeuu-no-genuino-conversaciones-programa-nuclear-iran-trax\/","url_meta":{"origin":1473423,"position":5},"title":"EE.UU. &#171;no es genuino&#187; en las conversaciones sobre el programa nuclear de Teher\u00e1n, dice funcionario iran\u00ed","author":"","date":"mayo 10, 2025","format":false,"excerpt":"Un funcionario iran\u00ed dijo a CNN que las recientes conversaciones indirectas con Estados Unidos, destinadas a abordar el programa nuclear de Teher\u00e1n y levantar sanciones, \u201cno fueron genuinas\u201d por parte de los estadounidenses y probablemente fueron dise\u00f1adas desde el principio como una \u201ctrampa para llevar la situaci\u00f3n hacia la tensi\u00f3n\u201d.De\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1473423"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473423\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1473423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1473423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1473423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}