{"id":1473469,"date":"2026-04-24T08:03:54","date_gmt":"2026-04-24T15:03:54","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/"},"modified":"2026-04-24T08:03:54","modified_gmt":"2026-04-24T15:03:54","slug":"peru-elecciones-renuncias-polemicos-conteo-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/kansas\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/","title":{"rendered":"Tras 12 d\u00edas de las elecciones en Per\u00fa, el resultado sigue siendo una inc\u00f3gnita y crece la incertidumbre"},"content":{"rendered":"<p>El procesamiento de actas electorales en Per\u00fa termin\u00f3 este jueves, pero todav\u00eda faltan semanas para conocer el resultado de las presidenciales en Per\u00fa, ya que la revisi\u00f3n de votos impugnados podr\u00eda cambiar la estrecha diferencia entre el segundo y el tercer puesto, mientras las autoridades son presionadas con posibles escenarios fuera de la ley por las cr\u00edticas al proceso de votaci\u00f3n.<\/p>\n<p>Mientras la conservadora Keiko Fujimori (17,05 %) tiene asegurado el pase a la segunda vuelta, programada para junio, el izquierdista Roberto S\u00e1nchez (12,03 %) tiene solo 20.000 votos de ventaja sobre el ultraderechista Rafael L\u00f3pez Aliaga (11,91 %), por lo que habr\u00e1 que esperar la revisi\u00f3n de las cerca de 5.000 actas enviadas a los Jurados Electorales Especiales, un 5,6 % del total.<\/p>\n<p>El Jurado Nacional de Elecciones (JNE) se <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/21\/latinoamerica\/peru-revision-votos-impugnados-resultados-reux\">fij\u00f3 como fecha l\u00edmite el 15 de mayo<\/a> para anunciar resultados definitivos, y as\u00ed darles tiempo a los candidatos antes de la segunda vuelta.<\/p>\n<p>La ca\u00f3tica jornada del domingo 12 en Lima, donde hubo fallas log\u00edsticas para el reparto del material que causaron demoras de varias horas para la apertura de cientos mesas, puso a la Oficina Nacional de Procesos Electorales (ONPE) en el centro de las cr\u00edticas.<\/p>\n<p>Tras d\u00edas de se\u00f1alamientos, el titular del organismo, Piero Corvetto, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/21\/latinoamerica\/peru-piero-corvetto-renuncia-onpe-orix\">present\u00f3 su renuncia<\/a>, la cual fue aceptada por la Junta Nacional de Justicia (JNJ), pese a que ley estipula que su cargo es \u201cirrenunciable\u201d mientras haya una elecci\u00f3n o consulta popular abierta.<\/p>\n<p>El fiscal general Tom\u00e1s G\u00e1lvez inform\u00f3 que el Ministerio P\u00fablico solicit\u00f3 la detenci\u00f3n preliminar de Corvetto, quien est\u00e1 siendo investigado por la presunta comisi\u00f3n del delito de colusi\u00f3n. Sin embargo, este arresto no se llev\u00f3 a cabo. El exfuncionario declar\u00f3 en su carta de dimisi\u00f3n que est\u00e1 a disposici\u00f3n de las autoridades para esclarecer los hechos.<\/p>\n<p>La Fiscal\u00eda y la Polic\u00eda peruana allanaron la casa de Corvetto en la madrugada del viernes. \u201cEn estos momentos, la la DircocorPNP ejecuta 12 allanamientos\u201d, se\u00f1al\u00f3 en <a href=\"https:\/\/x.com\/dircocorp\/status\/2047629174337122388?s=46&#038;t=em5txf_Q-rzvUfhi9QOV7w\">su cuenta de X<\/a> la Direcci\u00f3n contra la Corrupci\u00f3n de la Polic\u00eda. Las autoridades informaron que los allanamientos incluyeron \u201cinmuebles vinculados al exjefe de la Oficina Nacional de Procesos Electorales, exfuncionarios y al representante legal de la empresa Galaga por el presunto delito de colusi\u00f3n agravada\u201d.<\/p>\n<p>L\u00f3pez Aliaga, que afirma haber sido el m\u00e1s perjudicado por las demoras en Lima (su basti\u00f3n electoral) por los ciudadanos que habr\u00edan desistido de votar ante las largas filas, contin\u00faa denunciando un fraude, sin presentar pruebas. \u201cCorvetto va a tener 20 a\u00f1os en la c\u00e1rcel. Me voy a encargar de eso. Voy a perseguirlo hasta que se muera\u201d, dijo en una transmisi\u00f3n en sus redes sociales.<\/p>\n<p>El l\u00edder de Renovaci\u00f3n Nacional insisti\u00f3 en su reclamo al JNE para que anule los comicios o convoque a una jornada de elecciones complementarias, aunque ninguna de estas posibilidades est\u00e1 contemplada en la ley.<\/p>\n<p>Corvetto ha rechazado en declaraciones a medios locales las denuncias en su contra.<\/p>\n<p>En medio de la crisis de legitimidad electoral para un pa\u00eds ya sacudido por la inestabilidad pol\u00edtica y falta de institucionalidad, el JNE realiz\u00f3 este mi\u00e9rcoles una extensa reuni\u00f3n a la que tambi\u00e9n fue convocada el nuevo jefe interino de la ONPE, Bernardo Pachas. Las autoridades no han confirmado si es que est\u00e1n evaluando medidas de mayor alcance.<\/p>\n<p>De todos modos, Fujimori se pronunci\u00f3 sobre la posibilidad de una nueva votaci\u00f3n. \u201cEstamos atentos a las decisiones y anuncios del JNE con referencia a unas elecciones complementarias que a\u00fan no sabemos si se van a dar o no\u201d, dijo la candidata de Fuerza Popular, en declaraciones citadas por El Comercio.<\/p>\n<p>Por su parte, partidos de izquierda piden poner freno a esas especulaciones e hicieron un llamado a respetar el voto popular. Diversas agrupaciones realizaron el mi\u00e9rcoles un plant\u00f3n frente a la sede del JNE para que no ceda ante los pedidos de realizar una votaci\u00f3n complementaria en Lima o anular todo el proceso.<\/p>\n<p>\u201cLo que el Jurado Nacional de Elecciones pretende hacer es socavar y generar una decisi\u00f3n absolutamente ilegal e inconstitucional, unas elecciones complementarias que tiene como fondo un pedido que ha hecho Renovaci\u00f3n Popular\u201d, dijo la congresista Ruth Luque, candidata al Senado por el partido de centroizquierda Ahora Naci\u00f3n. En tanto, el abogado de Roberto S\u00e1nchez, Roy Mendoza, dijo que si el JNE accede a convocar una nueva votaci\u00f3n estar\u00eda cediendo a la presi\u00f3n y a la extorsi\u00f3n electoral de algunos partidos pol\u00edticos.<\/p>\n<p>En ese sentido, la Asociaci\u00f3n Civil Transparencia, miembro de una de las principales misiones de observaci\u00f3n electoral, exhort\u00f3 a las autoridades a seguir \u201cdentro del marco legal y con la transparencia necesaria para recuperar la confianza de la ciudadan\u00eda\u201d. En un comunicado, indic\u00f3 que \u201ces urgente que se culmine el conteo de votos de la primera vuelta y que se respete el cronograma previsto para la segunda elecci\u00f3n presidencial\u201d.<\/p>\n<p>Cuando Jos\u00e9 Mar\u00eda Balc\u00e1zar asumi\u00f3 la presidencia en febrero tras la destituci\u00f3n de Jos\u00e9 Jer\u00ed (el octavo cambio en el Ejecutivo en la \u00faltima d\u00e9cada), prometi\u00f3 que garantizar\u00eda una transici\u00f3n electoral pac\u00edfica y transparente. Sin embargo, su Gobierno qued\u00f3 envuelto esta semana en una nueva crisis pol\u00edtica.<\/p>\n<p>El mandatario orden\u00f3 frenar una <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/22\/latinoamerica\/peru-polemica-compra-aviones-renuncias-orix\">compra de aviones F-16 <\/a>a Estados Unidos, para que la decisi\u00f3n quede a cargo de la nueva gesti\u00f3n que deber\u00eda asumir a fines de julio. El mi\u00e9rcoles, el canciller y el ministro de Defensa renunciaron en rechazo a esa medida y sostuvieron que el presidente ment\u00eda porque el contrato ya se hab\u00eda firmado cuando Balc\u00e1zar afirmaba que no. Posteriormente, el Consejo de Ministros dijo que se apegar\u00e1 a lo acordado y la cartera de Econom\u00eda confirm\u00f3 el primer pago.<\/p>\n<p>\u00bfFirmaron las Fuerzas Armadas el contrato a sabiendas de la oposici\u00f3n del jefe de Estado? El saliente ministro de Defensa Carlos D\u00edaz asegur\u00f3 que la compra sigui\u00f3 los procedimientos formales y que Balc\u00e1zar no emiti\u00f3 una orden escrita. \u201cNadie puede paralizar un procedimiento de selecci\u00f3n solamente de palabra\u201d, declar\u00f3 a la prensa.<\/p>\n<p>Bajo ese marco, el tercer vicepresidente del Congreso, Ilich L\u00f3pez, anunci\u00f3 que impulsa una moci\u00f3n de censura contra Balc\u00e1zar por su postura sobre la compra de aviones. Fernando Rospigliosi, titular del Legislativo, coment\u00f3 al respecto que si se alcanzan las firmas necesarias habr\u00e1 que \u201cdarle tr\u00e1mite como corresponde\u201d. En ese caso, Per\u00fa estar\u00eda a pocos pasos de alcanzar la cifra de 10 presidentes en 10 a\u00f1os.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El procesamiento de actas electorales en Per\u00fa termin\u00f3 este jueves, pero todav\u00eda faltan semanas para conocer el resultado de las presidenciales en Per\u00fa, ya que la revisi\u00f3n de votos impugnados podr\u00eda cambiar la estrecha diferencia entre el segundo y el tercer puesto, mientras las autoridades son presionadas con posibles escenarios fuera de la ley por [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473469","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tras 12 d\u00edas de las elecciones en Per\u00fa, el resultado sigue siendo una inc\u00f3gnita y crece la incertidumbre - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tras 12 d\u00edas de las elecciones en Per\u00fa, el resultado sigue siendo una inc\u00f3gnita y crece la incertidumbre - Noticias\" \/>\n<meta property=\"og:description\" content=\"El procesamiento de actas electorales en Per\u00fa termin\u00f3 este jueves, pero todav\u00eda faltan semanas para conocer el resultado de las presidenciales en Per\u00fa, ya que la revisi\u00f3n de votos impugnados podr\u00eda cambiar la estrecha diferencia entre el segundo y el tercer puesto, mientras las autoridades son presionadas con posibles escenarios fuera de la ley por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-24T15:03:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Tras 12 d\u00edas de las elecciones en Per\u00fa, el resultado sigue siendo una inc\u00f3gnita y crece la incertidumbre\",\"datePublished\":\"2026-04-24T15:03:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/\"},\"wordCount\":1154,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/\",\"name\":\"Tras 12 d\u00edas de las elecciones en Per\u00fa, el resultado sigue siendo una inc\u00f3gnita y crece la incertidumbre - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-24T15:03:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tras 12 d\u00edas de las elecciones en Per\u00fa, el resultado sigue siendo una inc\u00f3gnita y crece la incertidumbre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tras 12 d\u00edas de las elecciones en Per\u00fa, el resultado sigue siendo una inc\u00f3gnita y crece la incertidumbre - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Tras 12 d\u00edas de las elecciones en Per\u00fa, el resultado sigue siendo una inc\u00f3gnita y crece la incertidumbre - Noticias","og_description":"El procesamiento de actas electorales en Per\u00fa termin\u00f3 este jueves, pero todav\u00eda faltan semanas para conocer el resultado de las presidenciales en Per\u00fa, ya que la revisi\u00f3n de votos impugnados podr\u00eda cambiar la estrecha diferencia entre el segundo y el tercer puesto, mientras las autoridades son presionadas con posibles escenarios fuera de la ley por [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-24T15:03:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/"},"author":{"name":"","@id":""},"headline":"Tras 12 d\u00edas de las elecciones en Per\u00fa, el resultado sigue siendo una inc\u00f3gnita y crece la incertidumbre","datePublished":"2026-04-24T15:03:54+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/"},"wordCount":1154,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/","name":"Tras 12 d\u00edas de las elecciones en Per\u00fa, el resultado sigue siendo una inc\u00f3gnita y crece la incertidumbre - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-24T15:03:54+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Tras 12 d\u00edas de las elecciones en Per\u00fa, el resultado sigue siendo una inc\u00f3gnita y crece la incertidumbre"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Tras 12 d\u00edas de las elecciones en Per\u00fa, el resultado sigue siendo una inc\u00f3gnita y crece la incertidumbre","url":"http:\/\/noticiasya.com\/kansas\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/kansas\/2026\/04\/24\/peru-elecciones-renuncias-polemicos-conteo-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-24T15:03:54Z","datePublished":"2026-04-24T15:03:54Z","dateModified":"2026-04-24T15:03:54Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Tras 12 d\\u00edas de las elecciones en Per\\u00fa, el resultado sigue siendo una inc\\u00f3gnita y crece la incertidumbre\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/24\\\/peru-elecciones-renuncias-polemicos-conteo-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/kansas\\\/2026\\\/04\\\/24\\\/peru-elecciones-renuncias-polemicos-conteo-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-24T15:03:54Z\",\"datePublished\":\"2026-04-24T15:03:54Z\",\"dateModified\":\"2026-04-24T15:03:54Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473144,"url":"https:\/\/noticiasya.com\/kansas\/2026\/04\/14\/demora-resultados-elecciones-peru-orix\/","url_meta":{"origin":1473469,"position":0},"title":"Por qu\u00e9 a\u00fan no est\u00e1n los resultados en Per\u00fa: estas son las explicaciones","author":"","date":"abril 14, 2026","format":false,"excerpt":"El conteo de votos en Per\u00fa avanza con m\u00e1s lentitud que en las dos elecciones previas y sin un plazo concreto para tener resultados oficiales, con un re\u00f1ido escenario entre los candidatos que aspiran a acompa\u00f1ar a la l\u00edder Keiko Fujimori a segunda vuelta.La promesa de tener el 60 %\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469153,"url":"https:\/\/noticiasya.com\/kansas\/2025\/12\/10\/crisis-electoral-honduras-escrutinio-especial-dos-candidatos-rechazan-datos-orix\/","url_meta":{"origin":1473469,"position":1},"title":"Crisis electoral en Honduras: a la espera del escrutinio especial, dos candidatos rechazan los datos y hay movilizaciones","author":"","date":"diciembre 10, 2025","format":false,"excerpt":"Honduras vive d\u00edas de crisis electoral tras los comicios generales del 30 de noviembre, con cuestionamientos a los datos preliminares del escrutinio por parte de dos de los tres candidatos a la presidencia, y a la espera del escrutinio especial para revisar las actas que presentan inconsistencias.Si bien en principio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451661,"url":"https:\/\/noticiasya.com\/kansas\/2024\/08\/07\/actas-resultados-venezuela-oposicion-cne-comprobar-orix\/","url_meta":{"origin":1473469,"position":2},"title":"\u00bfPor qu\u00e9 los resultados de la oposici\u00f3n en Venezuela se pueden comprobar y los del CNE no?","author":"","date":"agosto 7, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Un an\u00e1lisis de varios expertos a pedido de CNN de los resultados ofrecidos tanto por el Consejo Nacional Electoral (CNE) como por el opositor Comando Con Venezuela de las elecciones presidenciales de ese pa\u00eds concluye que los n\u00fameros que dan como ganador al presidente Nicol\u00e1s Maduro \u201cson\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451483,"url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/29\/maria-corina-machado-pagina-web-verificar-victoria-elecciones-venezuela-orix\/","url_meta":{"origin":1473469,"position":3},"title":"Mar\u00eda Corina Machado asegura que tiene forma de comprobar la victoria de la oposici\u00f3n con una p\u00e1gina web que alberga las actas digitalizadas","author":"","date":"julio 29, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Mar\u00eda Corina Machado asegur\u00f3 en conferencia de prensa que su equipo trabaj\u00f3 durante m\u00e1s de 12 horas para la creaci\u00f3n de una p\u00e1gina web que alberga los resultados de las actas electorales y muestra la victoria de la oposici\u00f3n venezolana.\"Ya tenemos c\u00f3mo probar la verdad de lo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451544,"url":"https:\/\/noticiasya.com\/kansas\/2024\/08\/01\/centro-carter-patricio-ballados-actas-cne-venezuela-orix\/","url_meta":{"origin":1473469,"position":4},"title":"Funcionario del Centro Carter cuestiona que el CNE tenga las actas suficientes para declarar a un ganador, &#171;pero no para publicarlas&#187;","author":"","date":"agosto 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Patricio Ballados Villag\u00f3mez, subjefe de la misi\u00f3n del Centro Carter en Venezuela, dijo a Gabriela Fr\u00edas de CNN que \"es incongruente\" que el Consejo Nacional Electoral (CNE) tenga las actas suficientes para declarar a un ganador de la elecci\u00f3n presidencial y vaya a entregarlas al Tribunal Supremo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451484,"url":"https:\/\/noticiasya.com\/kansas\/2024\/07\/29\/leopoldo-lopez-elecciones-venezuela-fin-dictadura-maduro-orix\/","url_meta":{"origin":1473469,"position":5},"title":"Leopoldo L\u00f3pez sobre las elecciones en Venezuela: &#171;Este es el inicio del fin de la dictadura de Maduro&#187;","author":"","date":"julio 29, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El pol\u00edtico opositor Leopoldo L\u00f3pez asegur\u00f3 en entrevista con Fernando del Rinc\u00f3n de CNN que Venezuela vive \"el inicio del fin de la dictadura de Nicol\u00e1s Maduro\", pues \"el fraude es insostenible\" ante la evidencia con la que cuenta la oposici\u00f3n.\"La gente vot\u00f3 ayer y vot\u00f3 masivamente. Fue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/kansas\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/comments?post=1473469"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/posts\/1473469\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/media?parent=1473469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/categories?post=1473469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/kansas\/wp-json\/wp\/v2\/tags?post=1473469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}