{"id":1447661,"date":"2024-04-02T15:03:43","date_gmt":"2024-04-02T22:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/"},"modified":"2024-04-02T15:03:43","modified_gmt":"2024-04-02T22:03:43","slug":"don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/","title":{"rendered":"El multimillonario cuya empresa respald\u00f3 la fianza de US$ 175 millones de Trump revela c\u00f3mo se logr\u00f3 el acuerdo"},"content":{"rendered":"<p>(CNN) &#8212; Don Hankey, presidente y accionista mayoritario de Knight Specialty Insurance, dijo a CNN el martes que el acuerdo para suscribir la fianza de US$ 175 millones del expresidente Donald Trump en Nueva York se concret\u00f3 r\u00e1pidamente y que Trump present\u00f3 todo el efectivo como garant\u00eda.<\/p>\n<p>\u201cEs lo que hacemos. Estoy feliz de hacerlo. Lo habr\u00edamos hecho por cualquier otra persona\u201d, dijo Hankey en una entrevista telef\u00f3nica. \u201cFue una transacci\u00f3n f\u00e1cil. Se arm\u00f3 r\u00e1pidamente\u201d.<\/p>\n<p>Con sede en California, Knight Specialty Insurance es conocida por ofrecer pr\u00e9stamos de alto riesgo a compradores de autom\u00f3viles con puntajes crediticios m\u00e1s d\u00e9biles.<\/p>\n<p>Trump paga la fianza de US$ 175 millones para apelar caso de fraude civil en Nueva York<\/p>\n<p>Hankey, quien apoy\u00f3 las campa\u00f1as presidenciales de Trump, dijo que inicialmente contact\u00f3 a la Organizaci\u00f3n Trump el mes pasado cuando el expresidente ten\u00eda problemas para reunir una fianza de US$ 464 millones. Hankey amas\u00f3 una fortuna que Forbes valora en US$ 7.400 millones.<\/p>\n<p>&#171;Tuvimos una conversaci\u00f3n sobre c\u00f3mo reunir una fianza de ese tama\u00f1o&#187;, dijo Hankey a CNN.<\/p>\n<p>Despu\u00e9s de que un tribunal de apelaciones de Nueva York recort\u00f3 el monto de la fianza a US$ 175 millones, el equipo de Trump finalmente contact\u00f3 nuevamente a Knight Specialty, seg\u00fan Hankey.<\/p>\n<p>Al principio, Trump plane\u00f3 publicar una combinaci\u00f3n de bonos de grado de inversi\u00f3n y efectivo como garant\u00eda (80% bonos y 20% efectivo), dijo Hankey. Aunque Knight Specialty recibi\u00f3 los bonos y los aprob\u00f3, dijo que al final no se publicaron.<\/p>\n<p>\u201cAl final, puso todo el efectivo\u201d, dijo Hankey, y agreg\u00f3 que no sabe de d\u00f3nde provienen los US$ 175 millones en efectivo que Trump envi\u00f3.<\/p>\n<p>Hankey confirm\u00f3 a CNN que \u00e9l y su esposa, as\u00ed como sus dos hijos, han donado a las campa\u00f1as presidenciales de Trump en el pasado y planean apoyarlo nuevamente en 2024.<\/p>\n<p>Aunque Hankey indic\u00f3 que no hab\u00eda tenido noticias directas del presidente, dijo que Eric Trump se acerc\u00f3 el martes por la ma\u00f1ana para agradecerle por la operaci\u00f3n.<\/p>\n<p>No es la primera vez que los negocios de Hankey y Trump se entrelazan.<\/p>\n<p>En 2022, Axos Bank, un prestamista de California, le prest\u00f3 a Trump US$ 100 millones para refinanciar la hipoteca de la Torre Trump.<\/p>\n<p>Aunque Hankey es un accionista l\u00edder de Axos y lo era en el momento del pr\u00e9stamo de 2022, dijo que no estaba al tanto del pr\u00e9stamo de la Torre Trump en ese entonces.<\/p>\n<p>Trump: No hice nada malo<\/p>\n<p>El expresidente Donald Trump habl\u00f3 el martes ante la c\u00e1mara por primera vez sobre el pago de la fianza de US$ 175 millones mientras apela la sentencia en su contra en el caso de fraude civil de Nueva York y sostuvo que no hubo irregularidades.<\/p>\n<p>\u201cSoy el \u00fanico que tiene que pagar una fianza, ya sabes, puse una fianza, no hice nada malo. Tuve que pagar una fianza esta ma\u00f1ana por US$ 175 millones. No hice nada malo\u201d, dijo Trump en un evento de campa\u00f1a en Grand Rapids, Michigan.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Don Hankey, presidente y accionista mayoritario de Knight Specialty Insurance, dijo a CNN el martes que el acuerdo para suscribir la fianza de US$ 175 millones del expresidente Donald Trump en Nueva York se concret\u00f3 r\u00e1pidamente y que Trump present\u00f3 todo el efectivo como garant\u00eda. \u201cEs lo que hacemos. Estoy feliz de hacerlo. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447661","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El multimillonario cuya empresa respald\u00f3 la fianza de US$ 175 millones de Trump revela c\u00f3mo se logr\u00f3 el acuerdo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El multimillonario cuya empresa respald\u00f3 la fianza de US$ 175 millones de Trump revela c\u00f3mo se logr\u00f3 el acuerdo - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Don Hankey, presidente y accionista mayoritario de Knight Specialty Insurance, dijo a CNN el martes que el acuerdo para suscribir la fianza de US$ 175 millones del expresidente Donald Trump en Nueva York se concret\u00f3 r\u00e1pidamente y que Trump present\u00f3 todo el efectivo como garant\u00eda. \u201cEs lo que hacemos. Estoy feliz de hacerlo. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-02T22:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El multimillonario cuya empresa respald\u00f3 la fianza de US$ 175 millones de Trump revela c\u00f3mo se logr\u00f3 el acuerdo\",\"datePublished\":\"2024-04-02T22:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/\"},\"wordCount\":547,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/\",\"name\":\"El multimillonario cuya empresa respald\u00f3 la fianza de US$ 175 millones de Trump revela c\u00f3mo se logr\u00f3 el acuerdo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-02T22:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El multimillonario cuya empresa respald\u00f3 la fianza de US$ 175 millones de Trump revela c\u00f3mo se logr\u00f3 el acuerdo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El multimillonario cuya empresa respald\u00f3 la fianza de US$ 175 millones de Trump revela c\u00f3mo se logr\u00f3 el acuerdo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El multimillonario cuya empresa respald\u00f3 la fianza de US$ 175 millones de Trump revela c\u00f3mo se logr\u00f3 el acuerdo - Noticias","og_description":"(CNN) &#8212; Don Hankey, presidente y accionista mayoritario de Knight Specialty Insurance, dijo a CNN el martes que el acuerdo para suscribir la fianza de US$ 175 millones del expresidente Donald Trump en Nueva York se concret\u00f3 r\u00e1pidamente y que Trump present\u00f3 todo el efectivo como garant\u00eda. \u201cEs lo que hacemos. Estoy feliz de hacerlo. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-02T22:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/"},"author":{"name":"","@id":""},"headline":"El multimillonario cuya empresa respald\u00f3 la fianza de US$ 175 millones de Trump revela c\u00f3mo se logr\u00f3 el acuerdo","datePublished":"2024-04-02T22:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/"},"wordCount":547,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/","name":"El multimillonario cuya empresa respald\u00f3 la fianza de US$ 175 millones de Trump revela c\u00f3mo se logr\u00f3 el acuerdo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-02T22:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El multimillonario cuya empresa respald\u00f3 la fianza de US$ 175 millones de Trump revela c\u00f3mo se logr\u00f3 el acuerdo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El multimillonario cuya empresa respald\u00f3 la fianza de US$ 175 millones de Trump revela c\u00f3mo se logr\u00f3 el acuerdo","url":"http:\/\/noticiasya.com\/laredo\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/04\/02\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-02T22:03:43Z","datePublished":"2024-04-02T22:03:43Z","dateModified":"2024-04-02T22:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El multimillonario cuya empresa respald\\u00f3 la fianza de US$ 175 millones de Trump revela c\\u00f3mo se logr\\u00f3 el acuerdo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/04\\\/02\\\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/04\\\/02\\\/don-hankey-revela-como-respaldo-fianza-millonaria-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-02T22:03:43Z\",\"datePublished\":\"2024-04-02T22:03:43Z\",\"dateModified\":\"2024-04-02T22:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1447620,"url":"https:\/\/noticiasya.com\/laredo\/2024\/04\/01\/trump-fianza-fraude-nueva-york-millones-trax\/","url_meta":{"origin":1447661,"position":0},"title":"Trump paga la fianza de US$ 175 millones para apelar caso de fraude civil en Nueva York","author":"","date":"abril 1, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El expresidente de Estados Unidos Donald Trump pag\u00f3 una fianza de 175 millones de d\u00f3lares para apelar el fallo en su contra en un caso de fraude civil en Nueva York, el cual present\u00f3 la fiscal general del estado Letitia James.Esto es lo que puede pasar si Trump\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446475,"url":"https:\/\/noticiasya.com\/laredo\/2024\/03\/04\/trump-liquidez-sentencias-500-trax-2\/","url_meta":{"origin":1447661,"position":1},"title":"\u00bfC\u00f3mo Trump (de repente sin liquidez) podr\u00eda recaudar m\u00e1s de US$ 500 millones para cumplir sentencias en su contra?","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) --\u00a0Donald Trump se enfrenta a una crisis de liquidez a medida que se acercan r\u00e1pidamente los plazos para liquidar los m\u00e1s de US$ 500 millones que debe en sentencias.Ahora puedes seguirnos en\u00a0WhatsApp ChannelEl mi\u00e9rcoles, un juez de la corte de apelaciones de Nueva York se neg\u00f3 a darle al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446153,"url":"https:\/\/noticiasya.com\/laredo\/2024\/03\/01\/trump-liquidez-sentencias-500-trax\/","url_meta":{"origin":1447661,"position":2},"title":"\u00bfC\u00f3mo Trump (de repente sin liquidez) podr\u00eda recaudar m\u00e1s de US$ 500 millones para cumplir sentencias en su contra?","author":"","date":"marzo 1, 2024","format":false,"excerpt":"(CNN) --\u00a0Donald Trump se enfrenta a una crisis de liquidez a medida que se acercan r\u00e1pidamente los plazos para liquidar los m\u00e1s de US$ 500 millones que debe en sentencias.El mi\u00e9rcoles, un juez de la corte de apelaciones de Nueva York se neg\u00f3 a darle al expresidente tiempo adicional para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447137,"url":"https:\/\/noticiasya.com\/laredo\/2024\/03\/20\/trump-modo-panico-plazo-pagar-millonaria-fianza-juicio-fraude-civil-trax\/","url_meta":{"origin":1447661,"position":3},"title":"Trump entra en modo p\u00e1nico mientras se enfrenta al plazo para pagar una enorme fianza en el juicio por fraude civil","author":"","date":"marzo 20, 2024","format":false,"excerpt":"(CNN) -- El expresidente Donald Trump est\u00e1 en modo de p\u00e1nico a medida que se acerca el plazo para asegurar una fianza de casi US$ 500 millones para apelar su caso de fraude civil en Nueva York, seg\u00fan m\u00faltiples fuentes familiarizadas con \u00e9l.Los abogados de Trump admitieron este lunes que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447305,"url":"https:\/\/noticiasya.com\/laredo\/2024\/03\/24\/trump-consigue-fianza-464-millones-nueva-york-trax\/","url_meta":{"origin":1447661,"position":4},"title":"Esto es lo que puede pasar si Trump no consigue la fianza de US$ 464 millones","author":"","date":"marzo 24, 2024","format":false,"excerpt":"(CNN) -- El equipo legal de Donald Trump y la oficina del fiscal general de Nueva York trabajan duro antes de que este lunes venza el plazo para que el expresidente obtenga una fianza por la multimillonaria sentencia por fraude civil que pesa en su contra.Trump debe personalmente m\u00e1s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447208,"url":"https:\/\/noticiasya.com\/laredo\/2024\/03\/21\/fiscal-general-nueva-york-embargo-bienes-trump-trax\/","url_meta":{"origin":1447661,"position":5},"title":"La Fiscal\u00eda de Nueva York da el primer paso para preparar el embargo de bienes de Trump","author":"","date":"marzo 21, 2024","format":false,"excerpt":"(CNN) \u2013\u2013\u00a0La Fiscal\u00eda General de Nueva York present\u00f3 sentencias en el condado de Westchester, en lo que representa la primera se\u00f1al de que el estado se prepara para intentar embargar el campo de golf y la finca privada de Donald Trump al norte de Manhattan, conocidos como Seven Springs.Los abogados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1447661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1447661"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1447661\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1447661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1447661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1447661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}