{"id":1447856,"date":"2024-04-08T13:03:59","date_gmt":"2024-04-08T20:03:59","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/"},"modified":"2024-04-08T13:03:59","modified_gmt":"2024-04-08T20:03:59","slug":"tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/","title":{"rendered":"Tiroteo en Las Vegas deja al menos dos personas muertas, adem\u00e1s del sospechoso, informa la Polic\u00eda"},"content":{"rendered":"<p>(CNN) \u2013\u2013 Dos personas murieron tras un tiroteo en una oficina de abogados en el \u00e1rea de Summerlin de Las Vegas, Nevada, este lunes, dijo el Departamento de Polic\u00eda Metropolitana de Las Vegas.<\/p>\n<p>El sospechoso tambi\u00e9n falleci\u00f3 despu\u00e9s de quitarse la vida, indic\u00f3 el sheriff Kevin McMahill durante una conferencia de prensa. Las v\u00edctimas fueron identificadas como un hombre y una mujer.<\/p>\n<p>Seg\u00fan la Polic\u00eda, no est\u00e1 claro c\u00f3mo se conoc\u00edan el sospechoso y las v\u00edctimas.<\/p>\n<p>Alrededor de las 10:00 a.m., hora local, las autoridades respondieron a llamadas sobre un incidente con un atacante en el quinto piso de un edificio de seis pisos ubicado en 10801 West Charleston.<\/p>\n<p>Seg\u00fan McMahill, ya no existe una amenaza para la comunidad. A\u00fan as\u00ed, cientos de personas que estaban en el edificio en ese momento todav\u00eda est\u00e1n siendo evaluadas despu\u00e9s de que las evacuaran.<\/p>\n<p>Los funcionarios tambi\u00e9n observan activamente el veh\u00edculo del sospechoso, a\u00f1adi\u00f3 McMahill. Hasta el momento no se ha identificado un motivo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 Dos personas murieron tras un tiroteo en una oficina de abogados en el \u00e1rea de Summerlin de Las Vegas, Nevada, este lunes, dijo el Departamento de Polic\u00eda Metropolitana de Las Vegas. El sospechoso tambi\u00e9n falleci\u00f3 despu\u00e9s de quitarse la vida, indic\u00f3 el sheriff Kevin McMahill durante una conferencia de prensa. Las v\u00edctimas fueron [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447856","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tiroteo en Las Vegas deja al menos dos personas muertas, adem\u00e1s del sospechoso, informa la Polic\u00eda - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tiroteo en Las Vegas deja al menos dos personas muertas, adem\u00e1s del sospechoso, informa la Polic\u00eda - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 Dos personas murieron tras un tiroteo en una oficina de abogados en el \u00e1rea de Summerlin de Las Vegas, Nevada, este lunes, dijo el Departamento de Polic\u00eda Metropolitana de Las Vegas. El sospechoso tambi\u00e9n falleci\u00f3 despu\u00e9s de quitarse la vida, indic\u00f3 el sheriff Kevin McMahill durante una conferencia de prensa. Las v\u00edctimas fueron [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-08T20:03:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Tiroteo en Las Vegas deja al menos dos personas muertas, adem\u00e1s del sospechoso, informa la Polic\u00eda\",\"datePublished\":\"2024-04-08T20:03:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/\"},\"wordCount\":210,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/\",\"name\":\"Tiroteo en Las Vegas deja al menos dos personas muertas, adem\u00e1s del sospechoso, informa la Polic\u00eda - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-08T20:03:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tiroteo en Las Vegas deja al menos dos personas muertas, adem\u00e1s del sospechoso, informa la Polic\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tiroteo en Las Vegas deja al menos dos personas muertas, adem\u00e1s del sospechoso, informa la Polic\u00eda - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/","og_locale":"es_ES","og_type":"article","og_title":"Tiroteo en Las Vegas deja al menos dos personas muertas, adem\u00e1s del sospechoso, informa la Polic\u00eda - Noticias","og_description":"(CNN) \u2013\u2013 Dos personas murieron tras un tiroteo en una oficina de abogados en el \u00e1rea de Summerlin de Las Vegas, Nevada, este lunes, dijo el Departamento de Polic\u00eda Metropolitana de Las Vegas. El sospechoso tambi\u00e9n falleci\u00f3 despu\u00e9s de quitarse la vida, indic\u00f3 el sheriff Kevin McMahill durante una conferencia de prensa. Las v\u00edctimas fueron [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/","og_site_name":"Noticias","article_published_time":"2024-04-08T20:03:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/"},"author":{"name":"","@id":""},"headline":"Tiroteo en Las Vegas deja al menos dos personas muertas, adem\u00e1s del sospechoso, informa la Polic\u00eda","datePublished":"2024-04-08T20:03:59+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/"},"wordCount":210,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/","url":"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/","name":"Tiroteo en Las Vegas deja al menos dos personas muertas, adem\u00e1s del sospechoso, informa la Polic\u00eda - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-08T20:03:59+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Tiroteo en Las Vegas deja al menos dos personas muertas, adem\u00e1s del sospechoso, informa la Polic\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Tiroteo en Las Vegas deja al menos dos personas muertas, adem\u00e1s del sospechoso, informa la Polic\u00eda","url":"http:\/\/noticiasya.com\/laredo\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/04\/08\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-08T20:03:59Z","datePublished":"2024-04-08T20:03:59Z","dateModified":"2024-04-08T20:03:59Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Tiroteo en Las Vegas deja al menos dos personas muertas, adem\\u00e1s del sospechoso, informa la Polic\\u00eda\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/04\\\/08\\\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/04\\\/08\\\/tiroteo-en-las-vegas-deja-al-menos-dos-personas-muertas-ademas-del-sospechoso-informa-la-policia\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-08T20:03:59Z\",\"datePublished\":\"2024-04-08T20:03:59Z\",\"dateModified\":\"2024-04-08T20:03:59Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1457158,"url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/02\/conductor-tesla-cybertruck-disparo-trax\/","url_meta":{"origin":1447856,"position":0},"title":"El conductor del Tesla Cybertruck se dispar\u00f3 antes de la explosi\u00f3n, dice la polic\u00eda","author":"","date":"enero 2, 2025","format":false,"excerpt":"El conductor del Tesla Cybertruck que explot\u00f3 frente al Trump International Hotel en Las Vegas el mi\u00e9rcoles se dispar\u00f3 en la cabeza antes de la explosi\u00f3n, seg\u00fan inform\u00f3 la polic\u00eda.Aunque los funcionarios solo se refirieron al conductor como el \u201csujeto\u201d y la \u201cpersona de inter\u00e9s\u201d, mostraron una foto de Matthew\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469413,"url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/19\/investigacion-sospechoso-tiroteo-universidad-brown-trax\/","url_meta":{"origin":1447856,"position":1},"title":"C\u00f3mo dieron con el sospechoso del tiroteo en la Universidad de Brown y lo vincularon con el asesinato de un profesor del MIT","author":"","date":"diciembre 19, 2025","format":false,"excerpt":"Cinco d\u00edas despu\u00e9s de que comenzara una extensa b\u00fasqueda, la polic\u00eda se acerc\u00f3 al sospechoso del tiroteo en la Universidad de Brown tras surgir aparentes v\u00ednculos entre el ataque del s\u00e1bado en la escuela de Providence, Rhode Island, y la muerte dos d\u00edas m\u00e1s tarde de un profesor del MIT\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457327,"url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/07\/boina-verde-cybertruck-uso-ia-explosion-trax\/","url_meta":{"origin":1447856,"position":2},"title":"El boina verde que hizo explotar un Cybertruck en Las Vegas us\u00f3 IA para planificar la explosi\u00f3n, seg\u00fan autoridades","author":"","date":"enero 7, 2025","format":false,"excerpt":"El boina verde del Ej\u00e9rcito de EE.UU. que, seg\u00fan las autoridades, hizo explotar una Tesla Cybertruck afuera del Trump International Hotel en Las Vegas la semana pasada, utiliz\u00f3 inteligencia artificial para planear la explosi\u00f3n, seg\u00fan el Departamento de Polic\u00eda Metropolitana de Las Vegas.El sheriff Kevin McMahill dijo en una conferencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462679,"url":"https:\/\/noticiasya.com\/laredo\/2025\/05\/22\/quien-es-sospechoso-tiroteo-washington-elias-rodriguez-orix\/","url_meta":{"origin":1447856,"position":3},"title":"\u00bfQui\u00e9n es El\u00edas Rodr\u00edguez, el sospechoso del tiroteo frente al Museo Jud\u00edo Capital en Washington?","author":"","date":"mayo 22, 2025","format":false,"excerpt":"Dos miembros del personal de la Embajada de Israel en Estados Unidos murieron la noche del mi\u00e9rcoles tras un tiroteo frente al Museo Jud\u00edo Capital, en Washington. El hecho ha sido calificado por las autoridades como un \u201cacto de violencia selectiva\u201d, y ha encendido las alarmas en varios pa\u00edses.El sospechoso,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450933,"url":"https:\/\/noticiasya.com\/laredo\/2024\/07\/07\/arrestan-a-tercer-sospechoso-de-tiroteo-masivo-en-celebracion-del-juneteenth-en-texas-que-dejo-2-muertos-y-14-heridos\/","url_meta":{"origin":1447856,"position":4},"title":"Arrestan a tercer sospechoso de tiroteo masivo en celebraci\u00f3n del Juneteenth en Texas que dej\u00f3 2 muertos y 14 heridos","author":"","date":"julio 7, 2024","format":false,"excerpt":"(CNN) -- Un tercer sospechoso fue\u00a0 arrestado en relaci\u00f3n con un tiroteo masivo en una celebraci\u00f3n del Juneteenth que dej\u00f3 dos personas muertas y otras 14 heridas en Round Rock, Texas, seg\u00fan la Polic\u00eda.Keshawn Dixon, de 18 a\u00f1os, fue arrestado este s\u00e1bado en Killeen, Texas, y llevado a la c\u00e1rcel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469443,"url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/20\/tiroteo-universidad-brown-mit-preguntas-trax\/","url_meta":{"origin":1447856,"position":5},"title":"Los interrogantes que a\u00fan persisten sobre el tiroteo de la Universidad de Brown y el asesinato de un profesor del MIT","author":"","date":"diciembre 20, 2025","format":false,"excerpt":"Las luces de la polic\u00eda brillaron durante horas mientras los agentes rodeaban un almac\u00e9n en Salem, New Hampshire, el jueves por la noche, acerc\u00e1ndose finalmente al sospechoso que desat\u00f3 ataques mortales en dos comunidades y hab\u00eda logrado evadirlos durante seis d\u00edas.Afuera hab\u00eda un auto abandonado relacionado con el tiroteo masivo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1447856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1447856"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1447856\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1447856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1447856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1447856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}