{"id":1448159,"date":"2024-04-16T13:03:48","date_gmt":"2024-04-16T20:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/"},"modified":"2024-04-16T13:03:48","modified_gmt":"2024-04-16T20:03:48","slug":"encienden-llama-olimpica-paris-2024-grecia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/","title":{"rendered":"Encienden la llama de Par\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\u00edmpicos"},"content":{"rendered":"<p>(CNN) &#8212; La llama de los Juegos Ol\u00edmpicos de Par\u00eds 2024 se encendi\u00f3 en Olimpia, la cuna de los antiguos Juegos Ol\u00edmpicos. La llama comenzar\u00e1 ahora su recorrido en un relevo para encender el pebetero que marcar\u00e1 la apertura de los Juegos en julio.<\/p>\n<p>Dignatarios y miembros del p\u00fablico se reunieron en el estadio, donde se celebraron los primeros Juegos registrados en el a\u00f1o 776 a. C., para presenciar el encendido de la llama.<\/p>\n<p>En un evento coreografiado lleno de simbolismo inspirado en las tradiciones y valores de la antigua Grecia, actrices vestidas como antiguas sacerdotisas ingresaron al estadio para acompa\u00f1ar elegantemente a la sacerdotisa principal al Templo de Hera, donde se cree que tuvieron lugar ceremonias religiosas en la antigua Grecia y donde se realiza la ceremonia de encendido.<\/p>\n<p>La actriz griega Mary Mina, que interpreta el papel de Suma Sacerdotisa, lleva la antorcha durante la ceremonia de encendido de la Llama Ol\u00edmpica para los Juegos Ol\u00edmpicos de Par\u00eds 2024. Alkis Konstantinidis\/Reuters<\/p>\n<p>Pidiendo ayuda al dios de la luz, Apolo, la sacerdotisa principal encendi\u00f3 la llama con la ayuda de los rayos del sol, sosteniendo una antorcha llena de combustible frente a un espejo parab\u00f3lico.<\/p>\n<p>El primer ritual coreografiado de este tipo se estableci\u00f3 por primera vez para los Juegos de Berl\u00edn de 1936, con el vestuario y los dise\u00f1os de las antorchas capturando las mentes de los creativos.<\/p>\n<p>En la antigua Olimpia, sede de los antiguos Juegos Ol\u00edmpicos durante m\u00e1s de 1.000 a\u00f1os, se pensaba que una llama ard\u00eda perpetuamente en un santuario, simbolizando el esp\u00edritu eterno de los Juegos: la b\u00fasqueda duradera de la excelencia y la unidad humana.<\/p>\n<p>La llama ser\u00e1 llevada por Grecia durante 11 d\u00edas antes de ser entregada a los organizadores de Par\u00eds el 26 de abril. Thanassis Stavrakis\/AP<\/p>\n<p>M\u00e1s de 10.000 portadores de la antorcha y miles de kil\u00f3metros<\/p>\n<p>El primer corredor del relevo de la antorcha ol\u00edmpica es el remero griego Stefanos Ntouskos, medallista de oro ol\u00edmpico.<\/p>\n<p>En declaraciones a CNN antes de la ceremonia, Ntouskos describi\u00f3 ser el primer portador de la antorcha como \u201cun gran honor\u201d.<\/p>\n<p>\u201cComo griego, me han criado con im\u00e1genes del relevo y es incre\u00edble estar hoy aqu\u00ed, en la antigua Olimpia, y recibir una llama que viajar\u00e1 hasta los Juegos Ol\u00edmpicos de Par\u00eds\u201d, a\u00f1adi\u00f3.<\/p>\n<p>El medallista de oro ol\u00edmpico griego Stefanos Ntouskos es el primer portador de la antorcha en el relevo de este a\u00f1o. Elinda Labropoulou\/CNN<\/p>\n<p>Ntouskos dijo que estaba un poco ansioso antes de competir en Par\u00eds 2024, pero tambi\u00e9n muy emocionado.<\/p>\n<p>\u201cHe hecho muchas carreras y s\u00e9 lo dif\u00edcil que es, pero creo que pasar\u00e9 grandes momentos all\u00ed\u201d, dijo.<\/p>\n<p>La primera parte del relevo es un viaje de 5.000 kil\u00f3metros a trav\u00e9s de Grecia durante 11 d\u00edas, en el que se espera que participen m\u00e1s de 600 portadores de la antorcha, desde atletas de \u00e9lite hasta miembros del p\u00fablico.<\/p>\n<p>La l\u00ednea de meta es el Estadio Panatenaico en el coraz\u00f3n de Atenas \u2013 el sitio hist\u00f3rico de los primeros Juegos Ol\u00edmpicos modernos en 1896 \u2013 donde, en una ceremonia de entrega el 26 de abril, se entregar\u00e1 la llama a los organizadores de los Juegos Ol\u00edmpicos de Par\u00eds.<\/p>\n<p>Luego se embarcar\u00e1 hacia la ciudad portuaria francesa de Marsella en el Belem, de tres m\u00e1stiles y 120 a\u00f1os de antig\u00fcedad, un buque hist\u00f3rico que comenz\u00f3 su vida como un carguero que transportaba az\u00facar desde las Indias Occidentales.<\/p>\n<p>Los relevos a lo largo de los a\u00f1os han incluido muchos viajes de aventuras; la llama ha dado la vuelta al mundo, ha ido al espacio, ha viajado bajo el agua y ha escalado el Everest.<\/p>\n<p>Se espera que llegue a Francia el 8 de mayo, donde comenzar\u00e1 la siguiente etapa del relevo.<\/p>\n<p>Ntouskos llevando el toque durante el inicio del relevo. M\u00e1s de 600 portadores de la antorcha participar\u00e1n en un viaje de 5.000 kil\u00f3metros a trav\u00e9s de Grecia durante los pr\u00f3ximos 11 d\u00edas antes de que la llama sea entregada a Francia. Louisa Gouliamaki\/Reuters<\/p>\n<p>A lo largo de los a\u00f1os, la antorcha ha sido llevada por cientos de miles de personas. En este recorrido, se espera que pase de mano en mano por unos 10.000 portadores de la antorcha y llegue al pebetero ol\u00edmpico en Par\u00eds el 26 de julio, donde permanecer\u00e1 encendido hasta la Ceremonia de Clausura dos semanas despu\u00e9s.<\/p>\n<p>La llama tambi\u00e9n iluminar\u00e1 los Juegos Paral\u00edmpicos, que tendr\u00e1n lugar del 28 de agosto al 8 de septiembre, donde 1.000 portadores de la antorcha ayudar\u00e1n a relevar la antorcha en 50 pueblos y ciudades francesas.<\/p>\n<p>Los franceses han prometido unos Juegos fastuosos y son los primeros en anunciar una ceremonia de apertura que se celebrar\u00e1 fuera de un estadio. Seg\u00fan los organizadores locales, el plan inicial es que unos 10.500 atletas desfilen por el coraz\u00f3n de la capital francesa a lo largo del r\u00edo Sena.<\/p>\n<p>Francia anunci\u00f3 recientemente que la capacidad de asistencia a la Ceremonia de Apertura se reducir\u00e1 a la mitad por razones de seguridad, hasta aproximadamente 324.000 personas de las 600.000 originales.<\/p>\n<p>En una entrevista el lunes, el presidente de Francia, Emmanuel Macron, dijo que, debido a preocupaciones de seguridad, se contempla un Plan B que podr\u00eda trasladar la ceremonia a un estadio. Tambi\u00e9n habl\u00f3 de sus intenciones de promover los ideales de la Tregua Ol\u00edmpica.<\/p>\n<p>Los Juegos antiguos serv\u00edan no s\u00f3lo como plataforma para la competici\u00f3n atl\u00e9tica sino tambi\u00e9n como s\u00edmbolo de unidad y promoci\u00f3n de la paz. Durante los Juegos se observ\u00f3 una tregua sagrada. El objetivo de la Tregua Ol\u00edmpica era proporcionar un paso seguro para los atletas y espectadores que viajaban hacia y desde Olimpia.<\/p>\n<p>Ha habido muchos esfuerzos para revivir la Tregua Ol\u00edmpica que la ONU invoca regularmente como objetivo universal desde 1993. Hasta ahora no ha tenido mucho \u00e9xito.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La llama de los Juegos Ol\u00edmpicos de Par\u00eds 2024 se encendi\u00f3 en Olimpia, la cuna de los antiguos Juegos Ol\u00edmpicos. La llama comenzar\u00e1 ahora su recorrido en un relevo para encender el pebetero que marcar\u00e1 la apertura de los Juegos en julio. Dignatarios y miembros del p\u00fablico se reunieron en el estadio, donde [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448159","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Encienden la llama de Par\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\u00edmpicos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encienden la llama de Par\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\u00edmpicos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La llama de los Juegos Ol\u00edmpicos de Par\u00eds 2024 se encendi\u00f3 en Olimpia, la cuna de los antiguos Juegos Ol\u00edmpicos. La llama comenzar\u00e1 ahora su recorrido en un relevo para encender el pebetero que marcar\u00e1 la apertura de los Juegos en julio. Dignatarios y miembros del p\u00fablico se reunieron en el estadio, donde [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-16T20:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Encienden la llama de Par\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\u00edmpicos\",\"datePublished\":\"2024-04-16T20:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/\"},\"wordCount\":1043,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/\",\"name\":\"Encienden la llama de Par\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\u00edmpicos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-16T20:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Encienden la llama de Par\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\u00edmpicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Encienden la llama de Par\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\u00edmpicos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Encienden la llama de Par\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\u00edmpicos - Noticias","og_description":"(CNN) &#8212; La llama de los Juegos Ol\u00edmpicos de Par\u00eds 2024 se encendi\u00f3 en Olimpia, la cuna de los antiguos Juegos Ol\u00edmpicos. La llama comenzar\u00e1 ahora su recorrido en un relevo para encender el pebetero que marcar\u00e1 la apertura de los Juegos en julio. Dignatarios y miembros del p\u00fablico se reunieron en el estadio, donde [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-16T20:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/"},"author":{"name":"","@id":""},"headline":"Encienden la llama de Par\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\u00edmpicos","datePublished":"2024-04-16T20:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/"},"wordCount":1043,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/","name":"Encienden la llama de Par\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\u00edmpicos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-16T20:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Encienden la llama de Par\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\u00edmpicos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Encienden la llama de Par\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\u00edmpicos","url":"http:\/\/noticiasya.com\/laredo\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-16T20:03:48Z","datePublished":"2024-04-16T20:03:48Z","dateModified":"2024-04-16T20:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Encienden la llama de Par\\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\\u00edmpicos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/04\\\/16\\\/encienden-llama-olimpica-paris-2024-grecia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/04\\\/16\\\/encienden-llama-olimpica-paris-2024-grecia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-16T20:03:48Z\",\"datePublished\":\"2024-04-16T20:03:48Z\",\"dateModified\":\"2024-04-16T20:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451406,"url":"https:\/\/noticiasya.com\/laredo\/2024\/07\/25\/origen-historia-juegos-olimpicos-orix\/","url_meta":{"origin":1448159,"position":0},"title":"\u00bfCu\u00e1l es el origen de los Juegos Ol\u00edmpicos y por qu\u00e9 se celebran cada cuatro a\u00f1os?","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Los Juegos Ol\u00edmpicos, uno de los eventos m\u00e1s importantes a nivel mundial, que vincula el deporte y la cultura, tiene una historia que se remonta a m\u00e1s de 2.000 de a\u00f1os.Desde sus comienzos en la antigua Grecia hasta su resurgimiento en la era moderna, los Juegos Ol\u00edmpicos han\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451361,"url":"https:\/\/noticiasya.com\/laredo\/2024\/07\/23\/donde-competira-deportes-juegos-olimpicos-paris-trax\/","url_meta":{"origin":1448159,"position":1},"title":"D\u00f3nde competir\u00e1 cada uno de los deportes de los Juegos Ol\u00edmpicos de Par\u00eds","author":"","date":"julio 23, 2024","format":false,"excerpt":"(CNN) -- Este verano est\u00e1n pasando muchas cosas a la vez en Par\u00eds.Los Juegos Ol\u00edmpicos llegan a la capital francesa y ya se conoce d\u00f3nde se desarrollar\u00e1n las 32 disciplinas.Muchos de los recintos ya exist\u00edan antes de los Juegos. La \u00fanica instalaci\u00f3n deportiva permanente construida para los Juegos Ol\u00edmpicos es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451730,"url":"https:\/\/noticiasya.com\/laredo\/2024\/08\/11\/conclusiones-ceremonia-clausura-juegos-olimpicos-trax\/","url_meta":{"origin":1448159,"position":2},"title":"Cinco conclusiones de una ceremonia de clausura de Juegos Ol\u00edmpicos memorable","author":"","date":"agosto 11, 2024","format":false,"excerpt":"(CNN) -- El Stade de France fue una fiesta que clausur\u00f3 dos semanas y media electrizantes de los Juegos Ol\u00edmpicos de verano con una celebraci\u00f3n de los atletas, las personas que hicieron posible los Juegos y un adelanto de lo que se puede esperar en cuatro a\u00f1os.Estos son cinco conclusiones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451727,"url":"https:\/\/noticiasya.com\/laredo\/2024\/08\/11\/tom-cruise-salto-techo-clausura-juegos-olimpicos-trax\/","url_meta":{"origin":1448159,"position":3},"title":"Tom Cruise salt\u00f3 desde el techo del estadio de Francia en la clausura de los Juegos Ol\u00edmpicos","author":"","date":"agosto 11, 2024","format":false,"excerpt":"(CNN) -- Los Juegos Ol\u00edmpicos est\u00e1n a punto de convertirse en algo propio de Hollywood, y Tom Cruise dio un adelanto de c\u00f3mo ser\u00e1 la pr\u00f3xima edici\u00f3n en Los \u00c1ngeles 2028.Durante la ceremonia de clausura del domingo, la estrella de \u201cMission: Impossible\u201d realiz\u00f3 un atrevido salto desde lo alto del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451447,"url":"https:\/\/noticiasya.com\/laredo\/2024\/07\/26\/donde-cuando-proximos-juegos-olimpicos-novedades-orix\/","url_meta":{"origin":1448159,"position":4},"title":"D\u00f3nde y cu\u00e1ndo se celebran los pr\u00f3ximos Juegos Ol\u00edmpicos (en 2028) y qu\u00e9 novedades tendr\u00e1n","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Faltan otros cuatro a\u00f1os para que los pr\u00f3ximos Juegos Ol\u00edmpicos de verano se celebren pero las dos ciudades sede que siguen ya se preparan para albergar a los mejores atletas del mundo que competir\u00e1n en una diversidad de deportes: desde los cl\u00e1sicos como la nataci\u00f3n o el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451370,"url":"https:\/\/noticiasya.com\/laredo\/2024\/07\/24\/ministerio-interior-francia-rechazo-solicitudes-acreditacion-juegos-olimpicos-trax\/","url_meta":{"origin":1448159,"position":5},"title":"El Ministerio del Interior franc\u00e9s rechaz\u00f3 unas 5.000 solicitudes de acreditaci\u00f3n de seguridad para voluntarios y trabajadores de los Juegos Ol\u00edmpicos, de las cuales unas 1.000 fueron bloqueadas por sospechas de intromisi\u00f3n o espionaje","author":"","date":"julio 24, 2024","format":false,"excerpt":"(CNN) -- El Ministerio del Interior de Francia rechaz\u00f3 alrededor de 5.000 solicitudes de acreditaci\u00f3n de seguridad para voluntarios y trabajadores de los Juegos Ol\u00edmpicos, y aproximadamente 1.000 de esos casos fueron bloqueados debido a sospechas de intromisi\u00f3n o espionaje.El Ministerio del Interior indic\u00f3 en un comunicado este martes que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1448159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1448159"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1448159\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1448159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1448159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1448159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}