{"id":1448166,"date":"2024-04-16T16:03:38","date_gmt":"2024-04-16T23:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/"},"modified":"2024-04-16T16:03:38","modified_gmt":"2024-04-16T23:03:38","slug":"respuesta-facebook-instagram-porno-inteligencia-artificial-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/","title":{"rendered":"La respuesta de Facebook e Instagram al porno generado con IA est\u00e1 en revisi\u00f3n por la junta de supervisi\u00f3n"},"content":{"rendered":"<p>(CNN) &#8212; La junta de supervisi\u00f3n de Meta evaluar\u00e1 el manejo de la pornograf\u00eda deepfake por parte de la compa\u00f1\u00eda en medio de crecientes preocupaciones de que la Inteligencia Artificial (IA) est\u00e9 impulsando un aumento en la creaci\u00f3n de im\u00e1genes falsas y gr\u00e1ficas como una forma de acoso.<\/p>\n<p>La junta de supervisi\u00f3n dijo este martes que revisar\u00e1 c\u00f3mo Meta abord\u00f3 dos im\u00e1genes gr\u00e1ficas generadas por inteligencia artificial de figuras p\u00fablicas femeninas, una de Estados Unidos y otra de la India, para evaluar si la compa\u00f1\u00eda cuenta con pol\u00edticas y pr\u00e1cticas apropiadas para abordar dicho contenido (y si est\u00e1 aplicando esas pol\u00edticas de manera consistente en todo el mundo).<\/p>\n<p>Generador de im\u00e1genes de IA de Meta recibe cr\u00edticas por sesgo racial<\/p>\n<p>La amenaza de la pornograf\u00eda generada por IA ha llamado la atenci\u00f3n en los \u00faltimos meses, y tanto celebridades como Taylor Swift como estudiantes de secundaria estadounidenses y otras mujeres de todo el mundo, han sido v\u00edctimas de esta forma de abuso digital. Las herramientas de IA generativa, que son muy accesibles, han hecho que crear este tipo de im\u00e1genes sea m\u00e1s r\u00e1pido, f\u00e1cil y barato. Mientras tanto, las plataformas de redes sociales permiten difundir estas im\u00e1genes r\u00e1pidamente.<\/p>\n<p>&#171;La pornograf\u00eda deepfake \u2014que alude a los sistemas inform\u00e1ticos que\u00a0permiten, mediante t\u00e9cnicas de Inteligencia Artificial, desarrollar videos manipulados extremadamente realistas\u2014 es una causa creciente de acoso por motivos de g\u00e9nero en l\u00ednea y se utiliza cada vez m\u00e1s para atacar, silenciar e intimidar a las mujeres, tanto online como offline&#187;, dijo en un comunicado la copresidenta de la junta de supervisi\u00f3n de Meta, Helle Thorning-Schmidt.<\/p>\n<p>&#171;Sabemos que Meta es m\u00e1s r\u00e1pido y eficaz a la hora de moderar contenidos en algunos mercados e idiomas que en otros&#187;, afirm\u00f3 Thorning-Schmidt, ex primer ministro de Dinamarca. &#171;Al tomar un caso de EE.UU. y otro de la India, queremos comprobar si Meta est\u00e1 protegiendo a todas las mujeres en todo el mundo de manera justa&#187;.<\/p>\n<p>La junta fiscalizadora del Meta es una entidad integrada por expertos en \u00e1reas como libertad de expresi\u00f3n y derechos humanos. A menudo se la describe como &#171;una especie de Corte Suprema de Meta&#187;, ya que permite a los usuarios apelar decisiones de contenido en las plataformas de la empresa. La junta hace recomendaciones a la empresa sobre c\u00f3mo manejar ciertas decisiones de moderaci\u00f3n de contenido, as\u00ed como sugerencias de pol\u00edticas m\u00e1s amplias.<\/p>\n<p>Apple, Google y Meta corren el riesgo de recibir fuertes multas en Europa<\/p>\n<p>Como parte de su revisi\u00f3n, la junta evaluar\u00e1 un caso de una imagen generada por IA que se asemeja a una figura p\u00fablica de la India y que fue compartida en Instagram por una cuenta que &#171;solo comparte im\u00e1genes de mujeres indias generadas por IA&#187;.<\/p>\n<p>Un usuario denunci\u00f3 la imagen por ser pornogr\u00e1fica, pero el informe se cerr\u00f3 autom\u00e1ticamente despu\u00e9s de que Instagram no recibi\u00f3 una revisi\u00f3n dentro de las 48 horas. El mismo usuario apel\u00f3 la decisi\u00f3n de Instagram de dejar la imagen, pero el informe nuevamente no fue revisado y se cerr\u00f3 autom\u00e1ticamente. Despu\u00e9s de que la junta de supervisi\u00f3n le inform\u00f3 a Meta su intenci\u00f3n de hacerse cargo del caso, la compa\u00f1\u00eda determin\u00f3 que hab\u00eda permitido err\u00f3neamente que la imagen permaneciera y la elimin\u00f3 por violar las reglas de intimidaci\u00f3n y acoso, seg\u00fan la junta.<\/p>\n<p>El segundo caso involucra una imagen generada por IA de una mujer desnuda siendo manoseada, que fue publicada en un grupo de Facebook de creaciones de IA. La imagen deb\u00eda parecerse a una figura p\u00fablica estadounidense, que tambi\u00e9n se menciona en el t\u00edtulo de la imagen.<\/p>\n<p>Meta identificar\u00e1 autom\u00e1ticamente im\u00e1genes de IA creadas por terceros<\/p>\n<p>La misma imagen hab\u00eda sido publicada previamente por un usuario diferente, pero se remiti\u00f3 a expertos en pol\u00edticas que decidieron eliminarla por violar las reglas de intimidaci\u00f3n y acoso, \u201cespec\u00edficamente por &#8216;Photoshop o dibujos despectivos y sexualizados&#8217;\u201d. Luego se agreg\u00f3 la imagen a un banco de coincidencias de fotograf\u00edas que detecta autom\u00e1ticamente cuando se vuelven a publicar im\u00e1genes que infringen las pol\u00edticas de uso, por lo que la publicaci\u00f3n del segundo usuario se elimin\u00f3 autom\u00e1ticamente.<\/p>\n<p>Como parte de esta \u00faltima revisi\u00f3n, la junta de supervisi\u00f3n est\u00e1 buscando comentarios p\u00fablicos, que pueden enviarse de forma an\u00f3nima, sobre la pornograf\u00eda deepfake, incluido c\u00f3mo dicho contenido puede da\u00f1ar a las mujeres y c\u00f3mo Meta ha respondido a publicaciones que presentan im\u00e1genes expl\u00edcitas generadas por IA. El periodo de comentarios p\u00fablicos cierra el 30 de abril.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La junta de supervisi\u00f3n de Meta evaluar\u00e1 el manejo de la pornograf\u00eda deepfake por parte de la compa\u00f1\u00eda en medio de crecientes preocupaciones de que la Inteligencia Artificial (IA) est\u00e9 impulsando un aumento en la creaci\u00f3n de im\u00e1genes falsas y gr\u00e1ficas como una forma de acoso. La junta de supervisi\u00f3n dijo este martes [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448166","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La respuesta de Facebook e Instagram al porno generado con IA est\u00e1 en revisi\u00f3n por la junta de supervisi\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La respuesta de Facebook e Instagram al porno generado con IA est\u00e1 en revisi\u00f3n por la junta de supervisi\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La junta de supervisi\u00f3n de Meta evaluar\u00e1 el manejo de la pornograf\u00eda deepfake por parte de la compa\u00f1\u00eda en medio de crecientes preocupaciones de que la Inteligencia Artificial (IA) est\u00e9 impulsando un aumento en la creaci\u00f3n de im\u00e1genes falsas y gr\u00e1ficas como una forma de acoso. La junta de supervisi\u00f3n dijo este martes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-16T23:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La respuesta de Facebook e Instagram al porno generado con IA est\u00e1 en revisi\u00f3n por la junta de supervisi\u00f3n\",\"datePublished\":\"2024-04-16T23:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/\"},\"wordCount\":851,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/\",\"name\":\"La respuesta de Facebook e Instagram al porno generado con IA est\u00e1 en revisi\u00f3n por la junta de supervisi\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-16T23:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La respuesta de Facebook e Instagram al porno generado con IA est\u00e1 en revisi\u00f3n por la junta de supervisi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La respuesta de Facebook e Instagram al porno generado con IA est\u00e1 en revisi\u00f3n por la junta de supervisi\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La respuesta de Facebook e Instagram al porno generado con IA est\u00e1 en revisi\u00f3n por la junta de supervisi\u00f3n - Noticias","og_description":"(CNN) &#8212; La junta de supervisi\u00f3n de Meta evaluar\u00e1 el manejo de la pornograf\u00eda deepfake por parte de la compa\u00f1\u00eda en medio de crecientes preocupaciones de que la Inteligencia Artificial (IA) est\u00e9 impulsando un aumento en la creaci\u00f3n de im\u00e1genes falsas y gr\u00e1ficas como una forma de acoso. La junta de supervisi\u00f3n dijo este martes [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-16T23:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/"},"author":{"name":"","@id":""},"headline":"La respuesta de Facebook e Instagram al porno generado con IA est\u00e1 en revisi\u00f3n por la junta de supervisi\u00f3n","datePublished":"2024-04-16T23:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/"},"wordCount":851,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/","name":"La respuesta de Facebook e Instagram al porno generado con IA est\u00e1 en revisi\u00f3n por la junta de supervisi\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-16T23:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La respuesta de Facebook e Instagram al porno generado con IA est\u00e1 en revisi\u00f3n por la junta de supervisi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La respuesta de Facebook e Instagram al porno generado con IA est\u00e1 en revisi\u00f3n por la junta de supervisi\u00f3n","url":"http:\/\/noticiasya.com\/laredo\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/04\/16\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-16T23:03:38Z","datePublished":"2024-04-16T23:03:38Z","dateModified":"2024-04-16T23:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La respuesta de Facebook e Instagram al porno generado con IA est\\u00e1 en revisi\\u00f3n por la junta de supervisi\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/04\\\/16\\\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/04\\\/16\\\/respuesta-facebook-instagram-porno-inteligencia-artificial-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-16T23:03:38Z\",\"datePublished\":\"2024-04-16T23:03:38Z\",\"dateModified\":\"2024-04-16T23:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448178,"url":"https:\/\/noticiasya.com\/laredo\/2024\/04\/17\/porno-deepfake-sin-consentimiento-convertirse-delito-inglaterra-trax\/","url_meta":{"origin":1448166,"position":0},"title":"Hacer porno &#8216;deepfake&#8217; sin consentimiento pronto podr\u00eda convertirse en un delito en Inglaterra","author":"","date":"abril 17, 2024","format":false,"excerpt":"(CNN) -- Es probable que la creaci\u00f3n de contenido \"deepfake\" sexualmente expl\u00edcito se convierta en un delito penal en Inglaterra y Gales a medida que crece la preocupaci\u00f3n por el uso de inteligencia artificial para explotar y acosar a las mujeres.Seg\u00fan un proyecto de ley, cualquiera que cree una imagen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451374,"url":"https:\/\/noticiasya.com\/laredo\/2024\/07\/24\/que-es-meta-ai-whatsapp-como-usarlo-como-desactivarla-orix\/","url_meta":{"origin":1448166,"position":1},"title":"Qu\u00e9 es Meta AI en WhatsApp, c\u00f3mo usarla y c\u00f3mo desactivarla","author":"","date":"julio 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Las capacidades de la inteligencia artificial cada vez se expanden a m\u00e1s rincones del mundo digital. Si vives en Am\u00e9rica Latina, ahora podr\u00e1s hacer uso de la IA incluso desde tu cuenta de WhatsApp.La compa\u00f1\u00eda Meta \u2014due\u00f1a de WhatsApp, Facebook, Messenger e Instagram\u2014 anunci\u00f3 el martes que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449753,"url":"https:\/\/noticiasya.com\/laredo\/2024\/05\/24\/busqueda-google-inteligencia-artificial-errores-obama-musulman-trax\/","url_meta":{"origin":1448166,"position":2},"title":"Una b\u00fasqueda de Google con Inteligencia Artificial dijo err\u00f3neamente que Obama es musulm\u00e1n. Ahora la empresa desactiva algunos resultados","author":"","date":"mayo 24, 2024","format":false,"excerpt":"Nueva York (CNN) -- Google prometi\u00f3 que sus nuevas herramientas de b\u00fasqueda con Inteligencia Artificial (IA) \u201char\u00edan el trabajo por ti\u201d y har\u00edan que la b\u00fasqueda de informaci\u00f3n en l\u00ednea sea m\u00e1s r\u00e1pida y sencilla. Pero apenas unos d\u00edas despu\u00e9s del lanzamiento, la compa\u00f1\u00eda ya est\u00e1 dando marcha atr\u00e1s tras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452438,"url":"https:\/\/noticiasya.com\/laredo\/2024\/09\/04\/junta-supervision-meta-dictamina-frase-apoyo-palestina-no-incitacion-odio-trax\/","url_meta":{"origin":1448166,"position":3},"title":"Junta de Supervisi\u00f3n de Meta dictamina que una frase de apoyo a Palestina no es incitaci\u00f3n al odio","author":"","date":"septiembre 4, 2024","format":false,"excerpt":"Nueva York (CNN) -- La Junta de Supervisi\u00f3n de Meta determin\u00f3 que la frase \"Del r\u00edo al mar\", utilizada para expresar el apoyo a Palestina, no infring\u00eda las pol\u00edticas de incitaci\u00f3n al odio de la empresa.Los detractores de la frase, que se refiere a la tierra entre el r\u00edo Jord\u00e1n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457463,"url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/12\/copresidente-supervision-meta-presion-politica-programa-verificacion-trax\/","url_meta":{"origin":1448166,"position":4},"title":"Copresidente de supervisi\u00f3n de Meta dice que la empresa &#171;cede a la presi\u00f3n pol\u00edtica&#187; al acabar con programa de verificaci\u00f3n","author":"","date":"enero 12, 2025","format":false,"excerpt":"La decisi\u00f3n de Meta de poner fin a su programa de verificaci\u00f3n de datos parece indicar que la empresa est\u00e1 \u201ccediendo\u201d ante presiones pol\u00edticas, dijo el copresidente del consejo de supervisi\u00f3n de Meta, Michael McConnell.McConnell, profesor de derecho en la Universidad de Stanford, dijo a NPR el viernes que le\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450020,"url":"https:\/\/noticiasya.com\/laredo\/2024\/06\/04\/carta-expertos-openai-advertencia-riesgos-inteligencia-artificial-trax\/","url_meta":{"origin":1448166,"position":5},"title":"Carta abierta de los expertos de OpenAI advierte sobre \u201criesgos graves\u201d y pide protecci\u00f3n para los denunciantes","author":"","date":"junio 4, 2024","format":false,"excerpt":"(CNN) -- Un grupo de expertos de OpenAI exige que las empresas de inteligencia artificial sean mucho m\u00e1s transparentes sobre los \u201cgraves riesgos\u201d de la IA y que protejan a los empleados que expresen preocupaciones sobre la tecnolog\u00eda que est\u00e1n desarrollando.\u201cLas empresas de inteligencia artificial tienen fuertes incentivos financieros para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1448166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1448166"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1448166\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1448166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1448166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1448166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}