{"id":1448183,"date":"2024-04-17T04:03:52","date_gmt":"2024-04-17T11:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/"},"modified":"2024-04-17T04:03:52","modified_gmt":"2024-04-17T11:03:52","slug":"hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/","title":{"rendered":"Los hijos de Paul McCartney y John Lennon lanzaron un sencillo juntos"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0Una nueva colaboraci\u00f3n entre Lennon y McCartney es lo \u00faltimo que nadie esperaba.<\/p>\n<p>Sin embargo, los fans de los Beatles han sido sorprendidos por un nuevo sencillo lanzado por los hijos de dos de los Fab Four: James McCartney y Sean Ono Lennon, ambos m\u00fasicos.<\/p>\n<p>El nuevo sencillo, titulado \u201cPrimrose Hill\u201d en honor a un parque en el norte de Londres que ofrece una vista panor\u00e1mica de la ciudad, fue anunciado por McCartney, hijo de Paul y su difunta esposa Linda, en Instagram hace cuatro d\u00edas.<\/p>\n<p>El ex Beatle John Lennon es fotografiado con su esposa Yoko Ono y su hijo Sean Lennon en Nueva York tres a\u00f1os antes de ser asesinado. (Cr\u00e9dito: Vinnie Zuffante\/Fotos de archivo\/Getty Images)<\/p>\n<p>Junto con una foto de la pareja, que se parecen sorprendentemente a sus famosos padres, escribi\u00f3: \u201c\u00a1&#8217;Primrose Hill&#8217; ya est\u00e1 aqu\u00ed! Hoy estoy muy emocionado de compartir mi \u00faltima canci\u00f3n coescrita por mi buen amigo @sean_ono_lennon . Con el lanzamiento de esta canci\u00f3n siento que realmente estamos poniendo las cosas en marcha y estoy muy emocionado de continuar compartiendo m\u00fasica con ustedes\u201d.<\/p>\n<p>En una publicaci\u00f3n separada, McCartney revel\u00f3 la inspiraci\u00f3n detr\u00e1s de la canci\u00f3n. Dijo: \u201cTuve una visi\u00f3n cuando era ni\u00f1o en Escocia, en lo que era un hermoso d\u00eda de verano. Al soltarme, vi en mi mente a mi verdadero amor y salvador. &#8216;Primrose Hill&#8217; se trata de ponerme manos a la obra y encontrar a esta persona&#187;.<\/p>\n<p>Escrita y compuesta por la pareja, la canci\u00f3n ac\u00fastica recuerda un tiempo pasado con un ser querido en el popular lugar de belleza.<\/p>\n<p>La hermana de McCartney, Mary, fot\u00f3grafa profesional, tambi\u00e9n particip\u00f3 en la promoci\u00f3n de la canci\u00f3n, capturando breves clips de su hermano tocando su piano y aparentemente en silueta en Primrose Hill.<\/p>\n<p>Los artistas de la segunda generaci\u00f3n nacieron en la d\u00e9cada de 1970, despu\u00e9s de que los Beatles se separaron.<\/p>\n<p>James con su famoso padre, Paul McCartney, all\u00e1 por 2015 Richard joven\/Shutterstock<\/p>\n<p>Parece que no hubo noticias de Ono Lennon, hijo de John y Yoko, pero la canci\u00f3n s\u00ed cont\u00f3 con el firme respaldo del propio Macca. Al anunciar el lanzamiento a sus millones de seguidores en todo el mundo en las redes sociales, Paul McCartney escribi\u00f3: \u201cMi hijo James tiene una nueva canci\u00f3n llamada &#8216;Primrose Hill&#8217;. \u00a1\u00c9chale un vistazo! Y mucho amor para Sean Ono Lennon, quien coescribi\u00f3 la canci\u00f3n\u201d.<\/p>\n<p>La imagen de la pareja utilizada para promocionar la canci\u00f3n no es nueva. Ono Lennon lo public\u00f3 por primera vez en Instagram en 2018, con la leyenda &#171;Peakaboo&#8230;&#187;<\/p>\n<p>Primrose Hill, un suburbio al norte de Londres, est\u00e1 a tiro de piedra del Regent&#8217;s Park de la ciudad y del famoso mercado de Camden Town. No es ajeno a los ricos y famosos, e incluso gener\u00f3 un &#171;set de Primrose Hill&#187; en la d\u00e9cada de 1990 despu\u00e9s de que una gran cantidad de estrellas, entre ellas Jude Law, Liam Gallagher y Kate Moss, se mudaran all\u00ed.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0Una nueva colaboraci\u00f3n entre Lennon y McCartney es lo \u00faltimo que nadie esperaba. Sin embargo, los fans de los Beatles han sido sorprendidos por un nuevo sencillo lanzado por los hijos de dos de los Fab Four: James McCartney y Sean Ono Lennon, ambos m\u00fasicos. El nuevo sencillo, titulado \u201cPrimrose Hill\u201d en honor a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448183","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los hijos de Paul McCartney y John Lennon lanzaron un sencillo juntos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los hijos de Paul McCartney y John Lennon lanzaron un sencillo juntos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0Una nueva colaboraci\u00f3n entre Lennon y McCartney es lo \u00faltimo que nadie esperaba. Sin embargo, los fans de los Beatles han sido sorprendidos por un nuevo sencillo lanzado por los hijos de dos de los Fab Four: James McCartney y Sean Ono Lennon, ambos m\u00fasicos. El nuevo sencillo, titulado \u201cPrimrose Hill\u201d en honor a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-17T11:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los hijos de Paul McCartney y John Lennon lanzaron un sencillo juntos\",\"datePublished\":\"2024-04-17T11:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/\"},\"wordCount\":548,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/\",\"name\":\"Los hijos de Paul McCartney y John Lennon lanzaron un sencillo juntos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-17T11:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los hijos de Paul McCartney y John Lennon lanzaron un sencillo juntos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los hijos de Paul McCartney y John Lennon lanzaron un sencillo juntos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los hijos de Paul McCartney y John Lennon lanzaron un sencillo juntos - Noticias","og_description":"(CNN) &#8212;\u00a0Una nueva colaboraci\u00f3n entre Lennon y McCartney es lo \u00faltimo que nadie esperaba. Sin embargo, los fans de los Beatles han sido sorprendidos por un nuevo sencillo lanzado por los hijos de dos de los Fab Four: James McCartney y Sean Ono Lennon, ambos m\u00fasicos. El nuevo sencillo, titulado \u201cPrimrose Hill\u201d en honor a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-17T11:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/"},"author":{"name":"","@id":""},"headline":"Los hijos de Paul McCartney y John Lennon lanzaron un sencillo juntos","datePublished":"2024-04-17T11:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/"},"wordCount":548,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/","name":"Los hijos de Paul McCartney y John Lennon lanzaron un sencillo juntos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-17T11:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los hijos de Paul McCartney y John Lennon lanzaron un sencillo juntos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los hijos de Paul McCartney y John Lennon lanzaron un sencillo juntos","url":"http:\/\/noticiasya.com\/laredo\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/04\/17\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-17T11:03:52Z","datePublished":"2024-04-17T11:03:52Z","dateModified":"2024-04-17T11:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los hijos de Paul McCartney y John Lennon lanzaron un sencillo juntos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/04\\\/17\\\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/04\\\/17\\\/hijos-de-paul-mccartney-y-john-lennon-lanzaron-un-sencillo-juntos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-17T11:03:52Z\",\"datePublished\":\"2024-04-17T11:03:52Z\",\"dateModified\":\"2024-04-17T11:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1445835,"url":"https:\/\/noticiasya.com\/laredo\/2024\/02\/21\/the-beatles-biopic-trax\/","url_meta":{"origin":1448183,"position":0},"title":"Preparan cuatro pel\u00edculas biogr\u00e1ficas de The Beatles, una por cada miembro de la m\u00edtica banda","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Un 'd\u00eda en la vida' de los cuatro miembros de The Beatles llega a la gran pantalla.Sam Mendes, ganador del Oscar, dirigir\u00e1 cuatro largometrajes\u00a0biogr\u00e1ficos separados que narran la historia de The Beatles a trav\u00e9s de los ojos de cada uno de sus miembros; Paul McCartney, Ringo Starr y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445777,"url":"https:\/\/noticiasya.com\/laredo\/2024\/02\/21\/preparan-cuatro-peliculas-biograficas-de-the-beatles-una-por-cada-miembro-de-la-mitica-banda\/","url_meta":{"origin":1448183,"position":1},"title":"Preparan cuatro pel\u00edculas biogr\u00e1ficas de The Beatles, una por cada miembro de la m\u00edtica banda","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Un 'd\u00eda en la vida' de los cuatro miembros de The Beatles llega a la gran pantalla.Sam Mendes, ganador del Oscar, dirigir\u00e1 cuatro largometrajes\u00a0biogr\u00e1ficos separados que narran la historia de The Beatles a trav\u00e9s de los ojos de cada uno de sus miembros; Paul McCartney, Ringo Starr y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445779,"url":"https:\/\/noticiasya.com\/laredo\/2024\/02\/21\/preparan-cuatro-peliculas-biograficas-de-the-beatles-una-por-cada-miembro-de-la-mitica-banda-2\/","url_meta":{"origin":1448183,"position":2},"title":"Preparan cuatro pel\u00edculas biogr\u00e1ficas de The Beatles, una por cada miembro de la m\u00edtica banda","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Un 'd\u00eda en la vida' de los cuatro miembros de The Beatles llega a la gran pantalla.Sam Mendes, ganador del Oscar, dirigir\u00e1 cuatro largometrajes\u00a0biogr\u00e1ficos separados que narran la historia de The Beatles a trav\u00e9s de los ojos de cada uno de sus miembros; Paul McCartney, Ringo Starr y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460691,"url":"https:\/\/noticiasya.com\/laredo\/2025\/04\/01\/beatles-peliculas-estrellas-sam-mendes-trax\/","url_meta":{"origin":1448183,"position":3},"title":"Anuncian a las estrellas de las pel\u00edculas de los Beatles dirigidas por Sam Mendes","author":"","date":"abril 1, 2025","format":false,"excerpt":"Sam Mendes dirigir\u00e1 cuatro pel\u00edculas biogr\u00e1ficas que narrar\u00e1n la historia de los Beatles desde la perspectiva de cada uno de sus miembros, y el reparto depara los cuatro m\u00fasicos ya est\u00e1 confirmado.Harris Dickinson interpretar\u00e1 a John Lennon, Paul Mescal a Paul McCartney, Barry Keoghan a Ringo Starr y Joseph Quinn\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470678,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/30\/beatles-peliculas-actores-primer-vistazo-cine-2028-orix\/","url_meta":{"origin":1448183,"position":4},"title":"As\u00ed se ver\u00e1n los integrantes de The Beatles en las pel\u00edculas biogr\u00e1ficas de la banda","author":"","date":"enero 30, 2026","format":false,"excerpt":"Sony Pictures dio a conocer c\u00f3mo se ver\u00e1n los actores que le dar\u00e1n vida a los integrantes de The Beatles en las pr\u00f3ximas pel\u00edculas biogr\u00e1ficas de la emblem\u00e1tica banda.A trav\u00e9s de diversas im\u00e1genes promocionales, se puede ver a Paul Mescal personificado como Paul McCartney, a Barry Keoghan en el papel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458607,"url":"https:\/\/noticiasya.com\/laredo\/2025\/02\/11\/paul-mccartney-concierto-sorpresa-nueva-york-trax\/","url_meta":{"origin":1448183,"position":5},"title":"Paul McCartney anunci\u00f3 un concierto sorpresa de una sola noche en Nueva York y los boletos se agotaron en 30 minutos","author":"","date":"febrero 11, 2025","format":false,"excerpt":"Paul McCartney est\u00e1 dando a los neoyorquinos la oportunidad de \u201creunirse\u201d por una noche, y solo por una noche.La leyenda de los Beatles anunci\u00f3 en Instagram la ma\u00f1ana de este martes que tocar\u00eda en un concierto sorpresa en el Bowery Ballroom de Nueva York m\u00e1s tarde esta noche. En la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1448183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1448183"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1448183\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1448183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1448183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1448183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}