{"id":1448253,"date":"2024-04-18T16:03:51","date_gmt":"2024-04-18T23:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/"},"modified":"2024-04-18T16:03:51","modified_gmt":"2024-04-18T23:03:51","slug":"petro-bogota-salir-reducir-consumo-agua-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/","title":{"rendered":"Petro pide a la poblaci\u00f3n de Bogot\u00e1 salir de la ciudad el fin de semana para reducir el consumo de agua"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de Colombia, Gustavo Petro, pidi\u00f3 a la poblaci\u00f3n de Bogot\u00e1 que salga de la ciudad durante el fin de semana, si tiene oportunidad de hacerlo, como una medida para reducir el consumo de agua en la capital del pa\u00eds, que enfrenta problemas de escasez.<\/p>\n<p>El llamado, que el mandatario public\u00f3 este jueves en su cuenta de X, se produce justo a una semana del comienzo del racionamiento del l\u00edquido en la capital de Colombia.<\/p>\n<p>Bogot\u00e1 con escasez de agua: as\u00ed solucionan las familias el racionamiento<\/p>\n<p>La Alcald\u00eda de Bogot\u00e1 dividi\u00f3 la ciudad en nueve zonas. A cada una se le asign\u00f3 un turno diario para la suspensi\u00f3n del suministro, con lo cual las autoridades de la capital colombiana buscan disminuir la demanda de agua y la presi\u00f3n sobre el sistema h\u00eddrico.<\/p>\n<p>El alcalde de Bogot\u00e1, Carlos Gal\u00e1n, dijo a CNN la semana pasada que los embalses que abastecen a Bogot\u00e1 no hab\u00edan tenido un nivel tan bajo desde la d\u00e9cada de 1980. El funcionario tambi\u00e9n pidi\u00f3 a la ciudadan\u00eda tomar medidas como ba\u00f1arse en menos de cinco minutos o dejar de hacerlo el fin de semana si las personas no tienen que salir de casa.<\/p>\n<p>Bogot\u00e1 empieza a racionar el agua para 9 millones de personas<\/p>\n<p>\u201cEst\u00e1n a punto de llegar las lluvias. Tratemos de pasar juntos la emergencia sin racionamientos\u201d, se\u00f1al\u00f3 Petro este jueves sobre esta situaci\u00f3n.<\/p>\n<p>Los problemas de escasez de agua no son exclusivos de Bogot\u00e1. Otras urbes de Am\u00e9rica Latina, como la Ciudad de M\u00e9xico, encaran dificultades similares derivadas de factores como una mayor demanda por el crecimiento de la poblaci\u00f3n, el aumento de las temperaturas y la falta de lluvias.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de Colombia, Gustavo Petro, pidi\u00f3 a la poblaci\u00f3n de Bogot\u00e1 que salga de la ciudad durante el fin de semana, si tiene oportunidad de hacerlo, como una medida para reducir el consumo de agua en la capital del pa\u00eds, que enfrenta problemas de escasez. El llamado, que el mandatario public\u00f3 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448253","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Petro pide a la poblaci\u00f3n de Bogot\u00e1 salir de la ciudad el fin de semana para reducir el consumo de agua - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petro pide a la poblaci\u00f3n de Bogot\u00e1 salir de la ciudad el fin de semana para reducir el consumo de agua - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El presidente de Colombia, Gustavo Petro, pidi\u00f3 a la poblaci\u00f3n de Bogot\u00e1 que salga de la ciudad durante el fin de semana, si tiene oportunidad de hacerlo, como una medida para reducir el consumo de agua en la capital del pa\u00eds, que enfrenta problemas de escasez. El llamado, que el mandatario public\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-18T23:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Petro pide a la poblaci\u00f3n de Bogot\u00e1 salir de la ciudad el fin de semana para reducir el consumo de agua\",\"datePublished\":\"2024-04-18T23:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/\"},\"wordCount\":336,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/\",\"name\":\"Petro pide a la poblaci\u00f3n de Bogot\u00e1 salir de la ciudad el fin de semana para reducir el consumo de agua - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-18T23:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Petro pide a la poblaci\u00f3n de Bogot\u00e1 salir de la ciudad el fin de semana para reducir el consumo de agua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Petro pide a la poblaci\u00f3n de Bogot\u00e1 salir de la ciudad el fin de semana para reducir el consumo de agua - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Petro pide a la poblaci\u00f3n de Bogot\u00e1 salir de la ciudad el fin de semana para reducir el consumo de agua - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El presidente de Colombia, Gustavo Petro, pidi\u00f3 a la poblaci\u00f3n de Bogot\u00e1 que salga de la ciudad durante el fin de semana, si tiene oportunidad de hacerlo, como una medida para reducir el consumo de agua en la capital del pa\u00eds, que enfrenta problemas de escasez. El llamado, que el mandatario public\u00f3 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-18T23:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/"},"author":{"name":"","@id":""},"headline":"Petro pide a la poblaci\u00f3n de Bogot\u00e1 salir de la ciudad el fin de semana para reducir el consumo de agua","datePublished":"2024-04-18T23:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/"},"wordCount":336,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/","name":"Petro pide a la poblaci\u00f3n de Bogot\u00e1 salir de la ciudad el fin de semana para reducir el consumo de agua - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-18T23:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Petro pide a la poblaci\u00f3n de Bogot\u00e1 salir de la ciudad el fin de semana para reducir el consumo de agua"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Petro pide a la poblaci\u00f3n de Bogot\u00e1 salir de la ciudad el fin de semana para reducir el consumo de agua","url":"http:\/\/noticiasya.com\/laredo\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/04\/18\/petro-bogota-salir-reducir-consumo-agua-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-18T23:03:51Z","datePublished":"2024-04-18T23:03:51Z","dateModified":"2024-04-18T23:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Petro pide a la poblaci\\u00f3n de Bogot\\u00e1 salir de la ciudad el fin de semana para reducir el consumo de agua\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/04\\\/18\\\/petro-bogota-salir-reducir-consumo-agua-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/04\\\/18\\\/petro-bogota-salir-reducir-consumo-agua-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-18T23:03:51Z\",\"datePublished\":\"2024-04-18T23:03:51Z\",\"dateModified\":\"2024-04-18T23:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1447862,"url":"https:\/\/noticiasya.com\/laredo\/2024\/04\/08\/racionamiento-agua-bogota-medidas-horarios-mapa-zonas-orix\/","url_meta":{"origin":1448253,"position":0},"title":"Racionamiento de agua en Bogot\u00e1: estas son las medidas, horarios y mapa de zonas de restricci\u00f3n","author":"","date":"abril 8, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Alcald\u00eda de Bogot\u00e1 orden\u00f3 el racionamiento del agua por sectores, en intervalos que durar\u00e1n 24 horas, a partir de este jueves 11 de abril, para hacer frente a la sequ\u00eda que ha disminuido a m\u00ednimos in\u00e9ditos el nivel de los embalses de la ciudad. La medida\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448462,"url":"https:\/\/noticiasya.com\/laredo\/2024\/04\/24\/gustavo-petro-colombia-analisis-mandato-calles-orix\/","url_meta":{"origin":1448253,"position":1},"title":"AN\u00c1LISIS | Petro se juega su mandato en las calles","author":"","date":"abril 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \"Yo aqu\u00ed no estar\u00e9 m\u00e1s all\u00e1 de agosto del 2026, pero el mandato popular me lleva a no estar ni un d\u00eda menos\", escribi\u00f3 este martes en su cuenta en la red social X Gustavo Petro, presidente de Colombia.La frase condensa el momento que atraviesa el mandatario\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457538,"url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/15\/incendio-parque-chingaza-bogota-agua-orix\/","url_meta":{"origin":1448253,"position":2},"title":"Alerta por incendio en el parque natural Chingaza, cerca de un embalse que abastece de agua a Bogot\u00e1","author":"","date":"enero 15, 2025","format":false,"excerpt":"M\u00e1s de 100 personas intentan controlar el incendio que comenz\u00f3 en el Parque Nacional Natural Chingaza, cerca de uno de los embalses que abastecen de agua a Bogot\u00e1, inform\u00f3 el alcalde de la ciudad, Carlos Fernando Gal\u00e1n. La capital de Colombia enfrenta un racionamiento de agua desde hace nueve meses.Decenas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466891,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/27\/departamento-estado-ee-uu-revocara-visa-petro-trax\/","url_meta":{"origin":1448253,"position":3},"title":"EE.UU. revoca visa a Petro por llamar a soldados estadounidenses a desobedecer a Trump","author":"","date":"septiembre 27, 2025","format":false,"excerpt":"Estados Unidos anunci\u00f3 este viernes que tiene intenciones de cancelar la visa del presidente de Colombia, Gustavo Petro, despu\u00e9s de que el mandatario sudamericano llamara p\u00fablicamente a los soldados estadounidenses a desobedecer a Donald Trump, tensando a\u00fan m\u00e1s las relaciones entre Washington y Bogot\u00e1.Petro, quien anteriormente se ha enfrentado con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448113,"url":"https:\/\/noticiasya.com\/laredo\/2024\/04\/15\/continua-racionamiento-agua-potable-bogota-orix\/","url_meta":{"origin":1448253,"position":4},"title":"Contin\u00faa el racionamiento de agua potable en Bogot\u00e1","author":"","date":"abril 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El racionamiento de agua potable en la ciudad de Bogot\u00e1, que comenz\u00f3 el jueves y que afecta tambi\u00e9n a otros municipios a los que presta servicio la\u00a0Empresa de Acueducto y Alcantarillado de Bogot\u00e1 (EAAB)\u00a0contin\u00faa este lunes, seg\u00fan inform\u00f3 la alcald\u00eda de la ciudad.La medida busca ahorrar 2.000\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472535,"url":"https:\/\/noticiasya.com\/laredo\/2026\/03\/25\/corpus-chriti-agua-demanda-industrial-trax\/","url_meta":{"origin":1448253,"position":5},"title":"Esta ciudad de Texas solo tiene reservas de agua para unos pocos meses y una demanda industrial insaciable","author":"","date":"marzo 25, 2026","format":false,"excerpt":"La r\u00e1pida disminuci\u00f3n de la l\u00ednea de costa del lago Corpus Christi en Texas ha dejado al descubierto amplias zonas del lecho lacustre, muelles que se extienden hacia el vac\u00edo y restos hist\u00f3ricos previamente sumergidos, desde puentes hasta cobertizos para botes.En una visita reciente, la residente local Isabel Araiza encontr\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1448253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1448253"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1448253\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1448253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1448253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1448253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}