{"id":1451414,"date":"2024-07-25T13:03:57","date_gmt":"2024-07-25T20:03:57","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/"},"modified":"2024-07-25T13:03:57","modified_gmt":"2024-07-25T20:03:57","slug":"como-funciona-sistema-y-poder-electoral-venezuela-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/","title":{"rendered":"\u00bfC\u00f3mo funciona el Poder Electoral en Venezuela?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013 El pr\u00f3ximo 28 de julio los venezolanos acudir\u00e1n a las urnas para elegir entre 10 candidatos, entre ellos el presidente Nicol\u00e1s Maduro, a la persona que llevar\u00e1 las riendas del pa\u00eds para el periodo 2025-2031.<\/p>\n<p>Para comprender el funcionamiento de los comicios, as\u00ed como el papel de los cinco rectores del proceso electoral, te explicamos c\u00f3mo funciona el sistema y el poder electoral en Venezuela.<\/p>\n<p>Sistema electoral<\/p>\n<p>La Constituci\u00f3n de Venezuela, en su art\u00edculo 6, determina que el gobierno y las entidades p\u00fablicas que lo componen son democr\u00e1ticas, participativas, pluralistas y de mandatos revocables.<\/p>\n<p>Arranca contienda electoral: \u00bfC\u00f3mo llegan los candidatos en Venezuela a la campa\u00f1a?<\/p>\n<p>Los cargos de presidente, gobernador de estado, alcalde de municipio y otros cargos unipersonales son elegidos con base en la mayor\u00eda relativa de votos, seg\u00fan el art\u00edculo 7 de la Ley Org\u00e1nica de Procesos Electorales.<\/p>\n<p>Venezuela tiene un sistema de votaci\u00f3n automatizado. El CNE afirma que las m\u00e1quinas de votaci\u00f3n representan \u201cuna alternativa innovadora, segura y 100% auditable para la automatizaci\u00f3n de consultas electorales\u201d.<\/p>\n<p>La plataforma utiliza una boleta electr\u00f3nica que permite a los electores activar la m\u00e1quina con su impresi\u00f3n dactilar. Cuando la huella es autenticada, la m\u00e1quina se activa para que el elector marque su voto directamente en la pantalla y en la boleta electr\u00f3nica. La opci\u00f3n seleccionada aparece en la pantalla y los votantes pueden confirmar su voto.<\/p>\n<p>El sufragio se almacena en la memoria de la m\u00e1quina y al final de la jornada queda plasmado en las actas impresas del total de votos. Una vez listo ese resultado el paquete de votos viaja encriptado a trav\u00e9s de una red de la empresa estatal de comunicaciones CANTV. La totalidad de resultados de las m\u00e1quinas llega finalmente a servidores m\u00e1s grandes.<\/p>\n<p>El pasado 30 de junio, las autoridades electorales llevaron a cabo un simulacro electoral a nivel nacional con el objetivo de que las personas pudieran familiarizarse con el sistema automatizado de votaci\u00f3n y conocer las ofertas electorales para los comicios.<\/p>\n<p>Poder Electoral<\/p>\n<p>El Poder Electoral es el encargado de organizar y supervisar todo lo relacionado con las elecciones a cargos p\u00fablicos del pa\u00eds, a trav\u00e9s del sufragio universal, directo y secreto, seg\u00fan su organismo rector, el Consejo Nacional Electoral (CNE).<\/p>\n<p>Este \u00f3rgano debe garantizar la igualdad, confiabilidad, imparcialidad, transparencia y eficacia de los procesos electorales, adem\u00e1s de la personalizaci\u00f3n del sufragio y la representaci\u00f3n proporcional, se\u00f1ala la Ley Org\u00e1nica del Poder Electoral.<\/p>\n<p>Entre sus principales funciones est\u00e1n: reglamentar las leyes electorales y resolver las dudas y vac\u00edos que generen, formular su presupuesto, emitir directivas vinculantes en materia de financiamiento y publicidad pol\u00edtico electorales y aplicar sanciones cuando no sean acatadas.<\/p>\n<p>AN\u00c1LISIS | \u00bfQu\u00e9 ofrecen el Gobierno y la oposici\u00f3n mayoritaria de Venezuela para los pr\u00f3ximos a\u00f1os?<\/p>\n<p>Tambi\u00e9n puede declarar la nulidad total o parcial de unas elecciones cuando sea el caso, organizar comicios de sindicatos, gremios profesionales y organizaciones con fines pol\u00edticos; organizar y supervisar el registro civil y electoral y controlar e investigar los fondos de financiamiento de las organizaciones con fines pol\u00edticos.<\/p>\n<p>En medio del proceso electoral en Venezuela, diversos actores han expresado su preocupaci\u00f3n por las garant\u00edas para la libertad electoral. Incluso, la l\u00edder de la oposici\u00f3n venezolana, Mar\u00eda Corina Machado, dijo previamente a CNN que est\u00e1s &#171;no son unas elecciones limpias y libres&#187; luego de que el Tribunal Supremo de Justicia la inhabilit\u00f3 para ejercer funciones p\u00fablicas por 15 a\u00f1os.<\/p>\n<p>Y recientemente, Estados Unidos pidi\u00f3 al presidente Nicol\u00e1s Maduro permitir unas elecciones \u201cinclusivas y competitivas\u201d.<\/p>\n<p>Sobre estas acusaciones, el fiscal general de Venezuela Tarek William Saab habl\u00f3 con CNN y dijo que las elecciones del domingo ser\u00e1n \u201climpias, transparentes y pac\u00edficas\u201d y se\u00f1al\u00f3 que hay un plan que &#171;garantiza la custodia del material electoral en todos los centros de votaci\u00f3n&#187;.<\/p>\n<p>La votaci\u00f3n comenzar\u00e1 a las 6 de la ma\u00f1ana y culminar\u00e1 a las 6 de la tarde, hora local, pero las mesas electorales se mantendr\u00e1n abiertas hasta que no haya electores en la fila para sufragar.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013 El pr\u00f3ximo 28 de julio los venezolanos acudir\u00e1n a las urnas para elegir entre 10 candidatos, entre ellos el presidente Nicol\u00e1s Maduro, a la persona que llevar\u00e1 las riendas del pa\u00eds para el periodo 2025-2031. Para comprender el funcionamiento de los comicios, as\u00ed como el papel de los cinco rectores del proceso [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451414","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfC\u00f3mo funciona el Poder Electoral en Venezuela? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo funciona el Poder Electoral en Venezuela? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) \u2013 El pr\u00f3ximo 28 de julio los venezolanos acudir\u00e1n a las urnas para elegir entre 10 candidatos, entre ellos el presidente Nicol\u00e1s Maduro, a la persona que llevar\u00e1 las riendas del pa\u00eds para el periodo 2025-2031. Para comprender el funcionamiento de los comicios, as\u00ed como el papel de los cinco rectores del proceso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-25T20:03:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfC\u00f3mo funciona el Poder Electoral en Venezuela?\",\"datePublished\":\"2024-07-25T20:03:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/\"},\"wordCount\":741,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/\",\"name\":\"\u00bfC\u00f3mo funciona el Poder Electoral en Venezuela? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-25T20:03:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo funciona el Poder Electoral en Venezuela?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo funciona el Poder Electoral en Venezuela? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo funciona el Poder Electoral en Venezuela? - Noticias","og_description":"(CNN Espa\u00f1ol) \u2013 El pr\u00f3ximo 28 de julio los venezolanos acudir\u00e1n a las urnas para elegir entre 10 candidatos, entre ellos el presidente Nicol\u00e1s Maduro, a la persona que llevar\u00e1 las riendas del pa\u00eds para el periodo 2025-2031. Para comprender el funcionamiento de los comicios, as\u00ed como el papel de los cinco rectores del proceso [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/","og_site_name":"Noticias","article_published_time":"2024-07-25T20:03:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfC\u00f3mo funciona el Poder Electoral en Venezuela?","datePublished":"2024-07-25T20:03:57+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/"},"wordCount":741,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/","url":"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/","name":"\u00bfC\u00f3mo funciona el Poder Electoral en Venezuela? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-25T20:03:57+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo funciona el Poder Electoral en Venezuela?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfC\u00f3mo funciona el Poder Electoral en Venezuela?","url":"http:\/\/noticiasya.com\/laredo\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/07\/25\/como-funciona-sistema-y-poder-electoral-venezuela-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-25T20:03:57Z","datePublished":"2024-07-25T20:03:57Z","dateModified":"2024-07-25T20:03:57Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfC\\u00f3mo funciona el Poder Electoral en Venezuela?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/07\\\/25\\\/como-funciona-sistema-y-poder-electoral-venezuela-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/07\\\/25\\\/como-funciona-sistema-y-poder-electoral-venezuela-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-25T20:03:57Z\",\"datePublished\":\"2024-07-25T20:03:57Z\",\"dateModified\":\"2024-07-25T20:03:57Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451066,"url":"https:\/\/noticiasya.com\/laredo\/2024\/07\/12\/como-votar-extranjero-elecciones-venezuela-2024-fecha-requisitos-orix\/","url_meta":{"origin":1451414,"position":0},"title":"C\u00f3mo votar desde el extranjero para las elecciones presidenciales de Venezuela: fecha y requisitos","author":"","date":"julio 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013 Miles de venezolanos en el extranjero participar\u00e1n en las elecciones presidenciales del 28 de julio para elegir, entre 10 candidatos, a quien ser\u00e1 su pr\u00f3ximo presidente.Para estos comicios solo pueden participar aquellos venezolanos que sean mayores de 18 a\u00f1os, que posean residencia o cualquier otro estatus que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451283,"url":"https:\/\/noticiasya.com\/laredo\/2024\/07\/20\/elecciones-presidenciales-venezuela-claves-orix\/","url_meta":{"origin":1451414,"position":1},"title":"Las 10 claves de las elecciones presidenciales en Venezuela","author":"","date":"julio 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El pr\u00f3ximo 28 de julio se llevar\u00e1n a cabo en Venezuela unas elecciones que mantienen en vilo al pa\u00eds y a la regi\u00f3n. Aqu\u00ed te contamos las claves.\u00bfQu\u00e9 se vota?Los venezolanos deber\u00e1n elegir entre 10 candidatos al pr\u00f3ximo presidente para el periodo 2025-2031Nicol\u00e1s Maduro (Cr\u00e9dito: Getty Images)\u00bfQui\u00e9nes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451381,"url":"https:\/\/noticiasya.com\/laredo\/2024\/07\/24\/opositores-que-no-ganaron-a-maduro-orix\/","url_meta":{"origin":1451414,"position":2},"title":"Los opositores que no le pudieron ganar a Maduro en elecciones anteriores","author":"","date":"julio 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Venezuela elegir\u00e1 a un nuevo presidente el 28 de julio entre diez candidatos, aunque, seg\u00fan las encuestas, hay dos aspirantes claramente despegados del resto: el presidente Nicol\u00e1s Maduro y el abanderado de la oposici\u00f3n mayoritaria, Edmundo Gonz\u00e1lez Urrutia.Maduro va por su tercer mandato y tambi\u00e9n por tercera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451523,"url":"https:\/\/noticiasya.com\/laredo\/2024\/07\/31\/maduro-recurso-tribunal-supremo-de-justicia-certifique-resultados-orix\/","url_meta":{"origin":1451414,"position":3},"title":"Maduro interpone un recurso ante el Tribunal Supremo de Justicia para que certifique los resultados","author":"","date":"julio 31, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Venezuela, Nicol\u00e1s Maduro, present\u00f3 este mi\u00e9rcoles un recurso contencioso electoral ante la Sala Electoral del Tribunal Supremo de Justicia para que haga un peritaje y certifique los resultados de las elecciones presidenciales del domingo.Maduro, quien seg\u00fan el Consejo Nacional Electoral obtuvo el triunfo con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464924,"url":"https:\/\/noticiasya.com\/laredo\/2025\/07\/28\/chavismo-alcaldias-elecciones-contrapeso-opositor-orix\/","url_meta":{"origin":1451414,"position":4},"title":"Chavismo obtiene m\u00e1s del 84 % de las alcald\u00edas en elecciones sin contrapeso opositor real","author":"","date":"julio 28, 2025","format":false,"excerpt":"Los venezolanos fueron convocados a elecciones por segunda vez en el a\u00f1o este domingo, en esta ocasi\u00f3n para elegir 335 alcaldes y 2.471 concejales. Seg\u00fan el primer bolet\u00edn emitido por el Consejo Nacional electoral con el escrutinio de 304 municipios, el partido de gobierno obtuvo 257 alcald\u00edas frente a las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450811,"url":"https:\/\/noticiasya.com\/laredo\/2024\/06\/30\/venezuela-simulacros-electorales-eleccion-presidencia-28-de-julio-orix\/","url_meta":{"origin":1451414,"position":5},"title":"El Consejo Nacional Electoral de Venezuela realiza simulacros electorales de cara a la elecci\u00f3n presidencial en julio","author":"","date":"junio 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Con total normalidad se llev\u00f3 a cabo este domingo el simulacro organizado por el Consejo Nacional Electoral (CNE) como parte de los preparativos para las elecciones presidenciales del 28 de julio en Venezuela. La participaci\u00f3n vari\u00f3 dependiendo de los centros de votaci\u00f3n, en este proceso voluntario en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1451414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1451414"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1451414\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1451414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1451414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1451414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}