{"id":1452098,"date":"2024-08-23T08:03:47","date_gmt":"2024-08-23T15:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/"},"modified":"2024-08-23T08:03:47","modified_gmt":"2024-08-23T15:03:47","slug":"mensajes-latinos-inmigracion-convencion-nacional-democrata-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/","title":{"rendered":"Los mensajes a los latinos y sobre inmigraci\u00f3n durante la Convenci\u00f3n Nacional Dem\u00f3crata"},"content":{"rendered":"<p>(CNN) &#8212; La Convenci\u00f3n Nacional Dem\u00f3crata cerr\u00f3 el jueves con un encendido discurso de Kamala Harris, quien apostar\u00e1 a aprovechar el impulso de los \u00faltimos cuatro d\u00edas para convertirse en la primera mujer negra de origen inmigrante en llegar al Sal\u00f3n Oval.<\/p>\n<p>Aunque el foco de la Convenci\u00f3n estuvo puesto en reivindicar a Harris y dar a conocer su historia familiar, adem\u00e1s de contrastarla con su rival republicano, el expresidente Donald Trump, uno de los grandes temas de esta campa\u00f1a ser\u00e1n los m\u00e1s de 36 millones de latinos que est\u00e1n habilitados para votar en noviembre.<\/p>\n<p>Kamala Harris y la comunidad latina: \u00bfmejoraron las posibilidades del Partido Dem\u00f3crata con su candidatura?<\/p>\n<p>CNN rastre\u00f3 cu\u00e1les fueron los mensajes m\u00e1s importantes dedicados a los latinos en estos cuatros d\u00edas y qu\u00e9 dijeron los distintos oradores en materia migratoria. Aqu\u00ed un resumen:<\/p>\n<p>Kamala Harris:<\/p>\n<p>Harris: Se puede estar a la altura de nuestra herencia migratoria 0:25<\/p>\n<p>Durante su discurso de cierre del jueves, Kamala Harris habl\u00f3 de la importancia de una reforma migratoria y de reforzar la seguridad en la frontera entre M\u00e9xico y Estados Unidos, sin olvidar la riqueza que implica para el pa\u00eds ser una naci\u00f3n de inmigrantes.<\/p>\n<p>&#171;S\u00e9 que podemos estar a la altura de nuestra orgullosa herencia como una naci\u00f3n inmigrantes y a la vez reformar nuestro roto sistema migratorio. Podemos crear un camino para que la ciudadan\u00eda se gane por m\u00e9ritos y asegurar nuestra frontera&#187;, dijo Harris, al tiempo que prometi\u00f3 que retomar\u00e1 el proyecto bipartidista que fue frenado a principio de a\u00f1o en el Congreso y lo har\u00e1 ley.<\/p>\n<p>Harris, en su discurso ante la audiencia dem\u00f3crata, subray\u00f3 que los dem\u00f3cratas y los republicanos redactaron juntos el proyecto de ley y que la Patrulla Fronteriza lo respald\u00f3, pero Trump lo hundi\u00f3.<\/p>\n<p>Ana Navarro:<\/p>\n<p>Republicana compara a Trump con Ortega, Maduro y los Castro 1:20<\/p>\n<p>El mensaje de la analista republicana Ana Navarro durante el segundo d\u00eda de la Convenci\u00f3n Nacional Dem\u00f3crata fue uno de los m\u00e1s destacados de la convenci\u00f3n, y de los m\u00e1s fuertes para el p\u00fablico latino. Navarro form\u00f3 parte de la lista de republicanos y exrepublicanos en la Convenci\u00f3n que abogaron porque los independientes y los cr\u00edticos de Trump votaran por Harris.<\/p>\n<p>&#171;Donald Trump y sus secuaces dicen que Kamala Harris es comunista. Yo conozco el comunismo&#187;, dijo Navarro, de origen nicarag\u00fcense, apuntando contra los ataques del expresidente hacia la candidata dem\u00f3crata.<\/p>\n<p>&#171;Hu\u00ed del comunismo de Nicaragua cuando ten\u00eda 8 a\u00f1os. No me lo tomo a la ligera. Y d\u00e9jenme decirles lo que hacen los dictadores comunistas \u2014y nunca lo hacen por un solo d\u00eda\u2014: atacan a la prensa libre, la acusan de ser enemigos del pueblo, como hace Ortega en Nicaragua; ponen a sus familiares no calificados en c\u00f3modos puestos gubernamentales para que puedan enriquecerse, como hacen los Castro en Cuba; y se niegan a aceptar elecciones cuando pierden y usan la violencia para mantenerse en el poder, como Maduro est\u00e1 haciendo ahora mismo en Venezuela&#187;.<\/p>\n<p>Tras una ovaci\u00f3n del p\u00fablico, Navarro pregunt\u00f3: &#171;\u00bfAlguna de esas cosas les suena familiar? \u00bfHay alguna persona que se est\u00e9 postulando para presidente que les recuerde a algo de eso?&#187;. Y se respondi\u00f3: &#171;Yo s\u00e9 una cosa: no es Kamala Harris&#187;.<\/p>\n<p>La campa\u00f1a de Harris lanza un canal de WhatsApp dirigido a los votantes latinos<\/p>\n<p>Barack Obama:<\/p>\n<p>El expresidente de EE.UU. Barack Obama habla el segundo d\u00eda de la Convenci\u00f3n Nacional Dem\u00f3crata (DNC) en el United Center en Chicago, Illinois, el 20 de agosto de 2024. (Foto de CHARLY TRIBALLEAU\/AFP v\u00eda Getty Images)<\/p>\n<p>El expresidente Barack Obama fue protagonista de uno de los discursos m\u00e1s celebrados de la Convenci\u00f3n Nacional Dem\u00f3crata, en su segunda jornada.\u00a0Tanto su discurso como el de su esposa, Michelle Obama, buscaron presentar a Harris en t\u00e9rminos m\u00e1s personales.<\/p>\n<p>El expresidente traz\u00f3 una conexi\u00f3n entre su propia familia y la de la candidata, al decir de sus abuelas: &#171;Sab\u00edan lo que era verdad. Sab\u00edan lo que importaba&#187;, dijo Obama. &#171;Cosas como la honestidad y la integridad, la amabilidad y el trabajo duro. No les impresionaban los fanfarrones ni los matones. No cre\u00edan que menospreciar a los dem\u00e1s te elevara o te hiciera fuerte. No pasaban mucho tiempo obsesionadas con lo que no ten\u00edan&#187;.<\/p>\n<p>Luego, estableci\u00f3 la conexi\u00f3n con Harris, se\u00f1alando a su madre india y a su padre jamaicano, ambos emigrados a Estados Unidos.\u00a0&#171;Seas dem\u00f3crata o republicano, o te encuentres en alg\u00fan punto intermedio, todos hemos tenido gente as\u00ed en nuestras vidas: gente como los padres de Kamala, que cruzaron oc\u00e9anos porque cre\u00edan en la promesa de Estados Unidos&#187;, dijo.<\/p>\n<p>Carlos Eduardo Espina:<\/p>\n<p>El creador de contenido Carlos Eduardo Espina habla en el tercer d\u00eda de la Convenci\u00f3n Nacional Dem\u00f3crata en el United Center en Chicago, Illinois, el 21 de agosto de 2024. (Foto de MANDEL NGAN\/AFP v\u00eda Getty Images)<\/p>\n<p>Carlos Eduador Espina, influencer y creador de contenidos, sostuvo que Estados Unidos es m\u00e1s fuerte con su cultura de inmigrantes y llam\u00f3 a proteger esos valores en estas elecciones. Lo hizo en el tercer d\u00eda de la Convenci\u00f3n Nacional Dem\u00f3crata.<\/p>\n<p>&#171;Estar a favor de los inmigrantes es estar a favor de Estados Unidos&#187;, dijo Espina en Chicago. &#171;Kamala Harris tambi\u00e9n entiende esto, y por eso, una vez elegida rechazar\u00e1 el odio y encontrar\u00e1 soluciones que hagan m\u00e1s fuerte a nuestra naci\u00f3n&#187;, dijo. &#171;As\u00ed que hagamos que sea elegida y aseguremos que nuestro pa\u00eds siga siendo un faro de libertad y oportunidades para todos&#187;.<\/p>\n<p>Espina, que naci\u00f3 en Montevideo, Uruguay, de padre uruguayo y madre mexicana, dijo que sus padres emigraron a Texas y que,\u00a0al igual que sus padres, otros inmigrantes con los que habla a diario creen que Estados Unidos es &#171;la tierra de las oportunidades donde todo es posible&#187;.<\/p>\n<p>Dijo que esas son &#171;las mismas personas que Donald Trump quiere hacer creer que est\u00e1n envenenando la sangre de nuestro pa\u00eds&#187;. Tambi\u00e9n calific\u00f3 esa ret\u00f3rica de &#171;peligrosa&#187; y &#171;antiestadounidense&#187;.<\/p>\n<p>Espina se describe a s\u00ed mismo como estudiante de Derecho y activista por los derechos de los inmigrantes en Instagram. Publica contenidos, muchos de ellos en espa\u00f1ol, a trav\u00e9s de sus plataformas de redes sociales, incluyendo algunos de la Convenci\u00f3n Nacional Dem\u00f3crata esta semana.<\/p>\n<p>Javier Salazar:<\/p>\n<p>El sheriff del condado de Bexar, Texas, Javier Salazar, habla en el tercer d\u00eda de la Convenci\u00f3n Nacional Dem\u00f3crata en el United Center en Chicago, Illinois, el 21 de agosto de 2024. (Foto de MANDEL NGAN\/AFP v\u00eda Getty Images)<\/p>\n<p>El sheriff del condado de Bexar (Texas), Javier Salazar, se dedic\u00f3 durante su discurso del mi\u00e9rcoles a socavar las cr\u00edticas de la campa\u00f1a de Trump a Harris relacionadas con la migraci\u00f3n.<\/p>\n<p>&#171;Ella fue a M\u00e9xico y trabaj\u00f3 para detener a los traficantes, y cuando los traficantes no se detuvieron, los meti\u00f3 en la c\u00e1rcel&#187;, dijo Salazar.<\/p>\n<p>El condado de Bexar abarca la ciudad de San Antonio.<\/p>\n<p>&#171;Los sheriff de frontera como yo, y yo, somos como Kamala. Protegemos y servimos. Y defendemos la ley. Somos compasivos, y peleamos duro para defender nuestra frontera&#187;, indic\u00f3.<\/p>\n<p>Salazar cerr\u00f3 su discurso diciendo: &#171;Cuando luchamos, ganamos\u201d en espa\u00f1ol, frase que repiti\u00f3 despu\u00e9s en ingl\u00e9s, en medio de una ovaci\u00f3n.<\/p>\n<p>Mar\u00eda Teresa Kumar:<\/p>\n<p>Mar\u00eda Teresa Kumar, de Voto Latino, habla durante el tercer d\u00eda de la Convenci\u00f3n Nacional Dem\u00f3crata de 2024 en Chicago el mi\u00e9rcoles 21 de agosto de 2024. (Bill Clark\/CQ-Roll Call, Inc v\u00eda Getty Images)<\/p>\n<p>Mar\u00eda Teresa Kumar, presidenta de Voto Latino, elogi\u00f3 el poder del bloque de votantes latinos durante su discurso del mi\u00e9rcoles. Kumar dijo que su organizaci\u00f3n ha registrado 1,5 millones de votantes de cara a las elecciones de 2024 &#171;y apenas estamos empezando&#187;.<\/p>\n<p>&#171;Desde 2020, 4 millones de j\u00f3venes latinos se han convertido en elegibles para votar en estas elecciones&#187;, dijo Kumar. &#171;Y no podr\u00eda estar m\u00e1s orgulloso porque los estamos registrando m\u00e1s r\u00e1pido que en cualquier otro momento de nuestra historia. Este a\u00f1o lo demostraremos de nuevo: Cuando los latinos votan, \u00a1los dem\u00f3cratas ganan! Otro dato curioso: este a\u00f1o votar\u00e1n m\u00e1s latinos que en ning\u00fan otro momento de nuestra historia. As\u00ed que eso significa, \u00a1s\u00ed se puede!&#187;.<\/p>\n<p>Olivia Troye:<\/p>\n<p>Exasesora de Mike Pence habla sobre su cambio de partido 3:56<\/p>\n<p>Troye es una mujer republicana, hija de una migrante mexicana y exasesora del exvicepresidente Mike Pence, quien habl\u00f3 con CNN durante la tercera noche de la Convenci\u00f3n Nacional Dem\u00f3crata sobre por qu\u00e9 abandon\u00f3 su partido y ahora apoya a Harris.<\/p>\n<p>&#171;Yo fui testigo de las cosas que hac\u00edan. De c\u00f3mo hablaban de los inmigrantes, de los latinos&#187;, record\u00f3. &#171;Y ese no es el Partido Republicano con el que yo me identifico&#187;. Seg\u00fan ella, Trump identificaba a los latinos con ladrones, criminales e incluso con miembros de c\u00e1rteles de drogas, todo eso en reuniones de las que ella participaba. &#171;Yo soy hija de una inmigrante mexicana, y ella ama a este pa\u00eds&#187;.<\/p>\n<p>&#171;Los inmigrantes son muy trabajadores. La mayor\u00eda trabaja, paga sus impuestos, contribuyen a nuestra cultura y a nuestra econom\u00eda. Entonces, qu\u00e9 insulto para nosotros&#187;, dijo Troye.<\/p>\n<p>&#171;Yo crec\u00ed en Texas, y he sido republicana toda mi vida, pero estos no son los valores tradicionales los que estamos viendo aqu\u00ed&#187;, a\u00f1adi\u00f3.<\/p>\n<p>Eva Longoria:<\/p>\n<p>La actriz latina Eva Longoria dio un discurso en la Convenci\u00f3n Nacional Dem\u00f3crata en el que apel\u00f3 a los hispanos y lo hizo en espa\u00f1ol. \u201cD\u00e9jenme decirles, en la comunidad latina tenemos un dicho: \u2018S\u00ed se puede'&#187;, dijo la reconocida actriz y productora.<\/p>\n<p>Longoria, quien dijo que Kamala Harris es &#171;como familia&#187;, lider\u00f3 entonces c\u00e1nticos de &#171;She (ella) se puede&#187;, un juego de palabras entre &#171;S\u00ed se puede&#187;, en espa\u00f1ol, y &#171;She can&#187;, &#171;ella puede&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La Convenci\u00f3n Nacional Dem\u00f3crata cerr\u00f3 el jueves con un encendido discurso de Kamala Harris, quien apostar\u00e1 a aprovechar el impulso de los \u00faltimos cuatro d\u00edas para convertirse en la primera mujer negra de origen inmigrante en llegar al Sal\u00f3n Oval. Aunque el foco de la Convenci\u00f3n estuvo puesto en reivindicar a Harris y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1452098","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los mensajes a los latinos y sobre inmigraci\u00f3n durante la Convenci\u00f3n Nacional Dem\u00f3crata - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los mensajes a los latinos y sobre inmigraci\u00f3n durante la Convenci\u00f3n Nacional Dem\u00f3crata - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La Convenci\u00f3n Nacional Dem\u00f3crata cerr\u00f3 el jueves con un encendido discurso de Kamala Harris, quien apostar\u00e1 a aprovechar el impulso de los \u00faltimos cuatro d\u00edas para convertirse en la primera mujer negra de origen inmigrante en llegar al Sal\u00f3n Oval. Aunque el foco de la Convenci\u00f3n estuvo puesto en reivindicar a Harris y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-23T15:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los mensajes a los latinos y sobre inmigraci\u00f3n durante la Convenci\u00f3n Nacional Dem\u00f3crata\",\"datePublished\":\"2024-08-23T15:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/\"},\"wordCount\":1735,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/\",\"name\":\"Los mensajes a los latinos y sobre inmigraci\u00f3n durante la Convenci\u00f3n Nacional Dem\u00f3crata - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-23T15:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los mensajes a los latinos y sobre inmigraci\u00f3n durante la Convenci\u00f3n Nacional Dem\u00f3crata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los mensajes a los latinos y sobre inmigraci\u00f3n durante la Convenci\u00f3n Nacional Dem\u00f3crata - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Los mensajes a los latinos y sobre inmigraci\u00f3n durante la Convenci\u00f3n Nacional Dem\u00f3crata - Noticias","og_description":"(CNN) &#8212; La Convenci\u00f3n Nacional Dem\u00f3crata cerr\u00f3 el jueves con un encendido discurso de Kamala Harris, quien apostar\u00e1 a aprovechar el impulso de los \u00faltimos cuatro d\u00edas para convertirse en la primera mujer negra de origen inmigrante en llegar al Sal\u00f3n Oval. Aunque el foco de la Convenci\u00f3n estuvo puesto en reivindicar a Harris y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/","og_site_name":"Noticias","article_published_time":"2024-08-23T15:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/"},"author":{"name":"","@id":""},"headline":"Los mensajes a los latinos y sobre inmigraci\u00f3n durante la Convenci\u00f3n Nacional Dem\u00f3crata","datePublished":"2024-08-23T15:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/"},"wordCount":1735,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/","url":"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/","name":"Los mensajes a los latinos y sobre inmigraci\u00f3n durante la Convenci\u00f3n Nacional Dem\u00f3crata - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-23T15:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los mensajes a los latinos y sobre inmigraci\u00f3n durante la Convenci\u00f3n Nacional Dem\u00f3crata"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los mensajes a los latinos y sobre inmigraci\u00f3n durante la Convenci\u00f3n Nacional Dem\u00f3crata","url":"http:\/\/noticiasya.com\/laredo\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/08\/23\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-23T15:03:47Z","datePublished":"2024-08-23T15:03:47Z","dateModified":"2024-08-23T15:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los mensajes a los latinos y sobre inmigraci\\u00f3n durante la Convenci\\u00f3n Nacional Dem\\u00f3crata\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/08\\\/23\\\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/08\\\/23\\\/mensajes-latinos-inmigracion-convencion-nacional-democrata-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-23T15:03:47Z\",\"datePublished\":\"2024-08-23T15:03:47Z\",\"dateModified\":\"2024-08-23T15:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451990,"url":"https:\/\/noticiasya.com\/laredo\/2024\/08\/19\/fotos-convencion-nacional-democrata-2024-trax\/","url_meta":{"origin":1452098,"position":0},"title":"FOTOS | Convenci\u00f3n Nacional Dem\u00f3crata de 2024","author":"","date":"agosto 19, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 La Convenci\u00f3n Nacional Dem\u00f3crata est\u00e1 en marcha en Chicago, y se espera que la candidata presidencial del partido, la vicepresidenta Kamala Harris, haga su primera aparici\u00f3n este lunes despu\u00e9s de un discurso en horario estelar del presidente Joe Biden.Biden puso fin a su campa\u00f1a de reelecci\u00f3n el mes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451959,"url":"https:\/\/noticiasya.com\/laredo\/2024\/08\/18\/hollywood-chicago-convencion-democrata-beyonce-taylor-swift-trax\/","url_meta":{"origin":1452098,"position":1},"title":"Hollywood se dirige a Chicago para la convenci\u00f3n dem\u00f3crata, mientras se especula con Beyonc\u00e9 y Taylor Swift","author":"","date":"agosto 18, 2024","format":false,"excerpt":"(CNN) -- Cuando Barack Obama acept\u00f3 su candidatura presidencial en la Convenci\u00f3n Nacional Dem\u00f3crata de 2008 en Denver, Jennifer Lopez estaba en la ciudad, Ben Affleck y Jennifer Garner asistieron juntos al acto y Kanye West dio un espect\u00e1culo en una fiesta de la campa\u00f1a de Obama.Cuatro convenciones m\u00e1s tarde,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452047,"url":"https:\/\/noticiasya.com\/laredo\/2024\/08\/21\/john-legend-miercoles-pink-cierre-convencion-nacional-democrata-trax\/","url_meta":{"origin":1452098,"position":2},"title":"Exclusiva: John Legend cantar\u00e1 este mi\u00e9rcoles y Pink estar\u00e1 a cargo del cierre de la Convenci\u00f3n Nacional Dem\u00f3crata","author":"","date":"agosto 21, 2024","format":false,"excerpt":"(CNN) --\u00a0 Pink es la elegida para una actuaci\u00f3n en la noche de clausura de la Convenci\u00f3n Nacional Dem\u00f3crata, dijo a CNN una fuente familiarizada con lo planificado.La galardonada cantautora e \u00edcono mundial del pop actuar\u00e1 el jueves por la noche, dijo la fuente, antes de que la vicepresidenta Kamala\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452082,"url":"https:\/\/noticiasya.com\/laredo\/2024\/08\/22\/kamala-harris-latinos-partido-democrata-orix\/","url_meta":{"origin":1452098,"position":3},"title":"Kamala Harris y la comunidad latina: \u00bfmejoraron las posibilidades del Partido Dem\u00f3crata con su candidatura?","author":"","date":"agosto 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 M\u00e1s de 36 millones de latinos estar\u00e1n habilitados para votar en las elecciones presidenciales de noviembre en Estados Unidos, constituyendo un grupo al que cualquier candidato deber\u00eda prestar especial atenci\u00f3n.De acuerdo con el Pew Reaserch Center, aunque los votantes latinos en EE.UU. usualmente han favorecido al Partido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451301,"url":"https:\/\/noticiasya.com\/laredo\/2024\/07\/21\/que-pasara-elecciones-ee-uu-biden-retirarse-candidato-democrata-kamala-trax\/","url_meta":{"origin":1452098,"position":4},"title":"Qu\u00e9 pasar\u00e1 con las elecciones de EE.UU. y la candidatura dem\u00f3crata tras el retiro de Biden de la contienda","author":"","date":"julio 21, 2024","format":false,"excerpt":"(CNN) -- El presidente Joe Biden decidi\u00f3 no presentarse a la reelecci\u00f3n, tras su desastrosa actuaci\u00f3n en el debate del mes pasado y su fracaso desde entonces para convencer a sus copartidarios dem\u00f3cratas de que puede derrotar al expresidente Donald Trump en oto\u00f1o.Los dem\u00f3cratas tienen ahora un reto sin precedentes,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451962,"url":"https:\/\/noticiasya.com\/laredo\/2024\/08\/18\/biden-convencion-democrata-espectador-presidente-trax\/","url_meta":{"origin":1452098,"position":5},"title":"Biden fue un espectador en su primera Convenci\u00f3n Nacional Dem\u00f3crata; ahora, en su decimotercera, es un presidente en ejercicio que pasa la antorcha","author":"","date":"agosto 18, 2024","format":false,"excerpt":"(CNN) -- Cuando Joe Biden viaj\u00f3 a Miami Beach para su primera Convenci\u00f3n Nacional Dem\u00f3crata en 1972, su presencia gener\u00f3 poco m\u00e1s que una nota a pie de p\u00e1gina.\u201cEl concejal Joseph R. Biden, dem\u00f3crata de Faulkland Heights, no delegado, tambi\u00e9n asistir\u00e1\u201d, se lee en la \u00fanica referencia a su presencia,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1452098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1452098"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1452098\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1452098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1452098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1452098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}