{"id":1452113,"date":"2024-08-23T18:03:54","date_gmt":"2024-08-24T01:03:54","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/"},"modified":"2024-08-23T18:03:54","modified_gmt":"2024-08-24T01:03:54","slug":"atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/","title":{"rendered":"Atienden por golpe de calor a m\u00e1s de 100 personas en mitin de Trump en Arizona"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0M\u00e1s de 100 personas fueron atendidas por enfermedades relacionadas con el calor mientras esperaban en Glendale, Arizona, el mitin del expresidente Donald Trump, inform\u00f3 The Arizona Republic.<\/p>\n<p>El subjefe Tim Pirtle del Departamento de Bomberos de Glendale dijo que \u201cel gran volumen de pacientes retras\u00f3 la capacidad de los bomberos de Glendale para tratar y transportar a las personas al hospital\u201d, seg\u00fan el diario.<\/p>\n<p>Al menos 20 de los atendidos \u201cfueron trasladados en transporte para recibir asistencia m\u00e9dica adicional\u201d, dijo a CNN Brent Stoddard, subdirector de la ciudad de Glendale, en un correo electr\u00f3nico el viernes por la noche.<\/p>\n<p>Robert F. Kennedy suspende su campa\u00f1a presidencial y apoya a Donald Trump<\/p>\n<p>&#171;Nuestros funcionarios de seguridad p\u00fablica y socorristas hicieron un trabajo incre\u00edble al establecer m\u00e1s de 100 contactos con personas que buscaban ayuda debido al calor y otros problemas m\u00e9dicos&#187;, dijo Stoddard. &#171;Aunque no conocemos el recuento final en este momento, al menos 20 de esos contactos fueron trasladados en transporte para recibir asistencia m\u00e9dica adicional&#187;.<\/p>\n<p>CNN se comunic\u00f3 con el Departamento de Bomberos de Glendale y la oficina del alcalde para obtener m\u00e1s informaci\u00f3n.<\/p>\n<p>La temperatura actual en Glendale es de 41 \u00b0C, seg\u00fan el equipo meteorol\u00f3gico de CNN.<\/p>\n<p>En junio, 11 personas fueron transportadas a hospitales despu\u00e9s de informes de agotamiento por calor en un evento de Trump en Phoenix.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0M\u00e1s de 100 personas fueron atendidas por enfermedades relacionadas con el calor mientras esperaban en Glendale, Arizona, el mitin del expresidente Donald Trump, inform\u00f3 The Arizona Republic. El subjefe Tim Pirtle del Departamento de Bomberos de Glendale dijo que \u201cel gran volumen de pacientes retras\u00f3 la capacidad de los bomberos de Glendale para [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1452113","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Atienden por golpe de calor a m\u00e1s de 100 personas en mitin de Trump en Arizona - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atienden por golpe de calor a m\u00e1s de 100 personas en mitin de Trump en Arizona - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0M\u00e1s de 100 personas fueron atendidas por enfermedades relacionadas con el calor mientras esperaban en Glendale, Arizona, el mitin del expresidente Donald Trump, inform\u00f3 The Arizona Republic. El subjefe Tim Pirtle del Departamento de Bomberos de Glendale dijo que \u201cel gran volumen de pacientes retras\u00f3 la capacidad de los bomberos de Glendale para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-24T01:03:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Atienden por golpe de calor a m\u00e1s de 100 personas en mitin de Trump en Arizona\",\"datePublished\":\"2024-08-24T01:03:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/\"},\"wordCount\":267,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/\",\"name\":\"Atienden por golpe de calor a m\u00e1s de 100 personas en mitin de Trump en Arizona - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-24T01:03:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atienden por golpe de calor a m\u00e1s de 100 personas en mitin de Trump en Arizona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atienden por golpe de calor a m\u00e1s de 100 personas en mitin de Trump en Arizona - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Atienden por golpe de calor a m\u00e1s de 100 personas en mitin de Trump en Arizona - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0M\u00e1s de 100 personas fueron atendidas por enfermedades relacionadas con el calor mientras esperaban en Glendale, Arizona, el mitin del expresidente Donald Trump, inform\u00f3 The Arizona Republic. El subjefe Tim Pirtle del Departamento de Bomberos de Glendale dijo que \u201cel gran volumen de pacientes retras\u00f3 la capacidad de los bomberos de Glendale para [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-24T01:03:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/"},"author":{"name":"","@id":""},"headline":"Atienden por golpe de calor a m\u00e1s de 100 personas en mitin de Trump en Arizona","datePublished":"2024-08-24T01:03:54+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/"},"wordCount":267,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/","name":"Atienden por golpe de calor a m\u00e1s de 100 personas en mitin de Trump en Arizona - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-24T01:03:54+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Atienden por golpe de calor a m\u00e1s de 100 personas en mitin de Trump en Arizona"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Atienden por golpe de calor a m\u00e1s de 100 personas en mitin de Trump en Arizona","url":"http:\/\/noticiasya.com\/laredo\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/08\/23\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-24T01:03:54Z","datePublished":"2024-08-24T01:03:54Z","dateModified":"2024-08-24T01:03:54Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Atienden por golpe de calor a m\\u00e1s de 100 personas en mitin de Trump en Arizona\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/08\\\/23\\\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/08\\\/23\\\/atienden-golpe-de-calor-asistentes-mitin-trump-arizona-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-24T01:03:54Z\",\"datePublished\":\"2024-08-24T01:03:54Z\",\"dateModified\":\"2024-08-24T01:03:54Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456112,"url":"https:\/\/noticiasya.com\/laredo\/2024\/11\/26\/arrestan-a-hombre-de-arizona-tras-amenazar-con-matar-a-trump-trax\/","url_meta":{"origin":1452113,"position":0},"title":"Arrestan a hombre de Arizona tras amenazar con matar a Trump","author":"","date":"noviembre 26, 2024","format":false,"excerpt":"(CNN) -- Un hombre de Arizona fue arrestado este lunes despu\u00e9s de supuestamente amenazar con matar al presidente electo Donald Trump en una serie de videos de Facebook, incluido uno en el que parece sostener un rifle estilo AR-15, seg\u00fan documentos judiciales.Manuel Tamayo-Torres enfrenta un cargo de delito grave por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451949,"url":"https:\/\/noticiasya.com\/laredo\/2024\/08\/18\/100-personas-tratadas-por-enfermedades-relacionadas-calor-espectaculo-aereo-colorado-dicen-autoridades-trax\/","url_meta":{"origin":1452113,"position":1},"title":"Unas 100 personas fueron tratadas por enfermedades relacionadas con el calor en un espect\u00e1culo a\u00e9reo de Colorado, dicen las autoridades","author":"","date":"agosto 18, 2024","format":false,"excerpt":"(CNN) -- Alrededor de 100 personas fueron tratadas por enfermedades relacionadas con el calor en un espect\u00e1culo a\u00e9reo en Colorado Springs y 10 fueron trasladadas a hospitales este s\u00e1bado, dijeron las autoridades, en un d\u00eda en el que las temperaturas alcanzaron los 32\u00b0 C grados en la ciudad del centro-este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450130,"url":"https:\/\/noticiasya.com\/laredo\/2024\/06\/07\/domo-calor-temperaturas-sofocantes-estados-unidos-trax\/","url_meta":{"origin":1452113,"position":2},"title":"Se pronostican m\u00e1s temperaturas sofocantes en el domo de calor en suroeste de EE.UU. un d\u00eda despu\u00e9s de que el Valle de la Muerte alcanzara los 50 \u00b0C","author":"","date":"junio 7, 2024","format":false,"excerpt":"(CNN) -- Una peligrosa ola de calor est\u00e1 trayendo temperaturas r\u00e9cord a partes de California, la Gran Cuenca y el suroeste de Estados Unidos este viernes, creando un riesgo de enfermedades relacionadas con el calor y otros peligros en algunas \u00e1reas.El motor de este calor prolongado y fuera de temporada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466644,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/20\/servicio-conmemorativo-charlie-kirk-trax\/","url_meta":{"origin":1452113,"position":3},"title":"As\u00ed ser\u00e1 la ceremonia en memoria de Charlie Kirk","author":"","date":"septiembre 20, 2025","format":false,"excerpt":"Miles de personas se reunir\u00e1n el domingo para honrar la vida del activista conservador asesinado Charlie Kirk en una ceremonia conmemorativa que se espera ponga de manifiesto su indeleble influencia en la pol\u00edtica estadounidense.Con una lista de oradores de los m\u00e1s altos niveles del Gobierno de Estados Unidos, incluido el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450777,"url":"https:\/\/noticiasya.com\/laredo\/2024\/06\/28\/tres-inmigrantes-muertos-excesivo-calor-desierto-arizona-trax\/","url_meta":{"origin":1452113,"position":4},"title":"Tres inmigrantes fueron hallados muertos en medio del excesivo calor del desierto de Arizona","author":"","date":"junio 28, 2024","format":false,"excerpt":"(CNN) --\u00a0Tres inmigrantes fueron encontrados muertos el mi\u00e9rcoles en una zona des\u00e9rtica de Arizona, y la Patrulla Fronteriza dice que murieron debido calor excesivo.\"Demasiadas personas que tomaron la decisi\u00f3n de poner sus vidas en manos de las organizaciones criminales han muerto por deshidrataci\u00f3n y golpe de calor\", dijo el subjefe\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465958,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/28\/patrulla-fronteriza-detiene-bomberos-incendio-washington-trax\/","url_meta":{"origin":1452113,"position":5},"title":"Patrulla Fronteriza detiene a dos bomberos por estar ilegalmente en EE.UU. mientras combat\u00edan el mayor incendio en Washington","author":"","date":"agosto 28, 2025","format":false,"excerpt":"Agentes de la Patrulla Fronteriza arrestaron el mi\u00e9rcoles a dos bomberos \u2014a quienes se\u00f1alan de estar en Estados Unidos de manera ilegal\u2014 mientras trabajaban para contener el mayor incendio forestal del estado de Washington.La Oficina de Administraci\u00f3n de Tierras (BLM, por sus siglas en ingl\u00e9s) y el Servicio Forestal de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1452113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1452113"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1452113\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1452113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1452113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1452113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}