{"id":1456372,"date":"2024-12-08T09:03:49","date_gmt":"2024-12-08T17:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/"},"modified":"2024-12-08T09:03:49","modified_gmt":"2024-12-08T17:03:49","slug":"netanyahu-ordena-ejercito-contencion-siria-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/","title":{"rendered":"Netanyahu ordena a las Fuerzas de Defensa de Israel tomar la zona de contenci\u00f3n de Siria"},"content":{"rendered":"<p>El primer ministro israel\u00ed, Benjamin Netanyahu, dijo el domingo que el colapso del r\u00e9gimen de Bashar al-Assad en Siria fue un \u201cresultado directo\u201d de la campa\u00f1a militar de Israel contra Ir\u00e1n y su representante en el L\u00edbano, Hezbollah.<\/p>\n<p>\u201cEste es un d\u00eda hist\u00f3rico en la historia del Medio Oriente\u201d, dijo.<\/p>\n<p>Pero en una se\u00f1al del peligro potencial que siente Israel por parte de gobernantes desconocidos en Damasco, Netanyahu dijo que hab\u00eda ordenado a los militares tomar la zona de amortiguaci\u00f3n que separa los Altos del Gol\u00e1n ocupados por Israel del resto de Siria.<\/p>\n<p>\u201cJunto con el ministro de Defensa y con el pleno apoyo del Gabinete, ayer orden\u00e9 a las Fuerzas de Defensa de Israel que tomaran el control de la zona de contenci\u00f3n y de las posiciones dominantes cercanas a ella\u201d, dijo durante su visita a los Altos del Gol\u00e1n. \u201cNo permitiremos que ninguna fuerza hostil se establezca en nuestra frontera\u201d.<\/p>\n<p>Es la primera vez que tropas israel\u00edes estar\u00e1n estacionadas en la zona de amortiguaci\u00f3n desde que en 1974 se firm\u00f3 un acuerdo que establec\u00eda la l\u00ednea de control entre Israel y Siria, aunque en el pasado han entrado en esa \u201ctierra de nadie\u201d durante breves per\u00edodos. Desde 1974, la zona de amortiguaci\u00f3n ha sido patrullada por fuerzas de paz de las Naciones Unidas. Israel arrebat\u00f3 los Altos del Gol\u00e1n a Siria en 1967 y los anex\u00f3 en 1981.<\/p>\n<p>Los dirigentes israel\u00edes observan con una mezcla de inquietud y alegr\u00eda los acontecimientos al otro lado de la frontera siria, mientras 50 a\u00f1os de distensi\u00f3n se ven trastocados en cuesti\u00f3n de horas.<\/p>\n<p>\u201cNo sabemos mucho\u201d, dijo Boaz Shapira, investigador de la Fundaci\u00f3n Alma, un centro de estudios dedicado a los problemas del norte de Israel. \u201cLa situaci\u00f3n a la que est\u00e1bamos acostumbrados en Siria en el pasado \u201350 a\u00f1os con el r\u00e9gimen de Asad\u2013 ha cambiado por completo\u201d.<\/p>\n<p>Bashar al-Assad no era precisamente un aliado, pero exist\u00eda un entendimiento que permit\u00eda la coexistencia entre ambos pa\u00edses. Aunque Israel <a href=\"https:\/\/www.cnn.com\/2013\/02\/17\/world\/meast\/israel-syria\/index.html\">ofrec\u00eda ocasionalmente asistencia m\u00e9dica<\/a> a las v\u00edctimas de la guerra civil siria, manten\u00eda oficialmente su neutralidad en el conflicto. El Ej\u00e9rcito israel\u00ed tambi\u00e9n atac\u00f3 durante a\u00f1os las l\u00edneas de suministro de Ir\u00e1n y su aliado Hezbollah en Siria (el caso m\u00e1s notable fue <a href=\"https:\/\/www.cnn.com\/2024\/04\/01\/middleeast\/iran-syrian-consulate-attack-intl\/index.html\">el asesinato de comandantes militares iran\u00edes<\/a> en el consulado iran\u00ed en Damasco, en abril), pero evit\u00f3 atacar al propio r\u00e9gimen de Assad.<\/p>\n<p>La r\u00e1pida captura de Damasco por parte de los rebeldes significa que los l\u00edderes israel\u00edes tendr\u00e1n que evaluar las implicaciones para su propia seguridad.<\/p>\n<p>Ir\u00e1n perdi\u00f3 uno de sus bastiones m\u00e1s importantes en la regi\u00f3n, lo que ser\u00e1 motivo de celebraci\u00f3n en Israel, que viene combatiendo a las fuerzas respaldadas por Ir\u00e1n en Gaza (Hamas) y L\u00edbano (Hezbollah) desde octubre del a\u00f1o pasado.<\/p>\n<p>Netanyahu, quien declar\u00f3 que el asesinato del l\u00edder de Hezbollah, Hassan Nasrallah, era un paso hacia el cambio \u201cdel equilibrio de poder en la regi\u00f3n para los pr\u00f3ximos a\u00f1os\u201d, ver\u00e1 esto como un avance hacia ese objetivo.<\/p>\n<p>Mordechai Kedar, que se especializ\u00f3 en asuntos sirios durante una carrera de 25 a\u00f1os en la inteligencia militar israel\u00ed, dijo que los acontecimientos en Siria fueron un efecto domin\u00f3 del ataque de Hamas del 7 de octubre contra Israel. \u201cNo es s\u00f3lo Israel, es todo el Medio Oriente el que va a celebrar\u201d, dijo a CNN.<\/p>\n<p>El colapso del r\u00e9gimen de Assad es un \u201cduro golpe\u201d para Ir\u00e1n, dijo Amos Yadlin, exgeneral de divisi\u00f3n de las Fuerzas de Defensa de Israel, quien tambi\u00e9n se desempe\u00f1\u00f3 como jefe de la Direcci\u00f3n de Inteligencia Militar.<\/p>\n<p>\u201cLos rebeldes que arrancaron carteles de (el comandante iran\u00ed Qasem) Soleimani y Nasrallah de la embajada iran\u00ed en Damasco ilustran la gravedad del golpe al eje\u201d, dijo. \u201cReconstruir Hezbollah parece a\u00fan m\u00e1s dif\u00edcil con la p\u00e9rdida de Siria, que era una retaguardia log\u00edstica para las armas de Assad, Ir\u00e1n y Rusia\u201d.<\/p>\n<p>Por otra parte, nadie sabe exactamente \u2013incluso en Israel\u2013 qui\u00e9nes son los rebeldes que ahora controlan Siria y c\u00f3mo implementar\u00e1n su poder.<\/p>\n<p>La ofensiva estuvo dirigida por Hayat Tahrir al-Sham, que antes era una filial de Al Qaeda. El Gobierno de Estados Unidos todav\u00eda ofrece una recompensa de US$ 10 millones por la cabeza de su l\u00edder, Abu Mohammad al-Jolani, cuyo verdadero nombre es Ahmed al-Sharaa.<\/p>\n<p>Kedar dijo que, a pesar de sus ra\u00edces radicales, los primeros indicios eran positivos. \u201cHasta ahora, son bastante racionales\u201d, dijo. \u201cPor ejemplo, est\u00e1n dejando que el Gobierno dirija el pa\u00eds\u201d.<\/p>\n<p>Jolani pidi\u00f3 a las fuerzas rebeldes que abandonen las instituciones estatales sin sufrir da\u00f1os. \u201cA todas las fuerzas militares de la ciudad de Damasco se les proh\u00edbe estrictamente acercarse a las instituciones p\u00fablicas, que permanecer\u00e1n bajo la supervisi\u00f3n del ex primer ministro hasta que sean entregadas oficialmente y tambi\u00e9n se les proh\u00edbe disparar balas al aire\u201d, escribi\u00f3 en Telegram.<\/p>\n<p>\u201cAqu\u00ed est\u00e1n aprendiendo de los errores de los estadounidenses en Iraq. No quieren destruir el pa\u00eds. Quieren que el sistema funcione, por supuesto, con otras reglas y un liderazgo diferente. Esta es una manera muy racional de dirigir el pa\u00eds\u201d.<\/p>\n<p>Yadlin dijo que Jolani hab\u00eda \u201cdemostrado una gran sofisticaci\u00f3n pol\u00edtica y conquistado Siria casi sin luchar\u201d.<\/p>\n<p>\u201cA corto plazo, los rebeldes no son una amenaza para Israel\u201d, afirm\u00f3. \u201cCuando se le pida que establezca su dominio en Siria, no se involucrar\u00e1 con la fuerza militar m\u00e1s poderosa de la regi\u00f3n. Israel necesita definir las reglas del juego contra Siria de la misma manera agresiva en que lo hace en el L\u00edbano\u201d.<\/p>\n<p>Esa opini\u00f3n no es universal. El ministro israel\u00ed de Di\u00e1spora y Lucha contra el Antisemitismo, Amichai Chiklisaid, <a href=\"https:\/\/x.com\/amichaichikli\/status\/1865627636896076062?s=48&#038;t=oJYe4pgmVb-WmxbKs9MKcQ\">dijo en una declaraci\u00f3n<\/a> que \u201cla conclusi\u00f3n es que la mayor parte de Siria est\u00e1 ahora bajo el control de afiliados a Al Qaeda y Daesh\u201d. Pidi\u00f3 que el ej\u00e9rcito israel\u00ed establezca un control total dentro de la zona de amortiguaci\u00f3n que existe desde 1974 entre el territorio controlado por Israel y el territorio controlado por Siria.<\/p>\n<p>De hecho, la m\u00e1xima prioridad de Israel ser\u00e1 asegurar su frontera con Siria. Las FDI afirmaron que el despliegue de tropas dentro de la zona de amortiguaci\u00f3n del Gol\u00e1n se realiz\u00f3 \u201cpara garantizar la seguridad de las comunidades de los Altos del Gol\u00e1n y de los ciudadanos de Israel\u201d.<\/p>\n<p>Shapira dijo que dudaba que Israel quisiera provocar a los nuevos l\u00edderes de Damasco avanzando hacia el Gol\u00e1n controlado por Siria. \u201cTomar m\u00e1s territorio significa que tenemos que lidiar con otros actores que podr\u00edan no estar tan contentos con ello\u201d, agreg\u00f3.<\/p>\n<p>\u201cHay decenas de milicias diferentes\u201d, dijo Shapira. \u201cVa a ser un gran desaf\u00edo para Israel\u201d.<\/p>\n<p>El Ej\u00e9rcito israel\u00ed, en su declaraci\u00f3n sobre las operaciones en el Gol\u00e1n, dijo: \u201cEl Estado de Israel no interfiere en el conflicto interno en Siria\u201d.<\/p>\n<p>Los principales l\u00edderes pol\u00edticos y de seguridad de Israel han guardado silencio sobre los acontecimientos en Siria, sin duda mientras eval\u00faan c\u00f3mo reaccionar.<\/p>\n<p>El l\u00edder de la oposici\u00f3n, Yair Lapid, dijo que la destituci\u00f3n de Assad puso de relieve la necesidad de \u201ccrear una fuerte coalici\u00f3n regional con Arabia Saudita y los pa\u00edses signatarios de los Acuerdos de Abraham (Bahr\u00e9in, Emiratos \u00c1rabes Unidos, Marruecos, Sud\u00e1n) para abordar conjuntamente la inestabilidad regional. El eje iran\u00ed se ha debilitado significativamente e Israel necesita esforzarse por conseguir un logro pol\u00edtico integral que tambi\u00e9n le ayude en Gaza y en la Ribera Occidental\u201d.<\/p>\n<p><em>Abeer Salman y Mike Schwartz de CNN contribuyeron a este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El primer ministro israel\u00ed, Benjamin Netanyahu, dijo el domingo que el colapso del r\u00e9gimen de Bashar al-Assad en Siria fue un \u201cresultado directo\u201d de la campa\u00f1a militar de Israel contra Ir\u00e1n y su representante en el L\u00edbano, Hezbollah. \u201cEste es un d\u00eda hist\u00f3rico en la historia del Medio Oriente\u201d, dijo. Pero en una se\u00f1al del [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456372","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Netanyahu ordena a las Fuerzas de Defensa de Israel tomar la zona de contenci\u00f3n de Siria - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Netanyahu ordena a las Fuerzas de Defensa de Israel tomar la zona de contenci\u00f3n de Siria - Noticias\" \/>\n<meta property=\"og:description\" content=\"El primer ministro israel\u00ed, Benjamin Netanyahu, dijo el domingo que el colapso del r\u00e9gimen de Bashar al-Assad en Siria fue un \u201cresultado directo\u201d de la campa\u00f1a militar de Israel contra Ir\u00e1n y su representante en el L\u00edbano, Hezbollah. \u201cEste es un d\u00eda hist\u00f3rico en la historia del Medio Oriente\u201d, dijo. Pero en una se\u00f1al del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-08T17:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Netanyahu ordena a las Fuerzas de Defensa de Israel tomar la zona de contenci\u00f3n de Siria\",\"datePublished\":\"2024-12-08T17:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/\"},\"wordCount\":1368,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/\",\"name\":\"Netanyahu ordena a las Fuerzas de Defensa de Israel tomar la zona de contenci\u00f3n de Siria - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-08T17:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Netanyahu ordena a las Fuerzas de Defensa de Israel tomar la zona de contenci\u00f3n de Siria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Netanyahu ordena a las Fuerzas de Defensa de Israel tomar la zona de contenci\u00f3n de Siria - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Netanyahu ordena a las Fuerzas de Defensa de Israel tomar la zona de contenci\u00f3n de Siria - Noticias","og_description":"El primer ministro israel\u00ed, Benjamin Netanyahu, dijo el domingo que el colapso del r\u00e9gimen de Bashar al-Assad en Siria fue un \u201cresultado directo\u201d de la campa\u00f1a militar de Israel contra Ir\u00e1n y su representante en el L\u00edbano, Hezbollah. \u201cEste es un d\u00eda hist\u00f3rico en la historia del Medio Oriente\u201d, dijo. Pero en una se\u00f1al del [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-08T17:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/"},"author":{"name":"","@id":""},"headline":"Netanyahu ordena a las Fuerzas de Defensa de Israel tomar la zona de contenci\u00f3n de Siria","datePublished":"2024-12-08T17:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/"},"wordCount":1368,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/","name":"Netanyahu ordena a las Fuerzas de Defensa de Israel tomar la zona de contenci\u00f3n de Siria - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-08T17:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Netanyahu ordena a las Fuerzas de Defensa de Israel tomar la zona de contenci\u00f3n de Siria"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Netanyahu ordena a las Fuerzas de Defensa de Israel tomar la zona de contenci\u00f3n de Siria","url":"http:\/\/noticiasya.com\/laredo\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-08T17:03:49Z","datePublished":"2024-12-08T17:03:49Z","dateModified":"2024-12-08T17:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Netanyahu ordena a las Fuerzas de Defensa de Israel tomar la zona de contenci\\u00f3n de Siria\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/08\\\/netanyahu-ordena-ejercito-contencion-siria-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/08\\\/netanyahu-ordena-ejercito-contencion-siria-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-08T17:03:49Z\",\"datePublished\":\"2024-12-08T17:03:49Z\",\"dateModified\":\"2024-12-08T17:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456440,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/","url_meta":{"origin":1456372,"position":0},"title":"Israel bombardea Siria y se apodera de territorio mientras Netanyahu promete cambiar &#171;la cara&#187; de Medio Oriente","author":"","date":"diciembre 10, 2024","format":false,"excerpt":"El colapso del r\u00e9gimen de Assad ha ocasionado una dura respuesta militar por parte de Israel, que ha lanzado ataques a\u00e9reos contra objetivos militares en toda Siria y ha desplegado tropas terrestres dentro y fuera de una zona de amortiguaci\u00f3n desmilitarizada por primera vez en 50 a\u00f1os.El primer ministro de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456632,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/15\/netanyahu-trump-llamada-siria-altos-del-golan-trax\/","url_meta":{"origin":1456372,"position":1},"title":"Netanyahu dice que habl\u00f3 con Trump sobre la necesidad de la &#171;victoria&#187; en una llamada telef\u00f3nica &#171;muy c\u00e1lida&#187;","author":"","date":"diciembre 15, 2024","format":false,"excerpt":"El primer ministro de Israel, Benjamin Netanyahu, dijo este domingo que tuvo una llamada telef\u00f3nica \u201cmuy c\u00e1lida\u201d con el presidente electo de Estados Unidos, Donald Trump, durante la cual hablaron sobre la necesidad de la victoria de Israel en su guerra contra Hamas en Gaza y su postura sobre Siria.En\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456593,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/14\/israel-siria-golan-monte-hermon-trax\/","url_meta":{"origin":1456372,"position":2},"title":"Por qu\u00e9 Israel captur\u00f3 la monta\u00f1a m\u00e1s alta de Siria horas despu\u00e9s de la ca\u00edda de Assad","author":"","date":"diciembre 14, 2024","format":false,"excerpt":"Israel no perdi\u00f3 tiempo tras la ca\u00edda de Bashar al-Assad para bombardear todos los activos militares sirios que quer\u00eda mantener fuera del alcance de los rebeldes: atac\u00f3 casi 500 objetivos, destruy\u00f3 la armada y elimin\u00f3, seg\u00fan afirma, el 90% de los misiles tierra-aire conocidos de Siria.Pero es la captura por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456744,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/18\/medio-oriente-fdi-monte-hermon-2025-trax\/","url_meta":{"origin":1456372,"position":3},"title":"Netanyahu dice a los soldados israel\u00edes que permanezcan en la zona del monte Herm\u00f3n sirio hasta finales de 2025","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"El primer ministro de Israel, Benjam\u00edn Netanyahu, dio instrucciones a las fuerzas armadas del pa\u00eds para que permanezca en la zona del monte Herm\u00f3n de Siria hasta al menos finales de 2025, seg\u00fan inform\u00f3 este mi\u00e9rcoles a CNN una fuente conocedora del asunto.Israel captur\u00f3 la monta\u00f1a de importancia estrat\u00e9gica, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456620,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/15\/israel-netanyahu-asentamientos-altos-golan-trax\/","url_meta":{"origin":1456372,"position":4},"title":"Gobierno de Israel aprueba plan de Netanyahu para expandir asentamientos en los Altos del Gol\u00e1n ocupados","author":"","date":"diciembre 15, 2024","format":false,"excerpt":"El gobierno de Israel aprob\u00f3 este domingo un plan del primer ministro, Benjamin Netanyahu, para expandir los asentamientos en los Altos del Gol\u00e1n ocupados, seg\u00fan un comunicado oficial.\u201cA la luz de la guerra y el nuevo frente abierto contra Siria, y con el deseo de duplicar la poblaci\u00f3n de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462419,"url":"https:\/\/noticiasya.com\/laredo\/2025\/05\/16\/israel-siria-conversaciones-trax\/","url_meta":{"origin":1456372,"position":5},"title":"Funcionarios israel\u00edes y sirios mantienen conversaciones directas inusuales, dice fuente israel\u00ed","author":"","date":"mayo 16, 2025","format":false,"excerpt":"Israel y el nuevo r\u00e9gimen sirio han mantenido recientemente conversaciones directas, seg\u00fan una fuente israel\u00ed familiarizada con el asunto, una indicaci\u00f3n de la din\u00e1mica cambiante entre los antiguos enemigos a medida que Israel expande su presencia militar en el pa\u00eds.Las conversaciones se llevaron a cabo en Azerbaiy\u00e1n y contaron con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1456372"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456372\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1456372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1456372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1456372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}