{"id":1456376,"date":"2024-12-08T14:03:41","date_gmt":"2024-12-08T22:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/"},"modified":"2024-12-08T14:03:41","modified_gmt":"2024-12-08T22:03:41","slug":"pasajero-avion-volaris-desviarlo-estados-unidos-efe","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/","title":{"rendered":"Un pasajero intenta apoderarse de avi\u00f3n y desviarlo de M\u00e9xico a Estados Unidos"},"content":{"rendered":"<p>La ma\u00f1ana de este domingo un pasajero intent\u00f3 apoderarse de un avi\u00f3n que cubr\u00eda la ruta de El Baj\u00edo, en el centro de M\u00e9xico, a la fronteriza Tijuana y desviarlo hacia Estados Unidos, pero fue detenido y puesto a disposici\u00f3n de las autoridades, inform\u00f3 la aerol\u00ednea mexicana Volaris.<\/p>\n<p>\u201cVolaris informa que esta ma\u00f1ana en el vuelo 3041, que cubr\u00eda la ruta de El Baj\u00edo a Tijuana, un pasajero intent\u00f3, mediante el uso de la fuerza, desviar el avi\u00f3n hacia Estados Unidos\u201d, se\u00f1al\u00f3 la compa\u00f1\u00eda en un <a href=\"https:\/\/x.com\/viajaVolaris\/status\/1865821678321725469\">comunicado en redes sociales<\/a>.<\/p>\n<p>Seg\u00fan la informaci\u00f3n, la tripulaci\u00f3n actu\u00f3 de acuerdo a los procedimientos de seguridad establecidos y conforme a protocolo, por lo que el avi\u00f3n tuvo que ser desviado al aeropuerto de Guadalajara, donde la aerol\u00ednea puso al pasajero \u201ca disposici\u00f3n y custodia de las autoridades competentes\u201d.<\/p>\n<p>Asimismo, inform\u00f3 que tanto pasajeros como la tripulaci\u00f3n y la aeronave se encuentran a salvo, especialmente detall\u00f3 que los pasajeros fueron protegidos para continuar su vuelo hacia su destino final.<\/p>\n<p>En el comunicado, Volaris apunt\u00f3 que se ha constituido como parte acusadora en un eventual proceso judicial contra esta persona, \u201cpara asegurar que enfrente todo el peso de la ley, hasta sus \u00faltimas consecuencias\u201d, y lament\u00f3 los inconvenientes que tal situaci\u00f3n caus\u00f3 a los pasajeros.<\/p>\n<p>Hasta el momento no se han dado detalles de la identidad del pasajero ni de los motivos que tuvo para intentar desviar el avi\u00f3n hacia Estados Unidos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ma\u00f1ana de este domingo un pasajero intent\u00f3 apoderarse de un avi\u00f3n que cubr\u00eda la ruta de El Baj\u00edo, en el centro de M\u00e9xico, a la fronteriza Tijuana y desviarlo hacia Estados Unidos, pero fue detenido y puesto a disposici\u00f3n de las autoridades, inform\u00f3 la aerol\u00ednea mexicana Volaris. \u201cVolaris informa que esta ma\u00f1ana en el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456376","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un pasajero intenta apoderarse de avi\u00f3n y desviarlo de M\u00e9xico a Estados Unidos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un pasajero intenta apoderarse de avi\u00f3n y desviarlo de M\u00e9xico a Estados Unidos - Noticias\" \/>\n<meta property=\"og:description\" content=\"La ma\u00f1ana de este domingo un pasajero intent\u00f3 apoderarse de un avi\u00f3n que cubr\u00eda la ruta de El Baj\u00edo, en el centro de M\u00e9xico, a la fronteriza Tijuana y desviarlo hacia Estados Unidos, pero fue detenido y puesto a disposici\u00f3n de las autoridades, inform\u00f3 la aerol\u00ednea mexicana Volaris. \u201cVolaris informa que esta ma\u00f1ana en el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-08T22:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un pasajero intenta apoderarse de avi\u00f3n y desviarlo de M\u00e9xico a Estados Unidos\",\"datePublished\":\"2024-12-08T22:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/\"},\"wordCount\":289,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/\",\"name\":\"Un pasajero intenta apoderarse de avi\u00f3n y desviarlo de M\u00e9xico a Estados Unidos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-08T22:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un pasajero intenta apoderarse de avi\u00f3n y desviarlo de M\u00e9xico a Estados Unidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un pasajero intenta apoderarse de avi\u00f3n y desviarlo de M\u00e9xico a Estados Unidos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/","og_locale":"es_ES","og_type":"article","og_title":"Un pasajero intenta apoderarse de avi\u00f3n y desviarlo de M\u00e9xico a Estados Unidos - Noticias","og_description":"La ma\u00f1ana de este domingo un pasajero intent\u00f3 apoderarse de un avi\u00f3n que cubr\u00eda la ruta de El Baj\u00edo, en el centro de M\u00e9xico, a la fronteriza Tijuana y desviarlo hacia Estados Unidos, pero fue detenido y puesto a disposici\u00f3n de las autoridades, inform\u00f3 la aerol\u00ednea mexicana Volaris. \u201cVolaris informa que esta ma\u00f1ana en el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/","og_site_name":"Noticias","article_published_time":"2024-12-08T22:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/"},"author":{"name":"","@id":""},"headline":"Un pasajero intenta apoderarse de avi\u00f3n y desviarlo de M\u00e9xico a Estados Unidos","datePublished":"2024-12-08T22:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/"},"wordCount":289,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/","url":"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/","name":"Un pasajero intenta apoderarse de avi\u00f3n y desviarlo de M\u00e9xico a Estados Unidos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-08T22:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un pasajero intenta apoderarse de avi\u00f3n y desviarlo de M\u00e9xico a Estados Unidos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un pasajero intenta apoderarse de avi\u00f3n y desviarlo de M\u00e9xico a Estados Unidos","url":"http:\/\/noticiasya.com\/laredo\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/12\/08\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-08T22:03:41Z","datePublished":"2024-12-08T22:03:41Z","dateModified":"2024-12-08T22:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un pasajero intenta apoderarse de avi\\u00f3n y desviarlo de M\\u00e9xico a Estados Unidos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/08\\\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/08\\\/pasajero-avion-volaris-desviarlo-estados-unidos-efe\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-08T22:03:41Z\",\"datePublished\":\"2024-12-08T22:03:41Z\",\"dateModified\":\"2024-12-08T22:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456391,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/09\/detienen-hombre-desviar-vuelo-eeuu\/","url_meta":{"origin":1456376,"position":0},"title":"Detienen a un hombre por supuestamente intentar desviar un vuelo interno de M\u00e9xico a EE.UU.","author":"","date":"diciembre 9, 2024","format":false,"excerpt":"Un pasajero fue detenido el domingo tras intentar presuntamente desviar un vuelo nacional de M\u00e9xico a Estados Unidos, seg\u00fan informaron la aerol\u00ednea Volaris y las autoridades mexicanas. Actualmente se est\u00e1 llevando a cabo una investigaci\u00f3n.Tras despegar de El Baj\u00edo con destino a Tijuana, el pasajero intent\u00f3 desviar la aeronave por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456403,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/09\/pasajeros-tranquilizaron-hombre-desviar-vuelo-mexico-orix\/","url_meta":{"origin":1456376,"position":1},"title":"Pasajeros cuentan c\u00f3mo tranquilizaron al hombre que trat\u00f3 de desviar un vuelo de M\u00e9xico a EE.UU.","author":"","date":"diciembre 9, 2024","format":false,"excerpt":"Varios pasajeros del vuelo 3041 de Volaris de este domingo dicen que se sintieron aterrorizados cuando un hombre intent\u00f3 desviar la aeronave desde M\u00e9xico hacia Estados Unidos. El episodio llev\u00f3 a un aterrizaje de emergencia en el aeropuerto de Guadalajara, informaron la aerol\u00ednea Volaris y las autoridades mexicanas.\u201cMe sent\u00ed muy\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462785,"url":"https:\/\/noticiasya.com\/laredo\/2025\/05\/25\/vuelo-tokio-desvio-seattle-pasajero-intentara-abrir-puerta-salida-trax\/","url_meta":{"origin":1456376,"position":2},"title":"Desv\u00edan a Seattle un avi\u00f3n que ven\u00eda de Tokio luego de que un pasajero intentara abrir una puerta durante el vuelo","author":"","date":"mayo 25, 2025","format":false,"excerpt":"Un vuelo de Tokio a Houston fue desviado a Seattle el s\u00e1bado despu\u00e9s de que un pasajero intent\u00f3 abrir una salida del avi\u00f3n en pleno vuelo, seg\u00fan el FBI y un portavoz del Puerto de Seattle.La tripulaci\u00f3n y los pasajeros sujetaron a la persona, que fue trasladada a un hospital\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460681,"url":"https:\/\/noticiasya.com\/laredo\/2025\/04\/01\/vuelo-pasajero-puerta-avion-oceano-indico-trax\/","url_meta":{"origin":1456376,"position":3},"title":"Vuelo da la vuelta despu\u00e9s de que un pasajero intenta forzar la puerta del avi\u00f3n sobre el oc\u00e9ano \u00cdndico","author":"","date":"abril 1, 2025","format":false,"excerpt":"Un vuelo que transportaba m\u00e1s de 200 personas desde Bali, Indonesia, a Melbourne, Australia, se vio obligado a dar la vuelta despu\u00e9s de que un pasajero intent\u00f3 forzar la puerta del avi\u00f3n mientras el avi\u00f3n volaba sobre el oc\u00e9ano \u00cdndico, dijo la aerol\u00ednea de bajo costo Jetstar en un comunicado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457338,"url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/08\/pasajero-jetblue-abrio-salida-emergencia-avion-trax\/","url_meta":{"origin":1456376,"position":4},"title":"La Polic\u00eda arresta a un pasajero de JetBlue que abri\u00f3 la salida de emergencia, lo que genera preocupaciones de seguridad","author":"","date":"enero 8, 2025","format":false,"excerpt":"La Polic\u00eda Estatal de Massachusetts fue llamada al Aeropuerto Internacional Logan de Boston este martes por la noche despu\u00e9s de que un pasajero de JetBlue abri\u00f3 la puerta de un avi\u00f3n, desplegando el tobog\u00e1n de emergencia, dijeron la Polic\u00eda y la aerol\u00ednea a CNN.Alrededor de las 7:30 p.m. hora local,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452699,"url":"https:\/\/noticiasya.com\/laredo\/2024\/09\/15\/arrestan-pasajero-intento-estrangular-azafata-dijo-avion-se-va-a-estrellar-vuelo-california-trax\/","url_meta":{"origin":1456376,"position":5},"title":"Arrestan a pasajero que intent\u00f3 estrangular a azafata y dijo que el avi\u00f3n &#171;se va a estrellar&#187; en un vuelo de California, dice el Departamento de Justicia","author":"","date":"septiembre 15, 2024","format":false,"excerpt":"(CNN) -- Un hombre de California enfrenta cargos federales despu\u00e9s de que supuestamente intent\u00f3 estrangular a una azafata y \u201cdijo que iba a matar a todos\u201d mientras estaba a bordo de un vuelo de Frontier Airlines a San Francisco que tuvo que ser desviado este\u00a0 lunes, dijeron las autoridades.Charles Angel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1456376"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456376\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1456376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1456376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1456376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}