{"id":1456397,"date":"2024-12-09T07:03:51","date_gmt":"2024-12-09T15:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/"},"modified":"2024-12-09T07:03:51","modified_gmt":"2024-12-09T15:03:51","slug":"corea-del-sur-prohibe-presidente-viajar-extranjero-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/","title":{"rendered":"Corea del Sur proh\u00edbe a su presidente viajar al extranjero mientras se ampl\u00eda la investigaci\u00f3n de insurrecci\u00f3n"},"content":{"rendered":"<p>Las autoridades de Corea del Sur impusieron una prohibici\u00f3n de viajar al extranjero al presidente del pa\u00eds, Yoon Suk Yeol, mientras los fiscales eval\u00faan posibles cargos de insurrecci\u00f3n por su fallido intento de imponer la ley marcial, la semana pasada.<\/p>\n<p>Aunque Yoon super\u00f3 el s\u00e1bado una votaci\u00f3n de destituci\u00f3n en un Parlamento liderado por la oposici\u00f3n, su supervivencia pol\u00edtica pende ahora de un hilo. La Oficina de Investigaci\u00f3n de la Corrupci\u00f3n confirm\u00f3 este lunes la prohibici\u00f3n de viaje impuesta al asediado l\u00edder del pa\u00eds.<\/p>\n<p>Su partido dijo previamente que pedir\u00eda la dimisi\u00f3n de Yoon e inst\u00f3 a suspender de sus funciones al presidente para proteger al pa\u00eds de un \u201cgrave peligro\u201d.<\/p>\n<p>Los surcoreanos contemplaron incr\u00e9dulos c\u00f3mo Yoon declaraba la ley marcial en un impactante anuncio televisado a \u00faltima hora del martes. Desafiando el decreto militar, los manifestantes se congregaron en las calles para exigir la dimisi\u00f3n de Yoon.<\/p>\n<p>En una noche de gran dramatismo, los legisladores se abrieron paso entre los casi 300 soldados desplegados ante el edificio de la Asamblea Nacional y votaron un\u00e1nimemente a favor de bloquear el decreto, que el presidente estaba legalmente obligado a obedecer, con lo que se revoc\u00f3 la orden unilateral del presidente.<\/p>\n<p>La declaraci\u00f3n de emergencia militar, aunque dur\u00f3 seis horas, <a href=\"https:\/\/www.cnn.com\/2024\/12\/04\/asia\/protesters-south-korea-martial-law-intl\/index.html\">caus\u00f3 gran indignaci\u00f3n<\/a> en todo el pa\u00eds, que sigue <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/04\/analisis-corea-del-sur-leyes-marciales-golpes-estado-trax\">profundamente marcado<\/a> por la brutalidad de la ley marcial impuesta durante d\u00e9cadas de dictadura militar antes de ganar una larga y sangrienta lucha por la democracia, en la d\u00e9cada de 1980.<\/p>\n<p>El s\u00e1bado, Yoon pidi\u00f3 disculpas a la naci\u00f3n en sus primeros comentarios p\u00fablicos desde su intento frustrado de imponer la ley marcial, reconociendo que \u201ccaus\u00f3 ansiedad e inconvenientes\u201d a los ciudadanos surcoreanos.<\/p>\n<p>\u201cEsta declaraci\u00f3n de emergencia de la ley marcial surgi\u00f3 de mi desesperaci\u00f3n como m\u00e1ximo responsable de los asuntos del Estado\u201d, dijo Yoon en un discurso de dos minutos.<\/p>\n<p>La decisi\u00f3n de la Polic\u00eda de imponer la prohibici\u00f3n de viaje a Yoon se produce mientras un comandante de las fuerzas especiales surcoreanas se disculp\u00f3 por ordenar a sus tropas irrumpir en el Parlamento, la semana pasada, tras la declaraci\u00f3n de la <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/03\/parlamento-corea-sur-voto-decreto-ley-marcial-trax\">ley marcial<\/a>, afirmando que las puso en \u201cgrave peligro\u201d.<\/p>\n<p>El coronel Kim Hyun-tae, comandante de la Fuerza Especial 707 de Corea del Sur, se describi\u00f3 a s\u00ed mismo ante los periodistas, en una sesi\u00f3n informativa celebrada este lunes, como un \u201ccomandante incompetente e irresponsable\u201d cuando autoriz\u00f3 a las tropas a irrumpir en la Asamblea Nacional durante la ef\u00edmera imposici\u00f3n de la ley marcial por parte del presidente Yoon Suk Yeol.<\/p>\n<p>\u201cOrden\u00e9 el despliegue en la Asamblea Nacional. Como comandante sobre el terreno de los 197 militares implicados, fui el primero en llegar en helic\u00f3ptero. Les di instrucciones de precintar el edificio, entablar enfrentamientos f\u00edsicos en las puertas delantera y trasera, romper ventanas y entrar en el recinto\u201d, declar\u00f3.<\/p>\n<p>\u201cSi esas \u00f3rdenes se hubieran dado en combate, todos habr\u00edan muerto\u201d, a\u00f1adi\u00f3. \u201cEstos efectivos son las v\u00edctimas m\u00e1s tr\u00e1gicas de esta situaci\u00f3n. No son culpables. Su \u00fanica culpa es haber seguido las \u00f3rdenes de un comandante incompetente. Por favor, perd\u00f3nenles\u201d.<\/p>\n<p>Kim tambi\u00e9n culp\u00f3 al exministro de Defensa del pa\u00eds Kim Yong-hyun de \u201cexplotar\u201d a los soldados durante la ca\u00f3tica noche.<\/p>\n<p>Una de las escenas m\u00e1s significativas de la noche fue el video de la periodista convertida en pol\u00edtica An Gwi-ryeong <a href=\"https:\/\/cnnespanol.cnn.com\/video\/soldado-corea-del-sur-mujer-legisladora-trax\">agarrando el arma de un soldado<\/a> mientras los legisladores se enfrentaban a las tropas que les hab\u00edan bloqueado el paso al edificio del Parlamento.<\/p>\n<p>Kim pidi\u00f3 comprensi\u00f3n y perd\u00f3n para sus soldados, que, seg\u00fan dijo, se limitaban a seguir sus \u00f3rdenes.<\/p>\n<p>\u201cEn este momento, mis militares est\u00e1n sufriendo inmensamente, y sus familias \u2013esposas e hijos\u2013 est\u00e1n viendo c\u00f3mo esto se desarrolla en agon\u00eda\u201d, dijo.<\/p>\n<p>Kim a\u00f1adi\u00f3 que asumir\u00eda toda la responsabilidad por sus actos y har\u00eda frente a cualquier consecuencia legal: \u201cCargar\u00e9 con el peso de todo lo que hicieron\u201d.<\/p>\n<p>La Polic\u00eda Nacional de Corea del Sur tambi\u00e9n est\u00e1 investigando al exministro de Defensa Kim Yong-hyun y a otros altos cargos por presunta traici\u00f3n. Kim Yong-hyun <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/08\/mundo\/fiscales-detienen-a-exjefe-defensa-ley-marcial-ap\">fue detenido<\/a> por la Fiscal\u00eda el domingo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las autoridades de Corea del Sur impusieron una prohibici\u00f3n de viajar al extranjero al presidente del pa\u00eds, Yoon Suk Yeol, mientras los fiscales eval\u00faan posibles cargos de insurrecci\u00f3n por su fallido intento de imponer la ley marcial, la semana pasada. Aunque Yoon super\u00f3 el s\u00e1bado una votaci\u00f3n de destituci\u00f3n en un Parlamento liderado por la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456397","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Corea del Sur proh\u00edbe a su presidente viajar al extranjero mientras se ampl\u00eda la investigaci\u00f3n de insurrecci\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corea del Sur proh\u00edbe a su presidente viajar al extranjero mientras se ampl\u00eda la investigaci\u00f3n de insurrecci\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las autoridades de Corea del Sur impusieron una prohibici\u00f3n de viajar al extranjero al presidente del pa\u00eds, Yoon Suk Yeol, mientras los fiscales eval\u00faan posibles cargos de insurrecci\u00f3n por su fallido intento de imponer la ley marcial, la semana pasada. Aunque Yoon super\u00f3 el s\u00e1bado una votaci\u00f3n de destituci\u00f3n en un Parlamento liderado por la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-09T15:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Corea del Sur proh\u00edbe a su presidente viajar al extranjero mientras se ampl\u00eda la investigaci\u00f3n de insurrecci\u00f3n\",\"datePublished\":\"2024-12-09T15:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/\"},\"wordCount\":772,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/\",\"name\":\"Corea del Sur proh\u00edbe a su presidente viajar al extranjero mientras se ampl\u00eda la investigaci\u00f3n de insurrecci\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-09T15:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corea del Sur proh\u00edbe a su presidente viajar al extranjero mientras se ampl\u00eda la investigaci\u00f3n de insurrecci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corea del Sur proh\u00edbe a su presidente viajar al extranjero mientras se ampl\u00eda la investigaci\u00f3n de insurrecci\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Corea del Sur proh\u00edbe a su presidente viajar al extranjero mientras se ampl\u00eda la investigaci\u00f3n de insurrecci\u00f3n - Noticias","og_description":"Las autoridades de Corea del Sur impusieron una prohibici\u00f3n de viajar al extranjero al presidente del pa\u00eds, Yoon Suk Yeol, mientras los fiscales eval\u00faan posibles cargos de insurrecci\u00f3n por su fallido intento de imponer la ley marcial, la semana pasada. Aunque Yoon super\u00f3 el s\u00e1bado una votaci\u00f3n de destituci\u00f3n en un Parlamento liderado por la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-09T15:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/"},"author":{"name":"","@id":""},"headline":"Corea del Sur proh\u00edbe a su presidente viajar al extranjero mientras se ampl\u00eda la investigaci\u00f3n de insurrecci\u00f3n","datePublished":"2024-12-09T15:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/"},"wordCount":772,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/","name":"Corea del Sur proh\u00edbe a su presidente viajar al extranjero mientras se ampl\u00eda la investigaci\u00f3n de insurrecci\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-09T15:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Corea del Sur proh\u00edbe a su presidente viajar al extranjero mientras se ampl\u00eda la investigaci\u00f3n de insurrecci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Corea del Sur proh\u00edbe a su presidente viajar al extranjero mientras se ampl\u00eda la investigaci\u00f3n de insurrecci\u00f3n","url":"http:\/\/noticiasya.com\/laredo\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/12\/09\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-09T15:03:51Z","datePublished":"2024-12-09T15:03:51Z","dateModified":"2024-12-09T15:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Corea del Sur proh\\u00edbe a su presidente viajar al extranjero mientras se ampl\\u00eda la investigaci\\u00f3n de insurrecci\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/09\\\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/09\\\/corea-del-sur-prohibe-presidente-viajar-extranjero-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-09T15:03:51Z\",\"datePublished\":\"2024-12-09T15:03:51Z\",\"dateModified\":\"2024-12-09T15:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457893,"url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/26\/acusan-insurreccion-al-presidente-corea-del-sur-ley-marcial-trax\/","url_meta":{"origin":1456397,"position":0},"title":"Acusan de insurrecci\u00f3n al presidente suspendido de Corea del Sur por declarar la ley marcial","author":"","date":"enero 26, 2025","format":false,"excerpt":"Los fiscales de Corea del Sur acusaron al presidente destituido Yoon Suk Yeol de cargos de insurrecci\u00f3n por su declaraci\u00f3n de la ley marcial, una medida que sumi\u00f3 al pa\u00eds en la agitaci\u00f3n pol\u00edtica.Yoon, quien ha negado haber actuado mal, ha estado detenido desde que fue arrestado a principios de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471418,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/19\/expresidente-corea-sur-condenado-cadena-perpetua-trax\/","url_meta":{"origin":1456397,"position":1},"title":"El expresidente de Corea del Sur Yoon Suk Yeol fue condenado a cadena perpetua por liderar una insurrecci\u00f3n","author":"","date":"febrero 19, 2026","format":false,"excerpt":"El expresidente de Corea del Sur Yoon Suk Yeol fue sentenciado este jueves a cadena por un tribunal que lo declar\u00f3 culpable de liderar una insurrecci\u00f3n durante su ef\u00edmera imposici\u00f3n de la ley marcial, que sumi\u00f3 al pa\u00eds en el caos pol\u00edtico y amenaz\u00f3 con desmantelar d\u00e9cadas de democracia.El veredicto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456453,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/10\/exministro-defensa-corea-sur-intento-suicidio-allanan-oficina-presidencial-trax\/","url_meta":{"origin":1456397,"position":2},"title":"Exministro de Defensa de Corea del Sur intenta suicidarse mientras allanan la oficina presidencial tras la ley marcial","author":"","date":"diciembre 10, 2024","format":false,"excerpt":"El exministro de Defensa de Corea del Sur, Kim Yong-hyun, intent\u00f3 suicidarse mientras estaba detenido, dijo este mi\u00e9rcoles el jefe del servicio penitenciario del pa\u00eds, mientras contin\u00faa creciendo la crisis pol\u00edtica provocada por la breve declaraci\u00f3n de la ley marcial por parte del presidente.Por otra parte, la Polic\u00eda de Corea\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457519,"url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/14\/autoridades-corea-del-sur-segundo-intento-arresto-interrogar-presidente-yoon-trax\/","url_meta":{"origin":1456397,"position":3},"title":"Las autoridades de Corea del Sur intentan por segunda vez detener al presidente para interrogarlo, informa Yonhap","author":"","date":"enero 14, 2025","format":false,"excerpt":"Las autoridades surcoreanas que investigan al presidente Yoon Suk Yeol llegaron a su residencia oficial en un segundo intento de detener al asediado l\u00edder para interrogarlo sobre su breve declaraci\u00f3n de ley marcial el mes pasado, seg\u00fan la agencia de noticias Yonhap de Corea del Sur.Seg\u00fan Yonhap, veh\u00edculos de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457469,"url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/13\/enfrentamiento-corea-del-sur-yoon-juicio-politico-posible-arresto-trax\/","url_meta":{"origin":1456397,"position":4},"title":"Se avecina una dram\u00e1tica disputa institucional en Corea del Sur mientras Yoon enfrenta un juicio pol\u00edtico y posible arresto","author":"","date":"enero 13, 2025","format":false,"excerpt":"Corea del Sur parece encaminarse a un dram\u00e1tico enfrentamiento pol\u00edtico esta semana, cuando comience el proceso de juicio de destituci\u00f3n del presidente suspendido, Yoon Suk Yeol, quien permanece escondido en su residencia fortificada evadiendo el arresto por una investigaci\u00f3n criminal separada.La breve declaraci\u00f3n de ley marcial por parte del atribulado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460811,"url":"https:\/\/noticiasya.com\/laredo\/2025\/04\/03\/destituyen-presidente-corea-del-sur-yoon-suk-yeol-trax\/","url_meta":{"origin":1456397,"position":5},"title":"Destituyen al presidente de Corea del Sur cuatro meses despu\u00e9s de haber declarado la ley marcial","author":"","date":"abril 3, 2025","format":false,"excerpt":"El tribunal m\u00e1s alto de Corea del Sur destituy\u00f3 al presidente Yoon Suk Yeol, poniendo fin a meses de incertidumbre y disputas legales despu\u00e9s de que declarara brevemente la ley marcial en diciembre y sumiera a la naci\u00f3n en una agitaci\u00f3n pol\u00edtica.La decisi\u00f3n del tribunal el viernes marca la destituci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1456397"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456397\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1456397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1456397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1456397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}