{"id":1456414,"date":"2024-12-10T01:03:42","date_gmt":"2024-12-10T09:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/"},"modified":"2024-12-10T01:03:42","modified_gmt":"2024-12-10T09:03:42","slug":"arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/","title":{"rendered":"Arrestan a una mujer con 10 kilos de metanfetamina envueltos como regalo de Navidad en un aeropuerto de Nueva Zelandia"},"content":{"rendered":"<p>Una mujer canadiense fue arrestada por presuntamente intentar contrabandear drogas a Nueva Zelandia, disfraz\u00e1ndolas como regalos de Navidad.<\/p>\n<p>Los funcionarios de aduanas de Nueva Zelanda dijeron que se descubrieron 10,2 kilogramos (22 libras) de metanfetamina por un valor de hasta 2,2 millones de d\u00f3lares en el equipaje de mano de la mujer cuando lleg\u00f3 al aeropuerto de Auckland en un vuelo desde Vancouver el domingo.<\/p>\n<p>La pasajera \u201cacaba de entrar en la lista de los malos de Santa Claus\u201d, dijo la aduana de Nueva Zelanda en una publicaci\u00f3n de Facebook. La mujer, cuyo nombre y edad no fueron revelados, fue detenida por cargos de importaci\u00f3n y posesi\u00f3n para el suministro de una droga controlada de clase A.<\/p>\n<p>\u201cSe trata de un intento cl\u00e1sico de los grupos delictivos organizados transnacionales de aprovechar la temporada alta de viajes\u201d, dijo Paul Williams, director de Aduanas del aeropuerto de Auckland, en un comunicado. \u201cPero un aeropuerto con mucha actividad no significa que la aduana no est\u00e9 pendiente de cualquiera que pueda suponer un riesgo de tr\u00e1fico de drogas\u201d.<\/p>\n<p>La aduana de Nueva Zelanda comparti\u00f3 fotograf\u00edas de los \u201cregalos de Navidad\u201d, que estaban envueltos en papel rojo brillante impreso con copos de nieve y guardados dentro de una bolsa de lona roja que la mujer supuestamente trajo a bordo de su vuelo.<\/p>\n<p>\u201cEstos grupos criminales cometen el error de pensar que la aduana no perseguir\u00e1 objetivos m\u00e1s peque\u00f1os, pero sabemos que las drogas enviadas desde Am\u00e9rica del Norte son un riesgo creciente y estamos preparados\u201d, agreg\u00f3 Williams.<\/p>\n<p>El a\u00f1o pasado, Nueva Zelandia descubri\u00f3 713 kilos de metanfetamina por un valor estimado de US$ 150 millones <a href=\"https:\/\/www.cnn.com\/2023\/06\/15\/world\/new-zealand-meth-bust-maple-syrup-intl-hnk\/index.html\">escondidos en contenedores de jarabe de arce canadiense<\/a>, la mayor incautaci\u00f3n de esta droga jam\u00e1s realizada en el pa\u00eds. Seis sospechosos fueron arrestados en una operaci\u00f3n encubierta en la que participaron agentes de Nueva Zelandia, Australia y Canad\u00e1.<\/p>\n<p>\u201cEl tr\u00e1fico internacional de drogas y los grupos del crimen organizado est\u00e1n causando estragos y da\u00f1os en comunidades de todo el mundo, y nuestra mejor oportunidad para interrumpir, interceptar y mantener nuestras comunidades seguras es trabajar en colaboraci\u00f3n con otras agencias y otras naciones\u201d, dijo el Comisionado de Polic\u00eda de Nueva Zelandia, Andrew Coster, en una declaraci\u00f3n en ese momento.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una mujer canadiense fue arrestada por presuntamente intentar contrabandear drogas a Nueva Zelandia, disfraz\u00e1ndolas como regalos de Navidad. Los funcionarios de aduanas de Nueva Zelanda dijeron que se descubrieron 10,2 kilogramos (22 libras) de metanfetamina por un valor de hasta 2,2 millones de d\u00f3lares en el equipaje de mano de la mujer cuando lleg\u00f3 al [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456414","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arrestan a una mujer con 10 kilos de metanfetamina envueltos como regalo de Navidad en un aeropuerto de Nueva Zelandia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arrestan a una mujer con 10 kilos de metanfetamina envueltos como regalo de Navidad en un aeropuerto de Nueva Zelandia - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una mujer canadiense fue arrestada por presuntamente intentar contrabandear drogas a Nueva Zelandia, disfraz\u00e1ndolas como regalos de Navidad. Los funcionarios de aduanas de Nueva Zelanda dijeron que se descubrieron 10,2 kilogramos (22 libras) de metanfetamina por un valor de hasta 2,2 millones de d\u00f3lares en el equipaje de mano de la mujer cuando lleg\u00f3 al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-10T09:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Arrestan a una mujer con 10 kilos de metanfetamina envueltos como regalo de Navidad en un aeropuerto de Nueva Zelandia\",\"datePublished\":\"2024-12-10T09:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/\"},\"wordCount\":420,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/\",\"name\":\"Arrestan a una mujer con 10 kilos de metanfetamina envueltos como regalo de Navidad en un aeropuerto de Nueva Zelandia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-10T09:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arrestan a una mujer con 10 kilos de metanfetamina envueltos como regalo de Navidad en un aeropuerto de Nueva Zelandia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arrestan a una mujer con 10 kilos de metanfetamina envueltos como regalo de Navidad en un aeropuerto de Nueva Zelandia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Arrestan a una mujer con 10 kilos de metanfetamina envueltos como regalo de Navidad en un aeropuerto de Nueva Zelandia - Noticias","og_description":"Una mujer canadiense fue arrestada por presuntamente intentar contrabandear drogas a Nueva Zelandia, disfraz\u00e1ndolas como regalos de Navidad. Los funcionarios de aduanas de Nueva Zelanda dijeron que se descubrieron 10,2 kilogramos (22 libras) de metanfetamina por un valor de hasta 2,2 millones de d\u00f3lares en el equipaje de mano de la mujer cuando lleg\u00f3 al [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-10T09:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/"},"author":{"name":"","@id":""},"headline":"Arrestan a una mujer con 10 kilos de metanfetamina envueltos como regalo de Navidad en un aeropuerto de Nueva Zelandia","datePublished":"2024-12-10T09:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/"},"wordCount":420,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/","name":"Arrestan a una mujer con 10 kilos de metanfetamina envueltos como regalo de Navidad en un aeropuerto de Nueva Zelandia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-10T09:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Arrestan a una mujer con 10 kilos de metanfetamina envueltos como regalo de Navidad en un aeropuerto de Nueva Zelandia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Arrestan a una mujer con 10 kilos de metanfetamina envueltos como regalo de Navidad en un aeropuerto de Nueva Zelandia","url":"http:\/\/noticiasya.com\/laredo\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/12\/10\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-10T09:03:42Z","datePublished":"2024-12-10T09:03:42Z","dateModified":"2024-12-10T09:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Arrestan a una mujer con 10 kilos de metanfetamina envueltos como regalo de Navidad en un aeropuerto de Nueva Zelandia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/10\\\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/10\\\/arrestan-mujer-10-kilos-metanfetamina-regalo-navidad-aeropuerto-nueva-zelanda-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-10T09:03:42Z\",\"datePublished\":\"2024-12-10T09:03:42Z\",\"dateModified\":\"2024-12-10T09:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1455266,"url":"https:\/\/noticiasya.com\/laredo\/2024\/10\/20\/aeropuerto-nueva-zelandia-limite-tiempo-para-abrazos-trax\/","url_meta":{"origin":1456414,"position":0},"title":"Aeropuerto de Nueva Zelandia introduce un l\u00edmite de tiempo para los abrazos","author":"","date":"octubre 20, 2024","format":false,"excerpt":"(CNN) -- Un aeropuerto de Nueva Zelandia restringir\u00e1 la duraci\u00f3n de ciertas muestras de afecto. El director general del aeropuerto explic\u00f3 la nueva norma citando un estudio que indica que abrazarse durante 20 segundos es suficiente.El aeropuerto de Dunedin en Nueva Zelandia desat\u00f3 un debate en todo el mundo con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447977,"url":"https:\/\/noticiasya.com\/laredo\/2024\/04\/11\/narcotraficantes-mexicanos-australia-metanfetamina-trax\/","url_meta":{"origin":1456414,"position":1},"title":"Los carteles de droga mexicanos \u201capuntan cada vez m\u00e1s\u201d a Australia, donde su oferta de metanfetamina supera a la de sus rivales, seg\u00fan la Polic\u00eda","author":"","date":"abril 11, 2024","format":false,"excerpt":"(CNN) -- Los c\u00e1rteles de la droga de Norteam\u00e9rica han superado a sus rivales en el sudeste asi\u00e1tico para convertirse en los principales proveedores de metanfetamina de Australia, dijo la polic\u00eda, advirtiendo que las bandas mexicanas est\u00e1n \"apuntando cada vez m\u00e1s\" al pa\u00eds.La Polic\u00eda Federal Australiana (AFP, por sus siglas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446895,"url":"https:\/\/noticiasya.com\/laredo\/2024\/03\/12\/chile-pasajeros-vuelo-latam-airlines-nueva-zelandia-evento-tecnico-lesionados-orix\/","url_meta":{"origin":1456414,"position":2},"title":"Regresan a Chile algunos pasajeros del vuelo de Latam Airlines a Nueva Zelandia que sufri\u00f3 un &#171;evento t\u00e9cnico&#187; y termin\u00f3 con decenas de lesionados","author":"","date":"marzo 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Un grupo de pasajeros a bordo de un vuelo de Latam Airlines que este lunes sufri\u00f3 un \"evento t\u00e9cnico\" y termin\u00f3 con decenas de heridos mientras viajaba de Australia a Nueva Zelandia lleg\u00f3 a Chile este martes, corrobor\u00f3 un equipo de CNN que estaba en el Aeropuerto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456125,"url":"https:\/\/noticiasya.com\/laredo\/2024\/11\/27\/arrestan-hombre-maletas-ropa-contaminada-metanfetamina-trax\/","url_meta":{"origin":1456414,"position":3},"title":"Arrestan a hombre en aeropuerto de Los \u00c1ngeles tras presuntamente registrar maletas de m\u00e1s de 30 kilos con ropa contaminada con metanfetamina","author":"","date":"noviembre 27, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Un hombre de California fue arrestado en el Aeropuerto Internacional de Los \u00c1ngeles despu\u00e9s de que supuestamente intentara registrar dos maletas que conten\u00edan m\u00e1s de 30 kilos de ropa llena de metanfetamina \u2014incluyendo una pijama de vaca\u2014 en un vuelo a Australia, dijeron el martes los fiscales federales.Raj\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448272,"url":"https:\/\/noticiasya.com\/laredo\/2024\/04\/19\/encontrar-marido-chico-londres-aplicacion-citas-trax\/","url_meta":{"origin":1456414,"position":4},"title":"Se propuso encontrar marido en un a\u00f1o. Luego conect\u00f3 con un chico del otro lado del mundo a trav\u00e9s de una aplicaci\u00f3n de citas","author":"","date":"abril 19, 2024","format":false,"excerpt":"(CNN) -- Samantha Hannah viajaba por Australia y Nueva Zelandia, empap\u00e1ndose de nuevos lugares y experiencias, al tiempo que reflexionaba sobre su pasado y se planteaba c\u00f3mo hab\u00eda sido su vida hasta el momento.Era finales de 2017. Samantha, de Perth, Escocia, ten\u00eda 31 a\u00f1os. Su hermano hab\u00eda fallecido inesperadamente un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459161,"url":"https:\/\/noticiasya.com\/laredo\/2025\/02\/25\/china-ejercicios-fuego-real-australia-nueva-zelanda-trax\/","url_meta":{"origin":1456414,"position":5},"title":"Australia se enter\u00f3 de los ejercicios con fuego real de la Marina china a trav\u00e9s de un piloto comercial, seg\u00fan un funcionario","author":"","date":"febrero 25, 2025","format":false,"excerpt":"Australia se enter\u00f3 de las maniobras navales chinas con fuego real frente a sus costas, que obligaron a desviar decenas de vuelos, gracias a la alerta de un piloto comercial, seg\u00fan informaron el lunes las autoridades.La demostraci\u00f3n de fuego sin precedentes de la Armada del Ej\u00e9rcito Popular de Liberaci\u00f3n (EPL)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1456414"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456414\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1456414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1456414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1456414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}