{"id":1456440,"date":"2024-12-10T15:03:46","date_gmt":"2024-12-10T23:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/"},"modified":"2024-12-10T15:03:46","modified_gmt":"2024-12-10T23:03:46","slug":"israel-bombardea-siria-netanyahu-medio-oriente-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/","title":{"rendered":"Israel bombardea Siria y se apodera de territorio mientras Netanyahu promete cambiar &#171;la cara&#187; de Medio Oriente"},"content":{"rendered":"<p>El colapso del r\u00e9gimen de Assad ha ocasionado una dura respuesta militar por parte de Israel, que ha lanzado ataques a\u00e9reos contra objetivos militares en toda Siria y ha desplegado tropas terrestres dentro y fuera de una zona de amortiguaci\u00f3n desmilitarizada por primera vez en 50 a\u00f1os.<\/p>\n<p>El primer ministro de Israel, Benjamin Netanyahu, dijo durante una inusual conferencia de prensa el lunes por la noche que el colapso del<a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/08\/mundo\/bashar-al-assad-quien-es-presidente-siria-trax\"> r\u00e9gimen de Bashar al-Assad<\/a> era \u201cun cap\u00edtulo nuevo y dram\u00e1tico\u201d.<\/p>\n<p>\u201cEl colapso del r\u00e9gimen sirio es el resultado directo de los duros golpes que hemos asestado a Hamas, Hezbollah e Ir\u00e1n\u201d, afirm\u00f3. \u201cEl eje a\u00fan no ha desaparecido, pero, como promet\u00ed, estamos cambiando la faz de Medio Oriente\u201d.<\/p>\n<p>Las autoridades israel\u00edes se han alegrado de la ca\u00edda de Assad, un fiel aliado de Ir\u00e1n que permiti\u00f3 que su pa\u00eds fuera utilizado como ruta de reabastecimiento para Hezbollah en el L\u00edbano, pero tambi\u00e9n temen lo que podr\u00eda suceder con los islamistas radicales que gobiernan Siria, que limita con Israel en los Altos del Gol\u00e1n ocupados.<\/p>\n<p>El ministro de Asuntos Exteriores, Gideon Sa\u2019ar, dijo a los periodistas el lunes que Israel estaba bombardeando instalaciones militares sirias que albergan arsenales de armas qu\u00edmicas y misiles de largo alcance para evitar que cayeran \u201cen manos de extremistas\u201d.<\/p>\n<p>\u201cEn lo que respecta a lo que suceder\u00e1 en el futuro, no soy un profeta\u201d, afirm\u00f3. \u201cEs importante ahora mismo tomar todas las medidas necesarias en el contexto de la seguridad de Israel\u201d.<\/p>\n<p>Un equipo de la CNN en Damasco escuch\u00f3 fuertes explosiones durante la madrugada de este martes, una continuaci\u00f3n de los ataques que comenzaron durante el fin de semana. Voice of the Capital, un grupo activista sirio, dijo que la campa\u00f1a de bombardeos durante la noche fue \u201cla m\u00e1s violenta en Damasco en 15 a\u00f1os\u201d.<\/p>\n<p>El ministro de Defensa israel\u00ed, Israel Katz, declar\u00f3 este martes que la Armada hab\u00eda destruido la flota naval siria durante la noche, y lo calific\u00f3 de \u201cgran \u00e9xito\u201d. Un fot\u00f3grafo de AFP mostr\u00f3 la destrucci\u00f3n a gran escala de buques militares en el puerto naval sirio de Latakia.<\/p>\n<p>Las im\u00e1genes tomadas por un periodista de AFP en la base a\u00e9rea de Mezzeh, al suroeste de Damasco, tambi\u00e9n mostraron helic\u00f3pteros militares sirios destruidos.<\/p>\n<p>Mientras tanto, varios estados \u00e1rabes han acusado a Israel de explotar la inestabilidad en Siria para llevar a cabo una apropiaci\u00f3n de tierras.<\/p>\n<p><a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/07\/mundo\/rebelion-siria-medio-oriente-explicacion-trax\">La Liga \u00c1rabe<\/a>, una agrupaci\u00f3n de naciones \u00e1rabes, dijo que Israel estaba \u201caprovech\u00e1ndose de los acontecimientos en la situaci\u00f3n interna en Siria\u201d, y Egipto dijo que sus movimientos \u201cconstituyen una explotaci\u00f3n del estado de fluidez y vac\u00edo\u2026 para ocupar m\u00e1s territorios sirios\u201d.<\/p>\n<p>Nadav Shoshani, portavoz de las fuerzas israel\u00edes, neg\u00f3 que las fuerzas estuvieran \u201cavanzando hacia\u201d Damasco, pero reconoci\u00f3 que estaban operando en Siria m\u00e1s all\u00e1 de la zona de contenci\u00f3n. Las fuerzas israel\u00edes han insistido en que \u201cno est\u00e1n interfiriendo en los acontecimientos internos de Siria\u201d.<\/p>\n<p>Katz dijo en una declaraci\u00f3n el lunes que Israel estaba creando una \u201czona de seguridad libre de armas estrat\u00e9gicas pesadas e infraestructuras terroristas\u201d en el sur de Siria, \u201cm\u00e1s all\u00e1 de la zona de amortiguaci\u00f3n\u201d.<\/p>\n<p>Este martes, Voice of the Capital dijo que las fuerzas israel\u00edes hab\u00edan avanzado hasta Beqaasem, a unos 25 kil\u00f3metros de la capital de Siria y varios kil\u00f3metros m\u00e1s all\u00e1 del lado sirio de la zona de contenci\u00f3n. CNN no pudo confirmar de forma independiente esa afirmaci\u00f3n, pero la aldea se encuentra en las estribaciones sirias del Monte Herm\u00f3n, que las fuerzas israel\u00edes capturaron el domingo. El Monte Herm\u00f3n es un punto alto estrat\u00e9gico que se encuentra en la frontera entre Siria, el L\u00edbano y los altos del Gol\u00e1n.<\/p>\n<p>Las fuerzas terrestres israel\u00edes entraron en territorio sirio despu\u00e9s de que Netanyahu ordenara el domingo al ej\u00e9rcito que tomara esa \u201czona de separaci\u00f3n\u201d desmilitarizada entre los altos del Gol\u00e1n ocupados por Israel y el resto de Siria. Esa zona se estableci\u00f3 en 1974, despu\u00e9s de que las fuerzas israel\u00edes \u2014en respuesta a un ataque sirio\u2014 capturaron los altos del Gol\u00e1n en 1967. Israel se anexion\u00f3 el territorio en 1981, pero a\u00fan se considera Siria ocupada seg\u00fan el derecho internacional.<\/p>\n<p>Los funcionarios israel\u00edes se han negado a dar detalles sobre hasta d\u00f3nde avanzar\u00e1n las fuerzas israel\u00edes o cu\u00e1nto tiempo permanecer\u00e1n all\u00ed. Danny Dannon, embajador de Israel ante las Naciones Unidas, dijo al Consejo de Seguridad en una carta el lunes que su pa\u00eds hab\u00eda \u201cdesplegado tropas temporalmente en algunos puntos\u201d. Dijo que eran \u201cmedidas limitadas y temporales para contrarrestar cualquier amenaza adicional a sus ciudadanos\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El colapso del r\u00e9gimen de Assad ha ocasionado una dura respuesta militar por parte de Israel, que ha lanzado ataques a\u00e9reos contra objetivos militares en toda Siria y ha desplegado tropas terrestres dentro y fuera de una zona de amortiguaci\u00f3n desmilitarizada por primera vez en 50 a\u00f1os. El primer ministro de Israel, Benjamin Netanyahu, dijo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456440","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Israel bombardea Siria y se apodera de territorio mientras Netanyahu promete cambiar &quot;la cara&quot; de Medio Oriente - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Israel bombardea Siria y se apodera de territorio mientras Netanyahu promete cambiar &quot;la cara&quot; de Medio Oriente - Noticias\" \/>\n<meta property=\"og:description\" content=\"El colapso del r\u00e9gimen de Assad ha ocasionado una dura respuesta militar por parte de Israel, que ha lanzado ataques a\u00e9reos contra objetivos militares en toda Siria y ha desplegado tropas terrestres dentro y fuera de una zona de amortiguaci\u00f3n desmilitarizada por primera vez en 50 a\u00f1os. El primer ministro de Israel, Benjamin Netanyahu, dijo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-10T23:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Israel bombardea Siria y se apodera de territorio mientras Netanyahu promete cambiar &#171;la cara&#187; de Medio Oriente\",\"datePublished\":\"2024-12-10T23:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/\"},\"wordCount\":854,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/\",\"name\":\"Israel bombardea Siria y se apodera de territorio mientras Netanyahu promete cambiar \\\"la cara\\\" de Medio Oriente - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-10T23:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Israel bombardea Siria y se apodera de territorio mientras Netanyahu promete cambiar &#171;la cara&#187; de Medio Oriente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Israel bombardea Siria y se apodera de territorio mientras Netanyahu promete cambiar \"la cara\" de Medio Oriente - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Israel bombardea Siria y se apodera de territorio mientras Netanyahu promete cambiar \"la cara\" de Medio Oriente - Noticias","og_description":"El colapso del r\u00e9gimen de Assad ha ocasionado una dura respuesta militar por parte de Israel, que ha lanzado ataques a\u00e9reos contra objetivos militares en toda Siria y ha desplegado tropas terrestres dentro y fuera de una zona de amortiguaci\u00f3n desmilitarizada por primera vez en 50 a\u00f1os. El primer ministro de Israel, Benjamin Netanyahu, dijo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-10T23:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/"},"author":{"name":"","@id":""},"headline":"Israel bombardea Siria y se apodera de territorio mientras Netanyahu promete cambiar &#171;la cara&#187; de Medio Oriente","datePublished":"2024-12-10T23:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/"},"wordCount":854,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/","name":"Israel bombardea Siria y se apodera de territorio mientras Netanyahu promete cambiar \"la cara\" de Medio Oriente - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-10T23:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Israel bombardea Siria y se apodera de territorio mientras Netanyahu promete cambiar &#171;la cara&#187; de Medio Oriente"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Israel bombardea Siria y se apodera de territorio mientras Netanyahu promete cambiar &#171;la cara&#187; de Medio Oriente","url":"http:\/\/noticiasya.com\/laredo\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/12\/10\/israel-bombardea-siria-netanyahu-medio-oriente-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-10T23:03:46Z","datePublished":"2024-12-10T23:03:46Z","dateModified":"2024-12-10T23:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Israel bombardea Siria y se apodera de territorio mientras Netanyahu promete cambiar &#171;la cara&#187; de Medio Oriente\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/10\\\/israel-bombardea-siria-netanyahu-medio-oriente-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/10\\\/israel-bombardea-siria-netanyahu-medio-oriente-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-10T23:03:46Z\",\"datePublished\":\"2024-12-10T23:03:46Z\",\"dateModified\":\"2024-12-10T23:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456372,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/08\/netanyahu-ordena-ejercito-contencion-siria-trax\/","url_meta":{"origin":1456440,"position":0},"title":"Netanyahu ordena a las Fuerzas de Defensa de Israel tomar la zona de contenci\u00f3n de Siria","author":"","date":"diciembre 8, 2024","format":false,"excerpt":"El primer ministro israel\u00ed, Benjamin Netanyahu, dijo el domingo que el colapso del r\u00e9gimen de Bashar al-Assad en Siria fue un \u201cresultado directo\u201d de la campa\u00f1a militar de Israel contra Ir\u00e1n y su representante en el L\u00edbano, Hezbollah.\u201cEste es un d\u00eda hist\u00f3rico en la historia del Medio Oriente\u201d, dijo.Pero en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456531,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/12\/rebeldes-siria-mapas-regimen-assad-trax\/","url_meta":{"origin":1456440,"position":1},"title":"C\u00f3mo los rebeldes de Siria derrocaron el r\u00e9gimen de Assad, en 7 mapas","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"Durante m\u00e1s de una d\u00e9cada, la guerra civil siria ha hecho estragos en m\u00faltiples frentes, dejando al pa\u00eds dividido y lleno de cicatrices. Y durante la mayor parte de ese largo tiempo, los combates dieron pocas se\u00f1ales de menguar. Pero entonces, en cuesti\u00f3n de un par de semanas, el r\u00e9gimen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456351,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/07\/rebelion-siria-medio-oriente-explicacion-trax\/","url_meta":{"origin":1456440,"position":2},"title":"Qu\u00e9 puede significar la rebeli\u00f3n siria para el equilibrio de poder en Medio Oriente","author":"","date":"diciembre 7, 2024","format":false,"excerpt":"Las partes interesadas de todo el mundo tienen que contar ahora con el impacto geopol\u00edtico de una ofensiva rebelde liderada por un grupo islamista en Siria que podr\u00eda amenazar el control del presidente Bashar al-Assad sobre el pa\u00eds.Los rebeldes sirios han realizado un avance rel\u00e1mpago en el norte del pa\u00eds,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462357,"url":"https:\/\/noticiasya.com\/laredo\/2025\/05\/14\/impacto-trump-presidente-interino-siria-trax\/","url_meta":{"origin":1456440,"position":3},"title":"Qu\u00e9 impacto podr\u00eda tener en Medio Oriente que Trump haya aceptado al presidente interino de Siria","author":"","date":"mayo 14, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, se reuni\u00f3 el mi\u00e9rcoles con un exyihadista cuya cabeza ten\u00eda una recompensa de US$ 10 millones en Estados Unidos hasta hace poco.El presidente interino sirio, Ahmed al-Sharaa, conocido anteriormente por su nombre de guerra militante, Abu Mohammed al-Jolani, se reuni\u00f3 con Trump en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456396,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/09\/caida-siria-golpe-putin-trax\/","url_meta":{"origin":1456440,"position":4},"title":"AN\u00c1LISIS | La ca\u00edda de Assad es un duro golpe para Putin y pone de relieve la fragilidad de su propio gobierno","author":"","date":"diciembre 9, 2024","format":false,"excerpt":"El mundo ya conoce los colores del paraca\u00eddas del dictador sirio Bashar al-Assad: el tricolor ruso.La huida de Assad a Mosc\u00fa tras el r\u00e1pido colapso de su r\u00e9gimen significa algo m\u00e1s que la p\u00e9rdida de un Estado cliente para el Kremlin.La ca\u00edda de la casa de Assad asesta un duro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456744,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/18\/medio-oriente-fdi-monte-hermon-2025-trax\/","url_meta":{"origin":1456440,"position":5},"title":"Netanyahu dice a los soldados israel\u00edes que permanezcan en la zona del monte Herm\u00f3n sirio hasta finales de 2025","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"El primer ministro de Israel, Benjam\u00edn Netanyahu, dio instrucciones a las fuerzas armadas del pa\u00eds para que permanezca en la zona del monte Herm\u00f3n de Siria hasta al menos finales de 2025, seg\u00fan inform\u00f3 este mi\u00e9rcoles a CNN una fuente conocedora del asunto.Israel captur\u00f3 la monta\u00f1a de importancia estrat\u00e9gica, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1456440"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456440\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1456440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1456440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1456440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}