{"id":1456472,"date":"2024-12-11T08:03:39","date_gmt":"2024-12-11T16:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/"},"modified":"2024-12-11T08:03:39","modified_gmt":"2024-12-11T16:03:39","slug":"muere-ministro-taliban-refugiados-ataque-suicida-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/","title":{"rendered":"Muere el ministro talib\u00e1n de los refugiados en un ataque suicida en Kabul"},"content":{"rendered":"<p>El ministro talib\u00e1n de refugiados muri\u00f3 este mi\u00e9rcoles en un atentado suicida en la capital de Afganist\u00e1n, Kabul, inform\u00f3 el ministerio del interior.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2021\/09\/14\/asia\/taliban-missing-leader-rumors-2021-intl\/index.html\">Khalil Haqqani <\/a>era el t\u00edo del actual ministro del Interior talib\u00e1n, Sirajuddin Haqqani, quien lidera la poderosa red Haqqani, una divisi\u00f3n de la organizaci\u00f3n talib\u00e1n m\u00e1s amplia.<\/p>\n<p>Este mi\u00e9rcoles, un atacante suicida se disfraz\u00f3 de visitante en el recinto del Ministerio de Refugiados y deton\u00f3 su bomba mientras Haqqani firmaba documentos, dijo un portavoz del ministerio a CNN. Seis personas m\u00e1s murieron, inform\u00f3 Reuters, citando a su sobrino.<\/p>\n<p>\u201cPerdimos a un muy valiente muyahid\u00edn,\u201d declar\u00f3 su sobrino Anas Haqqani a Reuters, utilizando el t\u00e9rmino de los talibanes para sus combatientes. \u201cNunca lo olvidaremos a \u00e9l ni a su sacrificio\u201d.<\/p>\n<p>Es la v\u00edctima m\u00e1s de alto perfil de un atentado en Afganist\u00e1n desde que los talibanes <a href=\"https:\/\/www.cnn.com\/2021\/08\/16\/middleeast\/taliban-control-afghanistan-explained-intl-hnk\/index.html\">regresaron al poder<\/a> hace tres a\u00f1os.<\/p>\n<p>En 2011, Estados Unidos clasific\u00f3 a Khalil Haqqani como<a href=\"https:\/\/rewardsforjustice.net\/rewards\/khalil-haqqani\/\"> terrorista global especialmente designado,<\/a> ofreciendo una recompensa de hasta US$ 5 millones por informaci\u00f3n relacionada con \u00e9l. Tambi\u00e9n est\u00e1 en la<a href=\"https:\/\/main.un.org\/securitycouncil\/en\/sanctions\/1988\/materials\/summaries\/individual\/khalil-ahmed-haqqani\"> Lista de Sanciones de 1988 <\/a>del Consejo de Seguridad de las Naciones Unidas.<\/p>\n<p>La red Haqqani ha perpetrado una serie de grandes atentados durante la guerra del pa\u00eds, por lo que han surgido tensiones entre ella y los talibanes.<\/p>\n<p>Designada como una<a href=\"https:\/\/rewardsforjustice.net\/rewards\/haqqani-network-hqn\/\"> Organizaci\u00f3n Terrorista Extranjera por parte de EE. UU<\/a>. y englobada bajo el paraguas talib\u00e1n, la red mantiene sus propias l\u00edneas de operaci\u00f3n distintas, <a href=\"https:\/\/www.understandingwar.org\/report\/haqqani-network\">seg\u00fan el Instituto para el Estudio de la Guerra.<\/a><\/p>\n<p>Las tensiones entre la red Haqqani y el resto de los talibanes se deben en gran medida a diferencias en la estrategia de Gobierno, seg\u00fan el <em>think tank<\/em> brit\u00e1nico Chatham House.<\/p>\n<p>Mientras que los ministros de Kabul parecen dispuestos a entablar relaciones con la comunidad internacional, los l\u00edderes talibanes de Kandahar, la segunda ciudad de Afganist\u00e1n, se muestran reacios a entablar contactos con el exterior, afirma Chatham House.<\/p>\n<p>Sirajuddin Haqqani incluso se puso en contacto con Occidente para pedir entrenamiento para las fuerzas fronterizas, afirma, mientras que los l\u00edderes de Kandahar temen que la cooperaci\u00f3n con los pa\u00edses occidentales antagonice con sus partidarios.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro talib\u00e1n de refugiados muri\u00f3 este mi\u00e9rcoles en un atentado suicida en la capital de Afganist\u00e1n, Kabul, inform\u00f3 el ministerio del interior. Khalil Haqqani era el t\u00edo del actual ministro del Interior talib\u00e1n, Sirajuddin Haqqani, quien lidera la poderosa red Haqqani, una divisi\u00f3n de la organizaci\u00f3n talib\u00e1n m\u00e1s amplia. Este mi\u00e9rcoles, un atacante suicida [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456472","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muere el ministro talib\u00e1n de los refugiados en un ataque suicida en Kabul - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muere el ministro talib\u00e1n de los refugiados en un ataque suicida en Kabul - Noticias\" \/>\n<meta property=\"og:description\" content=\"El ministro talib\u00e1n de refugiados muri\u00f3 este mi\u00e9rcoles en un atentado suicida en la capital de Afganist\u00e1n, Kabul, inform\u00f3 el ministerio del interior. Khalil Haqqani era el t\u00edo del actual ministro del Interior talib\u00e1n, Sirajuddin Haqqani, quien lidera la poderosa red Haqqani, una divisi\u00f3n de la organizaci\u00f3n talib\u00e1n m\u00e1s amplia. Este mi\u00e9rcoles, un atacante suicida [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-11T16:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Muere el ministro talib\u00e1n de los refugiados en un ataque suicida en Kabul\",\"datePublished\":\"2024-12-11T16:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/\"},\"wordCount\":410,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/\",\"name\":\"Muere el ministro talib\u00e1n de los refugiados en un ataque suicida en Kabul - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-11T16:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muere el ministro talib\u00e1n de los refugiados en un ataque suicida en Kabul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muere el ministro talib\u00e1n de los refugiados en un ataque suicida en Kabul - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Muere el ministro talib\u00e1n de los refugiados en un ataque suicida en Kabul - Noticias","og_description":"El ministro talib\u00e1n de refugiados muri\u00f3 este mi\u00e9rcoles en un atentado suicida en la capital de Afganist\u00e1n, Kabul, inform\u00f3 el ministerio del interior. Khalil Haqqani era el t\u00edo del actual ministro del Interior talib\u00e1n, Sirajuddin Haqqani, quien lidera la poderosa red Haqqani, una divisi\u00f3n de la organizaci\u00f3n talib\u00e1n m\u00e1s amplia. Este mi\u00e9rcoles, un atacante suicida [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-11T16:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/"},"author":{"name":"","@id":""},"headline":"Muere el ministro talib\u00e1n de los refugiados en un ataque suicida en Kabul","datePublished":"2024-12-11T16:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/"},"wordCount":410,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/","name":"Muere el ministro talib\u00e1n de los refugiados en un ataque suicida en Kabul - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-11T16:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Muere el ministro talib\u00e1n de los refugiados en un ataque suicida en Kabul"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Muere el ministro talib\u00e1n de los refugiados en un ataque suicida en Kabul","url":"http:\/\/noticiasya.com\/laredo\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/12\/11\/muere-ministro-taliban-refugiados-ataque-suicida-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-11T16:03:39Z","datePublished":"2024-12-11T16:03:39Z","dateModified":"2024-12-11T16:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Muere el ministro talib\\u00e1n de los refugiados en un ataque suicida en Kabul\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/11\\\/muere-ministro-taliban-refugiados-ataque-suicida-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/11\\\/muere-ministro-taliban-refugiados-ataque-suicida-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-11T16:03:39Z\",\"datePublished\":\"2024-12-11T16:03:39Z\",\"dateModified\":\"2024-12-11T16:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1460586,"url":"https:\/\/noticiasya.com\/laredo\/2025\/03\/29\/liberan-faye-hall-estadounidense-detenida-afganistan-trax\/","url_meta":{"origin":1456472,"position":0},"title":"Liberan a Faye Hall, la estadounidense que estaba detenida en Afganist\u00e1n","author":"","date":"marzo 29, 2025","format":false,"excerpt":"Una mujer estadounidense, que hab\u00eda estado detenida en Afganist\u00e1n por los talibanes desde febrero, fue liberada y se encuentra en \u201cbuen estado de salud\u201d, seg\u00fan una fuente con conocimiento de la liberaci\u00f3n.Faye Hall fue liberada el jueves \u201ctras una orden judicial y con el apoyo log\u00edstico de Qatar\u201d, que ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471528,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/22\/pakistan-lanza-ataques-aereos-afganistan-trax\/","url_meta":{"origin":1456472,"position":1},"title":"Pakist\u00e1n lanza ataques a\u00e9reos contra &#171;militantes&#187; con base en Afganist\u00e1n a quienes culpa de ataques transfronterizos","author":"","date":"febrero 22, 2026","format":false,"excerpt":"Pakist\u00e1n dijo este domingo que llev\u00f3 a cabo ataques a\u00e9reos contra campamentos militantes al otro lado de la frontera en Afganist\u00e1n, en una seria prueba para la fr\u00e1gil paz entre ambos vecinos.El ministerio de informaci\u00f3n de Pakist\u00e1n inform\u00f3 que sus fuerzas armadas realizaron \u201coperaciones selectivas basadas en inteligencia\u201d contra siete\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457798,"url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/23\/cpi-ordenes-arresto-talibanes-delitos-genero-trax\/","url_meta":{"origin":1456472,"position":2},"title":"La Corte Penal Internacional busca \u00f3rdenes de arresto contra funcionarios talibanes por delitos de g\u00e9nero","author":"","date":"enero 23, 2025","format":false,"excerpt":"La Corte Penal Internacional (CPI) est\u00e1 buscando \u00f3rdenes de arresto contra funcionarios talibanes por presuntos cr\u00edmenes de g\u00e9nero, mientras el grupo contin\u00faa reprimiendo los derechos de las mujeres en Afganist\u00e1n.En una declaraci\u00f3n de este jueves, la fiscal\u00eda de la CPI dijo que \u201chay motivos razonables para creer que el l\u00edder\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464201,"url":"https:\/\/noticiasya.com\/laredo\/2025\/07\/03\/rusia-primer-pais-reconocer-gobierno-taliban-afganistan-trax\/","url_meta":{"origin":1456472,"position":3},"title":"Rusia se convierte en el primer pa\u00eds en reconocer al Gobierno talib\u00e1n de Afganist\u00e1n desde la toma de poder en 2021","author":"","date":"julio 3, 2025","format":false,"excerpt":"Rusia se convirti\u00f3 en el primer pa\u00eds en reconocer al Gobierno talib\u00e1n de Afganist\u00e1n desde que tom\u00f3 el poder en 2021, al anunciar este jueves que ha aceptado a un embajador del grupo islamista.\u201cCreemos que el acto de reconocimiento oficial del gobierno del Emirato Isl\u00e1mico de Afganist\u00e1n dar\u00e1 un impulso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467354,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/14\/ministro-taliban-desafio-mujeres-periodistas-india-trax\/","url_meta":{"origin":1456472,"position":4},"title":"Ministro talib\u00e1n enfrenta un desaf\u00edo inusual en viaje al extranjero: mujeres periodistas","author":"","date":"octubre 14, 2025","format":false,"excerpt":"Tres d\u00edas despu\u00e9s de ser excluidas de una conferencia de prensa encabezada por el ministro de Asuntos Exteriores talib\u00e1n en la India, las mujeres periodistas tomaron sus asientos en una poderosa demostraci\u00f3n de fuerza para interrogarlo sobre la exclusi\u00f3n social de las mujeres afganas.Una imagen de la agencia de noticias\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472275,"url":"https:\/\/noticiasya.com\/laredo\/2026\/03\/17\/afganistan-denuncia-ataque-hospital-pakistan-reux\/","url_meta":{"origin":1456472,"position":5},"title":"Afganist\u00e1n dice que m\u00e1s de 400 personas murieron en ataque paquistan\u00ed contra un hospital en Kabul; Islamabad niega acusaci\u00f3n","author":"","date":"marzo 17, 2026","format":false,"excerpt":"M\u00e1s de 400 personas murieron y 265 resultaron heridas en un ataque a\u00e9reo perpetrado por Pakist\u00e1n contra un hospital de rehabilitaci\u00f3n para usuarios de drogas en Kabul, declar\u00f3 este martes un portavoz del gobierno talib\u00e1n afgano, lo que representa una marcada escalada en el conflicto entre ambos pa\u00edses vecinos.Pakist\u00e1n rechaz\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1456472"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456472\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1456472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1456472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1456472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}