{"id":1456544,"date":"2024-12-12T17:03:48","date_gmt":"2024-12-13T01:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/"},"modified":"2024-12-12T17:03:48","modified_gmt":"2024-12-13T01:03:48","slug":"que-es-bacteria-klebsiella-oxytoca-que-causa-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/","title":{"rendered":"Qu\u00e9 es la bacteria \u2018Klebsiella oxytoca\u2019 y qu\u00e9 causa en el cuerpo"},"content":{"rendered":"<p>Las autoridades de Salud de M\u00e9xico dijeron el martes que <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/10\/mexico\/klebsiella-oxytoca-enterobacter-cloacae-menores-muertos-mexico-orix\">al menos 17 ni\u00f1os<\/a> han muerto como consecuencia de un brote de infecciones bacterianas por <em>Klebsiella oxytoca<\/em> y <em>Enterobacter cloacae<\/em> que <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/12\/05\/mexico\/bacteria-klebsiella-oxytoca-muertos-estado-mexico-orix#:~:text=Agreg%C3%B3%20que%20el%20brote%20podr%C3%ADa%20estar%20relacionado%20a%20la%20posible%20contaminaci%C3%B3n%20de%20insumos%20de%20nutrici%C3%B3n%20parenteral%20o%20para%20la%20aplicaci%C3%B3n%20de%20esta%20en%20cuatro%20unidades%20de%20salud%20(tres%20centros%20p%C3%BAblicos%20y%20una%20cl%C3%ADnica%20privada)%20en%20ese%20estado%2C%20que%20circunda%20parcialmente%20a%20la%20Ciudad%20de%20M%C3%A9xico.\">se sospecha<\/a> est\u00e1n vinculadas a equipos m\u00e9dicos contaminados en ocho hospitales de tres estados del pa\u00eds (cuatro en el Estado de M\u00e9xico, dos en Michoac\u00e1n y dos en Guanajuato).<\/p>\n<p>Al menos 13 de las 17 muertes fueron causadas por la bacteria <em>Klebsiella oxytoca<\/em>, <a href=\"https:\/\/www.gob.mx\/presidencia\/es\/articulos\/version-estenografica-conferencia-de-prensa-de-la-presidenta-claudia-sheinbaum-pardo-del-10-de-diciembre-de-2024?idiom=es#:~:text=15%20pacientes%20en%20el%20Estado%20de%20M%C3%A9xico%20ten%C3%ADan%20Klebsiella%20oxytoca%20y%20fallecieron%2013%20de%20ellos%3B%20y%20se%20encontr%C3%B3%20en%20dos%20bolsas%20de%20nutrici%C3%B3n%20parenteral%20la%20misma%20Klebsiella.\">dijo<\/a> el secretario de Salud de M\u00e9xico, David Kershenobich, en una conferencia de prensa.<\/p>\n<p>Se registraron tres muertes en Michoac\u00e1n y una en Guanajuato vinculadas a <em>Klebsiella oxytoca<\/em> y <em>Enterobacter cloacae<\/em>, pero las autoridades no especificaron cu\u00e1l de ellas est\u00e1 implicada en estos casos.<\/p>\n<p>Kershenobich dijo que las infecciones bacterianas ocurrieron en unidades de terapia intensiva y pudieron haber sido causadas por el uso de dispositivos m\u00e9dicos invasivos contaminados, como cat\u00e9teres centrales y ventilaci\u00f3n mec\u00e1nica, y nutrici\u00f3n parenteral (como la intravenosa), cuya v\u00eda de administraci\u00f3n requiere \u201ccat\u00e9teres centrales o perif\u00e9ricos\u201d y \u201cconstituye una v\u00eda directa de acceso para las bacterias\u201d.<\/p>\n<p>El funcionario mexicano indic\u00f3 que por motivos de seguridad esperar\u00e1n que transcurra otra semana sin nuevos casos para que se considere que el brote ha terminado. A\u00f1adi\u00f3 que la investigaci\u00f3n sobre las infecciones y las muertes contin\u00faa.<\/p>\n<p><em>Klebsiella oxytoca<\/em> y <em>Enterobacter cloacae<\/em> son enterobacterias, una familia de bacterias que suele encontrarse en hospitales y otros centros sanitarios y que <a href=\"http:\/\/www.cnn.com\/videos\/bestoftv\/2013\/03\/06\/exp-early-cohen-cre.cnn\">ha desarrollado una enorme resistencia a los antibi\u00f3ticos<\/a>. Las bacterias <em>Klebsiella<\/em> y <em>E. coli<\/em> son bacterias que las personas tienen de forma natural en sus intestinos.<\/p>\n<p>Sin embargo, cuando se produce un brote o se contamina un material o espacio con estas bacterias, pueden infectar a personas particularmente vulnerables que se encuentran hospitalizadas en centros sanitarios, explic\u00f3 Kershenobich.<\/p>\n<p>Este tipo de bacterias tambi\u00e9n se conocen como \u201c<a href=\"https:\/\/www.gob.mx\/presidencia\/es\/articulos\/version-estenografica-conferencia-de-prensa-de-la-presidenta-claudia-sheinbaum-pardo-del-10-de-diciembre-de-2024?idiom=es#:~:text=Cuando%20en%20alg%C3%BAn,por%20esas%20bacterias.\">bacterias oportunistas<\/a>\u201d, ya que se asocian a infecciones en entornos hospitalarios, donde se aprovechan de los pacientes, muchos de ellos con sistemas inmunitarios debilitados debido al padecimiento de otras afecciones o al uso de medicamentos. Casi todos los ni\u00f1os que murieron en M\u00e9xico eran \u201cprematuros de bajo peso\u201d, con lo cual eran vulnerables a una infecci\u00f3n por estas bacterias.<\/p>\n<p>\u201cEn los centros sanitarios, las infecciones por <em>Klebsiella <\/em>suelen producirse entre pacientes enfermos que reciben tratamiento por otra afecci\u00f3n\u201d, <a href=\"https:\/\/www.cnn.com\/2023\/04\/27\/health\/seattle-klebsiella-outbreak\/index.html#:~:text=%E2%80%9CIn%20healthcare%20settings%2C%20Klebsiella%20infections%20commonly%20occur%20among%20sick%20patients%20who%20are%20receiving%20treatment%20for%20other%20condition%2C%E2%80%9D%20the%20CDC%20said.\">se\u00f1alan<\/a> los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE.UU. (CDC, por sus siglas en ingl\u00e9s).<\/p>\n<p>Seg\u00fan los CDC, los pacientes de un centro sanitario pueden estar expuestos a la bacteria <em>Klebsiella<\/em> por contacto de persona a persona o a trav\u00e9s de ventiladores o dispositivos m\u00e9dicos invasivos contaminados, como cat\u00e9teres.<\/p>\n<p>En general, la bacteria <em>Klebsiella<\/em> se encuentra normalmente en las heces y puede causar neumon\u00eda, infecciones del torrente sangu\u00edneo, infecciones de heridas quir\u00fargicas y meningitis, seg\u00fan los CDC.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las autoridades de Salud de M\u00e9xico dijeron el martes que al menos 17 ni\u00f1os han muerto como consecuencia de un brote de infecciones bacterianas por Klebsiella oxytoca y Enterobacter cloacae que se sospecha est\u00e1n vinculadas a equipos m\u00e9dicos contaminados en ocho hospitales de tres estados del pa\u00eds (cuatro en el Estado de M\u00e9xico, dos en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456544","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qu\u00e9 es la bacteria \u2018Klebsiella oxytoca\u2019 y qu\u00e9 causa en el cuerpo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 es la bacteria \u2018Klebsiella oxytoca\u2019 y qu\u00e9 causa en el cuerpo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las autoridades de Salud de M\u00e9xico dijeron el martes que al menos 17 ni\u00f1os han muerto como consecuencia de un brote de infecciones bacterianas por Klebsiella oxytoca y Enterobacter cloacae que se sospecha est\u00e1n vinculadas a equipos m\u00e9dicos contaminados en ocho hospitales de tres estados del pa\u00eds (cuatro en el Estado de M\u00e9xico, dos en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-13T01:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Qu\u00e9 es la bacteria \u2018Klebsiella oxytoca\u2019 y qu\u00e9 causa en el cuerpo\",\"datePublished\":\"2024-12-13T01:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/\"},\"wordCount\":525,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/\",\"name\":\"Qu\u00e9 es la bacteria \u2018Klebsiella oxytoca\u2019 y qu\u00e9 causa en el cuerpo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-13T01:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u00e9 es la bacteria \u2018Klebsiella oxytoca\u2019 y qu\u00e9 causa en el cuerpo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u00e9 es la bacteria \u2018Klebsiella oxytoca\u2019 y qu\u00e9 causa en el cuerpo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Qu\u00e9 es la bacteria \u2018Klebsiella oxytoca\u2019 y qu\u00e9 causa en el cuerpo - Noticias","og_description":"Las autoridades de Salud de M\u00e9xico dijeron el martes que al menos 17 ni\u00f1os han muerto como consecuencia de un brote de infecciones bacterianas por Klebsiella oxytoca y Enterobacter cloacae que se sospecha est\u00e1n vinculadas a equipos m\u00e9dicos contaminados en ocho hospitales de tres estados del pa\u00eds (cuatro en el Estado de M\u00e9xico, dos en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/","og_site_name":"Noticias","article_published_time":"2024-12-13T01:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/"},"author":{"name":"","@id":""},"headline":"Qu\u00e9 es la bacteria \u2018Klebsiella oxytoca\u2019 y qu\u00e9 causa en el cuerpo","datePublished":"2024-12-13T01:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/"},"wordCount":525,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/","url":"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/","name":"Qu\u00e9 es la bacteria \u2018Klebsiella oxytoca\u2019 y qu\u00e9 causa en el cuerpo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-13T01:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Qu\u00e9 es la bacteria \u2018Klebsiella oxytoca\u2019 y qu\u00e9 causa en el cuerpo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Qu\u00e9 es la bacteria \u2018Klebsiella oxytoca\u2019 y qu\u00e9 causa en el cuerpo","url":"http:\/\/noticiasya.com\/laredo\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/12\/12\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-13T01:03:48Z","datePublished":"2024-12-13T01:03:48Z","dateModified":"2024-12-13T01:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Qu\\u00e9 es la bacteria \\u2018Klebsiella oxytoca\\u2019 y qu\\u00e9 causa en el cuerpo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/12\\\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/12\\\/que-es-bacteria-klebsiella-oxytoca-que-causa-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-13T01:03:48Z\",\"datePublished\":\"2024-12-13T01:03:48Z\",\"dateModified\":\"2024-12-13T01:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456429,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/10\/klebsiella-oxytoca-enterobacter-cloacae-menores-muertos-mexico-orix\/","url_meta":{"origin":1456544,"position":0},"title":"Infecciones de bacterias \u2018Klebsiella oxytoca\u2019 y \u2018Enterobacter cloacae\u2019 dejan al menos 17 menores muertos en M\u00e9xico","author":"","date":"diciembre 10, 2024","format":false,"excerpt":"El secretario de Salud de M\u00e9xico, David Kershenobich, inform\u00f3 este martes que se reportan 17 ni\u00f1os fallecidos tras infectarse con dos bacterias, la Klebsiella oxytoca y la Enterobacter cloacae.Kershenobich inform\u00f3 que se notific\u00f3 a la Secretaria de Salud sobre un posible brote de dos enterobacterias en unidades de terapia intensiva.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456312,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/05\/bacteria-klebsiella-oxytoca-muertos-estado-mexico-orix\/","url_meta":{"origin":1456544,"position":1},"title":"Infecciones de bacteria \u2018Klebsiella oxytoca\u2019 dejan al menos 13 menores muertos en el Estado de M\u00e9xico","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"La Secretar\u00eda de Salud de M\u00e9xico inform\u00f3 este jueves en un comunicado que al menos 13 menores han muerto y otros siete pacientes de entre cero y 14 a\u00f1os se encuentran hospitalizados en el Estado de M\u00e9xico tras infectarse con la bacteria Klebsiella oxytoca, ante la cual el Sistema Nacional\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463053,"url":"https:\/\/noticiasya.com\/laredo\/2025\/05\/31\/investigan-34-muertes-fentanilo-contaminado-argentina-orix\/","url_meta":{"origin":1456544,"position":2},"title":"Investigan al menos 34 muertes por fentanilo contaminado en Argentina","author":"","date":"mayo 31, 2025","format":false,"excerpt":"Cuando los profesionales del Hospital Italiano de La Plata, en Argentina, empezaron a sospechar, ya ten\u00edan una decena de pacientes enfermos. Primero, pensaron que la neumon\u00eda que sufr\u00edan pod\u00eda haber sido causada por un virus intrahospitalario, pero les parec\u00eda extra\u00f1o que la mayor parte de los pacientes no hab\u00eda tenido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465340,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/09\/ecuador-confirma-muerte-12-bebes-hospital-publico-guayaquil-orix\/","url_meta":{"origin":1456544,"position":3},"title":"Ecuador confirma la muerte de 12 beb\u00e9s en un hospital p\u00fablico de Guayaquil. Se\u00f1ala &#171;causas multifactoriales&#187;","author":"","date":"agosto 9, 2025","format":false,"excerpt":"El Ministerio de Salud de Ecuador confirm\u00f3 este s\u00e1bado que 12 beb\u00e9s reci\u00e9n nacidos han muerto en el Hospital Universitario de Guayaquil, administrado por el Gobierno, debido a lo que llam\u00f3 \u201ccausas multifactoriales\u201d.El Ministerio no aclar\u00f3 el per\u00edodo en el que ocurrieron los fallecimientos. CNN est\u00e1 buscando conseguir detalles del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465999,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/30\/fentanilo-contaminado-argentina-orix\/","url_meta":{"origin":1456544,"position":4},"title":"Falta de controles, 10 detenidos y casi 100 muertes: la trama del fentanilo contaminado que escandaliza a Argentina","author":"","date":"agosto 30, 2025","format":false,"excerpt":"Cuando Sandra y Daniel escucharon el t\u00edtulo \u201cfentanilo contaminado\u201d de fondo, en un noticiero de televisi\u00f3n esa noche, apenas hab\u00edan pasado 15 d\u00edas de la muerte de su hijo. Daniel Oviedo, que llevaba el mismo nombre que su pap\u00e1, ten\u00eda 44 a\u00f1os el d\u00eda que sus padres lo vieron con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449541,"url":"https:\/\/noticiasya.com\/laredo\/2024\/05\/17\/seis-muertos-hechos-violentos-la-concordia-chiapas-en-mexico\/","url_meta":{"origin":1456544,"position":5},"title":"Tiroteo durante un acto de campa\u00f1a en La Concordia, Chiapas: una candidata a alcaldesa entre los seis muertos","author":"","date":"mayo 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La Fiscal\u00eda General de Chiapas inform\u00f3 este jueves a trav\u00e9s de un comunicado que se reportaron seis personas muertas y dos heridos por hechos violentos durante un acto pol\u00edtico en el municipio de La Concordia, Chiapas, en M\u00e9xico.Las autoridades informaron que la Polic\u00eda Estatal confirm\u00f3 la muerte de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1456544"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456544\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1456544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1456544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1456544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}