{"id":1456564,"date":"2024-12-13T09:03:52","date_gmt":"2024-12-13T17:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/"},"modified":"2024-12-13T09:03:52","modified_gmt":"2024-12-13T17:03:52","slug":"cancelan-miss-paises-bajos-cambio-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/","title":{"rendered":"Cancelan certamen de Miss Pa\u00edses Bajos: la organizaci\u00f3n dice que &#171;el mundo est\u00e1 cambiando&#187;"},"content":{"rendered":"<p>El certamen Miss Pa\u00edses Bajos ha sido cancelado, despu\u00e9s de que la organizaci\u00f3n dijera que era hora de un cambio.<\/p>\n<p>En consecuencia el concurso ya no se llevar\u00e1 a cabo, y en su lugar, quienes lo organizaban han introducido una nueva iniciativa destinada a \u201cinspirar\u201d a los j\u00f3venes de distintas maneras.<\/p>\n<p>La decisi\u00f3n se produce poco m\u00e1s de un a\u00f1o despu\u00e9s de que los jueces del concurso coronaran por primera vez a una mujer trans, Rikkie Koll\u00e9.<\/p>\n<p>Un comunicado en el sitio web del certamen anunci\u00f3 su cierre y el establecimiento de una nueva plataforma llamada \u201cNiet Meer Van Deze Tijd\u201d (\u201cYa no es de esta \u00e9poca\u201d).<\/p>\n<p>\u201cMiss Pa\u00edses Bajos se transforma en <em>Ya no es de esta \u00e9poca<\/em>: una plataforma que trabaja en torno a la salud mental, las redes sociales, la diversidad, la autoexpresi\u00f3n y mucho m\u00e1s. No m\u00e1s coronas, sino historias que conectan. No m\u00e1s vestidos, sino sue\u00f1os que cobran vida\u201d.<\/p>\n<p>El comunicado dice: \u201cDespu\u00e9s de a\u00f1os de historia llenos de glamour, talento e inspiraci\u00f3n, Miss Pa\u00edses Bajos se despide del nombre que lleg\u00f3 al coraz\u00f3n de muchas personas. Pero este no es el final; es un nuevo comienzo. El mundo est\u00e1 cambiando, y nosotros estamos cambiando con \u00e9l\u201d.<\/p>\n<p>\u201cAqu\u00ed inspiramos a los j\u00f3venes a ser ellos mismos en un mundo que est\u00e1 cambiando constantemente\u201d, a\u00f1ade.<\/p>\n<p>En un comunicado enviado a CNN, Monica van Ee, directora de Miss Pa\u00edses Bajos y fundadora de la nueva plataforma, dijo: \u201cLas mujeres se sienten inseguras debido, entre otras cosas, al auge de las redes sociales y sus im\u00e1genes irreales de belleza\u201d.<\/p>\n<p>Defendiendo el historial del concurso hasta ahora, dijo que su equipo hab\u00eda \u201ctrabajado intensamente con las participantes\u201d a lo largo de los a\u00f1os, y que el empoderamiento de las mujeres no eran solo \u201cpalabras vac\u00edas, sino un movimiento\u201d.<\/p>\n<p>Sin embargo, la retroalimentaci\u00f3n de los espectadores se ha vuelto cada vez m\u00e1s dif\u00edcil de gestionar.<\/p>\n<p>Van Ee dijo que la raz\u00f3n para dejar de lado los \u201ccasting y finales\u201d surgi\u00f3 inicialmente de \u201cla obstinaci\u00f3n del espectador\u201d y cr\u00edticas como \u201cella es demasiado blanca\u201d o \u201cella es demasiado negra\u201d.<\/p>\n<p>\u201cEsto genera una energ\u00eda negativa cada a\u00f1o\u201d, dijo.<\/p>\n<p>\u201cEn segundo lugar, nos gustar\u00eda usar nuestra energ\u00eda positiva en lugar de siempre tener que ponernos a la defensiva. Ahora podemos llegar a todos y proporcionar la solidaridad adecuada. Creemos en nuestra plataforma y que tal vez una banda y una corona est\u00e1n pasadas de moda. \u00a1Pero las mujeres que se apoyan mutuamente y se ayudan, eso siempre ha sido importante para nosotros!\u201d.<\/p>\n<p>Koll\u00e9, quien fue una de dos mujeres trans que compitieron en Miss Universo en 2023, utiliz\u00f3 su influencia para promover una visi\u00f3n m\u00e1s inclusiva del mundo de los cert\u00e1menes.<\/p>\n<p>En un video publicado en Instagram el a\u00f1o pasado, dijo: \u201cMiss Universo nos pidi\u00f3 que nos describi\u00e9ramos en una palabra. La palabra que yo elijo es \u2018victoria\u2019, porque como una ni\u00f1a peque\u00f1a conquist\u00e9 todas las cosas que se presentaron en mi camino, y mira a d\u00f3nde he llegado, de pie aqu\u00ed como una mujer trans fuerte, empoderadora y segura\u201d.<\/p>\n<p>El mundo de los cert\u00e1menes de belleza se ha visto obligado a modernizarse en los \u00faltimos a\u00f1os, ya que los valores que tradicionalmente abrazaban no resuenan con las generaciones m\u00e1s j\u00f3venes.<\/p>\n<p>Este a\u00f1o, Miss Universo, celebrado en la Ciudad de M\u00e9xico el mes pasado, admiti\u00f3 a mujeres mayores de 28 a\u00f1os por primera vez en la historia. Esto sigui\u00f3 a movimientos el a\u00f1o pasado para levantar la prohibici\u00f3n de incluir mujeres embarazadas o madres, y mujeres que est\u00e9n \u2014o hayan estado alguna vez\u2014 casadas.<\/p>\n<p>Sin embargo, esa regla sigue vigente en algunos cert\u00e1menes. En septiembre pasado, una mujer de Nueva York present\u00f3 una queja ante la Comisi\u00f3n de Derechos Humanos de la ciudad solicitando el fin de la exclusi\u00f3n de madres.<\/p>\n<p>La organizaci\u00f3n de Miss Universo fue objeto de escrutinio a principios de este a\u00f1o debido a que la empresa matriz detr\u00e1s de Miss Estados Unidos y Miss Teen Estados Unidos se vio salpicada cuando varias concursantes hicieron acusaciones de mala gesti\u00f3n, toxicidad y condiciones que afectaron su salud mental.<\/p>\n<p><em>Jacqui Palumbo, Ana Mar\u00eda Ca\u00f1izares y Abel Alvarado de CNN contribuyeron a este art\u00edculo.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El certamen Miss Pa\u00edses Bajos ha sido cancelado, despu\u00e9s de que la organizaci\u00f3n dijera que era hora de un cambio. En consecuencia el concurso ya no se llevar\u00e1 a cabo, y en su lugar, quienes lo organizaban han introducido una nueva iniciativa destinada a \u201cinspirar\u201d a los j\u00f3venes de distintas maneras. La decisi\u00f3n se produce [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456564","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cancelan certamen de Miss Pa\u00edses Bajos: la organizaci\u00f3n dice que &quot;el mundo est\u00e1 cambiando&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cancelan certamen de Miss Pa\u00edses Bajos: la organizaci\u00f3n dice que &quot;el mundo est\u00e1 cambiando&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"El certamen Miss Pa\u00edses Bajos ha sido cancelado, despu\u00e9s de que la organizaci\u00f3n dijera que era hora de un cambio. En consecuencia el concurso ya no se llevar\u00e1 a cabo, y en su lugar, quienes lo organizaban han introducido una nueva iniciativa destinada a \u201cinspirar\u201d a los j\u00f3venes de distintas maneras. La decisi\u00f3n se produce [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-13T17:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cancelan certamen de Miss Pa\u00edses Bajos: la organizaci\u00f3n dice que &#171;el mundo est\u00e1 cambiando&#187;\",\"datePublished\":\"2024-12-13T17:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/\"},\"wordCount\":786,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/\",\"name\":\"Cancelan certamen de Miss Pa\u00edses Bajos: la organizaci\u00f3n dice que \\\"el mundo est\u00e1 cambiando\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-13T17:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cancelan certamen de Miss Pa\u00edses Bajos: la organizaci\u00f3n dice que &#171;el mundo est\u00e1 cambiando&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cancelan certamen de Miss Pa\u00edses Bajos: la organizaci\u00f3n dice que \"el mundo est\u00e1 cambiando\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cancelan certamen de Miss Pa\u00edses Bajos: la organizaci\u00f3n dice que \"el mundo est\u00e1 cambiando\" - Noticias","og_description":"El certamen Miss Pa\u00edses Bajos ha sido cancelado, despu\u00e9s de que la organizaci\u00f3n dijera que era hora de un cambio. En consecuencia el concurso ya no se llevar\u00e1 a cabo, y en su lugar, quienes lo organizaban han introducido una nueva iniciativa destinada a \u201cinspirar\u201d a los j\u00f3venes de distintas maneras. La decisi\u00f3n se produce [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-13T17:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/"},"author":{"name":"","@id":""},"headline":"Cancelan certamen de Miss Pa\u00edses Bajos: la organizaci\u00f3n dice que &#171;el mundo est\u00e1 cambiando&#187;","datePublished":"2024-12-13T17:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/"},"wordCount":786,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/","name":"Cancelan certamen de Miss Pa\u00edses Bajos: la organizaci\u00f3n dice que \"el mundo est\u00e1 cambiando\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-13T17:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cancelan certamen de Miss Pa\u00edses Bajos: la organizaci\u00f3n dice que &#171;el mundo est\u00e1 cambiando&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cancelan certamen de Miss Pa\u00edses Bajos: la organizaci\u00f3n dice que &#171;el mundo est\u00e1 cambiando&#187;","url":"http:\/\/noticiasya.com\/laredo\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/12\/13\/cancelan-miss-paises-bajos-cambio-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-13T17:03:52Z","datePublished":"2024-12-13T17:03:52Z","dateModified":"2024-12-13T17:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cancelan certamen de Miss Pa\\u00edses Bajos: la organizaci\\u00f3n dice que &#171;el mundo est\\u00e1 cambiando&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/13\\\/cancelan-miss-paises-bajos-cambio-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/13\\\/cancelan-miss-paises-bajos-cambio-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-13T17:03:52Z\",\"datePublished\":\"2024-12-13T17:03:52Z\",\"dateModified\":\"2024-12-13T17:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450075,"url":"https:\/\/noticiasya.com\/laredo\/2024\/06\/05\/miss-universo-ecuador-46-anos-hijos-orix\/","url_meta":{"origin":1456564,"position":0},"title":"Miss Universo Ecuador tiene su primera candidata de 46 a\u00f1os y siete concursantes son madres","author":"","date":"junio 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El certamen de Miss Universo Ecuador est\u00e1 atravesando por un momento distinto desde que la organizaci\u00f3n internacional del Miss Universo modific\u00f3 ciertas reglas con la finalidad de promover un concurso m\u00e1s inclusivo y diverso.En 2024 ya no existe un l\u00edmite de edad para participar y, por esa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468818,"url":"https:\/\/noticiasya.com\/laredo\/2025\/11\/29\/miss-universo-controversia-mexico-trax\/","url_meta":{"origin":1456564,"position":1},"title":"La crisis de este a\u00f1o en Miss Universo demuestra lo desagradables que se han vuelto los concursos de belleza","author":"","date":"noviembre 29, 2025","format":false,"excerpt":"La belleza est\u00e1 en el ojo de quien mira. Y para el certamen de Miss Universo, plagado de esc\u00e1ndalos, esto se est\u00e1 convirtiendo en gran parte del problema.Los criterios de votaci\u00f3n opacos y subjetivos han dificultado desentra\u00f1ar la red de acusaciones en torno a la final de este a\u00f1o. La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467740,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/25\/audrey-eckert-miss-ee-uu-escandalos-trax\/","url_meta":{"origin":1456564,"position":2},"title":"Eligen a la nueva Miss EE.UU. mientras el certamen, envuelto en esc\u00e1ndalos, anuncia una &#171;nueva era&#187;","author":"","date":"octubre 25, 2025","format":false,"excerpt":"Audrey Eckert de Nebraska fue coronada como la nueva Miss Estados Unidos este viernes, mientras el certamen anual, envuelto en esc\u00e1ndalos, regres\u00f3 bajo una nueva administraci\u00f3n.La defensora de la seguridad digital, de 22 a\u00f1os, venci\u00f3 a otras 50 concursantes para quedarse con la corona en el Grand Sierra Resort en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451538,"url":"https:\/\/noticiasya.com\/laredo\/2024\/08\/01\/miss-usa-miss-teen-usa-2024-previa-trax\/","url_meta":{"origin":1456564,"position":3},"title":"Tras un a\u00f1o escandaloso, vuelven los concursos Miss Teen USA y Miss USA","author":"","date":"agosto 1, 2024","format":false,"excerpt":"(CNN) -- Tras un a\u00f1o turbulento para los concursos de Miss EE.UU. y Miss Teen EE.UU., en el que las dos ganadoras de 2023 dimitieron por primera vez en su historia, ambos cert\u00e1menes regresan esta semana a Los \u00c1ngeles para coronar a dos nuevas ganadoras.Para competir por los t\u00edtulos, las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455884,"url":"https:\/\/noticiasya.com\/laredo\/2024\/11\/17\/victoria-kjaer-theilvig-gana-miss-universo-2024-trax\/","url_meta":{"origin":1456564,"position":4},"title":"Victoria Kj\u00e6r Theilvig de Dinamarca es la ganadora de Miss Universo 2024","author":"","date":"noviembre 17, 2024","format":false,"excerpt":"(CNN) -- Victoria Kj\u00e6r Theilvig de Dinamarca fue coronada Miss Universo 2024, convirti\u00e9ndose en la primera danesa en ganar este certamen de belleza.La joven de 21 a\u00f1os, bailarina, empresaria y aspirante a abogada, venci\u00f3 a otras 126 concursantes para ganar el concurso de belleza anual en la Ciudad de M\u00e9xico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468566,"url":"https:\/\/noticiasya.com\/laredo\/2025\/11\/20\/gana-miss-universo-2025-trax\/","url_meta":{"origin":1456564,"position":5},"title":"F\u00e1tima Bosch, representante de M\u00e9xico, gana Miss Universo 2025","author":"","date":"noviembre 20, 2025","format":false,"excerpt":"La mexicana F\u00e1tima Bosch gan\u00f3 el certamen de belleza Miss Universo 2025. Bosch se convirti\u00f3 en una de las favoritas del p\u00fablico despu\u00e9s de ser reprendida por un director tailand\u00e9s del certamen durante una reuni\u00f3n transmitida en vivo, lo que provoc\u00f3 que las concursantes abandonaran el evento.Praveenar Singh de Tailandia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1456564"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456564\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1456564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1456564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1456564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}