{"id":1456569,"date":"2024-12-13T10:03:47","date_gmt":"2024-12-13T18:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/"},"modified":"2024-12-13T10:03:47","modified_gmt":"2024-12-13T18:03:47","slug":"nancy-pelosi-hospital-luxemburgo-lesion-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/","title":{"rendered":"Nancy Pelosi fue ingresada en un hospital en Luxemburgo tras sufrir una lesi\u00f3n"},"content":{"rendered":"<p>La representante estadounidense Nancy Pelosi fue ingresada en un hospital en Luxemburgo despu\u00e9s de \u201csufrir una lesi\u00f3n durante un compromiso oficial\u201d, seg\u00fan un comunicado de su oficina.<\/p>\n<p>Pelosi, de 84 a\u00f1os, contin\u00faa trabajando y actualmente recibe un tratamiento \u201cexcelente\u201d por parte de m\u00e9dicos y profesionales de la salud.<\/p>\n<p>\u201cDurante un viaje con una delegaci\u00f3n bipartidista del Congreso en Luxemburgo para conmemorar el 80 aniversario de la Batalla de las Ardenas, la Presidenta Em\u00e9rita Nancy Pelosi sufri\u00f3 una lesi\u00f3n durante un compromiso oficial y fue ingresada en el hospital para una evaluaci\u00f3n\u201d, dec\u00eda el comunicado.<\/p>\n<p>\u201cLa Presidenta Em\u00e9rita Pelosi est\u00e1 recibiendo actualmente un excelente tratamiento por parte de m\u00e9dicos y profesionales de la salud. Ella contin\u00faa trabajando y lamenta no poder asistir al resto de los compromisos del CODEL para honrar el valor de nuestros militares durante uno de los mayores actos de hero\u00edsmo estadounidense en la historia de nuestra naci\u00f3n\u201d, se\u00f1ala el comunicado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La representante estadounidense Nancy Pelosi fue ingresada en un hospital en Luxemburgo despu\u00e9s de \u201csufrir una lesi\u00f3n durante un compromiso oficial\u201d, seg\u00fan un comunicado de su oficina. Pelosi, de 84 a\u00f1os, contin\u00faa trabajando y actualmente recibe un tratamiento \u201cexcelente\u201d por parte de m\u00e9dicos y profesionales de la salud. \u201cDurante un viaje con una delegaci\u00f3n bipartidista [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456569","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nancy Pelosi fue ingresada en un hospital en Luxemburgo tras sufrir una lesi\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nancy Pelosi fue ingresada en un hospital en Luxemburgo tras sufrir una lesi\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"La representante estadounidense Nancy Pelosi fue ingresada en un hospital en Luxemburgo despu\u00e9s de \u201csufrir una lesi\u00f3n durante un compromiso oficial\u201d, seg\u00fan un comunicado de su oficina. Pelosi, de 84 a\u00f1os, contin\u00faa trabajando y actualmente recibe un tratamiento \u201cexcelente\u201d por parte de m\u00e9dicos y profesionales de la salud. \u201cDurante un viaje con una delegaci\u00f3n bipartidista [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-13T18:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Nancy Pelosi fue ingresada en un hospital en Luxemburgo tras sufrir una lesi\u00f3n\",\"datePublished\":\"2024-12-13T18:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/\"},\"wordCount\":198,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/\",\"name\":\"Nancy Pelosi fue ingresada en un hospital en Luxemburgo tras sufrir una lesi\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-13T18:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nancy Pelosi fue ingresada en un hospital en Luxemburgo tras sufrir una lesi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nancy Pelosi fue ingresada en un hospital en Luxemburgo tras sufrir una lesi\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Nancy Pelosi fue ingresada en un hospital en Luxemburgo tras sufrir una lesi\u00f3n - Noticias","og_description":"La representante estadounidense Nancy Pelosi fue ingresada en un hospital en Luxemburgo despu\u00e9s de \u201csufrir una lesi\u00f3n durante un compromiso oficial\u201d, seg\u00fan un comunicado de su oficina. Pelosi, de 84 a\u00f1os, contin\u00faa trabajando y actualmente recibe un tratamiento \u201cexcelente\u201d por parte de m\u00e9dicos y profesionales de la salud. \u201cDurante un viaje con una delegaci\u00f3n bipartidista [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-13T18:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/"},"author":{"name":"","@id":""},"headline":"Nancy Pelosi fue ingresada en un hospital en Luxemburgo tras sufrir una lesi\u00f3n","datePublished":"2024-12-13T18:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/"},"wordCount":198,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/","name":"Nancy Pelosi fue ingresada en un hospital en Luxemburgo tras sufrir una lesi\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-13T18:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Nancy Pelosi fue ingresada en un hospital en Luxemburgo tras sufrir una lesi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Nancy Pelosi fue ingresada en un hospital en Luxemburgo tras sufrir una lesi\u00f3n","url":"http:\/\/noticiasya.com\/laredo\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/12\/13\/nancy-pelosi-hospital-luxemburgo-lesion-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-13T18:03:47Z","datePublished":"2024-12-13T18:03:47Z","dateModified":"2024-12-13T18:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Nancy Pelosi fue ingresada en un hospital en Luxemburgo tras sufrir una lesi\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/13\\\/nancy-pelosi-hospital-luxemburgo-lesion-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/13\\\/nancy-pelosi-hospital-luxemburgo-lesion-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-13T18:03:47Z\",\"datePublished\":\"2024-12-13T18:03:47Z\",\"dateModified\":\"2024-12-13T18:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450601,"url":"https:\/\/noticiasya.com\/laredo\/2024\/06\/21\/declaran-culpable-david-depape-ataque-paul-pelosi-esposo-nancy-pelosi-trax\/","url_meta":{"origin":1456569,"position":0},"title":"Declaran culpable de cinco cargos estatales a David DePape por el ataque a Paul Pelosi, esposo de Nancy Pelosi","author":"","date":"junio 21, 2024","format":false,"excerpt":"(CNN) -- David DePape, el hombre condenado en un tribunal federal por atacar violentamente al marido de la presidenta em\u00e9rita de la C\u00e1mara de Representantes Nancy Pelosi, Paul Pelosi, fue declarado culpable de cinco cargos en un tribunal estatal.Un jurado de California encontr\u00f3 a DePape culpable de robo en primer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449556,"url":"https:\/\/noticiasya.com\/laredo\/2024\/05\/17\/condenan-30-anios-prision-hombre-ataco-esposo-nancy-pelosi-trax\/","url_meta":{"origin":1456569,"position":1},"title":"Condenan a 30 a\u00f1os de prisi\u00f3n al hombre que atac\u00f3 al esposo de Nancy Pelosi","author":"","date":"mayo 17, 2024","format":false,"excerpt":"(CNN) -- Un juez federal conden\u00f3 este viernes a David DePape a 30 a\u00f1os de prisi\u00f3n, tras ser declarado culpable del violento ataque de octubre de 2022 contra Paul Pelosi, esposo de la expresidenta de la C\u00e1mara de Representantes Nancy Pelosi.DePape fue sentenciado a 30 a\u00f1os por agresi\u00f3n y 20\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450653,"url":"https:\/\/noticiasya.com\/laredo\/2024\/06\/24\/hospitalizan-princesa-ana-heridas-leves-trax\/","url_meta":{"origin":1456569,"position":2},"title":"Hospitalizan a la princesa Ana con heridas leves tras un incidente en su casa","author":"","date":"junio 24, 2024","format":false,"excerpt":"(CNN) -- La hermana del rey Carlos III, la princesa Ana, ha sido hospitalizada por precauci\u00f3n tras sufrir heridas leves y una conmoci\u00f3n cerebral despu\u00e9s de un \"incidente\" en su casa de Gatcome Park, en el oeste de Inglaterra, seg\u00fan informa el Palacio de Buckingham en un comunicado.\"La princesa real\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458810,"url":"https:\/\/noticiasya.com\/laredo\/2025\/02\/16\/shakira-suspende-primer-concierto-lima-hospitalizada-efe\/","url_meta":{"origin":1456569,"position":3},"title":"Shakira suspende su primer concierto en Lima tras ser hospitalizada por dolor abdominal","author":"","date":"febrero 16, 2025","format":false,"excerpt":"La cantante colombiana Shakira anunci\u00f3 que fue hospitalizada en Lima tras sufrir de un dolor abdominal, por lo que se suspendi\u00f3 el primer concierto que iba a presentar este domingo en el Estadio Nacional de la capital peruana.\u201cLamento informarles que anoche tuve que acudir a urgencias por un cuadro abdominal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459714,"url":"https:\/\/noticiasya.com\/laredo\/2025\/03\/10\/principe-federico-luxemburgo-muere-enfermedad-rara-trax\/","url_meta":{"origin":1456569,"position":4},"title":"El pr\u00edncipe Federico de Luxemburgo muere a causa de una enfermedad rara","author":"","date":"marzo 10, 2025","format":false,"excerpt":"El pr\u00edncipe Federico de Luxemburgo muri\u00f3 tras una larga batalla contra un raro trastorno gen\u00e9tico conocido como enfermedad mitocondrial POLG.Falleci\u00f3 el 1 de marzo en Par\u00eds, anunci\u00f3 su familia en el sitio web de la Fundaci\u00f3n POLG, que Frederik inici\u00f3 en 2022.\u201cCon gran pesar, mi esposa y yo queremos informarles\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458483,"url":"https:\/\/noticiasya.com\/laredo\/2025\/02\/09\/boxeador-irlandes-john-cooney-muere-28-anios-lesion-cerebral-combate-titulo-trax\/","url_meta":{"origin":1456569,"position":5},"title":"El boxeador irland\u00e9s John Cooney muere a los 28 a\u00f1os tras sufrir una lesi\u00f3n cerebral en un combate por el t\u00edtulo","author":"","date":"febrero 9, 2025","format":false,"excerpt":"El boxeador irland\u00e9s John Cooney falleci\u00f3 a los 28 a\u00f1os a causa de las lesiones cerebrales que sufri\u00f3 en un combate, anunci\u00f3 el s\u00e1bado su promotor.\u201cEs con profundo pesar que tenemos que anunciar que, despu\u00e9s de una semana de luchar por su vida, John Cooney tristemente falleci\u00f3\u201d, dijo el promotor\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1456569"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456569\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1456569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1456569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1456569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}