{"id":1456581,"date":"2024-12-13T16:03:43","date_gmt":"2024-12-14T00:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/"},"modified":"2024-12-13T16:03:43","modified_gmt":"2024-12-14T00:03:43","slug":"funcionarios-explicacion-drones-nueva-york-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/","title":{"rendered":"Funcionarios exigen explicaciones sobre drones misteriosos tras nuevos avistamientos en el \u00e1rea metropolitana de Nueva York"},"content":{"rendered":"<p>Las agencias federales se encuentran bajo intensa presi\u00f3n este viernes debido a la demanda del p\u00fablico de m\u00e1s detalles sobre los avistamientos inexplicables de drones en el \u00e1rea metropolitana de la ciudad de Nueva York. Los drones son vistos desde hace semanas en vecindarios residenciales, as\u00ed como en sitios restringidos e infraestructuras cr\u00edticas.<\/p>\n<p>\u201cLa conclusi\u00f3n es esta: no est\u00e1n dando suficiente informaci\u00f3n al p\u00fablico, y el p\u00fablico est\u00e1 preocupado\u201d, dijo el representante estadounidense Josh Gottheimer, un dem\u00f3crata de Nueva Jersey y miembro del Comit\u00e9 de Inteligencia de la C\u00e1mara, a Kate Bolduan de CNN este viernes. \u201cCr\u00e9eme, estoy escuchando a mis electores hablar sobre esto todo el tiempo, y creo que es hora de que salgan de inmediato y nos den un informe\u201d.<\/p>\n<p>La representante republicana de Nueva York, Nicole Malliotakis, calific\u00f3 la situaci\u00f3n de \u201cindignante\u201d, y a\u00f1adi\u00f3: hay \u201cdrones y sistemas a\u00e9reos no tripulados volando sobre nosotros y nuestro Gobierno no nos dice qui\u00e9n los est\u00e1 operando ni con qu\u00e9 prop\u00f3sito\u201d.<\/p>\n<p>Malliotakis apoyo la demanda de respuestas hecha por el presidente del distrito de Staten Island, Vito Fossella.<\/p>\n<p>Fossella dijo que los drones, que a menudo fueron vistos volando de noche, han sido avistados sobrevolando infraestructuras cr\u00edticas como el Puerto Liberty de Nueva York cerca del Puente Goethals, el Puente Verrazzano-Narrows y Fort Wadsworth, una de las instalaciones militares m\u00e1s antiguas del pa\u00eds.<\/p>\n<p>Representantes de las agencias federales que investigan los drones y que han informado a los funcionarios locales a puerta cerrada dijeron que los drones a veces parecen volar en un patr\u00f3n coordinado y pueden estar en vuelo hasta seis horas, seg\u00fan el alcalde de Montvale, Nueva Jersey, Mike Ghassali.<\/p>\n<p>El senador dem\u00f3crata Andy Kim de Nueva Jersey public\u00f3 videos en su cuenta de X mostrando lo que parec\u00eda ser un grupo de drones sobre el embalse Round Valley en la noche del jueves.<\/p>\n<p>\u201cEsto ha estado ocurriendo durante semanas\u201d, escribi\u00f3 Kim. \u201cEs dif\u00edcil entender c\u00f3mo con la tecnolog\u00eda que tenemos no somos capaces de rastrear estos dispositivos para determinar su origen, y me preocupa mucho m\u00e1s por nuestras capacidades en general cuando se trata de detecci\u00f3n de drones y contramedidas\u201d.<\/p>\n<p>Funcionarios federales han tratado de calmar las preocupaciones sobre los avistamientos de drones, pero sin dar m\u00e1s detalles sobre lo que podr\u00edan implicar.<\/p>\n<p>\u201cNo tenemos evidencia en este momento de que los avistamientos de drones reportados representen una amenaza para la seguridad nacional o para la seguridad p\u00fablica, o tengan un nexo extranjero\u201d, dijo el asesor de comunicaciones de Seguridad Nacional de la Casa Blanca, John Kirby, en una rueda de prensa el jueves.<\/p>\n<p>Kirby agreg\u00f3 que muchos de \u201clos avistamientos reportados son en realidad aeronaves tripuladas que est\u00e1n siendo operadas legalmente\u201d.<\/p>\n<p>La Oficina de Seguridad Nacional y Preparaci\u00f3n de Nueva Jersey dijo que hab\u00eda \u201cuna investigaci\u00f3n federal activa\u201d sobre los avistamientos de drones, pero hay una demanda por m\u00e1s informaci\u00f3n.<\/p>\n<p>\u201cDeber\u00edamos estar haciendo un an\u00e1lisis de inteligencia y sacarlos del cielo, especialmente si est\u00e1n volando sobre aeropuertos o bases militares\u201d, dijo el senador estadounidense Richard Blumenthal, quien forma parte del Comit\u00e9 de Seguridad Nacional y Asuntos Gubernamentales del Senado, el jueves. \u201cDeber\u00edan ser derribados, si es necesario, porque est\u00e1n volando sobre \u00e1reas sensibles\u201d.<\/p>\n<p>Los residentes del condado de Rockland en Nueva York reportan avistamientos de drones desde el mes de noviembre.<\/p>\n<p>El ejecutivo del condado, Ed Day, envi\u00f3 una carta al presidente Joe Biden este viernes en la que pidi\u00f3 respuestas e inst\u00f3 al Gobierno, junto con la Administraci\u00f3n Federal de Aviaci\u00f3n (FAA) y el FBI, a investigar y proporcionar claridad sobre el asunto.<\/p>\n<p>\u201cEl hecho de que este problema haya persistido durante semanas sin respuestas claras es completamente inaceptable, no solo para la gente del condado de Rockland, sino para las comunidades de todo el pa\u00eds\u201d, dijo Day en la carta. \u201cEs hora de que el Gobierno federal de un paso adelante, asuma la responsabilidad y proporcione las respuestas que todos merecemos\u201d.<\/p>\n<p>Malliotakis dijo que la situaci\u00f3n \u201cest\u00e1 creando caos, la gente est\u00e1 confundida, preocupada, tienen ansiedad, no saben qu\u00e9 est\u00e1 pasando\u201d.<\/p>\n<p>Agencias de inteligencia de EE.UU. y fuerzas del orden federales no sospechan de la participaci\u00f3n extranjera en los avistamientos de drones en Nueva Jersey, dijeron funcionarios de seguridad a miembros del Congreso el jueves en una sesi\u00f3n informativa privada.<\/p>\n<p>A los legisladores asignados a los comit\u00e9s de seguridad nacional del Congreso se les dijo que los investigadores no creen actualmente que los avistamientos involucren una conexi\u00f3n en el extranjero, el uso de drones extranjeros, ni un operador en tierra conectado a un Gobierno extranjero, seg\u00fan una fuente familiarizada con la sesi\u00f3n informativa realizada por representantes del FBI, el Departamento de Seguridad Nacional y la Administraci\u00f3n Federal de Aviaci\u00f3n.<\/p>\n<p>Los funcionarios dijeron que los drones avistados han sido observados con luces anticolisi\u00f3n requeridas por la FAA y que no se cree que hayan ingresado a ning\u00fan espacio a\u00e9reo restringido, de acuerdo con la fuente.<\/p>\n<p>A los legisladores tambi\u00e9n se les dijo que muchos de los avistamientos reportados recientemente se cree que han sido aeronaves civiles confundidas con drones, dijo la fuente.<\/p>\n<p>Aunque las autoridades a\u00fan no han identificado el origen de los vuelos misteriosos de drones, la fuente dijo que una investigaci\u00f3n activa del FBI sigue en curso para identificar a la persona o personas que los operan, y para determinar si se han producido violaciones a la ley.<\/p>\n<p>Aunque los drones a menudo muestran luces intermitentes, frecuentemente apagan las luces y evaden helic\u00f3pteros de la polic\u00eda cuando se acercan, dijo el alcalde Michael Melham de Belleville Township en un video con una actualizaci\u00f3n publicado en Facebook el mi\u00e9rcoles.<\/p>\n<p>La FAA emiti\u00f3 restricciones temporales de vuelo sobre el Arsenal Picatinny, una instalaci\u00f3n de investigaci\u00f3n militar de EE.UU., y sobre el campo de golf del presidente electo Donald Trump en Bedminster despu\u00e9s de que se avistaran drones en esas \u00e1reas.<\/p>\n<p>\u201cHasta que sepamos el origen y cu\u00e1l es la intenci\u00f3n de estos drones, \u00bfc\u00f3mo pueden decir que no hay una amenaza inminente?\u201d, dijo a CNN el alcalde Tony Perry de Middletown, Nueva Jersey, el jueves.<\/p>\n<p>La sensaci\u00f3n de que a los funcionarios locales no les est\u00e1n dando toda la informaci\u00f3n disponible es parcialmente el resultado de leyes obsoletas que mantienen la regulaci\u00f3n de los cielos completamente en manos federales, de acuerdo con el director ejecutivo de una empresa que rastrea vuelos no autorizados de drones.<\/p>\n<p>\u201cLas leyes que regulan las aeronaves no est\u00e1n dise\u00f1adas para empoderar a la polic\u00eda para lidiar con los drones\u201d, dijo el CEO de Axon, Rick Smith, a CNN News Central este viernes. \u201cAs\u00ed que si tu feria estatal local tiene un dron acerc\u00e1ndose que la polic\u00eda cree que podr\u00eda ser peligroso, en este momento no hay nada que se pueda hacer al respecto\u201d.<\/p>\n<p>Dar m\u00e1s autoridad a las fuerzas del orden locales sobre los drones est\u00e1 siendo considerado, dijo Smith, porque la tecnolog\u00eda de seguimiento de aeronaves tradicional no es efectiva para veh\u00edculos que flotan solo a unos pocos cientos de metros del suelo.<\/p>\n<p>\u201cEl radar y sistema de seguimiento que usas para un 747 simplemente no funciona\u201d, dijo Smith.<\/p>\n<p><em>Esta historia fue escrita por Andy Rose en Atlanta, con reportes de Artemis Moshtaghian y Polo Sandoval en Nueva York, y Josh Campbell en Los \u00c1ngeles.<\/em><\/p>\n<p><em>Brynn Gingras, Samantha Waldenberg, Ted Barrett, Holmes Lybrand, Maria Aguilar Prieto, Polo Sandoval, Lauren Mascarenhas, Elizabeth Wolfe, Josh Campbell, Haley Britzky, Hanna Park, Omar Jimenez y Dakin Andone de CNN contribuyeron a este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las agencias federales se encuentran bajo intensa presi\u00f3n este viernes debido a la demanda del p\u00fablico de m\u00e1s detalles sobre los avistamientos inexplicables de drones en el \u00e1rea metropolitana de la ciudad de Nueva York. Los drones son vistos desde hace semanas en vecindarios residenciales, as\u00ed como en sitios restringidos e infraestructuras cr\u00edticas. \u201cLa conclusi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456581","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Funcionarios exigen explicaciones sobre drones misteriosos tras nuevos avistamientos en el \u00e1rea metropolitana de Nueva York - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Funcionarios exigen explicaciones sobre drones misteriosos tras nuevos avistamientos en el \u00e1rea metropolitana de Nueva York - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las agencias federales se encuentran bajo intensa presi\u00f3n este viernes debido a la demanda del p\u00fablico de m\u00e1s detalles sobre los avistamientos inexplicables de drones en el \u00e1rea metropolitana de la ciudad de Nueva York. Los drones son vistos desde hace semanas en vecindarios residenciales, as\u00ed como en sitios restringidos e infraestructuras cr\u00edticas. \u201cLa conclusi\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-14T00:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Funcionarios exigen explicaciones sobre drones misteriosos tras nuevos avistamientos en el \u00e1rea metropolitana de Nueva York\",\"datePublished\":\"2024-12-14T00:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/\"},\"wordCount\":1348,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/\",\"name\":\"Funcionarios exigen explicaciones sobre drones misteriosos tras nuevos avistamientos en el \u00e1rea metropolitana de Nueva York - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-14T00:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Funcionarios exigen explicaciones sobre drones misteriosos tras nuevos avistamientos en el \u00e1rea metropolitana de Nueva York\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Funcionarios exigen explicaciones sobre drones misteriosos tras nuevos avistamientos en el \u00e1rea metropolitana de Nueva York - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Funcionarios exigen explicaciones sobre drones misteriosos tras nuevos avistamientos en el \u00e1rea metropolitana de Nueva York - Noticias","og_description":"Las agencias federales se encuentran bajo intensa presi\u00f3n este viernes debido a la demanda del p\u00fablico de m\u00e1s detalles sobre los avistamientos inexplicables de drones en el \u00e1rea metropolitana de la ciudad de Nueva York. Los drones son vistos desde hace semanas en vecindarios residenciales, as\u00ed como en sitios restringidos e infraestructuras cr\u00edticas. \u201cLa conclusi\u00f3n [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-14T00:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/"},"author":{"name":"","@id":""},"headline":"Funcionarios exigen explicaciones sobre drones misteriosos tras nuevos avistamientos en el \u00e1rea metropolitana de Nueva York","datePublished":"2024-12-14T00:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/"},"wordCount":1348,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/","name":"Funcionarios exigen explicaciones sobre drones misteriosos tras nuevos avistamientos en el \u00e1rea metropolitana de Nueva York - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-14T00:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Funcionarios exigen explicaciones sobre drones misteriosos tras nuevos avistamientos en el \u00e1rea metropolitana de Nueva York"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Funcionarios exigen explicaciones sobre drones misteriosos tras nuevos avistamientos en el \u00e1rea metropolitana de Nueva York","url":"http:\/\/noticiasya.com\/laredo\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/12\/13\/funcionarios-explicacion-drones-nueva-york-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-14T00:03:43Z","datePublished":"2024-12-14T00:03:43Z","dateModified":"2024-12-14T00:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Funcionarios exigen explicaciones sobre drones misteriosos tras nuevos avistamientos en el \\u00e1rea metropolitana de Nueva York\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/13\\\/funcionarios-explicacion-drones-nueva-york-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/13\\\/funcionarios-explicacion-drones-nueva-york-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-14T00:03:43Z\",\"datePublished\":\"2024-12-14T00:03:43Z\",\"dateModified\":\"2024-12-14T00:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456623,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/15\/que-sabemos-misteriosos-drones-costa-este-ee-uu-trax\/","url_meta":{"origin":1456581,"position":0},"title":"Lo que sabemos sobre los misteriosos drones reportados sobre la costa este de EE.UU.","author":"","date":"diciembre 15, 2024","format":false,"excerpt":"Objetos voladores misteriosos en el cielo. Preocupaci\u00f3n y confusi\u00f3n. Y llamados a la intervenci\u00f3n militar.Esto no es la trama de \u201cLa guerra de los mundos\u201d sino el resultado de numerosos avistamientos de drones no identificados en la costa este de Estados Unidos en las \u00faltimas semanas. Los drones han sido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456528,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/12\/drones-nueva-jersey-seguridad-trax\/","url_meta":{"origin":1456581,"position":1},"title":"Misteriosos avistamientos de drones en Nueva Jersey suscitan preocupaciones de seguridad. Esto sabemos","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"Semanas de avistamientos inexplicables de drones en Nueva Jersey han sembrado la inquietud entre residentes, pol\u00edticos y funcionarios de seguridad p\u00fablica.Aunque el gobernador de Nueva Jersey, Phil Murphy, ha subrayado que no existe ninguna amenaza conocida para la seguridad p\u00fablica, los residentes y m\u00faltiples funcionarios p\u00fablicos est\u00e1n pidiendo una respuesta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456651,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/16\/viejo-oeste-drones-ansiedad-funcionarios-tranquilizar-trax\/","url_meta":{"origin":1456581,"position":2},"title":"&#171;El viejo oeste de los drones&#187;: aumenta la ansiedad en EE.UU. mientras los funcionarios buscan tranquilizar al p\u00fablico","author":"","date":"diciembre 16, 2024","format":false,"excerpt":"A medida que aumenta la presi\u00f3n sobre funcionarios federales de Estados Unidos para abordar las preocupaciones persistentes sobre posibles avistamientos de drones, los residentes de la costa este del pa\u00eds, especialmente en Nueva Jersey, permanecen en tensi\u00f3n, con informes similares que ahora surgen en Ohio, incluyendo un cierre temporal del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456562,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/13\/drones-misteriosos-nueva-jersey-para-que-sirven-trax\/","url_meta":{"origin":1456581,"position":3},"title":"Drones misteriosos est\u00e1n volando sobre Nueva Jersey. \u00bfPara qu\u00e9 sirve este tipo de artefacto?","author":"","date":"diciembre 13, 2024","format":false,"excerpt":"Los grandes drones se han convertido en un gran tema de conversaci\u00f3n en Nueva Jersey: los residentes han informado haber visto drones del tama\u00f1o de coches peque\u00f1os volando por la noche; los funcionarios no est\u00e1n seguros si est\u00e1n viendo algo inusual, o si realmente son drones.Pero incluso si los avistamientos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467102,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/04\/actividad-drones-retrasa-reapertura-aeropuerto-munich-trax\/","url_meta":{"origin":1456581,"position":4},"title":"Nueva actividad de drones retrasa reapertura del aeropuerto de Munich antes del final del Oktoberfest","author":"","date":"octubre 4, 2025","format":false,"excerpt":"El aeropuerto de Munich, en Alemania, retras\u00f3 brevemente el relanzamiento de las operaciones de vuelo este s\u00e1bado en la ma\u00f1ana, hora local, debido a avistamientos de drones que detuvieran todo el tr\u00e1fico de la terminal durante varias horas. Las dos pistas de Munich estuvieron cerradas inicialmente durante la noche del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456657,"url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/16\/drones-base-fuerza-aerea-ee-uu-trax\/","url_meta":{"origin":1456581,"position":5},"title":"Importante base de la Fuerza A\u00e9rea de EE.UU. cierra espacio a\u00e9reo en medio de avistamientos de drones","author":"","date":"diciembre 16, 2024","format":false,"excerpt":"La actividad de drones caus\u00f3 que los funcionarios cerraran el espacio a\u00e9reo sobre una de las bases m\u00e1s cr\u00edticas de la Fuerza A\u00e9rea de Estados Unidos durante casi cuatro horas el viernes por la noche y el s\u00e1bado por la ma\u00f1ana, seg\u00fan un portavoz de la base y un Aviso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1456581"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456581\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1456581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1456581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1456581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}