{"id":1456584,"date":"2024-12-13T18:03:42","date_gmt":"2024-12-14T02:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/"},"modified":"2024-12-13T18:03:42","modified_gmt":"2024-12-14T02:03:42","slug":"tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/","title":{"rendered":"El vertebrado m\u00e1s longevo podr\u00eda ofrecer pistas para alargar la vida humana, afirman los cient\u00edficos"},"content":{"rendered":"<p>El tibur\u00f3n de Groenlandia es conocido por ser escurridizo y por haber ocultado durante a\u00f1os sus rasgos m\u00e1s sorprendentes. Estas lentas criaturas se esconden principalmente en las aguas profundas y fr\u00edas de los oc\u00e9anos <a href=\"https:\/\/www.britannica.com\/animal\/Greenland-shark\">Atl\u00e1ntico Norte y \u00c1rtic<\/a>o, y son los \u00fanicos tiburones que soportan las g\u00e9lidas temperaturas durante todo el a\u00f1o. Algunos ejemplares de la especie podr\u00edan haber estado nadando all\u00ed desde la \u00e9poca colonial, y los investigadores est\u00e1n empezando a descifrar c\u00f3mo.<\/p>\n<p>Debido al lento metabolismo de este animal marino, los cient\u00edficos sospecharon durante mucho tiempo que el tibur\u00f3n de Groenlandia ten\u00eda una vida \u00fatil inusualmente larga, pero no hab\u00eda forma de determinar la magnitud exacta hasta hace poco. <a href=\"https:\/\/www.cnn.com\/2016\/08\/11\/health\/greenland-sharks-long-lives\/index.html\">Una investigaci\u00f3n publicada en 2016<\/a> determin\u00f3 que los tiburones son los vertebrados m\u00e1s longevos, con una edad estimada de entre 272 y m\u00e1s de 500 a\u00f1os. Ahora, un estudio diferente tiene como objetivo comprender el mecanismo detr\u00e1s de esa longevidad.<\/p>\n<p>Un equipo internacional de cient\u00edficos ha sido el primero en mapear el genoma del tibur\u00f3n de Groenlandia, secuenciando cerca del 92% de su ADN y brindando informaci\u00f3n sobre el funcionamiento interno de este longevo pez. El ensamblaje, la representaci\u00f3n computacional de su genoma, no solo agrega informaci\u00f3n a lo que se sabe sobre la estructura de los tiburones y c\u00f3mo funcionan sus cuerpos, sino que tambi\u00e9n proporciona pistas sobre por qu\u00e9 los animales tienen tanta capacidad de resistencia, dijeron los investigadores.<\/p>\n<p>\u201cSolo con el ensamblaje del genoma podemos entender realmente qu\u00e9 mutaciones, por ejemplo, se han acumulado en el tibur\u00f3n que llevaron a esta enorme esperanza de vida\u201d, dijo el Dr. Steve Hoffman, autor principal de la nueva investigaci\u00f3n sobre el tibur\u00f3n de Groenlandia y bi\u00f3logo computacional del Instituto Leibniz sobre el Envejecimiento en Alemania. \u201cPara este fin, este genoma es una especie de herramienta, por as\u00ed decirlo, que nos permite, y por supuesto tambi\u00e9n a otros investigadores, estudiar estos mecanismos moleculares de la longevidad\u201d.<\/p>\n<p>Los autores del estudio publicaron sus hallazgos <a href=\"https:\/\/www.biorxiv.org\/content\/10.1101\/2024.09.09.611499v1.full.pdf\">como una preimpresi\u00f3n<\/a> (un art\u00edculo cient\u00edfico que no ha pasado por el proceso de revisi\u00f3n por pares) mientras invitan a m\u00e1s cient\u00edficos a estudiar el genoma y realizar su propio an\u00e1lisis del ADN del tibur\u00f3n, dijo Hoffman.<\/p>\n<p>Hay pocas especies de animales que viven m\u00e1s que los humanos, particularmente en comparaci\u00f3n con nuestro peso y tama\u00f1o corporal. Al estudiar los mecanismos de longevidad del tibur\u00f3n de Groenlandia, los cient\u00edficos tambi\u00e9n podr\u00edan obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo extender potencialmente la vida humana, dijeron los autores.<\/p>\n<p>Los tiburones de Groenlandia crecen a <a href=\"https:\/\/oceanservice.noaa.gov\/facts\/greenland-shark.html#:~:text=Scientists%20could%20only%20guess%20that%20the%20sharks,can%20reach%20over%206%20meters%20in%20size.&#038;text=Because%20the%20sharks%20grow%20so%20slowly%2C%20they,maturity%20until%20they're%20over%20a%20century%20old.\">un ritmo extremadamente lento<\/a> de menos de 1 cent\u00edmetro (0,4 pulgadas) al a\u00f1o, pero eventualmente pueden alcanzar m\u00e1s de 6 metros (alrededor de 20 pies) de longitud, y no alcanzan la madurez sexual hasta que tienen m\u00e1s de un siglo. Se sospecha que la especie m\u00e1s antigua podr\u00eda sobrevivir m\u00e1s de medio milenio.<\/p>\n<p>Los autores del estudio descubrieron que el genoma del tibur\u00f3n es extraordinariamente grande, el doble de largo que el de un humano y m\u00e1s grande que cualquier otro genoma de tibur\u00f3n secuenciado hasta la fecha. Los investigadores est\u00e1n analizando el genoma para explorar qu\u00e9 puede significar su gran tama\u00f1o para la longevidad del tibur\u00f3n. Una raz\u00f3n para que el genoma sea m\u00e1s largo podr\u00eda ser la capacidad del tibur\u00f3n para reparar su ADN, un rasgo que se ha observado com\u00fanmente en otras especies con una esperanza de vida excepcional, incluida la rata topo desnuda, el roedor m\u00e1s longevo que puede vivir hasta 30 a\u00f1os o m\u00e1s, y <a href=\"https:\/\/news.yale.edu\/2018\/12\/03\/death-lonesome-george-reveals-why-giant-tortoises-live-so-long\">ciertas especies de tortugas<\/a> que pueden vivir m\u00e1s de 100 a\u00f1os.<\/p>\n<p>El tibur\u00f3n de Groenlandia es \u00fanico en el sentido de que una gran parte (m\u00e1s del 70%) de su genoma est\u00e1 formado <a href=\"https:\/\/www.nature.com\/scitable\/topicpage\/barbara-mcclintock-and-the-discovery-of-jumping-34083\/\">por los llamados genes saltadores<\/a>, que pueden moverse dentro de la secuencia de ADN duplic\u00e1ndose, a veces creando mutaciones. A menudo, estas duplicaciones se denominan par\u00e1sitos gen\u00e9ticos debido a sus posibles efectos nocivos, incluidas enfermedades gen\u00e9ticas como el c\u00e1ncer.<\/p>\n<p>Sin embargo, parece que en el tibur\u00f3n de Groenlandia, los genes que reparan el ADN han estado actuando como genes saltadores, distribuy\u00e9ndose en el genoma y ralentizando el proceso de envejecimiento al reparar el ADN da\u00f1ado. Como resultado, \u201cel efecto perjudicial de estos elementos transponibles (genes saltadores) no solo se cancela, sino que tal vez incluso se invierte, de modo que la integridad del genoma es a\u00fan mejor en el tibur\u00f3n de Groenlandia\u201d, dijo el autor principal, el Dr. Arne Sahm, bioinform\u00e1tico y profesor adjunto de la Universidad del Ruhr de Bochum en Alemania.<\/p>\n<p>Los autores sugieren que los genes de reparaci\u00f3n del ADN de la especie en alg\u00fan momento desarrollaron la capacidad de multiplicarse, lo que contribuye a\u00fan m\u00e1s a la reparaci\u00f3n del ADN y, a su vez, a la longevidad. Los investigadores quieren explorar y analizar m\u00e1s a fondo el ADN del tibur\u00f3n de Groenlandia, a la vez que comparan su genoma con el de otras especies de tiburones y peces de vida m\u00e1s corta, para proporcionar evidencia adicional de este rasgo \u00fanico, dijo Hoffman.<\/p>\n<p>Antes de que los investigadores secuenciaran el genoma del tibur\u00f3n de Groenlandia, solo hab\u00eda disponibles unos 10 genomas para todos los elasmobranquios (una subclase de peces que incluye tiburones, rayas y mantarrayas), dijo la Dra. Nicole Phillips, profesora asociada de ecolog\u00eda y biolog\u00eda de organismos en la Universidad del Sur de Mississippi en Hattiesburg. Phillips no particip\u00f3 en la investigaci\u00f3n realizada por Hoffman, Sahm y su equipo.<\/p>\n<p>\u201cCuantos m\u00e1s genomas de alta calidad se secuencien, mejor podremos comprender los fundamentos gen\u00e9ticos de los rasgos compartidos y \u00fanicos de este antiguo grupo\u201d, dijo Phillips en un correo electr\u00f3nico. \u201cLa identificaci\u00f3n de la base gen\u00e9tica de la esperanza de vida en diferentes especies, incluidos los tiburones de vida larga, permite a los investigadores comprender la biolog\u00eda del envejecimiento y la longevidad\u201d.<\/p>\n<p>Debido a la preferencia de los tiburones por las aguas profundas, hist\u00f3ricamente la mayor parte de la informaci\u00f3n sobre el tibur\u00f3n de Groenlandia proven\u00eda de registros de pesca comercial. En la \u00faltima d\u00e9cada, los investigadores han utilizado cada vez m\u00e1s videos, incluidos veh\u00edculos operados a distancia y c\u00e1maras con cebo, as\u00ed como observaciones en espec\u00edmenes capturados para investigar al esquivo tibur\u00f3n.<\/p>\n<p>Para secuenciar y estudiar la composici\u00f3n gen\u00e9tica del tibur\u00f3n, los autores sacrificaron varios espec\u00edmenes para obtener una muestra de tejido, para lo cual ten\u00edan un permiso de investigaci\u00f3n. Pero los cient\u00edficos esperan que su trabajo sobre el genoma del tibur\u00f3n de Groenlandia ayude en \u00faltima instancia a la conservaci\u00f3n de la especie, dijo Hoffman. El tibur\u00f3n de Groenlandia est\u00e1 actualmente<a href=\"https:\/\/www.iucnredlist.org\/species\/60213\/124452872\"> catalogado como vulnerable<\/a> en la Lista Roja de Especies Amenazadas de la Uni\u00f3n Internacional para la Conservaci\u00f3n de la Naturaleza, con su \u00faltima evaluaci\u00f3n en junio de 2019.<\/p>\n<p>\u201cLos autores pudieron obtener informaci\u00f3n sobre un animal que realmente se encuentra en un lugar \u00fanico en el \u00e1rbol evolutivo de la vida. \u201cEs muy ancestral, y por eso podr\u00eda representar, al menos en los tiburones, potencialmente c\u00f3mo evolucionaron todos los genomas, porque proporciona esta instant\u00e1nea de un genoma realmente interesante y muy especializado\u201d, dijo el Dr. Toby Daly-Engel, profesor asociado de ingenier\u00eda oce\u00e1nica y ciencias marinas en el Instituto de Tecnolog\u00eda de Florida en Melbourne y director del Laboratorio de Conservaci\u00f3n de Tiburones de Florida Tech. Daly-Engel no particip\u00f3 en la investigaci\u00f3n.<\/p>\n<p>\u201cPor un lado, creo que el conocimiento de estos genes saltarines es realmente interesante, y sin embargo, por otro lado, no es sorprendente que est\u00e9n viendo cosas que nunca hemos visto antes\u201d, agreg\u00f3, \u201cporque aunque hemos secuenciado otros genomas de tiburones, las especies de tiburones son tan diferentes entre s\u00ed que podemos esperar cosas nuevas con cada especie\u201d.<\/p>\n<p>En investigaciones anteriores, los cient\u00edficos han podido prolongar la esperanza de vida de ciertas especies de vida corta, <a href=\"https:\/\/www.ucl.ac.uk\/news\/2021\/feb\/genetic-treatment-extends-fruit-fly-lifespan-and-prevents-alzheimers-damage\">como las moscas y los ratones<\/a>, mediante modificaciones gen\u00e9ticas. Al investigar m\u00e1s especies de vida larga, los cient\u00edficos pueden comprender mejor el proceso de envejecimiento de todas las especies y las herramientas que podr\u00edan aplicarse potencialmente para prolongar la esperanza de vida humana, dijo Sahm.<\/p>\n<p>\u201cLa evoluci\u00f3n no siempre elige el mismo camino. Entonces, si, digamos, el objetivo es tener una mejor reparaci\u00f3n del ADN, pero se puede lograr mediante m\u00faltiples mecanismos, y los mecanismos son diferentes en ratas topo, ballenas y tiburones, necesitamos aprender sobre todos ellos y luego ver cu\u00e1les podemos adaptar m\u00e1s f\u00e1cilmente para el uso humano\u201d, dijo la Dra. Vera Gorbunova, profesora de medicina y biolog\u00eda en la Universidad de Rochester en Nueva York y autora principal de un <a href=\"https:\/\/www.nature.com\/articles\/s41586-023-06463-0\">estudio de 2023<\/a> que utiliz\u00f3 genes transferidos de ratas topo desnudas para extender la esperanza de vida de los ratones. Gorbunova no particip\u00f3 en la investigaci\u00f3n del tibur\u00f3n de Groenlandia.<\/p>\n<p>\u201cUna vez que los investigadores comprendan el mecanismo\u2026 entonces podremos ver si podemos dise\u00f1ar un f\u00e1rmaco espec\u00edfico que act\u00fae sobre esta enzima del genoma de esta manera\u201d, a\u00f1adi\u00f3. \u201cSe puede so\u00f1ar con la terapia gen\u00e9tica, tal vez podamos darle a la gente un gen del tibur\u00f3n de Groenlandia, pero eso puede ser un enfoque m\u00e1s de ciencia ficci\u00f3n, pero algo m\u00e1s f\u00e1cilmente traducible ser\u00eda, bueno, tal vez podamos dise\u00f1ar un f\u00e1rmaco que act\u00fae sobre (un) gen humano y lo haga funcionar un poco m\u00e1s como el del tibur\u00f3n de Groenlandia. Y eso\u2026 mejorar\u00eda la reparaci\u00f3n del ADN en los humanos\u201d.<\/p>\n<p>Hay muchas influencias ambientales que da\u00f1an el ADN humano, como la luz solar o el tabaco. Al aprender m\u00e1s sobre la t\u00e9cnica \u00fanica de reparaci\u00f3n del ADN del tibur\u00f3n de Groenlandia, los cient\u00edficos pueden comenzar a estudiar c\u00f3mo el rasgo contribuye a otros factores que retrasan el envejecimiento, como la supresi\u00f3n de tumores en las c\u00e9lulas del tibur\u00f3n de Groenlandia, as\u00ed como los posibles efectos en las c\u00e9lulas de otras especies, incluida la nuestra, dijo Sahm.<\/p>\n<p>\u201cSi realmente queremos aumentar significativamente la expectativa de vida humana, o quiz\u00e1s incluso mejor, extender el porcentaje de nuestra vida (en el que) estamos realmente sanos y en forma y podemos hacer cosas\u2026 es bueno observar los trucos de los animales muy longevos\u201d, agreg\u00f3, \u201cc\u00f3mo cambian su sistema en general, qu\u00e9 estrategias usan y luego aprender de\u2026 esas estrategias\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El tibur\u00f3n de Groenlandia es conocido por ser escurridizo y por haber ocultado durante a\u00f1os sus rasgos m\u00e1s sorprendentes. Estas lentas criaturas se esconden principalmente en las aguas profundas y fr\u00edas de los oc\u00e9anos Atl\u00e1ntico Norte y \u00c1rtico, y son los \u00fanicos tiburones que soportan las g\u00e9lidas temperaturas durante todo el a\u00f1o. Algunos ejemplares de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1456584","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El vertebrado m\u00e1s longevo podr\u00eda ofrecer pistas para alargar la vida humana, afirman los cient\u00edficos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El vertebrado m\u00e1s longevo podr\u00eda ofrecer pistas para alargar la vida humana, afirman los cient\u00edficos - Noticias\" \/>\n<meta property=\"og:description\" content=\"El tibur\u00f3n de Groenlandia es conocido por ser escurridizo y por haber ocultado durante a\u00f1os sus rasgos m\u00e1s sorprendentes. Estas lentas criaturas se esconden principalmente en las aguas profundas y fr\u00edas de los oc\u00e9anos Atl\u00e1ntico Norte y \u00c1rtico, y son los \u00fanicos tiburones que soportan las g\u00e9lidas temperaturas durante todo el a\u00f1o. Algunos ejemplares de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-14T02:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El vertebrado m\u00e1s longevo podr\u00eda ofrecer pistas para alargar la vida humana, afirman los cient\u00edficos\",\"datePublished\":\"2024-12-14T02:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/\"},\"wordCount\":1862,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/\",\"name\":\"El vertebrado m\u00e1s longevo podr\u00eda ofrecer pistas para alargar la vida humana, afirman los cient\u00edficos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-12-14T02:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El vertebrado m\u00e1s longevo podr\u00eda ofrecer pistas para alargar la vida humana, afirman los cient\u00edficos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El vertebrado m\u00e1s longevo podr\u00eda ofrecer pistas para alargar la vida humana, afirman los cient\u00edficos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El vertebrado m\u00e1s longevo podr\u00eda ofrecer pistas para alargar la vida humana, afirman los cient\u00edficos - Noticias","og_description":"El tibur\u00f3n de Groenlandia es conocido por ser escurridizo y por haber ocultado durante a\u00f1os sus rasgos m\u00e1s sorprendentes. Estas lentas criaturas se esconden principalmente en las aguas profundas y fr\u00edas de los oc\u00e9anos Atl\u00e1ntico Norte y \u00c1rtico, y son los \u00fanicos tiburones que soportan las g\u00e9lidas temperaturas durante todo el a\u00f1o. Algunos ejemplares de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/","og_site_name":"Noticias","article_published_time":"2024-12-14T02:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/"},"author":{"name":"","@id":""},"headline":"El vertebrado m\u00e1s longevo podr\u00eda ofrecer pistas para alargar la vida humana, afirman los cient\u00edficos","datePublished":"2024-12-14T02:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/"},"wordCount":1862,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/","url":"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/","name":"El vertebrado m\u00e1s longevo podr\u00eda ofrecer pistas para alargar la vida humana, afirman los cient\u00edficos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-12-14T02:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El vertebrado m\u00e1s longevo podr\u00eda ofrecer pistas para alargar la vida humana, afirman los cient\u00edficos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El vertebrado m\u00e1s longevo podr\u00eda ofrecer pistas para alargar la vida humana, afirman los cient\u00edficos","url":"http:\/\/noticiasya.com\/laredo\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2024\/12\/13\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-12-14T02:03:42Z","datePublished":"2024-12-14T02:03:42Z","dateModified":"2024-12-14T02:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El vertebrado m\\u00e1s longevo podr\\u00eda ofrecer pistas para alargar la vida humana, afirman los cient\\u00edficos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/13\\\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2024\\\/12\\\/13\\\/tiburon-groenlandia-vertebrado-longevo-pistas-vida-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-12-14T02:03:42Z\",\"datePublished\":\"2024-12-14T02:03:42Z\",\"dateModified\":\"2024-12-14T02:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452511,"url":"https:\/\/noticiasya.com\/laredo\/2024\/09\/07\/tiburon-vigilada-cientificos-devorada-depredador-trax\/","url_meta":{"origin":1456584,"position":0},"title":"Una tibur\u00f3n en gestaci\u00f3n fue marcada y vigilada por 5 meses, y luego desapareci\u00f3. Cient\u00edficos averiguaron lo que pas\u00f3","author":"","date":"septiembre 7, 2024","format":false,"excerpt":"(CNN) -- Cuando un grupo de cient\u00edficos colocaron una marca a una hembra de tibur\u00f3n marrajo sardinero en octubre de 2020 para conocer mejor el h\u00e1bitat de esta criatura, no esperaban que el rastreador captara pruebas de c\u00f3mo los tiburones grandes se cazan unos a otros.Pero cuando el rastreador registr\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446188,"url":"https:\/\/noticiasya.com\/laredo\/2024\/03\/02\/orca-solitaria-tiburon-blanco-cientificos-cambio-ecologico-trax\/","url_meta":{"origin":1456584,"position":1},"title":"Una orca solitaria mat\u00f3 a un tibur\u00f3n blanco en menos de dos minutos. Los cient\u00edficos dicen que podr\u00eda indicar un cambio ecol\u00f3gico","author":"","date":"marzo 2, 2024","format":false,"excerpt":"(CNN) -- Un par de orcas que trabajan en conjunto estuvieron matando tiburones blancos a lo largo de un tramo de la costa sudafricana desde al menos 2017, saqueando los h\u00edgados ricos en nutrientes de los tiburones y descartando el resto.Los cient\u00edficos estuvieron tratando de encontrarle sentido al enfoque de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446418,"url":"https:\/\/noticiasya.com\/laredo\/2024\/03\/04\/orca-solitaria-tiburon-blanco-cientificos-cambio-ecologico-trax-2\/","url_meta":{"origin":1456584,"position":2},"title":"Una orca solitaria mat\u00f3 a un tibur\u00f3n blanco en menos de dos minutos. Los cient\u00edficos dicen que podr\u00eda indicar un cambio ecol\u00f3gico","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) -- Un par de orcas que trabajan en conjunto estuvieron matando tiburones blancos a lo largo de un tramo de la costa sudafricana desde al menos 2017, saqueando los h\u00edgados ricos en nutrientes de los tiburones y descartando el resto.Los cient\u00edficos estuvieron tratando de encontrarle sentido al enfoque de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458183,"url":"https:\/\/noticiasya.com\/laredo\/2025\/02\/03\/tiburon-bebe-nace-acuario-hembras-trax\/","url_meta":{"origin":1456584,"position":3},"title":"Un tibur\u00f3n beb\u00e9 nace misteriosamente en un acuario que solo alberga hembras","author":"","date":"febrero 3, 2025","format":false,"excerpt":"La llegada de un tibur\u00f3n globo beb\u00e9 a un acuario de Louisiana ha causado una gran expectaci\u00f3n, despu\u00e9s de que el huevo eclosionara a pesar de que no parece que haya habido ning\u00fan tibur\u00f3n macho involucrado.La cr\u00eda de tibur\u00f3n Yoko naci\u00f3 a principios de enero, seg\u00fan el acuario de Shreveport,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451139,"url":"https:\/\/noticiasya.com\/laredo\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/","url_meta":{"origin":1456584,"position":4},"title":"El f\u00f3sil de un antiguo tibur\u00f3n de la era de los dinosaurios resuelve un misterio de siglos","author":"","date":"julio 15, 2024","format":false,"excerpt":"(CNN) --\u00a0Durante el per\u00edodo Cret\u00e1cico, un g\u00e9nero de tiburones navegaba por el mar con hileras de dientes inusuales. Estos dientes, en su mayor\u00eda grandes y redondeados, no ten\u00edan como funci\u00f3n cortar a sus presas, sino triturar criaturas con caparaz\u00f3n.Sin embargo, desde su descubrimiento en el siglo XVIII, los cient\u00edficos han\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444735,"url":"https:\/\/noticiasya.com\/laredo\/2024\/02\/01\/investigadores-reportan-el-primer-avistamiento-de-un-tiburon-blanco-recien-nacido\/","url_meta":{"origin":1456584,"position":5},"title":"Investigadores reportan el primer avistamiento de un tibur\u00f3n blanco reci\u00e9n nacido","author":"","date":"febrero 1, 2024","format":false,"excerpt":"(CNN) -- Im\u00e1genes tomadas con drones frente a la costa del sur de California pueden haber revelado el primer vistazo de un tibur\u00f3n blanco reci\u00e9n nacido en estado salvaje.El tibur\u00f3n blanco, de 1,5 metros de largo fue avistado el 9 de julio de 2023, a 400 metros de la costa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1456584"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1456584\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1456584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1456584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1456584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}