{"id":1457769,"date":"2025-01-22T11:03:52","date_gmt":"2025-01-22T19:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/"},"modified":"2025-01-22T11:03:52","modified_gmt":"2025-01-22T19:03:52","slug":"marco-rubio-prioridades-departamento-estado-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/","title":{"rendered":"Marco Rubio establece prioridades y misi\u00f3n del Departamento de Estado"},"content":{"rendered":"<p>El flamante secretario de Estado de EE.UU., Marco Rubio, comparti\u00f3 este mi\u00e9rcoles las prioridades que abordar\u00e1 el Departamento de Estado, entre las que incluyen frenar la migraci\u00f3n masiva, eliminar los requisitos de <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/21\/que-es-dei-y-por-que-hay-division-en-estados-unidos-trax\">diversidad, equidad, igualdad y accesibilidad (DEIA)<\/a> y detener la censura y la supresi\u00f3n de informaci\u00f3n.<\/p>\n<p>\u201cDebemos frenar la migraci\u00f3n masiva y asegurar nuestras fronteras. El Departamento de Estado ya no emprender\u00e1 ninguna actividad que facilite o fomente la migraci\u00f3n masiva. Nuestras relaciones diplom\u00e1ticas con otros pa\u00edses, particularmente en el hemisferio occidental, priorizar\u00e1n la seguridad de las fronteras de Estados Unidos, detener la migraci\u00f3n ilegal y desestabilizadora y negociar la repatriaci\u00f3n de inmigrantes ilegales\u201d, dijo Rubio en un comunicado.<\/p>\n<p>Luego destac\u00f3 sus planes para recompensar el desempe\u00f1o y el m\u00e9rito, mientras lleva a cabo el decreto de Trump que elimina los requisitos, programas y oficinas de \u201cDEIA\u201d en todo el gobierno.<\/p>\n<p>Rubio se comprometi\u00f3 a poner fin a la censura y la supresi\u00f3n de informaci\u00f3n, y dijo en la declaraci\u00f3n: \u201cEl Departamento de Estado que dirijo apoyar\u00e1 y defender\u00e1 los derechos de los estadounidenses a la libertad de expresi\u00f3n, poniendo fin a cualquier programa que de alguna manera conduzca a la censura del pueblo estadounidense. \u201c<\/p>\n<p>Tambi\u00e9n expuso entre sus prioridades la eliminaci\u00f3n de \u201cnuestro enfoque en causas pol\u00edticas y culturales que son divisivas en el pa\u00eds y profundamente impopulares en el extranjero\u201d y \u201caprovechar nuestras fortalezas y acabar con las pol\u00edticas clim\u00e1ticas que debilitan a Estados Unidos\u201d.<\/p>\n<p>Rubio, quien ha sido senador de Estados Unidos durante m\u00e1s de una d\u00e9cada, dijo que Trump le dio \u201cuna direcci\u00f3n clara para colocar nuestro inter\u00e9s nacional central como la misi\u00f3n rectora de la pol\u00edtica exterior estadounidense\u201d.<\/p>\n<p>Fue <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/21\/eeuu\/marco-rubio-juramenta-secretario-estado-trax\">ratificado como secretario de Estado<\/a> este lunes en una votaci\u00f3n abrumadoramente bipartidista (99 a 0, sin que ning\u00fan senador votara en contra de la nominaci\u00f3n). La confirmaci\u00f3n marc\u00f3 el primer cargo de alto nivel del gabinete de la nueva administraci\u00f3n en ser aprobado por la c\u00e1mara.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El flamante secretario de Estado de EE.UU., Marco Rubio, comparti\u00f3 este mi\u00e9rcoles las prioridades que abordar\u00e1 el Departamento de Estado, entre las que incluyen frenar la migraci\u00f3n masiva, eliminar los requisitos de diversidad, equidad, igualdad y accesibilidad (DEIA) y detener la censura y la supresi\u00f3n de informaci\u00f3n. \u201cDebemos frenar la migraci\u00f3n masiva y asegurar nuestras [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457769","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marco Rubio establece prioridades y misi\u00f3n del Departamento de Estado - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marco Rubio establece prioridades y misi\u00f3n del Departamento de Estado - Noticias\" \/>\n<meta property=\"og:description\" content=\"El flamante secretario de Estado de EE.UU., Marco Rubio, comparti\u00f3 este mi\u00e9rcoles las prioridades que abordar\u00e1 el Departamento de Estado, entre las que incluyen frenar la migraci\u00f3n masiva, eliminar los requisitos de diversidad, equidad, igualdad y accesibilidad (DEIA) y detener la censura y la supresi\u00f3n de informaci\u00f3n. \u201cDebemos frenar la migraci\u00f3n masiva y asegurar nuestras [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-22T19:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Marco Rubio establece prioridades y misi\u00f3n del Departamento de Estado\",\"datePublished\":\"2025-01-22T19:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/\"},\"wordCount\":382,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/\",\"name\":\"Marco Rubio establece prioridades y misi\u00f3n del Departamento de Estado - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-22T19:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marco Rubio establece prioridades y misi\u00f3n del Departamento de Estado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marco Rubio establece prioridades y misi\u00f3n del Departamento de Estado - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Marco Rubio establece prioridades y misi\u00f3n del Departamento de Estado - Noticias","og_description":"El flamante secretario de Estado de EE.UU., Marco Rubio, comparti\u00f3 este mi\u00e9rcoles las prioridades que abordar\u00e1 el Departamento de Estado, entre las que incluyen frenar la migraci\u00f3n masiva, eliminar los requisitos de diversidad, equidad, igualdad y accesibilidad (DEIA) y detener la censura y la supresi\u00f3n de informaci\u00f3n. \u201cDebemos frenar la migraci\u00f3n masiva y asegurar nuestras [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-22T19:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/"},"author":{"name":"","@id":""},"headline":"Marco Rubio establece prioridades y misi\u00f3n del Departamento de Estado","datePublished":"2025-01-22T19:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/"},"wordCount":382,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/","name":"Marco Rubio establece prioridades y misi\u00f3n del Departamento de Estado - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-22T19:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Marco Rubio establece prioridades y misi\u00f3n del Departamento de Estado"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Marco Rubio establece prioridades y misi\u00f3n del Departamento de Estado","url":"http:\/\/noticiasya.com\/laredo\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/01\/22\/marco-rubio-prioridades-departamento-estado-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-22T19:03:52Z","datePublished":"2025-01-22T19:03:52Z","dateModified":"2025-01-22T19:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Marco Rubio establece prioridades y misi\\u00f3n del Departamento de Estado\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/01\\\/22\\\/marco-rubio-prioridades-departamento-estado-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/01\\\/22\\\/marco-rubio-prioridades-departamento-estado-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-22T19:03:52Z\",\"datePublished\":\"2025-01-22T19:03:52Z\",\"dateModified\":\"2025-01-22T19:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458716,"url":"https:\/\/noticiasya.com\/laredo\/2025\/02\/13\/rubio-de-la-fuente-conversan-acciones-frontera-mexico-orix\/","url_meta":{"origin":1457769,"position":0},"title":"Rubio y De la Fuente hablan sobre &#171;acciones conjuntas para asegurar la frontera&#187; con M\u00e9xico, informa Departamento de Estado","author":"","date":"febrero 13, 2025","format":false,"excerpt":"El secretario de Estado de EE.UU., Marco Rubio, mantuvo una conversaci\u00f3n este mi\u00e9rcoles con el secretario de Relaciones Exteriores de M\u00e9xico, Juan Ram\u00f3n de la Fuente, para analizar \u201cacciones conjuntas para asegurar la frontera\u201d entre los dos pa\u00edses, inform\u00f3 este jueves el Departamento de Estado a trav\u00e9s de un comunicado.Estas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458106,"url":"https:\/\/noticiasya.com\/laredo\/2025\/02\/01\/rubio-centroamerica-gobierno-trump-intenta-frenar-migracion-trax\/","url_meta":{"origin":1457769,"position":1},"title":"Marco Rubio se dirige a Centroam\u00e9rica mientras el Gobierno de Trump intenta frenar la migraci\u00f3n a EE.UU.","author":"","date":"febrero 1, 2025","format":false,"excerpt":"El secretario de Estado de Estados Unidos, Marco Rubio, llega a Panam\u00e1 este s\u00e1bado en su primer viaje como m\u00e1ximo diplom\u00e1tico de EE.UU., un viaje que pondr\u00e1 a prueba si su diplomacia puede construir sobre el enfoque beligerante y transaccional de la pol\u00edtica exterior \u201cAmerican First\u201d del presidente del pa\u00eds,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446927,"url":"https:\/\/noticiasya.com\/laredo\/2024\/03\/13\/gobierno-biden-guantanamo-inmigrantes-haitianos-trax\/","url_meta":{"origin":1457769,"position":2},"title":"El Gobierno de Biden eval\u00faa utilizar Guant\u00e1namo ante la posible llegada de inmigrantes haitianos","author":"","date":"marzo 13, 2024","format":false,"excerpt":"(CNN) -- El Gobierno del presidente Joe Biden eval\u00faa la posibilidad de utilizar la Bah\u00eda de Guant\u00e1namo para procesar a los posibles migrantes haitianos que lleguen, ante la preocupaci\u00f3n de un \u00e9xodo masivo en medio del la ola de violencia que atraviesa el pa\u00eds, seg\u00fan un funcionario estadounidense.Desde hace a\u00f1os,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458251,"url":"https:\/\/noticiasya.com\/laredo\/2025\/02\/04\/republica-dominicana-eeuu-fondos-usaid-mision-haiti-orix\/","url_meta":{"origin":1457769,"position":3},"title":"Rep\u00fablica Dominicana espera que EE.UU. levante a la brevedad fondos suspendidos de USAID para misi\u00f3n multinacional en Hait\u00ed","author":"","date":"febrero 4, 2025","format":false,"excerpt":"El Gobierno de Rep\u00fablica Dominicana espera que Estados Unidos levante a la brevedad la suspensi\u00f3n de fondos para la Misi\u00f3n Multinacional de Apoyo a la Seguridad en Hait\u00ed (MSS, por sus siglas en ingl\u00e9s), a trav\u00e9s de la Agencia para el Desarrollo Internacional (USAID, por sus siglas en ingl\u00e9s), dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466053,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/01\/ecuador-300-deportados-anio-eeuu-visita-rubio-orix\/","url_meta":{"origin":1457769,"position":4},"title":"Ecuador se prepara para recibir 300 deportados al a\u00f1o desde EE.UU. sin antecedentes judiciales","author":"","date":"septiembre 1, 2025","format":false,"excerpt":"A tan solo horas de que inicie la visita oficial a Quito del secretario de Estado de Estados Unidos, Marco Rubio, la canciller de Ecuador, Gabriela Sommerfeld, anunci\u00f3 este lunes que uno de los acuerdos que el pa\u00eds suscribir\u00e1 con el representante estadounidense ser\u00e1 para recibir hasta 300 personas deportadas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470556,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/28\/marco-rubio-fuerza-gobierno-delcy-venezuela-trax\/","url_meta":{"origin":1457769,"position":5},"title":"Rubio dice que EE.UU. est\u00e1 preparado para usar la fuerza si Gobierno encargado de Venezuela se resiste a cooperar","author":"","date":"enero 28, 2026","format":false,"excerpt":"El secretario de Estado de EE.UU., Marco Rubio, planea amenazar con el uso de la fuerza \u201cpara garantizar la m\u00e1xima cooperaci\u00f3n\u201d del Gobierno encargado de Venezuela cuando testifique p\u00fablicamente por primera vez desde la operaci\u00f3n militar para capturar y derrocar a Nicol\u00e1s Maduro, llevada a cabo a principios de enero.\u201cSeguiremos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1457769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1457769"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1457769\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1457769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1457769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1457769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}