{"id":1457799,"date":"2025-01-23T05:03:48","date_gmt":"2025-01-23T13:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/"},"modified":"2025-01-23T05:03:48","modified_gmt":"2025-01-23T13:03:48","slug":"kremlin-amenaza-trump-aplicar-sanciones-rusia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/","title":{"rendered":"El Kremlin dice que no hay nada &#171;fundamentalmente nuevo&#187; en la amenaza de Trump de aplicar sanciones a Rusia"},"content":{"rendered":"<p>Mosc\u00fa rest\u00f3 importancia a la <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/22\/mundo\/trump-sanciones-aranceles-rusia-trax\">amenaza <\/a>del presidente de EE.UU., Donald Trump, de aplicar m\u00e1s \u201cimpuestos, aranceles y sanciones\u201d a Rusia hasta que termine su guerra en Ucrania, diciendo que no hay nada \u201cfundamentalmente nuevo\u201d en sus comentarios.<\/p>\n<p>El portavoz del Kremlin, Dmitry Peskov, dijo que durante el primer mandato de Trump, el presidente estadounidense \u201crecurri\u00f3 con mayor frecuencia a m\u00e9todos de sanciones\u201d, y agreg\u00f3 que \u201ca \u00e9l (el presidente Trump) le gustan estos m\u00e9todos\u201d.<\/p>\n<p>Dijo que Mosc\u00fa est\u00e1 preparada para un di\u00e1logo igualitario y respetuoso con Estados Unidos, pero a\u00fan no ha visto una intenci\u00f3n similar de Washington.<\/p>\n<p>\u201cEstamos siguiendo de cerca toda la ret\u00f3rica y las declaraciones. Tomamos nota cuidadosamente de cada matiz y seguimos listos para el di\u00e1logo. El presidente (Vladimir) Putin ha expresado repetidamente su disposici\u00f3n a un di\u00e1logo igualitario y mutuamente respetuoso, como vimos entre los dos presidentes durante la primera presidencia de Trump\u201d, dijo Peskov este jueves.<\/p>\n<p>A\u00f1adi\u00f3: \u201cEstamos esperando se\u00f1ales que a\u00fan no hemos recibido\u201d.<\/p>\n<p>Anteriormente, el diputado ruso y presentador de la televisi\u00f3n estatal Yevgeny Popov desestim\u00f3 las amenazas de Trump contra Rusia, haciendo hincapi\u00e9 en la soberan\u00eda y la resistencia del pa\u00eds. Afirm\u00f3 que ni Trump ni ning\u00fan l\u00edder occidental pueden dictar el resultado de la guerra, afirmando que Rusia lograr\u00e1 sus objetivos \u201cya sea en el campo de batalla o en la mesa de negociaciones\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mosc\u00fa rest\u00f3 importancia a la amenaza del presidente de EE.UU., Donald Trump, de aplicar m\u00e1s \u201cimpuestos, aranceles y sanciones\u201d a Rusia hasta que termine su guerra en Ucrania, diciendo que no hay nada \u201cfundamentalmente nuevo\u201d en sus comentarios. El portavoz del Kremlin, Dmitry Peskov, dijo que durante el primer mandato de Trump, el presidente estadounidense [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457799","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Kremlin dice que no hay nada &quot;fundamentalmente nuevo&quot; en la amenaza de Trump de aplicar sanciones a Rusia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Kremlin dice que no hay nada &quot;fundamentalmente nuevo&quot; en la amenaza de Trump de aplicar sanciones a Rusia - Noticias\" \/>\n<meta property=\"og:description\" content=\"Mosc\u00fa rest\u00f3 importancia a la amenaza del presidente de EE.UU., Donald Trump, de aplicar m\u00e1s \u201cimpuestos, aranceles y sanciones\u201d a Rusia hasta que termine su guerra en Ucrania, diciendo que no hay nada \u201cfundamentalmente nuevo\u201d en sus comentarios. El portavoz del Kremlin, Dmitry Peskov, dijo que durante el primer mandato de Trump, el presidente estadounidense [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-23T13:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Kremlin dice que no hay nada &#171;fundamentalmente nuevo&#187; en la amenaza de Trump de aplicar sanciones a Rusia\",\"datePublished\":\"2025-01-23T13:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/\"},\"wordCount\":279,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/\",\"name\":\"El Kremlin dice que no hay nada \\\"fundamentalmente nuevo\\\" en la amenaza de Trump de aplicar sanciones a Rusia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-23T13:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Kremlin dice que no hay nada &#171;fundamentalmente nuevo&#187; en la amenaza de Trump de aplicar sanciones a Rusia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Kremlin dice que no hay nada \"fundamentalmente nuevo\" en la amenaza de Trump de aplicar sanciones a Rusia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Kremlin dice que no hay nada \"fundamentalmente nuevo\" en la amenaza de Trump de aplicar sanciones a Rusia - Noticias","og_description":"Mosc\u00fa rest\u00f3 importancia a la amenaza del presidente de EE.UU., Donald Trump, de aplicar m\u00e1s \u201cimpuestos, aranceles y sanciones\u201d a Rusia hasta que termine su guerra en Ucrania, diciendo que no hay nada \u201cfundamentalmente nuevo\u201d en sus comentarios. El portavoz del Kremlin, Dmitry Peskov, dijo que durante el primer mandato de Trump, el presidente estadounidense [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-23T13:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/"},"author":{"name":"","@id":""},"headline":"El Kremlin dice que no hay nada &#171;fundamentalmente nuevo&#187; en la amenaza de Trump de aplicar sanciones a Rusia","datePublished":"2025-01-23T13:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/"},"wordCount":279,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/","name":"El Kremlin dice que no hay nada \"fundamentalmente nuevo\" en la amenaza de Trump de aplicar sanciones a Rusia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-23T13:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Kremlin dice que no hay nada &#171;fundamentalmente nuevo&#187; en la amenaza de Trump de aplicar sanciones a Rusia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Kremlin dice que no hay nada &#171;fundamentalmente nuevo&#187; en la amenaza de Trump de aplicar sanciones a Rusia","url":"http:\/\/noticiasya.com\/laredo\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/01\/23\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-23T13:03:48Z","datePublished":"2025-01-23T13:03:48Z","dateModified":"2025-01-23T13:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Kremlin dice que no hay nada &#171;fundamentalmente nuevo&#187; en la amenaza de Trump de aplicar sanciones a Rusia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/01\\\/23\\\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/01\\\/23\\\/kremlin-amenaza-trump-aplicar-sanciones-rusia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-23T13:03:48Z\",\"datePublished\":\"2025-01-23T13:03:48Z\",\"dateModified\":\"2025-01-23T13:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465240,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/08\/plazo-trump-rusia-posible-cumbre-putin-trax\/","url_meta":{"origin":1457799,"position":0},"title":"A medida que se acerca el plazo de Trump para Rusia, la Casa Blanca se prepara para una posible cumbre con Putin","author":"","date":"agosto 8, 2025","format":false,"excerpt":"La fecha l\u00edmite del presidente Donald Trump para que Rusia ponga fin a su guerra en Ucrania o sufra un severo castigo econ\u00f3mico vence este viernes, pero no est\u00e1 claro c\u00f3mo planea proceder el mandatario en medio de nuevos esfuerzos hacia una cumbre con Vladimir Putin y delicadas negociaciones comerciales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466407,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/12\/rusia-ucrania-trump-conversaciones-paz-no-avanzan-trax\/","url_meta":{"origin":1457799,"position":1},"title":"Rusia acaba de decir lo que Ucrania lleva meses intentando comunicarle a Trump: las conversaciones de paz no avanzan","author":"","date":"septiembre 12, 2025","format":false,"excerpt":"Las conversaciones de paz entre Rusia y Ucrania est\u00e1n \u201cm\u00e1s en pausa\u201d que activas, dijo el Kremlin este viernes, en un reconocimiento que confirma lo que Ucrania lleva meses advirtiendo: las negociaciones est\u00e1n fracasando a pesar del impulso del presidente de Estados Unidos, Donald Trump.\u201cLos canales de comunicaci\u00f3n existen y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458271,"url":"https:\/\/noticiasya.com\/laredo\/2025\/02\/05\/kremlin-estados-unidos-conversaciones-ucrania-trax\/","url_meta":{"origin":1457799,"position":2},"title":"El Kremlin confirma que Estados Unidos y Rusia han &#171;intensificado&#187; las conversaciones sobre Ucrania","author":"","date":"febrero 5, 2025","format":false,"excerpt":"El gobierno de Rusia confirm\u00f3 por primera vez que se est\u00e1n llevando a cabo conversaciones sobre Ucrania entre funcionarios estadounidenses y rusos.El portavoz del Kremlin, Dmitry Peskov, declar\u00f3 este mi\u00e9rcoles: \u201cDe hecho, hay contactos entre departamentos individuales, y se han intensificado recientemente\u201d. Se neg\u00f3 a proporcionar m\u00e1s detalles.Los comentarios de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462879,"url":"https:\/\/noticiasya.com\/laredo\/2025\/05\/27\/trump-considera-nuevas-sanciones-rusia-trax\/","url_meta":{"origin":1457799,"position":3},"title":"Trump considera nuevas sanciones contra Rusia mientras crece su furia contra Putin","author":"","date":"mayo 27, 2025","format":false,"excerpt":"Cuando el presidente Donald Trump habl\u00f3 la semana pasada por tel\u00e9fono con Vladimir Putin, el l\u00edder ruso se comprometi\u00f3 a redactar y enviar lo que describi\u00f3 como un \u201cmemorando de paz\u201d en los pr\u00f3ximos d\u00edas, detallando los requisitos rusos para un alto el fuego con Ucrania, seg\u00fan un funcionario estadounidense\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465170,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/06\/witkoff-putin-amenaza-sanciones-trump-trax\/","url_meta":{"origin":1457799,"position":4},"title":"Witkoff se re\u00fane con Putin ante la amenaza de sanciones de Trump","author":"","date":"agosto 6, 2025","format":false,"excerpt":"El enviado exterior de confianza del presidente Donald Trump, Steve Witkoff, se re\u00fane este mi\u00e9rcoles con el presidente de Rusia, Vladimir Putin, despu\u00e9s de que el Kremlin solicitara la visita de diplom\u00e1tico en un \u00faltimo esfuerzo por evitar las nuevas sanciones que el republicano ha amenazado con imponer esta semana,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451193,"url":"https:\/\/noticiasya.com\/laredo\/2024\/07\/17\/kremlin-trump-nada-particularmente-bueno-para-rusia-dialogo-trax\/","url_meta":{"origin":1457799,"position":5},"title":"El Kremlin dice que el gobierno de Trump no represent\u00f3 &#171;nada particularmente bueno&#187; para Rusia, pero que existi\u00f3 di\u00e1logo","author":"","date":"julio 17, 2024","format":false,"excerpt":"(CNN) -- El Kremlin dijo este mi\u00e9rcoles que no ocurri\u00f3 nada bueno para Rusia durante la presidencia de Donald Trump, pero que hubo un aspecto positivo en el di\u00e1logo continuo entre Washington y Mosc\u00fa durante la administraci\u00f3n anterior.\"Ustedes saben que bajo Trump no se hizo nada particularmente bueno para Rusia;\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1457799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1457799"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1457799\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1457799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1457799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1457799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}