{"id":1457802,"date":"2025-01-23T07:03:39","date_gmt":"2025-01-23T15:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/"},"modified":"2025-01-23T07:03:39","modified_gmt":"2025-01-23T15:03:39","slug":"inmigracion-hospitales-no-rechazaran-pacientes-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/","title":{"rendered":"Mientras los estados discrepan en materia de inmigraci\u00f3n, los hospitales dicen que no rechazar\u00e1n a los pacientes"},"content":{"rendered":"<p>Autoridades de California <a href=\"https:\/\/oag.ca.gov\/sites\/all\/files\/agweb\/pdfs\/immigration\/healthcare-guidance.pdf\">est\u00e1n aconsejando<\/a> a los proveedores de atenci\u00f3n m\u00e9dica que no escriban el estatus migratorio de los pacientes en las facturas y los registros m\u00e9dicos y les dijeron que no tienen que ayudar a los agentes federales en las detenciones. Algunos hospitales y cl\u00ednicas de Massachusetts est\u00e1n publicando avisos sobre derechos de privacidad en las salas de emergencia y de espera en espa\u00f1ol y otros idiomas.<\/p>\n<p>Mientras tanto, Florida y Texas est\u00e1n exigiendo a los centros de atenci\u00f3n m\u00e9dica que pregunten el estatus migratorio de los pacientes y calculen el costo para los contribuyentes de brindar atenci\u00f3n a inmigrantes que viven en Estados Unidos sin autorizaci\u00f3n.<\/p>\n<p>Donald Trump regres\u00f3 a la Casa Blanca y declar\u00f3 una <a href=\"https:\/\/www.whitehouse.gov\/presidential-actions\/2025\/01\/declaring-a-national-emergency-at-the-southern-border-of-the-united-states\/\">emergencia nacional<\/a> en la frontera entre Estados Unidos y M\u00e9xico, <a href=\"https:\/\/www.whitehouse.gov\/presidential-actions\/2025\/01\/realigning-the-united-states-refugee-admissions-program\/\">suspendi\u00f3 las admisiones de refugiados<\/a> y <a href=\"https:\/\/www.whitehouse.gov\/presidential-actions\/2025\/01\/protecting-the-meaning-and-value-of-american-citizenship\/\">amenaz\u00f3 con retirar la ciudadan\u00eda por derecho de nacimiento<\/a>, o la pol\u00edtica de otorgar ciudadan\u00eda estadounidense a cualquier persona nacida en Estados Unidos. Mientras comienza a llevar a cabo la \u201d<a href=\"https:\/\/youtube.com\/shorts\/YJTHjky5tYI?feature=shared\">operaci\u00f3n de deportaci\u00f3n m\u00e1s grande<\/a>\u201d en la historia de la naci\u00f3n, los estados han ofrecido pautas marcadamente diferentes a los hospitales, cl\u00ednicas comunitarias y otras instalaciones de salud para pacientes inmigrantes.<\/p>\n<p>Trump tambi\u00e9n ha <a href=\"https:\/\/www.dhs.gov\/news\/2025\/01\/21\/statement-dhs-spokesperson-directives-expanding-law-enforcement-and-ending-abuse\">anulado una pol\u00edtica de larga data<\/a> de no arrestar a personas sin estatus legal en lugares sensibles o cerca de ellos, como escuelas, iglesias y hospitales. <a href=\"https:\/\/www.congress.gov\/bill\/118th-congress\/house-bill\/5166\">Una propuesta<\/a> para formalizar esas protecciones fracas\u00f3 en el Congreso, en 2023.<\/p>\n<p>Pero, independientemente de las directrices que emitan los estados, los hospitales de todo Estados Unidos afirman que no se rechazar\u00e1 a los pacientes debido a su estatus migratorio. \u201cNada de esto cambia la atenci\u00f3n que reciben los pacientes\u201d, dijo <a href=\"https:\/\/www.tha.org\/author\/cwilliams\/\">Carrie Williams<\/a>, portavoz de la Asociaci\u00f3n de Hospitales de Texas, que representa a los hospitales y sistemas de atenci\u00f3n m\u00e9dica del estado. \u201cNo queremos que las personas desatiendan los cuidados y empeoren su situaci\u00f3n porque est\u00e1n preocupadas por cuestiones de inmigraci\u00f3n\u201d.<\/p>\n<p>Durante el primer mandato de Trump, los agentes de inmigraci\u00f3n arrestaron a personas que recib\u00edan atenci\u00f3n de emergencia en hospitales y a un ni\u00f1o durante un <a href=\"https:\/\/www.nytimes.com\/2017\/10\/25\/us\/girl-cerebral-palsy-detained-immigration.html\">traslado en ambulancia<\/a>. En Texas, los agentes de inmigraci\u00f3n arrestaron a una <a href=\"http:\/\/www.latimes.com\/nation\/la-na-hospital-seizure-20170223-story.html\">mujer que esperaba una cirug\u00eda cerebral<\/a> en un hospital de Fort Worth. En Portland, Oregon, los agentes <a href=\"https:\/\/www.wweek.com\/news\/courts\/2017\/10\/31\/ice-arrested-an-undocumented-immigrant-just-outside-a-portland-hospital\/\">arrestaron a un joven<\/a> que sal\u00eda de un hospital y, en San Bernardino, California, una mujer <a href=\"https:\/\/www.theguardian.com\/us-news\/2018\/aug\/18\/california-man-pregnant-wife-ice-immigration\">condujo hasta el hospital<\/a> para dar a luz despu\u00e9s de que su marido fuera arrestado en una gasolinera.<\/p>\n<p>Se estima que cerca de 11 millones de inmigrantes viven en Estados Unidos sin autorizaci\u00f3n, y <a href=\"https:\/\/www.pewresearch.org\/short-reads\/2024\/07\/22\/what-we-know-about-unauthorized-immigrants-living-in-the-us\/\">la mayor parte se concentra<\/a> en California, Texas, Florida, Nueva York, Nueva Jersey e Illinois, seg\u00fan el Pew Research Center.<\/p>\n<p>La mitad de los adultos inmigrantes que probablemente no tengan autorizaci\u00f3n no tienen seguro, en comparaci\u00f3n con menos de 1 de cada 10 ciudadanos, seg\u00fan la <a href=\"https:\/\/www.kff.org\/racial-equity-and-health-policy\/issue-brief\/health-and-health-care-experiences-of-immigrants-the-2023-kff-la-times-survey-of-immigrants\/\">Encuesta de Inmigrantes de KFF-Los Angeles Times de 2023<\/a>, la encuesta no gubernamental m\u00e1s grande sobre inmigrantes en EE.UU. hasta la fecha. Si bien algunos estados est\u00e1n destacando los gastos de atenci\u00f3n m\u00e9dica en los que incurren los inmigrantes, un <a href=\"https:\/\/www.kff.org\/racial-equity-and-health-policy\/issue-brief\/immigrants-have-lower-health-care-expenditures-than-their-u-s-born-counterparts\/\">informe de KFF<\/a> se\u00f1al\u00f3 que los inmigrantes contribuyen m\u00e1s al sistema a trav\u00e9s de las primas de seguro m\u00e9dico y los impuestos de lo que gastan. Los inmigrantes tambi\u00e9n tienen costos de atenci\u00f3n m\u00e9dica m\u00e1s bajos que los ciudadanos.<\/p>\n<p>Algunos proveedores de servicios de salud temen que los agentes de Control de Inmigraci\u00f3n y de Aduanas interrumpan su trabajo en los centros de salud y provoquen que los pacientes, en particular los ni\u00f1os, no reciban atenci\u00f3n m\u00e9dica. En el primer d\u00eda de Trump, el presidente republicano emiti\u00f3 un decreto destinado a poner fin a la ciudadan\u00eda por derecho de nacimiento para los ni\u00f1os nacidos de un padre sin autorizaci\u00f3n legal o con una visa, lo que podr\u00eda dejarlos sin derecho a programas sociales y de salud federales. La orden fue impugnada de inmediato <a href=\"https:\/\/apnews.com\/article\/birthright-citizenship-trump-executive-order-immigrants-fc7dd75ba1fb0a10f56b2a85b92dbe53\">por los estados<\/a> y un <a href=\"https:\/\/www.aclu.org\/cases\/new-hampshire-indonesian-community-support-v-donald-j-trump?document=Complaint\">grupo de derechos civiles<\/a>.<\/p>\n<p>\u201cEst\u00e1n infundiendo miedo en personas que pueden postergar los cuidados m\u00e9dicos, que pueden quedarse sin atenci\u00f3n m\u00e9dica, cuyos hijos pueden no recibir las vacunas que necesitan, que pueden no recibir tratamiento para una infecci\u00f3n de o\u00eddo o una cirug\u00eda\u201d, dijo Minal Giri, pediatra y presidenta de la Iniciativa de Salud Infantil para Refugiados e Inmigrantes en el Cap\u00edtulo de Illinois de la Academia Estadounidense de Pediatr\u00eda.<\/p>\n<p>Una <a href=\"https:\/\/www.usf.edu\/arts-sciences\/centers\/iwrc\/documents\/report-sb-1718-final-nov2024.pdf\">encuesta reciente<\/a> realizada por el Centro de Investigaci\u00f3n sobre el Bienestar de los Inmigrantes de la Universidad del Sur de Florida revel\u00f3 que el 66% de los no ciudadanos manifestaron una mayor vacilaci\u00f3n a la hora de buscar atenci\u00f3n m\u00e9dica despu\u00e9s de que el gobernador de Florida, Ron DeSantis, firmara en 2023 <a href=\"https:\/\/www.flsenate.gov\/Session\/Bill\/2023\/1718\">una ley<\/a> que exige que los hospitales que aceptan Medicaid pregunten sobre el estatus legal de los pacientes. Esta cifra es del 27% entre los ciudadanos.<\/p>\n<p>\u201cRealmente me alarm\u00f3 ver c\u00f3mo esta ley hac\u00eda que la gente dudara en ir al m\u00e9dico, incluso frente a una emergencia\u201d, dijo <a href=\"https:\/\/iwbcollab.org\/about\/\">Liz Ventura Molina<\/a>, coautora de la encuesta y el informe.<\/p>\n<p>Al firmar la ley, DeSantis <a href=\"https:\/\/www.flgov.com\/eog\/news\/press\/2023\/governor-ron-desantis-signs-strongest-anti-illegal-immigration-legislation-country\">la promocion\u00f3<\/a> como \u201cla legislaci\u00f3n antiinmigraci\u00f3n ilegal m\u00e1s ambiciosa\u201d del pa\u00eds. Este mes, el gobernador republicano convoc\u00f3 a una sesi\u00f3n especial de la legislatura estatal para ayudar a apoyar la agenda de inmigraci\u00f3n de Trump.<\/p>\n<p>Jackson Health System, un proveedor de seguridad p\u00fablica en Miami, dijo en un comunicado que los informes trimestrales al estado no contienen informaci\u00f3n individual de los pacientes. \u201cNos adherimos a toda la cooperaci\u00f3n requerida con las agencias de aplicaci\u00f3n de la ley, incluido el ICE, como parte de cualquier investigaci\u00f3n criminal, entendiendo que las leyes de privacidad exigen que solo divulguemos informaci\u00f3n privada de los pacientes a trav\u00e9s de una orden judicial\u201d.<\/p>\n<p>En agosto, el gobernador de Texas, el republicano Greg Abbott, emiti\u00f3 un decreto similar a la ley de Florida para registrar los costos de atenci\u00f3n m\u00e9dica en que incurren los inmigrantes sin autorizaci\u00f3n legal. Se espera que todos los hospitales que reciben fondos de Medicaid o del Programa de Seguro M\u00e9dico para Ni\u00f1os comiencen a informar los datos al Departamento de Salud y Servicios Humanos de Texas en marzo.<\/p>\n<p>Incluso las ciudades controladas por los dem\u00f3cratas est\u00e1n caminando sobre una delgada l\u00ednea. El alcalde de la ciudad de Nueva York, Eric Adams, se reuni\u00f3 en diciembre con el nuevo \u201czar de la frontera\u201d de Trump, Tom Homan, y se comprometi\u00f3 a <a href=\"https:\/\/www.nyc.gov\/office-of-the-mayor\/news\/919-24\/mayor-adams-proposals-protect-longtime-new-yorkers-immigrant-families-repeat-\">expulsar a los inmigrantes<\/a> que hayan sido condenados por delitos graves y carezcan de estatus legal para permanecer en el pa\u00eds.<\/p>\n<p>Al mismo tiempo, Adams propuso una campa\u00f1a de concientizaci\u00f3n para que los inmigrantes y solicitantes de asilo sepan que pueden utilizar de forma segura los sistemas hospitalarios de la ciudad.<\/p>\n<p>Algunos estados est\u00e1n yendo m\u00e1s all\u00e1 y aconsejando a los centros de salud que hagan todo lo posible para proteger a los pacientes inmigrantes.<\/p>\n<p>En diciembre, el fiscal estatal de California, Rob Bonta, public\u00f3 un documento de 42 p\u00e1ginas en el que recomendaba a los proveedores evitar incluir el estatus migratorio de los pacientes en las facturas y los registros m\u00e9dicos. La gu\u00eda tambi\u00e9n enfatizaba que, si bien los proveedores no deben obstruir f\u00edsicamente a los agentes de inmigraci\u00f3n, no tienen obligaci\u00f3n de ayudar en un arresto.<\/p>\n<p>Seg\u00fan el documento, los centros de atenci\u00f3n de salud deben publicar informaci\u00f3n sobre el derecho de los pacientes a permanecer en silencio y se les anima a proporcionar a los pacientes informaci\u00f3n de contacto de grupos de ayuda legal \u201cen caso de que un padre sea detenido por las autoridades de inmigraci\u00f3n\u201d. Si es posible, dice, el centro debe designar un enlace de asuntos de inmigraci\u00f3n para ayudar a capacitar al personal y proporcionar asesoramiento no legal a las familias.<\/p>\n<p>\u201cNo podemos permitir que la maquinaria de deportaci\u00f3n de Trump cree una cultura de miedo y desconfianza que impida a los inmigrantes acceder a servicios p\u00fablicos vitales\u201d, dijo Bonta, dem\u00f3crata.<\/p>\n<p>Este martes, la administraci\u00f3n de Trump le orden\u00f3 al Departamento de Justicia que <a href=\"https:\/\/www.washingtonpost.com\/national-security\/2025\/01\/22\/justice-immigrantion-memo-sanctuary-cities\/\">investigara a los funcionarios estatales y locales<\/a> que no cooperaran con las autoridades migratorias. Durante el primer mandato de Trump, California limit\u00f3 la cooperaci\u00f3n con las autoridades federales tras alegar preocupaciones sobre la seguridad p\u00fablica y la confianza de la comunidad. El Departamento de Justicia, entonces bajo el mando de Jeff Sessions, <a href=\"https:\/\/www.justice.gov\/opa\/pr\/justice-department-files-preemption-lawsuit-against-state-california-stop-interference\">present\u00f3 una demanda para bloquear la ley<\/a>, pero el estado gan\u00f3 en un tribunal federal tras argumentar que los estados tienen la autoridad para decidir si se utilizan recursos locales para hacer cumplir la ley federal. La administraci\u00f3n de Trump apel\u00f3, pero la Corte Suprema rechaz\u00f3 la petici\u00f3n.<\/p>\n<p>Seg\u00fan la ley de California, los centros de salud estatales deben adoptar pol\u00edticas para limitar su participaci\u00f3n en la aplicaci\u00f3n de las leyes de inmigraci\u00f3n, y se alienta a las entidades privadas a seguir protocolos similares. David Simon, portavoz de la Asociaci\u00f3n de Hospitales de California, que representa a m\u00e1s de 400 hospitales, dijo que los miembros han incorporado dichas pol\u00edticas, lo que garantiza la privacidad de los pacientes.<\/p>\n<p>\u201cLos hospitales no llaman al ICE por los pacientes\u201d, dijo Simon.<\/p>\n<p>California se prepara para una nueva ronda de enfrentamientos con Trump. El gobernador Gavin Newsom y otros l\u00edderes dem\u00f3cratas del estado acordaron reservar US$ 50 millones para litigios y subvenciones a grupos inmigrantes sin fines de lucro.<\/p>\n<p>Los legisladores de Nueva Jersey est\u00e1n <a href=\"https:\/\/njleg.state.nj.us\/bill-search\/2024\/S3672\">considerando una ley<\/a> para limitar que los centros de atenci\u00f3n m\u00e9dica pregunten sobre el estatus migratorio de los pacientes. El proyecto de ley tambi\u00e9n exigir\u00eda que el fiscal general del estado establezca pol\u00edticas para los hospitales y los centros de atenci\u00f3n m\u00e9dica a fin de garantizar el acceso de los pacientes.<\/p>\n<p>En la ciudad de Nueva York, los administradores de los hospitales est\u00e1n instruyendo al personal a buscar la orientaci\u00f3n de un \u201cenlace de inmigraci\u00f3n\u201d si las autoridades de inmigraci\u00f3n se presentan, y a tomar fotos y videos de cualquier acci\u00f3n de cumplimiento si no pueden comunicarse con ellos primero. Tambi\u00e9n est\u00e1n disuadiendo al personal de ayudar activamente a una persona a esconderse del ICE. En Massachusetts, algunas cl\u00ednicas y hospitales est\u00e1n capacitando al personal sobre c\u00f3mo leer las \u00f3rdenes judiciales del ICE y planean exigir a los agentes del ICE que se identifiquen y presenten una orden judicial si quieren ingresar a un \u00e1rea privada.<\/p>\n<p>\u201cNo podemos estar apurados en este momento\u201d, dijo Altaf Saadi, neur\u00f3logo que codirige una cl\u00ednica para solicitantes de asilo en el Hospital General de Massachusetts. \u201cTenemos que prepararnos para estos escenarios de peor caso, y esperamos que no ocurran, pero tenemos que estar preparados\u201d.<\/p>\n<p><em>Este art\u00edculo fue producido por <\/em><a href=\"https:\/\/kffhealthnews.org\/about-us\/\"><em>KFF Health News<\/em><\/a><em>, una sala de prensa nacional que produce periodismo en profundidad sobre temas de salud y es uno de los principales programas operativos de <\/em><a href=\"https:\/\/www.kff.org\/about-us\/\"><em>KFF<\/em><\/a><em>, la fuente independiente de investigaci\u00f3n, encuestas y periodismo sobre pol\u00edticas de salud. KFF Health News es el editor de <\/em><a href=\"http:\/\/californiahealthline.org\/\"><em>California Healthline<\/em><\/a><em>, un servicio editorialmente independiente de la <\/em><a href=\"https:\/\/www.chcf.org\/\"><em>California Health Care Foundation<\/em><\/a><em>.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades de California est\u00e1n aconsejando a los proveedores de atenci\u00f3n m\u00e9dica que no escriban el estatus migratorio de los pacientes en las facturas y los registros m\u00e9dicos y les dijeron que no tienen que ayudar a los agentes federales en las detenciones. Algunos hospitales y cl\u00ednicas de Massachusetts est\u00e1n publicando avisos sobre derechos de privacidad [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1457802","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mientras los estados discrepan en materia de inmigraci\u00f3n, los hospitales dicen que no rechazar\u00e1n a los pacientes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mientras los estados discrepan en materia de inmigraci\u00f3n, los hospitales dicen que no rechazar\u00e1n a los pacientes - Noticias\" \/>\n<meta property=\"og:description\" content=\"Autoridades de California est\u00e1n aconsejando a los proveedores de atenci\u00f3n m\u00e9dica que no escriban el estatus migratorio de los pacientes en las facturas y los registros m\u00e9dicos y les dijeron que no tienen que ayudar a los agentes federales en las detenciones. Algunos hospitales y cl\u00ednicas de Massachusetts est\u00e1n publicando avisos sobre derechos de privacidad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-23T15:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mientras los estados discrepan en materia de inmigraci\u00f3n, los hospitales dicen que no rechazar\u00e1n a los pacientes\",\"datePublished\":\"2025-01-23T15:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/\"},\"wordCount\":1982,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/\",\"name\":\"Mientras los estados discrepan en materia de inmigraci\u00f3n, los hospitales dicen que no rechazar\u00e1n a los pacientes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-01-23T15:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mientras los estados discrepan en materia de inmigraci\u00f3n, los hospitales dicen que no rechazar\u00e1n a los pacientes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mientras los estados discrepan en materia de inmigraci\u00f3n, los hospitales dicen que no rechazar\u00e1n a los pacientes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Mientras los estados discrepan en materia de inmigraci\u00f3n, los hospitales dicen que no rechazar\u00e1n a los pacientes - Noticias","og_description":"Autoridades de California est\u00e1n aconsejando a los proveedores de atenci\u00f3n m\u00e9dica que no escriban el estatus migratorio de los pacientes en las facturas y los registros m\u00e9dicos y les dijeron que no tienen que ayudar a los agentes federales en las detenciones. Algunos hospitales y cl\u00ednicas de Massachusetts est\u00e1n publicando avisos sobre derechos de privacidad [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/","og_site_name":"Noticias","article_published_time":"2025-01-23T15:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/"},"author":{"name":"","@id":""},"headline":"Mientras los estados discrepan en materia de inmigraci\u00f3n, los hospitales dicen que no rechazar\u00e1n a los pacientes","datePublished":"2025-01-23T15:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/"},"wordCount":1982,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/","url":"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/","name":"Mientras los estados discrepan en materia de inmigraci\u00f3n, los hospitales dicen que no rechazar\u00e1n a los pacientes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-01-23T15:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mientras los estados discrepan en materia de inmigraci\u00f3n, los hospitales dicen que no rechazar\u00e1n a los pacientes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mientras los estados discrepan en materia de inmigraci\u00f3n, los hospitales dicen que no rechazar\u00e1n a los pacientes","url":"http:\/\/noticiasya.com\/laredo\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/01\/23\/inmigracion-hospitales-no-rechazaran-pacientes-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-01-23T15:03:39Z","datePublished":"2025-01-23T15:03:39Z","dateModified":"2025-01-23T15:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mientras los estados discrepan en materia de inmigraci\\u00f3n, los hospitales dicen que no rechazar\\u00e1n a los pacientes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/01\\\/23\\\/inmigracion-hospitales-no-rechazaran-pacientes-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/01\\\/23\\\/inmigracion-hospitales-no-rechazaran-pacientes-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-01-23T15:03:39Z\",\"datePublished\":\"2025-01-23T15:03:39Z\",\"dateModified\":\"2025-01-23T15:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1455505,"url":"https:\/\/noticiasya.com\/laredo\/2024\/11\/01\/pacientes-hospitales-texas-consultados-legalmente-ap\/","url_meta":{"origin":1457802,"position":0},"title":"A partir de este viernes, los pacientes de hospitales de Texas ser\u00e1n consultados sobre si se encuentran en Estados Unidos legalmente","author":"","date":"noviembre 1, 2024","format":false,"excerpt":"(AP) -- A partir de este viernes se les preguntar\u00e1 a los pacientes de los hospitales de Texas si est\u00e1n en EE.UU. legalmente.La nueva pol\u00edtica surge de una orden del gobernador republicano Greg Abbott y representa una escalada en el enfrentamiento del estado con la administraci\u00f3n Biden en materia de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470908,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/05\/hospitales-alerta-ice-datos-medicaid-pacientes-inmigrantes-trax\/","url_meta":{"origin":1457802,"position":1},"title":"El uso de datos de Medicaid por ICE pone en jaque a hospitales y pacientes inmigrantes","author":"","date":"febrero 5, 2026","format":false,"excerpt":"La decisi\u00f3n del Gobierno de Trump de otorgar a los funcionarios de deportaci\u00f3n acceso a los datos de Medicaid est\u00e1 poniendo a los hospitales y a los estados en una posici\u00f3n dif\u00edcil, ya que deben considerar si alertan a los pacientes inmigrantes de que su informaci\u00f3n personal, incluyendo las direcciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461469,"url":"https:\/\/noticiasya.com\/laredo\/2025\/04\/21\/republica-dominicana-atencion-medica-extranjeros-repatriaciones-orix\/","url_meta":{"origin":1457802,"position":2},"title":"Rep\u00fablica Dominicana no negar\u00e1 atenci\u00f3n m\u00e9dica a extranjeros, pero advierte posibles repatriaciones tras brindar servicios","author":"","date":"abril 21, 2025","format":false,"excerpt":"El Gobierno de Rep\u00fablica Dominicana inici\u00f3 este lunes la implementaci\u00f3n de un nuevo protocolo migratorio en 33 hospitales p\u00fablicos del pa\u00eds, en el marco de las medidas anunciadas por el presidente Luis Abinader a principios de abril para reforzar el control fronterizo y el uso de los servicios p\u00fablicos por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471469,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/20\/inmigracion-medicos-ice-atencion-sanitaria-crisis-trax\/","url_meta":{"origin":1457802,"position":3},"title":"La ofensiva migratoria de Trump est\u00e1 generando una crisis sanitaria en Estados Unidos, advierten los m\u00e9dicos","author":"","date":"febrero 20, 2026","format":false,"excerpt":"Dado que muchas personas no pueden o tienen miedo de acceder a la atenci\u00f3n m\u00e9dica, algunos proveedores dicen que est\u00e1n viendo una disminuci\u00f3n en el n\u00famero de pacientes que no hab\u00edan visto desde la pandemia de covid-19, esta vez brindando atenci\u00f3n mientras potencialmente tratan con agentes federales con equipo t\u00e1ctico.Los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467103,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/04\/cierre-gobierno-atencion-medica-inmigrantes-trax\/","url_meta":{"origin":1457802,"position":4},"title":"La verdad sobre el cierre del Gobierno y la atenci\u00f3n m\u00e9dica para los inmigrantes","author":"","date":"octubre 4, 2025","format":false,"excerpt":"La guerra de mensajes sobre el cierre del Gobierno est\u00e1 en pleno apogeo, y los primeros indicios son que los republicanos se encuentran en una situaci\u00f3n dif\u00edcil, dado que la demanda de los dem\u00f3cratas de extender los subsidios mejorados del Obamacare parece bastante popular.As\u00ed, los l\u00edderes republicanos han vuelto a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450045,"url":"https:\/\/noticiasya.com\/laredo\/2024\/06\/04\/ciberataque-ransomware-interrumpio-atencion-pacientes-hospitales-londres-cancelaron-operaciones-trax\/","url_meta":{"origin":1457802,"position":5},"title":"Un ciberataque interrumpi\u00f3 la atenci\u00f3n a los pacientes en los hospitales de Londres y se cancelaron varias operaciones","author":"","date":"junio 4, 2024","format":false,"excerpt":"(CNN) --Un ciberataque contra un contratista del Servicio Nacional de Salud de Inglaterra oblig\u00f3 a varios grandes hospitales de Londres a cancelar operaciones, an\u00e1lisis de sangre, citas y\u00a0 a reubicar a los pacientes a otros lugares.El King's College Hospital, el Guy's y el St Thomas' fueron afectados, al igual que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1457802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1457802"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1457802\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1457802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1457802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1457802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}