{"id":1466188,"date":"2025-09-05T10:03:50","date_gmt":"2025-09-05T17:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/"},"modified":"2025-09-05T10:03:50","modified_gmt":"2025-09-05T17:03:50","slug":"deportation-depot-centro-inmigrantes-florida-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/","title":{"rendered":"El nuevo centro de detenci\u00f3n de inmigrantes &#171;Deportation Depot&#187; ya est\u00e1 operativo en Florida"},"content":{"rendered":"<p><a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/14\/eeuu\/florida-centro-detencion-inmigrantes-deportation-depot-trax\">\u201cDeportation Depot\u201d,<\/a> el nuevo centro de detenci\u00f3n de inmigrantes de Florida, ya alberga a detenidos, informaron este viernes funcionarios estatales.<\/p>\n<p>El centro, ubicado en la Instituci\u00f3n Correccional Baker del estado, alberga a 117 detenidos y tiene capacidad para recibir hasta 1.500 personas, seg\u00fan la oficina del gobernador Ron DeSantis. La prisi\u00f3n estatal, temporalmente cerrada, se encuentra a unos 72 kil\u00f3metros al oeste de Jacksonville, cerca del Bosque Nacional Osceola.<\/p>\n<p>Este es el segundo centro de detenci\u00f3n de inmigrantes que el estado inaugura desde la construcci\u00f3n de un controvertido centro en los Everglades conocido como \u201cAlligator Alcatraz\u201d. Varios otros estados han anunciado sitios similares con nombres como \u201cSpeedway Slammer\u201d en Indiana.<\/p>\n<p>La apertura del \u201cDeportation Depot\u201d se anunci\u00f3 en agosto, justo antes de que una jueza federal dictara una orden judicial preliminar sobre \u201cAlligator Alcatraz\u201d que clausurar\u00eda dicho centro.<\/p>\n<p>Desde entonces, un tribunal federal de apelaciones ha suspendido la orden del tribunal inferior de forzar el cierre de \u201cAlligator Alcatraz\u201d. El estado ha dicho que continuar\u00e1 trasladando a los detenidos fuera de all\u00ed.<\/p>\n<p>El estado ha anunciado que explorar\u00e1 la posibilidad de a\u00f1adir un tercer centro de detenci\u00f3n en la zona noroeste de Florida, al que DeSantis ha llamado \u201cPanhandle Pokey\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cDeportation Depot\u201d, el nuevo centro de detenci\u00f3n de inmigrantes de Florida, ya alberga a detenidos, informaron este viernes funcionarios estatales. El centro, ubicado en la Instituci\u00f3n Correccional Baker del estado, alberga a 117 detenidos y tiene capacidad para recibir hasta 1.500 personas, seg\u00fan la oficina del gobernador Ron DeSantis. La prisi\u00f3n estatal, temporalmente cerrada, se [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466188","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El nuevo centro de detenci\u00f3n de inmigrantes &quot;Deportation Depot&quot; ya est\u00e1 operativo en Florida - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El nuevo centro de detenci\u00f3n de inmigrantes &quot;Deportation Depot&quot; ya est\u00e1 operativo en Florida - Noticias\" \/>\n<meta property=\"og:description\" content=\"\u201cDeportation Depot\u201d, el nuevo centro de detenci\u00f3n de inmigrantes de Florida, ya alberga a detenidos, informaron este viernes funcionarios estatales. El centro, ubicado en la Instituci\u00f3n Correccional Baker del estado, alberga a 117 detenidos y tiene capacidad para recibir hasta 1.500 personas, seg\u00fan la oficina del gobernador Ron DeSantis. La prisi\u00f3n estatal, temporalmente cerrada, se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-05T17:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El nuevo centro de detenci\u00f3n de inmigrantes &#171;Deportation Depot&#187; ya est\u00e1 operativo en Florida\",\"datePublished\":\"2025-09-05T17:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/\"},\"wordCount\":238,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/\",\"name\":\"El nuevo centro de detenci\u00f3n de inmigrantes \\\"Deportation Depot\\\" ya est\u00e1 operativo en Florida - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-05T17:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El nuevo centro de detenci\u00f3n de inmigrantes &#171;Deportation Depot&#187; ya est\u00e1 operativo en Florida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El nuevo centro de detenci\u00f3n de inmigrantes \"Deportation Depot\" ya est\u00e1 operativo en Florida - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El nuevo centro de detenci\u00f3n de inmigrantes \"Deportation Depot\" ya est\u00e1 operativo en Florida - Noticias","og_description":"\u201cDeportation Depot\u201d, el nuevo centro de detenci\u00f3n de inmigrantes de Florida, ya alberga a detenidos, informaron este viernes funcionarios estatales. El centro, ubicado en la Instituci\u00f3n Correccional Baker del estado, alberga a 117 detenidos y tiene capacidad para recibir hasta 1.500 personas, seg\u00fan la oficina del gobernador Ron DeSantis. La prisi\u00f3n estatal, temporalmente cerrada, se [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-05T17:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/"},"author":{"name":"","@id":""},"headline":"El nuevo centro de detenci\u00f3n de inmigrantes &#171;Deportation Depot&#187; ya est\u00e1 operativo en Florida","datePublished":"2025-09-05T17:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/"},"wordCount":238,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/","name":"El nuevo centro de detenci\u00f3n de inmigrantes \"Deportation Depot\" ya est\u00e1 operativo en Florida - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-05T17:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El nuevo centro de detenci\u00f3n de inmigrantes &#171;Deportation Depot&#187; ya est\u00e1 operativo en Florida"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El nuevo centro de detenci\u00f3n de inmigrantes &#171;Deportation Depot&#187; ya est\u00e1 operativo en Florida","url":"http:\/\/noticiasya.com\/laredo\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/09\/05\/deportation-depot-centro-inmigrantes-florida-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-05T17:03:50Z","datePublished":"2025-09-05T17:03:50Z","dateModified":"2025-09-05T17:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El nuevo centro de detenci\\u00f3n de inmigrantes &#171;Deportation Depot&#187; ya est\\u00e1 operativo en Florida\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/09\\\/05\\\/deportation-depot-centro-inmigrantes-florida-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/09\\\/05\\\/deportation-depot-centro-inmigrantes-florida-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-05T17:03:50Z\",\"datePublished\":\"2025-09-05T17:03:50Z\",\"dateModified\":\"2025-09-05T17:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1465502,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/14\/florida-centro-detencion-inmigrantes-deportation-depot-trax\/","url_meta":{"origin":1466188,"position":0},"title":"Florida planea abrir el &#171;Deportation Depot&#187;, un nuevo centro de detenci\u00f3n de inmigrantes","author":"","date":"agosto 14, 2025","format":false,"excerpt":"Florida se est\u00e1 preparando para albergar a inmigrantes detenidos en un nuevo centro de detenci\u00f3n situado en una zona remota del norte del estado, el segundo desde que se inaugur\u00f3 hace poco m\u00e1s de un mes el centro de detenci\u00f3n provisional denominado \u201cAlligator Alcatraz\u201d en los Everglades.\u201cLo llamamos Deportation Depot\u201d,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466136,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/03\/trump-camp-57-centro-detencion-ice-louisiana-trax\/","url_meta":{"origin":1466188,"position":1},"title":"Gobierno de Trump abrir\u00e1 &#171;Camp 57&#187;, un nuevo centro de detenci\u00f3n del ICE, en una prisi\u00f3n de Louisiana","author":"","date":"septiembre 3, 2025","format":false,"excerpt":"El Gobierno de Trump abrir\u00e1 un nuevo campamento dentro de una conocida prisi\u00f3n estatal en Louisiana para albergar a inmigrantes indocumentados acusados de cometer delitos graves, anunciaron funcionarios este mi\u00e9rcoles.El nuevo centro de detenci\u00f3n, llamado \u201cCamp 57\u201d, estar\u00e1 ubicado en la prisi\u00f3n de m\u00e1xima seguridad m\u00e1s grande del pa\u00eds, la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465596,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/18\/alligator-alcatraz-audiencia-florida-trax\/","url_meta":{"origin":1466188,"position":2},"title":"&#171;Alligator Alcatraz&#187; es un &#171;agujero negro donde las personas desaparecen&#187;, advierten abogados antes de audiencia","author":"","date":"agosto 18, 2025","format":false,"excerpt":"Abogados que representan a los detenidos en el controvertido centro de detenci\u00f3n para inmigrantes \u201cAlligator Alcatraz\u201d estar\u00e1n este lunes en un tribunal federal buscando permitir que los detenidos se re\u00fanan con sus abogados.Los abogados de grupos como ACLU, US Immigration Law Counsel y Florida Keys Immigration presentaron en julio una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461057,"url":"https:\/\/noticiasya.com\/laredo\/2025\/04\/10\/centro-detencion-inmigrantes-krome-florida-orix\/","url_meta":{"origin":1466188,"position":3},"title":"&#171;Dorm\u00eda en el patio, en el piso&#187;: denuncian trato inhumano y hacinamiento en centro de detenci\u00f3n de inmigrantes en Florida","author":"","date":"abril 10, 2025","format":false,"excerpt":"\u201cEstaba enfermo, ten\u00eda fr\u00edo, y nadie le daba atenci\u00f3n m\u00e9dica\u201d, as\u00ed es como Mar\u00eda L\u00f3pez asegura que su padre, un hombre de 70 a\u00f1os, pas\u00f3 una semana recluido en el Centro de Procesamiento de Krome, en el sur de la Florida, donde el Servicio de Inmigraci\u00f3n y Control de Aduanas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460434,"url":"https:\/\/noticiasya.com\/laredo\/2025\/03\/26\/donde-estan-inmigrantes-arrestados-ice-10-estados-mas-detenidos-orix\/","url_meta":{"origin":1466188,"position":4},"title":"\u00bfD\u00f3nde est\u00e1n los inmigrantes arrestados por ICE? Estos son los 10 estados de EE.UU. con m\u00e1s detenidos","author":"","date":"marzo 26, 2025","format":false,"excerpt":"Ya pasaron m\u00e1s de 50 d\u00edas del comienzo del segundo mandato presidencial de Donald Trump y, como lo prometi\u00f3 antes de iniciar su gobierno, una de las acciones m\u00e1s notorias de su administraci\u00f3n ha sido la campa\u00f1a contra la inmigraci\u00f3n ilegal.Trump dijo que en su nuevo gobierno habr\u00eda detenciones masivas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466161,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/04\/tribunal-bloquea-orden-jueza-desmantelar-alligator-alcatraz-trax\/","url_meta":{"origin":1466188,"position":5},"title":"Un tribunal de apelaciones bloquea la orden de una jueza para desmantelar &#171;Alligator Alcatraz&#187;","author":"","date":"septiembre 4, 2025","format":false,"excerpt":"Un tribunal federal de apelaciones bloque\u00f3 la orden de una jueza que exig\u00eda a Florida y al Gobierno federal cerrar y desmantelar un controvertido centro de detenci\u00f3n de inmigrantes construido en los Everglades, conocido popularmente como \u201cAlligator Alcatraz\u201d.Este jueves, el Tribunal de Apelaciones del 11\u00ba Circuito de EE.UU. acept\u00f3 las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1466188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1466188"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1466188\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1466188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1466188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1466188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}