{"id":1466193,"date":"2025-09-05T15:03:40","date_gmt":"2025-09-05T22:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/"},"modified":"2025-09-05T15:03:40","modified_gmt":"2025-09-05T22:03:40","slug":"gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/","title":{"rendered":"Gritos, llanto, tristeza: as\u00ed fue la redada de inmigraci\u00f3n de tres horas en Nueva York que dej\u00f3 decenas de detenidos"},"content":{"rendered":"<p>Eran alrededor de las 9 de la ma\u00f1ana del jueves. Como cualquier otro d\u00eda, decenas de personas trabajaban en la f\u00e1brica Nutrition Bar Confectioners, ubicada en Cato, Nueva York, el escenario m\u00e1s reciente de una <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/05\/eeuu\/inmigrantes-indocumentados-detenidos-hyundai-georgia-trax#:~:text=Decenas%20de%20detenidos%20en%20redada%20en%20Nueva%20York\">redada de inmigraci\u00f3n<\/a>. La normalidad se quebr\u00f3 cuando algunos empleados se asomaron por la ventana y observaron agentes migratorios.<\/p>\n<p>\u201cRodearon la compa\u00f1\u00eda, toda la gente se espant\u00f3, les dio miedo, y nosotros nos quedamos ah\u00ed, no nos quisimos mover\u201d, relata a CNN un residente legal estadounidense originario de Guatemala que se encontraba trabajando en la f\u00e1brica y que pidi\u00f3 no ser identificado con su nombre por temor a represalias a pesar de tener documentos.<\/p>\n<p>El miedo fue mucho mayor poco despu\u00e9s. Se escucharon gritos por la llegada de los agentes, algunas personas lloraban, \u201cespecialmente las mujeres que tienen ni\u00f1os\u201d, dijo el trabajador.<\/p>\n<p>Cuando la gente quiso moverse, las fuerzas federales ya estaban dentro de la compa\u00f1\u00eda. Ingresaron directamente por los empleados, sin tratar de hablar con el due\u00f1o antes, menciona el trabajador guatemalteco.<\/p>\n<p>El residente, que lleva casi una d\u00e9cada en Estados Unidos, dice que los agentes llevaron a todos los empleados al comedor de la f\u00e1brica. Seg\u00fan recuerda, eran unos 70 trabajadores, tanto mujeres como hombres.<\/p>\n<p>Los agentes \u201ccon los hombres se portaron agresivos, a las mujeres las apartaron\u201d, dice. Preguntaban \u201cde qu\u00e9 pa\u00eds \u00e9ramos, que si ten\u00edamos alg\u00fan permiso de estar aqu\u00ed en Estados Unidos\u201d.<\/p>\n<p>\u00c9l dice que mostr\u00f3 sus papeles de residente y los agentes le dijeron que pod\u00eda irse, pero decenas fueron detenidos, atados de las manos con cinta blanca.<\/p>\n<p>Subieron a los migrantes detenidos a furgonetas, para ser llevados a diferentes condados, dijo a CNN Wilmer Jim\u00e9nez, director de Programaci\u00f3n de Rural &#038; Migrant Ministry (RMM), organizaci\u00f3n sin fines de lucro que est\u00e1 ayudando en esta situaci\u00f3n y que conoce a varias de las personas detenidas.<\/p>\n<p>La redada migratoria dur\u00f3 unas tres horas, desde la llegada de los agentes hasta la salida de las furgonetas, de acuerdo con el trabajador.<\/p>\n<p>\u201cLa verdad me dio mucha tristeza al ver todo lo que estaba pasando, todos los compa\u00f1eros m\u00edos, me dio tristeza de ver c\u00f3mo los hab\u00edan agarrado, c\u00f3mo se los llevaban, me dio mucha tristeza de verlos\u201d, dice el guatemalteco. Otros trabajadores tambi\u00e9n eran de ah\u00ed, as\u00ed como de Nicaragua, seg\u00fan cuenta.<\/p>\n<p>Jim\u00e9nez, de RMM, asegur\u00f3 que entre 60 y 70 personas fueron detenidas, pr\u00e1cticamente toda la fuerza laboral de la f\u00e1brica, incluso migrantes con permisos de trabajo.<\/p>\n<p>\u201cLas personas que pudieron mostrar su identificaci\u00f3n como de estudiantes legales o ciudadanos los pudieron dejar ir. A las personas que no pod\u00edan probar eso, los estuvieron deteniendo. Una de las cosas que tambi\u00e9n escuch\u00e9 de alguien que dejaron ir es que los agentes de migraci\u00f3n hab\u00edan mencionado que los permisos de trabajo no eran v\u00e1lidos, as\u00ed que toda persona que ten\u00eda permiso de trabajo fue arrestada\u201d, se\u00f1al\u00f3.<\/p>\n<p>CNN contacto al Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) y al Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) para saber si los detenidos ten\u00edan permisos de trabajo y espera respuesta.<\/p>\n<p>RMM <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.facebook.com%2Fwatch%2F%3Fv%3D1252360006749538%26rdid%3DO9G80bLQXglEeZR2&#038;data=05%7C02%7Ckelly.mccleary%40cnn.com%7Ce51e5bf86fcd4d27128508ddec3fb290%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638926480720947604%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=oGfYurLANt9k%2FrMtxWpN20Bw%2FkES2C%2BUhPidTi28Fwk%3D&#038;reserved=0\">public\u00f3 un video<\/a> en su p\u00e1gina de Facebook que mostraba a agentes conduciendo a personas a una camioneta con la inscripci\u00f3n \u201cPatrulla Fronteriza\u201d. Durante la redada, los trabajadores fueron llevados a la cocina de la planta e \u201cinterrogados uno por uno durante varias horas\u201d, seg\u00fan la organizaci\u00f3n.<\/p>\n<p>Un grupo de mujeres detenidas fue trasladado al condado de Oswego \u2014donde se program\u00f3 una <a href=\"https:\/\/www.facebook.com\/ruralmigrantministry\/posts\/pfbid0Qhi3JmmcQYHMXuegr794QxJkRFwp8VRwzeqCoUnkBTYw4qfgF118G7bsuxDtS8oHl\">protesta pac\u00edfica<\/a> para este viernes\u2014, pero otro grupo, en el que la mayor\u00eda son hombres, no se sabe su paradero y el equipo legal de RMM est\u00e1 trabajando para averiguar su paradero, dijo Jim\u00e9nez.<\/p>\n<p>La gobernadora de Nueva York, Kathy Hochul, dijo que hubo m\u00e1s de 40 detenidos y conden\u00f3 la operaci\u00f3n de inmigraci\u00f3n en su estado.<\/p>\n<p>Tales operaciones \u201cno har\u00e1n que Nueva York sea un lugar m\u00e1s seguro\u201d y \u201cdestrozar\u00e1n a familias trabajadoras que simplemente est\u00e1n tratando de construir una vida aqu\u00ed\u201d, dijo Hochul en un comunicado.<\/p>\n<p>El ICE confirm\u00f3 a <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fcnycentral.com%2Fnews%2Flocal%2Fimmigrant-agency-sends-rapid-response-to-cato-after-authorities-descend-on-business-immigrations-customs-enforcement-police-heavy-law-enforcement-presence&#038;data=05%7C02%7Ckelly.mccleary%40cnn.com%7Ce51e5bf86fcd4d27128508ddec3fb290%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C638926480720972321%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=h8%2B7dmDPoteNePrkT5%2B2LLu56qY7gQyH5BOL8XNQP5s%3D&#038;reserved=0\">WSTM, afiliada de CNN<\/a>, que llev\u00f3 a cabo una \u201cacci\u00f3n coercitiva autorizada por el tribunal\u201d en Cato.<\/p>\n<p>CNN tambi\u00e9n pregunt\u00f3 al DHS y al ICE por m\u00e1s detalles de dicha acci\u00f3n, pero a\u00fan no recibe respuesta.<\/p>\n<p>Mark Schmidt, propietario de Nutrition Bar Confectioners \u2014 que produce barras nutritivas y que opera desde 1978\u2014, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/05\/eeuu\/inmigrantes-indocumentados-detenidos-hyundai-georgia-trax#:~:text=Mark%20Schmidt%2C%20propietario,ADVERTISEMENT\">declar\u00f3<\/a> al <a href=\"https:\/\/www.nytimes.com\/2025\/09\/04\/nyregion\/immigration-raid-new-york.html\">New York Times<\/a> que todos sus trabajadores contaban con la documentaci\u00f3n legal para trabajar en Estados Unidos. \u201cHemos hecho todo lo posible para verificar la informaci\u00f3n de las personas que contratamos\u201d, afirm\u00f3.<\/p>\n<p>Schmidt describi\u00f3 la redada de ICE como \u201cexagerada\u201d. Su hijo Lenny Schmidt, vicepresidente de la compa\u00f1\u00eda, declar\u00f3 al Times que la escena era \u201ccasi teatral\u201d, y describi\u00f3 los perros polic\u00eda y los veh\u00edculos todoterreno que participaron en la operaci\u00f3n.<\/p>\n<p>\u201cPodr\u00eda haberse manejado de forma mucho m\u00e1s humana y decente\u201d, dijo. \u201cEste tipo de operaciones dan la sensaci\u00f3n de ser una redada antidrogas o de trata de personas\u201d.<\/p>\n<p>CNN se ha puesto en contacto con la empresa para recibir m\u00e1s comentarios.<\/p>\n<p>La redada de inmigraci\u00f3n en Nueva York <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/05\/eeuu\/inmigrantes-indocumentados-detenidos-hyundai-georgia-trax\">ocurri\u00f3<\/a> el mismo d\u00eda de otra realizada por varias agencias en la planta Hyundai Metaplant en Georgia, la cual result\u00f3 en la detenci\u00f3n de 475 personas. Esa redada marca la mayor operaci\u00f3n de control en un solo lugar en la historia de la Oficina de Investigaciones de Seguridad Nacional (HSI, por sus siglas en ingl\u00e9s), con la participaci\u00f3n de otras agencias federales.<\/p>\n<p>En Nueva York, el <a href=\"https:\/\/www.schools.nyc.gov\/calendar\/2025-2026-school-year-calendar\">primer d\u00eda de clases<\/a> en escuelas p\u00fablicas fue el jueves, el mismo d\u00eda de la redada en Nutrition Bar Confectioners.<\/p>\n<p>Varios de los detenidos son padres de familia que, antes de su turno laboral, llevaron a sus hijos a la escuela, sin saber que despu\u00e9s ser\u00edan detenidos en su lugar de trabajo, afirm\u00f3 el directivo de RMM.<\/p>\n<p>Por tanto, las familias no solo tienen miedo por lo que pueda pasar con los migrantes detenidos en las c\u00e1rceles o centros de detenci\u00f3n, sino tambi\u00e9n por el trauma que pueda causar a los ni\u00f1os, de acuerdo con el activista.<\/p>\n<p>\u201cMuchas de las familias tienen miedo de que los familiares sean enviados a estos centros de detenci\u00f3n que han estado anunciando por meses y que se escucha qu\u00e9 tan agresivamente ellos tratan a la gente. La otra es el p\u00e1nico de que muchos de ellos tienen hijos, las mam\u00e1s ya no regresaron a casa. Ayer fue el primer d\u00eda de clases para los ni\u00f1os, y los ni\u00f1os regresaron a casa y ya no pueden ver a mam\u00e1 o a pap\u00e1\u201d, dijo Jim\u00e9nez.<\/p>\n<p>\u201cEntonces eso tambi\u00e9n est\u00e1 causando el p\u00e1nico, qu\u00e9 va a pasar con los ni\u00f1os, c\u00f3mo est\u00e1 la situaci\u00f3n. Lo otro es el trauma que los ni\u00f1os tambi\u00e9n est\u00e1n pasando por el hecho de saber que su padre o su madre fueron detenidos de la nada, donde una ma\u00f1ana vieron a su mam\u00e1 y para la tarde no se sabe d\u00f3nde est\u00e1\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Seg\u00fan Jim\u00e9nez, sus padres y madres, en algunos casos, han vivido en EE.UU. desde hace 15 o hasta 20 a\u00f1os.<\/p>\n<p>\u201cSon miembros de las comunidades alrededor de la f\u00e1brica. La realidad es que todas estas personas son gente trabajadora, no son criminales, y eso es lo m\u00e1s triste y doloroso, ver que est\u00e1n siendo detenidas las personas que aportan much\u00edsimo a nuestras comunidades, especialmente las comunidades rurales\u201d, subray\u00f3 el directivo de RMM.<\/p>\n<p>La gobernadora Kathy Hochul <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/05\/eeuu\/inmigrantes-indocumentados-detenidos-hyundai-georgia-trax\">se\u00f1al\u00f3<\/a> que entre los detenidos hay \u201cpadres de al menos una docena de ni\u00f1os que corr\u00edan el riesgo de regresar de la escuela a una casa vac\u00eda\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eran alrededor de las 9 de la ma\u00f1ana del jueves. Como cualquier otro d\u00eda, decenas de personas trabajaban en la f\u00e1brica Nutrition Bar Confectioners, ubicada en Cato, Nueva York, el escenario m\u00e1s reciente de una redada de inmigraci\u00f3n. La normalidad se quebr\u00f3 cuando algunos empleados se asomaron por la ventana y observaron agentes migratorios. \u201cRodearon [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466193","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gritos, llanto, tristeza: as\u00ed fue la redada de inmigraci\u00f3n de tres horas en Nueva York que dej\u00f3 decenas de detenidos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gritos, llanto, tristeza: as\u00ed fue la redada de inmigraci\u00f3n de tres horas en Nueva York que dej\u00f3 decenas de detenidos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Eran alrededor de las 9 de la ma\u00f1ana del jueves. Como cualquier otro d\u00eda, decenas de personas trabajaban en la f\u00e1brica Nutrition Bar Confectioners, ubicada en Cato, Nueva York, el escenario m\u00e1s reciente de una redada de inmigraci\u00f3n. La normalidad se quebr\u00f3 cuando algunos empleados se asomaron por la ventana y observaron agentes migratorios. \u201cRodearon [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-05T22:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Gritos, llanto, tristeza: as\u00ed fue la redada de inmigraci\u00f3n de tres horas en Nueva York que dej\u00f3 decenas de detenidos\",\"datePublished\":\"2025-09-05T22:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/\"},\"wordCount\":1398,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/\",\"name\":\"Gritos, llanto, tristeza: as\u00ed fue la redada de inmigraci\u00f3n de tres horas en Nueva York que dej\u00f3 decenas de detenidos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-05T22:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gritos, llanto, tristeza: as\u00ed fue la redada de inmigraci\u00f3n de tres horas en Nueva York que dej\u00f3 decenas de detenidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gritos, llanto, tristeza: as\u00ed fue la redada de inmigraci\u00f3n de tres horas en Nueva York que dej\u00f3 decenas de detenidos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Gritos, llanto, tristeza: as\u00ed fue la redada de inmigraci\u00f3n de tres horas en Nueva York que dej\u00f3 decenas de detenidos - Noticias","og_description":"Eran alrededor de las 9 de la ma\u00f1ana del jueves. Como cualquier otro d\u00eda, decenas de personas trabajaban en la f\u00e1brica Nutrition Bar Confectioners, ubicada en Cato, Nueva York, el escenario m\u00e1s reciente de una redada de inmigraci\u00f3n. La normalidad se quebr\u00f3 cuando algunos empleados se asomaron por la ventana y observaron agentes migratorios. \u201cRodearon [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/","og_site_name":"Noticias","article_published_time":"2025-09-05T22:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/"},"author":{"name":"","@id":""},"headline":"Gritos, llanto, tristeza: as\u00ed fue la redada de inmigraci\u00f3n de tres horas en Nueva York que dej\u00f3 decenas de detenidos","datePublished":"2025-09-05T22:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/"},"wordCount":1398,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/","url":"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/","name":"Gritos, llanto, tristeza: as\u00ed fue la redada de inmigraci\u00f3n de tres horas en Nueva York que dej\u00f3 decenas de detenidos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-05T22:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Gritos, llanto, tristeza: as\u00ed fue la redada de inmigraci\u00f3n de tres horas en Nueva York que dej\u00f3 decenas de detenidos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Gritos, llanto, tristeza: as\u00ed fue la redada de inmigraci\u00f3n de tres horas en Nueva York que dej\u00f3 decenas de detenidos","url":"http:\/\/noticiasya.com\/laredo\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-05T22:03:40Z","datePublished":"2025-09-05T22:03:40Z","dateModified":"2025-09-05T22:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Gritos, llanto, tristeza: as\\u00ed fue la redada de inmigraci\\u00f3n de tres horas en Nueva York que dej\\u00f3 decenas de detenidos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/09\\\/05\\\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/09\\\/05\\\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-05T22:03:40Z\",\"datePublished\":\"2025-09-05T22:03:40Z\",\"dateModified\":\"2025-09-05T22:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466202,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/06\/cato-nueva-york-redada-ice-detenidos-trax\/","url_meta":{"origin":1466193,"position":0},"title":"Redada del ICE en un negocio de Nueva York dej\u00f3 trabajadores aterrorizados y ralentiz\u00f3 la producci\u00f3n, dice copropietario","author":"","date":"septiembre 6, 2025","format":false,"excerpt":"Cuando Lenny Schmidt lleg\u00f3 a su negocio familiar de fabricaci\u00f3n de barras nutricionales en el norte del estado de Nueva York el jueves por la ma\u00f1ana, los agentes federales de inmigraci\u00f3n ya estaban all\u00ed.\u201cLos agentes hab\u00edan invadido la planta\u201d, dijo. \u201cProbablemente hab\u00eda m\u00e1s de 100 agentes, en veh\u00edculos de cuatro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461889,"url":"https:\/\/noticiasya.com\/laredo\/2025\/05\/02\/migrantes-vulnerables-redadas-jornaleros-trax\/","url_meta":{"origin":1466193,"position":1},"title":"C\u00f3mo el miedo a las redadas en lugares vulnerables est\u00e1 cambiando el comportamiento de los migrantes indocumentados","author":"","date":"mayo 2, 2025","format":false,"excerpt":"Todo lo que Carlos pudo hacer fue llorar.Vio c\u00f3mo otros jornaleros en un estacionamiento de Home Depot en Pomona, California, eran detenidos por agentes de la Aduana y Protecci\u00f3n Fronteriza el 22 de abril.M\u00e1s tarde, Carlos \u2013 quien pidi\u00f3 que no se publicara su apellido \u2013 se present\u00f3 ante los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465541,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/15\/hombre-muere-redada-inmigracion-ice-autopista-los-angeles-trax\/","url_meta":{"origin":1466193,"position":2},"title":"Muere un hombre que hu\u00eda de una redada de inmigraci\u00f3n tras correr hacia una autopista de Los \u00c1ngeles, seg\u00fan las autoridades","author":"","date":"agosto 15, 2025","format":false,"excerpt":"Un hombre que hu\u00eda mientras se desarrollaba una redada de inmigraci\u00f3n en un Home Depot en el sur de California muri\u00f3 cuando corri\u00f3 hacia una autopista mientras agentes federales ingresaban, dijeron funcionarios locales.La Red Nacional de Jornaleros identific\u00f3 al hombre como Roberto Carlos Montoya Vald\u00e9s, de 52 a\u00f1os y originario\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466200,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/06\/redada-hyundai-detenidos-inmigrantes-trax\/","url_meta":{"origin":1466193,"position":3},"title":"Dentro de la redada: c\u00f3mo un operativo federal de inmigraci\u00f3n que dur\u00f3 meses condujo a 475 arrestos en una planta de Hyundai","author":"","date":"septiembre 6, 2025","format":false,"excerpt":"Una extensa planta de fabricaci\u00f3n de Hyundai en una tranquila comunidad del sureste de Georgia se convirti\u00f3 el jueves en la zona cero de una de las redadas de inmigraci\u00f3n m\u00e1s extensas en la historia reciente de Estados Unidos. La operaci\u00f3n, que se gest\u00f3 durante meses, culmin\u00f3 con 475 arrestos,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464435,"url":"https:\/\/noticiasya.com\/laredo\/2025\/07\/11\/aumentan-tensiones-sur-california-redadas-inmigracion-que-sabemos-trax\/","url_meta":{"origin":1466193,"position":4},"title":"Aumentan las tensiones en el sur de California por las redadas contra la inmigraci\u00f3n. Esto es lo que sabemos","author":"","date":"julio 11, 2025","format":false,"excerpt":"Tras las grandes demostraciones de fuerza por parte de agentes federales de inmigraci\u00f3n en el sur de California, una jueza est\u00e1 a punto de emitir un fallo que busca detener las redadas contra la inmigraci\u00f3n en Los \u00c1ngeles.Los acontecimientos volvieron a poner el foco en la regi\u00f3n, que emergi\u00f3 hace\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466163,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/04\/venezolana-nueva-york-hijos-escuela-detencion-esposo-orix\/","url_meta":{"origin":1466193,"position":5},"title":"&#171;Mam\u00e1, \u00bfy si no vuelves m\u00e1s?&#187;: Venezolana en Nueva York teme enviar a sus hijos a la escuela tras detenci\u00f3n de su esposo","author":"","date":"septiembre 4, 2025","format":false,"excerpt":"\u201cMam\u00e1, \u00bfy si yo me quedo en la escuela y t\u00fa te vas, y no vuelves m\u00e1s?\u201d.Los hijos de esta joven inmigrante venezolana en Nueva York, de 9 y 12 a\u00f1os, tienen muchas preguntas y un solo temor: que al igual que pas\u00f3 con su padre, las autoridades de inmigraci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1466193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1466193"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1466193\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1466193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1466193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1466193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}