{"id":1466205,"date":"2025-09-06T08:03:43","date_gmt":"2025-09-06T15:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/"},"modified":"2025-09-06T08:03:43","modified_gmt":"2025-09-06T15:03:43","slug":"empleo-eeuu-desempleo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/","title":{"rendered":"\u00bfQu\u00e9 implica para ti el \u00faltimo informe de empleo?\u2026 Abr\u00f3chate el cintur\u00f3n"},"content":{"rendered":"<p>Tras a\u00f1os de abundantes oportunidades de empleo, importantes aumentos salariales y un gasto desenfrenado impulsado por el ahorro acumulado durante la pandemia, los trabajadores estadounidenses se enfrentan ahora a una realidad econ\u00f3mica preocupante: cada vez es m\u00e1s dif\u00edcil encontrar trabajo, y cada vez m\u00e1s sectores est\u00e1n <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/05\/eeuu\/estancamiento-empleo-ee-uu-trax\">eliminando puestos<\/a>.<\/p>\n<p>El <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/05\/eeuu\/estancamiento-empleo-ee-uu-trax\">\u00faltimo informe de empleo<\/a>, publicado el viernes, indic\u00f3 que la econom\u00eda estadounidense cre\u00f3 solo unos 22.000 empleos en agosto y que la tasa de desempleo subi\u00f3 al 4,3 %, su nivel m\u00e1s alto en casi cuatro a\u00f1os.<\/p>\n<p>El mercado laboral se est\u00e1 estancando, declar\u00f3 a CNN el viernes el economista de Glassdoor, Daniel Zhao. \u201cSe est\u00e1 desacelerando a una velocidad peligrosa\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Es que el crecimiento del empleo es pr\u00e1cticamente inexistente.<\/p>\n<p>Y si el mercado laboral muestra signos de resfriado, eso no augura nada bueno para la salud general de la econom\u00eda.<\/p>\n<p>A continuaci\u00f3n, un resumen de los datos m\u00e1s recientes y un an\u00e1lisis de c\u00f3mo la situaci\u00f3n podr\u00eda mejorar o empeorar:<\/p>\n<p>El crecimiento del empleo no solo ha sido d\u00e9bil, sino que recientemente se volvi\u00f3 negativo: durante los \u00faltimos tres meses, la econom\u00eda estadounidense ha experimentado una ganancia neta de aproximadamente 29.000 empleos al mes, seg\u00fan datos de la Oficina de Estad\u00edsticas Laborales.<\/p>\n<p>Si esto suena a poco, es porque lo es: excluyendo la ca\u00edda masiva del empleo al comienzo de la pandemia, se trata del promedio trimestral m\u00e1s lento desde el verano de 2010, cuando Estados Unidos a\u00fan se recuperaba de la Gran Recesi\u00f3n.<\/p>\n<p>El informe de junio, ahora revisado a la baja, redujo ese promedio. La segunda revisi\u00f3n de ese mes (que incluye informes m\u00e1s completos de empresas estadounidenses) ahora muestra una p\u00e9rdida neta de 13.000 empleos.<\/p>\n<p>En agosto, m\u00e1s industrias perdieron empleos que las que los crearon: el informe contiene un indicador t\u00e9cnico (un \u00edndice de difusi\u00f3n) que busca mostrar la amplitud de los cambios en el empleo en 250 industrias del sector privado.<\/p>\n<p>Si supera 50, significa que m\u00e1s industrias crearon empleos que los que los perdieron. Se ha mantenido por debajo de 50 desde abril y registr\u00f3 49,6 en agosto. Sin embargo, la mayor\u00eda de esas ganancias fueron m\u00ednimas.<\/p>\n<p>Y los sectores m\u00e1s afectados son los de bienes: la pol\u00edtica arancelaria del presidente Donald Trump y su aplicaci\u00f3n irregular est\u00e1n teniendo un impacto \u201cinnegable\u201d en las contrataciones, escribi\u00f3 el economista estadounidense de RSM, Joe Brusuelas, en una nota a los inversores el viernes.<\/p>\n<p>Las empresas de bienes han registrado \u201ccuatro meses consecutivos de ca\u00eddas desde mayo\u201d, escribi\u00f3. \u201cLa manufactura, que se supon\u00eda que se beneficiar\u00eda de las pol\u00edticas comerciales restrictivas, en cambio retrocedi\u00f3 a medida que se profundizaba la incertidumbre en la cadena de suministro\u201d.<\/p>\n<p>Adem\u00e1s, las oportunidades son cada vez m\u00e1s limitadas: el sector sanitario, que cuenta con el envejecimiento de la poblaci\u00f3n estadounidense a su favor, ha sido un importante impulsor del crecimiento del empleo en los \u00faltimos a\u00f1os.<\/p>\n<p>Ahora es pr\u00e1cticamente la \u00fanica opci\u00f3n disponible.<\/p>\n<p>Se estima que las empresas del sector sanitario crearon 46.800 puestos de trabajo en agosto. Sin embargo, el sector representa solo el 15 % del empleo total en Estados Unidos, seg\u00fan datos de la Oficina de Estad\u00edsticas Laborales (BLS).<\/p>\n<p>\u201cEl 85 % de los trabajadores no que se creen una gran cantidadad de empleos\u201d, declar\u00f3 a CNN esta semana Kory Kantenga, director de econom\u00eda para las Am\u00e9ricas de LinkedIn.<\/p>\n<p>La se\u00f1al de alerta est\u00e1 sonando: la tasa de desempleo de los trabajadores negros en Estados Unidos volvi\u00f3 a subir el mes pasado hasta el 7,5 %, el nivel m\u00e1s alto desde octubre de 2021.<\/p>\n<p>Durante los \u00faltimos dos meses, esa tasa ha aumentado considerablemente, pasando del 6 % al 6,8 % en junio y luego al 7,2 % en julio.<\/p>\n<p>\u201cLa tasa de desempleo de los trabajadores negros suele aumentar m\u00e1s que la de los trabajadores blancos cuando el mercado laboral se debilita, pero suelen evolucionar en la misma direcci\u00f3n\u201d, se\u00f1al\u00f3 el viernes el economista Dean Baker, cofundador del Centro de Investigaci\u00f3n Econ\u00f3mica y Pol\u00edtica.<\/p>\n<p>En comparaci\u00f3n, la tasa de desempleo de los trabajadores blancos se redujo 0,1 puntos porcentuales, hasta el 3,7 %.<\/p>\n<p>Un aumento en la tasa de desempleo de los trabajadores negros suele considerarse la se\u00f1al de alerta, ya que presagia una desaceleraci\u00f3n generalizada del mercado laboral.<\/p>\n<p>Los trabajadores negros est\u00e1n empleados de forma desproporcionada en sectores de primera l\u00ednea y con salarios m\u00e1s bajos, as\u00ed como en la administraci\u00f3n p\u00fablica. Los economistas advirtieron a principios de este a\u00f1o que los cambios radicales de Trump en las pol\u00edticas comerciales, de inmigraci\u00f3n, las reducciones de empleo federales, as\u00ed como las medidas dr\u00e1sticas contra las iniciativas de diversidad, equidad e inclusi\u00f3n, podr\u00edan revertir algunos de los avances hist\u00f3ricos en materia de empleo logrados recientemente por mujeres, trabajadores negros, trabajadores latinos y otros estadounidenses subrepresentados.<\/p>\n<p>Los obst\u00e1culos econ\u00f3micos y la incertidumbre est\u00e1n frenando la contrataci\u00f3n: no hay una \u00fanica causa para la desaceleraci\u00f3n del mercado laboral, pero la incertidumbre ciertamente no ha ayudado, afirm\u00f3 Zhao, economista de Glassdoor.<\/p>\n<p>\u201cIncluso antes de este a\u00f1o, el mercado ya mostraba una tendencia a la desaceleraci\u00f3n, con tasas de inter\u00e9s bastante altas, pero los datos de los \u00faltimos meses muestran que algunos sectores sensibles a los aranceles, como la manufactura o la construcci\u00f3n, se han desacelerado y, de hecho, han comenzado a perder empleos\u201d, afirm\u00f3. \u201cPor lo tanto, parece que los aranceles y la incertidumbre asociada a ellos tienen cierto impacto\u201d.<\/p>\n<p>\u201cNo se trata solo de la implementaci\u00f3n de estos aranceles, sino que la incertidumbre pol\u00edtica dificulta enormemente que las empresas se comprometan con sus planes de contrataci\u00f3n\u201d, a\u00f1adi\u00f3.<\/p>\n<p>El aumento del desempleo puede descontrolarse r\u00e1pidamente: la tasa del 4,3 % a\u00fan se sit\u00faa en el rango de empleo \u201csaludable\u201d\/pleno, pero si sigue aumentando, representa un grave problema.<\/p>\n<p>El desempleo se ha mantenido relativamente bajo, en parte debido a la menor demanda de trabajadores, as\u00ed como a la baja oferta (el envejecimiento de las personas y la reducci\u00f3n de trabajadores inmigrantes).<\/p>\n<p>\u201cPero, a medida que empezamos a ver un aumento del desempleo, esto empieza a sugerir que no se debe solo a cambios en la oferta laboral\u201d, afirm\u00f3 Zhao. \u201cCuando el desempleo empieza a aumentar, esos impactos pueden acumularse de forma muy r\u00e1pida e impredecible\u201d.<\/p>\n<p>Y si el mercado laboral se enfr\u00eda a\u00fan m\u00e1s, eso implicar\u00e1 menos dinero en los bolsillos de los hogares estadounidenses y menos gasto para impulsar una mayor contrataci\u00f3n.<\/p>\n<p>\u201cEso puede generar un ciclo de desaceleraci\u00f3n econ\u00f3mica m\u00e1s pronunciada\u201d, concluy\u00f3. Sin embargo, una recesi\u00f3n no es necesariamente inminente: la din\u00e1mica actual del mercado laboral depende de factores c\u00edclicos y estructurales impulsados \u200b\u200bprincipalmente por las pol\u00edticas comerciales y de inmigraci\u00f3n, afirm\u00f3 Brusuelas. Dicha din\u00e1mica, as\u00ed como los efectos de la \u201cincertidumbre generalizada\u201d, se manifestar\u00e1n a corto y mediano plazo, se\u00f1al\u00f3 el viernes.<\/p>\n<p>\u201cPrevemos que el crecimiento y la contrataci\u00f3n se reaceleren a medida que la combinaci\u00f3n de recortes de tasas de inter\u00e9s, recortes de impuestos y la contabilizaci\u00f3n completa de la inversi\u00f3n empresarial impulse la demanda de mano de obra a finales de este a\u00f1o y principios del pr\u00f3ximo\u201d, escribi\u00f3 en la nota. \u201cPor lo tanto, no prevemos que la econom\u00eda entre en recesi\u00f3n a corto plazo\u201d.<\/p>\n<p>Una reducci\u00f3n de las tasas de inter\u00e9s, incluso peque\u00f1a, podr\u00eda reactivar la demanda acumulada: hacia finales del a\u00f1o pasado, incluso despu\u00e9s de las elecciones, la contrataci\u00f3n y la inversi\u00f3n repuntaron, al igual que la confianza, especialmente porque la inflaci\u00f3n parec\u00eda estar control\u00e1ndose, seg\u00fan declar\u00f3 a CNN Ron Hetrick, economista laboral s\u00e9nior de Lightcast.<\/p>\n<p>\u201cLuego se desperdici\u00f3 todo eso cuando empezamos a aplicar aranceles y se introdujo la posibilidad de inflaci\u00f3n. La Reserva Federal dijo: \u2018Oigan, todo eso ya est\u00e1 descartado\u2019. As\u00ed, todo este fervor subterr\u00e1neo desapareci\u00f3\u201d, dijo. \u201cAl bajar la tasa de inter\u00e9s, la Fed est\u00e1 indicando: \u2018Creemos que es hora de reactivar este motor\u2019\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras a\u00f1os de abundantes oportunidades de empleo, importantes aumentos salariales y un gasto desenfrenado impulsado por el ahorro acumulado durante la pandemia, los trabajadores estadounidenses se enfrentan ahora a una realidad econ\u00f3mica preocupante: cada vez es m\u00e1s dif\u00edcil encontrar trabajo, y cada vez m\u00e1s sectores est\u00e1n eliminando puestos. El \u00faltimo informe de empleo, publicado el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466205","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 implica para ti el \u00faltimo informe de empleo?\u2026 Abr\u00f3chate el cintur\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 implica para ti el \u00faltimo informe de empleo?\u2026 Abr\u00f3chate el cintur\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"Tras a\u00f1os de abundantes oportunidades de empleo, importantes aumentos salariales y un gasto desenfrenado impulsado por el ahorro acumulado durante la pandemia, los trabajadores estadounidenses se enfrentan ahora a una realidad econ\u00f3mica preocupante: cada vez es m\u00e1s dif\u00edcil encontrar trabajo, y cada vez m\u00e1s sectores est\u00e1n eliminando puestos. El \u00faltimo informe de empleo, publicado el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-06T15:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 implica para ti el \u00faltimo informe de empleo?\u2026 Abr\u00f3chate el cintur\u00f3n\",\"datePublished\":\"2025-09-06T15:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/\"},\"wordCount\":1420,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/\",\"name\":\"\u00bfQu\u00e9 implica para ti el \u00faltimo informe de empleo?\u2026 Abr\u00f3chate el cintur\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-06T15:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 implica para ti el \u00faltimo informe de empleo?\u2026 Abr\u00f3chate el cintur\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 implica para ti el \u00faltimo informe de empleo?\u2026 Abr\u00f3chate el cintur\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 implica para ti el \u00faltimo informe de empleo?\u2026 Abr\u00f3chate el cintur\u00f3n - Noticias","og_description":"Tras a\u00f1os de abundantes oportunidades de empleo, importantes aumentos salariales y un gasto desenfrenado impulsado por el ahorro acumulado durante la pandemia, los trabajadores estadounidenses se enfrentan ahora a una realidad econ\u00f3mica preocupante: cada vez es m\u00e1s dif\u00edcil encontrar trabajo, y cada vez m\u00e1s sectores est\u00e1n eliminando puestos. El \u00faltimo informe de empleo, publicado el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-06T15:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 implica para ti el \u00faltimo informe de empleo?\u2026 Abr\u00f3chate el cintur\u00f3n","datePublished":"2025-09-06T15:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/"},"wordCount":1420,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/","name":"\u00bfQu\u00e9 implica para ti el \u00faltimo informe de empleo?\u2026 Abr\u00f3chate el cintur\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-06T15:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 implica para ti el \u00faltimo informe de empleo?\u2026 Abr\u00f3chate el cintur\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 implica para ti el \u00faltimo informe de empleo?\u2026 Abr\u00f3chate el cintur\u00f3n","url":"http:\/\/noticiasya.com\/laredo\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/09\/06\/empleo-eeuu-desempleo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-06T15:03:43Z","datePublished":"2025-09-06T15:03:43Z","dateModified":"2025-09-06T15:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 implica para ti el \\u00faltimo informe de empleo?\\u2026 Abr\\u00f3chate el cintur\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/09\\\/06\\\/empleo-eeuu-desempleo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/09\\\/06\\\/empleo-eeuu-desempleo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-06T15:03:43Z\",\"datePublished\":\"2025-09-06T15:03:43Z\",\"dateModified\":\"2025-09-06T15:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470860,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/04\/empleo-sector-privado-desplome-enero-trax\/","url_meta":{"origin":1466205,"position":0},"title":"La contrataci\u00f3n del sector privado se desplom\u00f3 en enero: se crearon solo 22.000 empleos","author":"","date":"febrero 4, 2026","format":false,"excerpt":"El breve cierre del Gobierno de EE.UU. ha retrasado el informe oficial de empleo de enero (los datos se publicar\u00e1n el 11 de febrero en lugar del pr\u00f3ximo viernes). Sin embargo, un primer an\u00e1lisis de la actividad de contrataci\u00f3n en el sector privado mostr\u00f3 que el crecimiento del empleo se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451986,"url":"https:\/\/noticiasya.com\/laredo\/2024\/08\/19\/estadounidenses-preocupados-perder-empleo-trax\/","url_meta":{"origin":1466205,"position":1},"title":"Cada vez son m\u00e1s los estadounidenses preocupados por perder su empleo","author":"","date":"agosto 19, 2024","format":false,"excerpt":"(CNN) --\u00a0El estado del mercado laboral estadounidense est\u00e1 cambiando, el crecimiento del empleo se est\u00e1 desacelerando y los nuevos datos de encuestas publicados el lunes muestran que los estadounidenses empiezan a sentirse cada vez m\u00e1s inquietos por todo ello.La \u00faltima encuesta del Banco de la Reserva Federal de Nueva York\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465060,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/02\/fed-error-tasas-empleo-trax\/","url_meta":{"origin":1466205,"position":2},"title":"\u00bfAcaba de cometer la Fed un grave error?","author":"","date":"agosto 2, 2025","format":false,"excerpt":"Solo tom\u00f3 unos d\u00edas para que la \u00faltima decisi\u00f3n de la Reserva Federal sobre las tasas de inter\u00e9s envejeciera mal.El banco central de EE.UU. anunci\u00f3 el mi\u00e9rcoles que manten\u00eda los costos de los pr\u00e9stamos sin cambios una vez m\u00e1s, prolongando un patr\u00f3n de espera que comenz\u00f3 en enero. Ese mismo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455501,"url":"https:\/\/noticiasya.com\/laredo\/2024\/11\/01\/reporte-de-empleo-elecciones-economia-12-000-puestos-huelgas-conflictos-trax\/","url_meta":{"origin":1466205,"position":3},"title":"El \u00faltimo reporte de empleo antes de las elecciones muestra que la econom\u00eda de EE.UU. sum\u00f3 12.000 puestos en medio de huelgas y huracanes","author":"","date":"noviembre 1, 2024","format":false,"excerpt":"(CNN) --\u00a0El informe final de empleo antes de las elecciones present\u00f3 una imagen poco clara de la econom\u00eda, con solo 12.000 empleos nuevos en octubre, ya que los huracanes y los trabajadores en huelga empa\u00f1aron los datos, seg\u00fan datos de la Oficina de Estad\u00edsticas Laborales publicados este viernes.Si bien esto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458431,"url":"https:\/\/noticiasya.com\/laredo\/2025\/02\/07\/datos-mercado-laboral-saludable-trump-no-de-acuerdo-trax\/","url_meta":{"origin":1466205,"position":4},"title":"Los datos muestran un mercado laboral saludable en EE.UU, pero Trump no est\u00e1 de acuerdo y culpa a Biden","author":"","date":"febrero 7, 2025","format":false,"excerpt":"Por muchas medidas, el mercado laboral de Estados Unidos parece estar en buena forma: en enero, el desempleo estaba en un hist\u00f3ricamente bajo 4% mientras los empleadores continuaban con la segunda racha m\u00e1s larga de crecimiento de empleo en la historia de EE.UU., seg\u00fan nuevos datos del Gobierno publicados este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466186,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/05\/inmigracion-datos-de-empleo-incognita-trax\/","url_meta":{"origin":1466205,"position":5},"title":"Sigue siendo una inc\u00f3gnita la manera en que impactan los cambios en materia de inmigraci\u00f3n en los datos de empleo","author":"","date":"septiembre 5, 2025","format":false,"excerpt":"El informe de empleo de este viernes, elaborado por la Oficina de Estad\u00edsticas Laborales (BLS, por sus siglas en ingl\u00e9s), genera m\u00e1s preguntas que respuestas sobre la econom\u00eda de EE.UU. Sin embargo, uno de los mayores puntos ciegos en los datos del mercado laboral es c\u00f3mo est\u00e1 cambiando el panorama\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1466205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1466205"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1466205\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1466205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1466205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1466205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}