{"id":1466208,"date":"2025-09-06T14:03:49","date_gmt":"2025-09-06T21:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/"},"modified":"2025-09-06T14:03:49","modified_gmt":"2025-09-06T21:03:49","slug":"jerome-adams-rfk-jr-despedido-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/","title":{"rendered":"El excirujano general de Trump pide que despidan a Robert F. Kennedy Jr."},"content":{"rendered":"<p>Jerome Adams, quien se desempe\u00f1\u00f3 como cirujano general de EE.UU. durante el primer Gobierno del presidente Donald Trump, pidi\u00f3 que el secretario de Salud y Servicios Humanos, Robert F. Kennedy Jr., sea despedido por su manejo de las aprobaciones de vacunas.<\/p>\n<p>Cuando Victor Blackwell, de CNN, le pregunt\u00f3 este s\u00e1bado si Trump deber\u00eda despedir a Kennedy, Adams respondi\u00f3: \u201cCreo absolutamente que deber\u00eda hacerlo por el bien de la naci\u00f3n y por el bien de su legado\u201d.<\/p>\n<p>Los comentarios de Adams llegan despu\u00e9s de una pol\u00e9mica audiencia en el Capitolio a principios de esta semana, donde Kennedy fue interrogado tanto por dem\u00f3cratas como por republicanos acerca de sus opiniones sobre las vacunas y sobre el \u00e9xodo reciente de los Centros para el Control y la Prevenci\u00f3n de Enfermedades (CDC, por sus siglas en ingl\u00e9s), incluyendo la renuncia de su directora, debido a pol\u00edticas de vacunaci\u00f3n m\u00e1s estrictas impulsadas por Kennedy.<\/p>\n<p>\u201cEstoy profundamente preocupado por la salud y la seguridad de nuestra naci\u00f3n bajo el liderazgo actual de RFK\u201d, dijo Adams a Blackwell, y luego agreg\u00f3: \u201cCreo absolutamente que est\u00e1 da\u00f1ando de manera \u00fanica la credibilidad de agencias federales como los CDC, y nos est\u00e1 poniendo en riesgo\u201d.<\/p>\n<p>El excirujano general tambi\u00e9n expres\u00f3 su preocupaci\u00f3n por la estrecha relaci\u00f3n de Trump con Kennedy, y argument\u00f3 que el presidente deber\u00eda tomar el control de la pol\u00edtica de salud.<\/p>\n<p>\u201cEstoy realmente asombrado, para ser honesto, de que parece tener al presidente Trump bajo su hechizo\u201d, dijo Adams. \u201cEl presidente Trump es claramente el l\u00edder en pol\u00edtica exterior, claramente el l\u00edder en econom\u00eda y aranceles. Pero cuando se trata de salud, est\u00e1 haciendo todo lo que dice RFK\u201d.<\/p>\n<p>Sin embargo, Adams dijo que tiene \u201cesperanza\u201d de que Trump reconozca lo que describi\u00f3 como \u201cel peligro\u201d que representa Kennedy.<\/p>\n<p>\u201cA\u00fan tengo la esperanza de que el presidente Trump comience a ver el peligro que presenta\u2014no solo para Estados Unidos, sino para su propio legado\u2014 mantener a RFK en este puesto, tomando las decisiones horribles que est\u00e1 tomando\u201d, dijo Adams a Blackwell.<\/p>\n<p>Durante la audiencia del Congreso del jueves, Kennedy defendi\u00f3 los cambios en los CDC, y afirm\u00f3 que \u201cfueron ajustes absolutamente necesarios para que la agencia recuperara su rol como el est\u00e1ndar de oro mundial en salud p\u00fablica\u201d.<\/p>\n<p>Cuando la senadora dem\u00f3crata Elizabeth Warren argument\u00f3 que la decisi\u00f3n del mes pasado de la Administraci\u00f3n de Alimentos y Medicamentos de los Estados Unidos (FDA, en ingl\u00e9s) \u2014que est\u00e1 bajo la supervisi\u00f3n de Kennedy\u2014 est\u00e1 efectivamente negando a algunas personas el acceso a las vacunas actualizadas contra el covid-19 tras aprobarla solo para un grupo limitado de personas, Kennedy puso en duda la eficacia de la vacuna.<\/p>\n<p>\u201cNo voy a recomendar un producto para el que no hay datos cl\u00ednicos. \u00bfEso es lo que deber\u00eda hacer?\u201d, pregunt\u00f3 Kennedy a Warren.<\/p>\n<p>Despu\u00e9s de la audiencia, Trump elogi\u00f3 el desempe\u00f1o de Kennedy, y aunque dijo que no vio la audiencia agreg\u00f3: \u201cEscuch\u00e9 que le fue muy bien hoy\u201d.<\/p>\n<p>Pero el viernes, Trump pareci\u00f3 distanciarse de la decisi\u00f3n de Florida de eliminar los requisitos de vacunaci\u00f3n escolar, que implica que todas las personas deben recibir ciertas vacunas.<\/p>\n<p>\u201cCreo que hay que tener mucho cuidado cuando se dice que algunas personas no tienen que vacunarse\u201d, dijo. \u201cHay vacunas que funcionan, simplemente funcionan. No son nada controvertidas, y creo que esas vacunas deben usarse, de lo contrario algunas personas se van a contagiar, y ponen en peligro a otras personas\u201d.<\/p>\n<p><em>Adam Cancryn de CNN contribuy\u00f3 a este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jerome Adams, quien se desempe\u00f1\u00f3 como cirujano general de EE.UU. durante el primer Gobierno del presidente Donald Trump, pidi\u00f3 que el secretario de Salud y Servicios Humanos, Robert F. Kennedy Jr., sea despedido por su manejo de las aprobaciones de vacunas. Cuando Victor Blackwell, de CNN, le pregunt\u00f3 este s\u00e1bado si Trump deber\u00eda despedir a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466208","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El excirujano general de Trump pide que despidan a Robert F. Kennedy Jr. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El excirujano general de Trump pide que despidan a Robert F. Kennedy Jr. - Noticias\" \/>\n<meta property=\"og:description\" content=\"Jerome Adams, quien se desempe\u00f1\u00f3 como cirujano general de EE.UU. durante el primer Gobierno del presidente Donald Trump, pidi\u00f3 que el secretario de Salud y Servicios Humanos, Robert F. Kennedy Jr., sea despedido por su manejo de las aprobaciones de vacunas. Cuando Victor Blackwell, de CNN, le pregunt\u00f3 este s\u00e1bado si Trump deber\u00eda despedir a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-06T21:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El excirujano general de Trump pide que despidan a Robert F. Kennedy Jr.\",\"datePublished\":\"2025-09-06T21:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/\"},\"wordCount\":643,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/\",\"name\":\"El excirujano general de Trump pide que despidan a Robert F. Kennedy Jr. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-06T21:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El excirujano general de Trump pide que despidan a Robert F. Kennedy Jr.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El excirujano general de Trump pide que despidan a Robert F. Kennedy Jr. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El excirujano general de Trump pide que despidan a Robert F. Kennedy Jr. - Noticias","og_description":"Jerome Adams, quien se desempe\u00f1\u00f3 como cirujano general de EE.UU. durante el primer Gobierno del presidente Donald Trump, pidi\u00f3 que el secretario de Salud y Servicios Humanos, Robert F. Kennedy Jr., sea despedido por su manejo de las aprobaciones de vacunas. Cuando Victor Blackwell, de CNN, le pregunt\u00f3 este s\u00e1bado si Trump deber\u00eda despedir a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-06T21:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/"},"author":{"name":"","@id":""},"headline":"El excirujano general de Trump pide que despidan a Robert F. Kennedy Jr.","datePublished":"2025-09-06T21:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/"},"wordCount":643,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/","name":"El excirujano general de Trump pide que despidan a Robert F. Kennedy Jr. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-06T21:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El excirujano general de Trump pide que despidan a Robert F. Kennedy Jr."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El excirujano general de Trump pide que despidan a Robert F. Kennedy Jr.","url":"http:\/\/noticiasya.com\/laredo\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/09\/06\/jerome-adams-rfk-jr-despedido-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-06T21:03:49Z","datePublished":"2025-09-06T21:03:49Z","dateModified":"2025-09-06T21:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El excirujano general de Trump pide que despidan a Robert F. Kennedy Jr.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/09\\\/06\\\/jerome-adams-rfk-jr-despedido-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/09\\\/06\\\/jerome-adams-rfk-jr-despedido-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-06T21:03:49Z\",\"datePublished\":\"2025-09-06T21:03:49Z\",\"dateModified\":\"2025-09-06T21:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452105,"url":"https:\/\/noticiasya.com\/laredo\/2024\/08\/23\/robert-f-kennedy-suspende-campana-presidencial-trax\/","url_meta":{"origin":1466208,"position":0},"title":"Robert F. Kennedy suspende su campa\u00f1a presidencial y apoya a Donald Trump","author":"","date":"agosto 23, 2024","format":false,"excerpt":"(CNN) --\u00a0El candidato presidencial independiente Robert F. Kennedy Jr. anunci\u00f3 este viernes que suspende su campa\u00f1a presidencial en una conferencia de prensa en Phoenix, Arizona.\"En mi coraz\u00f3n, ya no creo tener un camino realista hacia la victoria electoral frente a esta censura implacable y sistem\u00e1tica y al control de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455831,"url":"https:\/\/noticiasya.com\/laredo\/2024\/11\/14\/trump-elige-robert-f-kennedy-jr-secretario-departamento-salud-y-servicios-humanos-trax\/","url_meta":{"origin":1466208,"position":1},"title":"Trump elige a Robert F. Kennedy Jr. como secretario del Departamento de Salud y Servicios Humanos","author":"","date":"noviembre 14, 2024","format":false,"excerpt":"(CNN) -- El presidente electo Donald Trump eligi\u00f3 a Robert F. Kennedy Jr. como su pr\u00f3ximo secretario del Departamento de Salud y Servicios Humanos (HHS, por sus siglas en ingl\u00e9s), una elecci\u00f3n que se sumar\u00e1 a la lista de selecciones provocativas de Trump, cuyos procesos de confirmaci\u00f3n pondr\u00e1n a prueba\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462735,"url":"https:\/\/noticiasya.com\/laredo\/2025\/05\/23\/robert-kennedy-junior-familia-noboa-amistad-orix\/","url_meta":{"origin":1466208,"position":2},"title":"Robert Kennedy Jr. y los Noboa: 30 a\u00f1os de amistad que se fortalece con el nuevo mandato en Ecuador","author":"","date":"mayo 23, 2025","format":false,"excerpt":"Los momentos compartidos entre la familia del presidente de Ecuador, Daniel Noboa, y el secretario de Salud de Estados Unidos, Robert Kennedy Jr., han sido diversos y dan cuenta de una estrecha relaci\u00f3n de amistad que ha durado m\u00e1s de 30 a\u00f1os.Robert Kennedy Jr. es el invitado especial de Noboa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458703,"url":"https:\/\/noticiasya.com\/laredo\/2025\/02\/13\/senado-confirma-robert-f-kennedy-jr-secretario-salud-servicios-humanos-trax\/","url_meta":{"origin":1466208,"position":3},"title":"El Senado de EE.UU. confirma a Robert F. Kennedy Jr. como secretario de Salud y Servicios Humanos","author":"","date":"febrero 13, 2025","format":false,"excerpt":"El Senado vot\u00f3 este jueves a favor de confirmar a Robert F. Kennedy Jr. como secretario de Salud y Servicios Humanos, una victoria para el presidente de Estados Unidos, Donald Trump, despu\u00e9s de que Kennedy enfrent\u00f3 intenso escrutinio por sus controvertidas opiniones sobre las vacunas y la pol\u00edtica de salud\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470991,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/08\/nancy-pelosi-nieto-jfk-camara-representantes-trax\/","url_meta":{"origin":1466208,"position":4},"title":"Nancy Pelosi respaldar\u00e1 a nieto de John F. Kennedy para un esca\u00f1o en la C\u00e1mara de Representantes de EE.UU.","author":"","date":"febrero 8, 2026","format":false,"excerpt":"Seg\u00fan una fuente familiarizada con el tema, la expresidenta de la C\u00e1mara de Representantes, Nancy Pelosi, planea respaldar a Jack Schlossberg en su candidatura para un disputado esca\u00f1o en la C\u00e1mara de Representantes de EE.UU.Schlossberg, nieto de John F. Kennedy y primo del secretario de Salud y Servicios Humanos Robert\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455852,"url":"https:\/\/noticiasya.com\/laredo\/2024\/11\/15\/kennedy-jr-salud-estados-unidos-preocupa-expertos-trax\/","url_meta":{"origin":1466208,"position":5},"title":"El plan de Robert F. Kennedy Jr. para hacer &#171;saludable&#187; a Estados Unidos preocupa a los expertos en salud","author":"","date":"noviembre 15, 2024","format":false,"excerpt":"(CNN) -- La elecci\u00f3n por parte del presidente Donald Trump de Robert F. Kennedy Jr. como secretario del Departamento de Salud y Servicios Humanos de EE.UU. \"es una elecci\u00f3n extraordinariamente mala para la salud del pueblo estadounidense\", advirti\u00f3 el jueves el Dr. Ashish Jha, decano de la Escuela de Salud\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1466208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1466208"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1466208\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1466208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1466208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1466208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}