{"id":1466212,"date":"2025-09-06T18:03:41","date_gmt":"2025-09-07T01:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/"},"modified":"2025-09-06T18:03:41","modified_gmt":"2025-09-07T01:03:41","slug":"miedo-ice-chicago-evento-independencia-mexico-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/","title":{"rendered":"El miedo a operativos del ICE en Chicago pospone un importante evento de la Independencia de M\u00e9xico"},"content":{"rendered":"<p>Uno de los eventos m\u00e1s grandes del D\u00eda de la Independencia de M\u00e9xico que suele celebrarse en el \u00e1rea de Chicago a mediados de septiembre se est\u00e1 posponiendo, confirmaron los organizadores a CNN el jueves, ya que se espera que aumenten las acciones de control migratorio en la zona, posiblemente reforzadas por un despliegue de la Guardia Nacional.<\/p>\n<p>El desfile y festival Fiesta Patrias se celebra cada a\u00f1o en Waukegan, un suburbio al norte a orillas del lago Michigan, cerca de la Base Naval Great Lakes, la instalaci\u00f3n que se utilizar\u00e1 como centro de mando para los agentes de inmigraci\u00f3n que llegar\u00e1n.<\/p>\n<p>\u201cS\u00e9 que quiz\u00e1s los vendedores est\u00e1n molestos, pero es lo que es: por la seguridad de la gente\u201d, dijo Margaret Carrasco, presidenta de Fiesta Patrias, que se ha reprogramado provisionalmente para el 1 de noviembre en lugar del 14 de septiembre.<\/p>\n<p>\u201cEn cambio, vamos a dejar que Chicago sea el objetivo, vamos a retirarnos de este desfile\u2026 Nunca pens\u00e9 en un mill\u00f3n de a\u00f1os que esto suceder\u00eda\u201d, agreg\u00f3 sobre el primer aplazamiento en los 30 a\u00f1os de historia del evento.<\/p>\n<p>Algunos han cuestionado el momento del aumento de las acciones de control migratorio: \u201cTenemos razones para creer que (el secretario general adjunto de la Casa Blanca) Stephen Miller eligi\u00f3 el mes de septiembre para venir a Chicago debido a las celebraciones por el D\u00eda de la Independencia de M\u00e9xico que se realizan aqu\u00ed cada a\u00f1o\u201d, dijo el gobernador dem\u00f3crata J. B. Pritzker.<\/p>\n<p>El Grito Chicago, un festival de dos d\u00edas en el Grant Park del centro, tambi\u00e9n decidi\u00f3 posponer citando preocupaciones por la \u201cseguridad de nuestra comunidad\u201d.<\/p>\n<p>\u201cNos entristece la p\u00e9rdida de una oportunidad para promover una visi\u00f3n de dignidad, fuerza y pertenencia en un momento en que es sumamente necesario\u201d, dijeron los organizadores del evento en un comunicado.<\/p>\n<p>\u201cMe parte el coraz\u00f3n informar que nos han dicho que el ICE intentar\u00e1 interrumpir los picnics comunitarios y los desfiles pac\u00edficos\u201d, dijo Pritzker esta semana en t\u00e9rminos generales. \u201cSeamos claros: el terror y la crueldad son el objetivo, no la seguridad de quienes viven aqu\u00ed\u201d, dijo.<\/p>\n<p>Cuando se le pregunt\u00f3 el jueves si la gente en la ciudad deber\u00eda quedarse en casa para evitar cualquier posible acci\u00f3n policial o de inmigraci\u00f3n, el alcalde Johnson rechaz\u00f3 la idea.<\/p>\n<p>\u201cYo s\u00e9 que el presidente est\u00e1 trabajando duro para intimidar a la gente de Chicago\u201d, dijo. \u201cYo no estoy intimidado. Y nadie deber\u00eda estarlo\u201d.<\/p>\n<p>Por otro lado, el barrio de Pilsen en Chicago es predominantemente latino y la celebraci\u00f3n del desfile por el D\u00eda de la Independencia de M\u00e9xico se realiz\u00f3 en gran medida con normalidad este s\u00e1bado, a pesar de las preocupaciones por el aumento de operativos de inmigraci\u00f3n en la ciudad.<\/p>\n<p>\u201cSiempre es un buen momento para celebrar nuestra cultura y nuestras costumbres. Creo que ahora m\u00e1s que nunca debemos demostrar que estamos unidos y que somos una comunidad\u201d, dijo Araceli Lucio, residente de larga data, a CNN.<\/p>\n<p>Lucio no tuvo temor de asistir a las celebraciones pese a la creciente preocupaci\u00f3n por los operativos migratorios en la ciudad, aunque considera que el presidente Donald Trump est\u00e1 \u201csembrando miedo\u201d, incluso entre quienes \u201csolo vienen a trabajar\u201d.<\/p>\n<p>\u201cHay mucho miedo\u201d en los barrios de Chicago en este momento, se\u00f1al\u00f3, especialmente \u201centre quienes sienten que pueden ser deportados y que inmigraci\u00f3n podr\u00eda llegar en cualquier momento\u201d.<\/p>\n<p>Lucio tambi\u00e9n critic\u00f3 algunos de los m\u00e9todos que el Gobierno de Trump ha utilizado hasta ahora para la aplicaci\u00f3n de las leyes migratorias, a veces de manera muy visible y publicitada.<\/p>\n<p>\u201cSi alguien est\u00e1 cometiendo delitos, creo que hay otras formas de hacer su trabajo sin generar tanto temor en la comunidad\u201d, dijo a CNN.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los eventos m\u00e1s grandes del D\u00eda de la Independencia de M\u00e9xico que suele celebrarse en el \u00e1rea de Chicago a mediados de septiembre se est\u00e1 posponiendo, confirmaron los organizadores a CNN el jueves, ya que se espera que aumenten las acciones de control migratorio en la zona, posiblemente reforzadas por un despliegue de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466212","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El miedo a operativos del ICE en Chicago pospone un importante evento de la Independencia de M\u00e9xico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El miedo a operativos del ICE en Chicago pospone un importante evento de la Independencia de M\u00e9xico - Noticias\" \/>\n<meta property=\"og:description\" content=\"Uno de los eventos m\u00e1s grandes del D\u00eda de la Independencia de M\u00e9xico que suele celebrarse en el \u00e1rea de Chicago a mediados de septiembre se est\u00e1 posponiendo, confirmaron los organizadores a CNN el jueves, ya que se espera que aumenten las acciones de control migratorio en la zona, posiblemente reforzadas por un despliegue de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-07T01:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El miedo a operativos del ICE en Chicago pospone un importante evento de la Independencia de M\u00e9xico\",\"datePublished\":\"2025-09-07T01:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/\"},\"wordCount\":681,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/\",\"name\":\"El miedo a operativos del ICE en Chicago pospone un importante evento de la Independencia de M\u00e9xico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-07T01:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El miedo a operativos del ICE en Chicago pospone un importante evento de la Independencia de M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El miedo a operativos del ICE en Chicago pospone un importante evento de la Independencia de M\u00e9xico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El miedo a operativos del ICE en Chicago pospone un importante evento de la Independencia de M\u00e9xico - Noticias","og_description":"Uno de los eventos m\u00e1s grandes del D\u00eda de la Independencia de M\u00e9xico que suele celebrarse en el \u00e1rea de Chicago a mediados de septiembre se est\u00e1 posponiendo, confirmaron los organizadores a CNN el jueves, ya que se espera que aumenten las acciones de control migratorio en la zona, posiblemente reforzadas por un despliegue de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-07T01:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/"},"author":{"name":"","@id":""},"headline":"El miedo a operativos del ICE en Chicago pospone un importante evento de la Independencia de M\u00e9xico","datePublished":"2025-09-07T01:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/"},"wordCount":681,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/","name":"El miedo a operativos del ICE en Chicago pospone un importante evento de la Independencia de M\u00e9xico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-07T01:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El miedo a operativos del ICE en Chicago pospone un importante evento de la Independencia de M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El miedo a operativos del ICE en Chicago pospone un importante evento de la Independencia de M\u00e9xico","url":"http:\/\/noticiasya.com\/laredo\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/09\/06\/miedo-ice-chicago-evento-independencia-mexico-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-07T01:03:41Z","datePublished":"2025-09-07T01:03:41Z","dateModified":"2025-09-07T01:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El miedo a operativos del ICE en Chicago pospone un importante evento de la Independencia de M\\u00e9xico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/09\\\/06\\\/miedo-ice-chicago-evento-independencia-mexico-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/09\\\/06\\\/miedo-ice-chicago-evento-independencia-mexico-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-07T01:03:41Z\",\"datePublished\":\"2025-09-07T01:03:41Z\",\"dateModified\":\"2025-09-07T01:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466167,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/04\/eventos-cancelados-oposicion-trump-chicago-guardia-nacional-orix\/","url_meta":{"origin":1466212,"position":0},"title":"Comunidad latina en Chicago se prepara para la posible llegada de la Guardia Nacional entre el miedo y la oposici\u00f3n a Trump","author":"","date":"septiembre 4, 2025","format":false,"excerpt":"Chicago, la ciudad m\u00e1s grande del estado de Illinois, se encuentra atrapada entre el miedo y la incertidumbre debido a las pol\u00edticas migratorias del Gobierno de Donald Trump.Esta semana, el gobernador de Illinois, J. B. Pritzker, dijo que en los siguientes d\u00edas esperan que la Casa Blanca lleve a cabo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466242,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/07\/chicago-dia-independencia-mexico-inmigracion-trax\/","url_meta":{"origin":1466212,"position":1},"title":"En Chicago, las celebraciones del D\u00eda de la Independencia de M\u00e9xico se ven opacadas por amenazas de redadas del ICE","author":"","date":"septiembre 7, 2025","format":false,"excerpt":"En el suroeste de Chicago, la m\u00fasica retumbaba y las banderas verde, blanca y roja ondeaban por las calles del barrio mayoritariamente latino de Pilsen, donde el s\u00e1bado multitudes se reunieron para dar inicio a las celebraciones del D\u00eda de la Independencia de M\u00e9xico.Artistas disfrazados y ni\u00f1os con canastas llenas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464933,"url":"https:\/\/noticiasya.com\/laredo\/2025\/07\/28\/congresistas-interrumpen-discurso-boluarte-fiestas-patrias-orix\/","url_meta":{"origin":1466212,"position":2},"title":"Congresistas interrumpen discurso de la presidenta Dina Boluarte por la celebraci\u00f3n de las Fiestas Patrias","author":"","date":"julio 28, 2025","format":false,"excerpt":"Jaime Quito fue uno de los parlamentarios que se manifest\u00f3 mientras la mandataria se dirig\u00eda al Congreso. Quito alz\u00f3 un cartel que dec\u00eda \u201cDina, el pueblo te repudia\u201d.En declaraciones a CNN, el parlamentario calific\u00f3 la primera parte del discurso de la mandataria de \u201cprovocador\u201d y que trat\u00f3 de \u201cjustificar los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452720,"url":"https:\/\/noticiasya.com\/laredo\/2024\/09\/16\/grito-independencia-2024-ciudad-de-mexico-horarios-programacion-conciertos-orix\/","url_meta":{"origin":1466212,"position":3},"title":"Grito de Independencia 2024 en Ciudad de M\u00e9xico: horarios, programaci\u00f3n y conciertos","author":"","date":"septiembre 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Los festejos por el D\u00eda de la Independencia en la Ciudad de M\u00e9xico se concentrar\u00e1n en el Z\u00f3calo, la principal plaza p\u00fablica del pa\u00eds, donde Andr\u00e9s Manuel L\u00f3pez Obrador dar\u00e1 su \u00faltimo \u201cGrito de Dolores\u201d como presidente de M\u00e9xico, unas semanas antes de que termine su sexenio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1426797,"url":"https:\/\/noticiasya.com\/laredo\/2022\/09\/16\/video-a-golpes-asi-terminaron-las-fiestas-patrias-en-juarez\/","url_meta":{"origin":1466212,"position":4},"title":"VIDEO: \u00a1A golpes! As\u00ed terminaron las fiestas patrias en Ju\u00e1rez","author":"agomez","date":"septiembre 16, 2022","format":"video","excerpt":"Se ve a algunos huir, mientras que otros, prefirieron quedarse a grabar el momento.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/laredo\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466487,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/15\/celebraciones-independencia-mexico-los-angeles-chicago-eeuu-orix\/","url_meta":{"origin":1466212,"position":5},"title":"As\u00ed fueron las celebraciones por el d\u00eda de la Independencia de M\u00e9xico en Los \u00c1ngeles, Chicago y otras ciudades de EE.UU.","author":"agomez","date":"septiembre 15, 2025","format":false,"excerpt":"Mariachis en carros aleg\u00f3ricos, ni\u00f1os ondeando banderas tricolores y familias enteras vestidas con trajes t\u00edpicos mexicanos marcaron este fin de semana las celebraciones por el D\u00eda de la Independencia de M\u00e9xico en varias ciudades de Estados Unidos.En Chicago, Los \u00c1ngeles y Nueva York las comunidades mexicanas se reunieron para festejar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1466212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1466212"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1466212\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1466212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1466212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1466212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}