{"id":1466227,"date":"2025-09-07T09:03:39","date_gmt":"2025-09-07T16:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/"},"modified":"2025-09-07T09:03:39","modified_gmt":"2025-09-07T16:03:39","slug":"ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/","title":{"rendered":"EE.UU. reembolsar\u00e1 cerca de la mitad de los aranceles si la Corte Suprema falla contra Trump, dice Bessent"},"content":{"rendered":"<p>El Departamento del Tesoro emitir\u00e1 reembolsos si la Corte Suprema confirma un fallo que sostiene que los aranceles \u201crec\u00edprocos\u201d del presidente Donald Trump fueron un exceso de poder, dijo este domingo el secretario del Tesoro, Scott Bessent.<\/p>\n<p>\u201cTendr\u00edamos que devolver alrededor de la mitad de los aranceles, lo que ser\u00eda terrible para el Tesoro\u201d, dijo Bessent durante una aparici\u00f3n en \u201cMeet the Press\u201d de NBC News.<\/p>\n<p>Agreg\u00f3: \u201cSi la corte lo dice, tendr\u00edamos que hacerlo\u201d.<\/p>\n<p>Pero existen \u201cnumerosas otras v\u00edas\u201d en lugar de los reembolsos, dijo Bessent, sin dar detalles.<\/p>\n<p>Un tribunal federal de apelaciones fall\u00f3 el 29 de agosto que los aranceles \u201crec\u00edprocos\u201d de Trump estaban entre los derechos de importaci\u00f3n que exceden la autoridad presidencial, al se\u00f1alar que la Ley de Poderes Econ\u00f3micos en Caso de Emergencia Internacional (IEEPA, por sus siglas en ingl\u00e9s) no autoriza los aranceles de emergencia que Trump impuso a principios de este a\u00f1o.<\/p>\n<p>\u201cNo discernimos ninguna autorizaci\u00f3n clara del Congreso en la IEEPA para aranceles de la magnitud de los Aranceles Rec\u00edprocos y los Aranceles por Tr\u00e1fico\u201d, dijo el tribunal en su fallo mayoritario.<\/p>\n<p>La nueva tanda de los llamados aranceles \u201crec\u00edprocos\u201d del Gobierno de Trump, que entr\u00f3 en vigor a principios de agosto, seguir\u00e1 vigente despu\u00e9s de que el tribunal retrasara la aplicaci\u00f3n de su orden hasta el 14 de octubre.<\/p>\n<p>El fallo judicial ha puesto en duda la capacidad del Gobierno de Trump de continuar las negociaciones comerciales. El Gobierno de Trump apel\u00f3 el fallo ante la Corte Suprema el mi\u00e9rcoles, advirtiendo de una \u201cnaci\u00f3n pobre\u201d sin aranceles.<\/p>\n<p>Bessent dijo este domingo que est\u00e1 \u201cseguro\u201d de que el Gobierno de Trump ganar\u00e1 en la Corte Suprema.<\/p>\n<p>Pero el impacto de las pol\u00edticas econ\u00f3micas de Trump puede estar empezando a revelarse. El informe de empleo de agosto de la Oficina de Estad\u00edsticas Laborales indic\u00f3 que la econom\u00eda de EE.UU. a\u00f1adi\u00f3 alrededor de 22.000 puestos de trabajo en ese mes y que la tasa de desempleo subi\u00f3 a 4,3 %, su nivel m\u00e1s alto en casi cuatro a\u00f1os.<\/p>\n<p>Entre los sectores m\u00e1s golpeados est\u00e1n los de bienes. La pol\u00edtica arancelaria, y la manera vol\u00e1til en que se aplica, han tenido un impacto \u201cinnegable\u201d en la contrataci\u00f3n, escribi\u00f3 el economista de RSM US Joe Brusuelas en una nota a inversionistas el viernes. Los negocios de bienes han registrado \u201ccuatro meses consecutivos de ca\u00eddas desde mayo\u201d, se\u00f1al\u00f3 Brusuelas.<\/p>\n<p>\u201cNo podemos chasquear los dedos y tener f\u00e1bricas construidas\u201d, dijo Bessent, y a\u00f1adi\u00f3 que \u201cvamos a ver empleos en la construcci\u00f3n y en la manufactura\u201d, en parte debido a la aprobaci\u00f3n de la \u201cGran y Hermosa Ley \u00danica\u201d.<\/p>\n<p>El Gobierno de Trump ha insistido en que las compa\u00f1\u00edas estadounidenses deber\u00edan \u201cabsorber\u201d los costos adicionales de los aranceles, negando que esos derechos sean un impuesto a los consumidores. Pero Nike, Hasbro y Walmart est\u00e1n entre las empresas que advierten que los aranceles derivar\u00e1n en aumentos de precios a medida que EE.UU. recauda ingresos aduaneros de las importaciones.<\/p>\n<p>Estados Unidos recaud\u00f3 aproximadamente US$ 28.000 millones en derechos de aduana en julio, seg\u00fan el informe mensual del Tesoro. En abril, el Tesoro inform\u00f3 que recaud\u00f3 US$ 16.800 millones en derechos de aduana brutos.<\/p>\n<p>En junio, el Departamento de Seguridad Nacional dijo que la Oficina de Aduanas y Protecci\u00f3n Fronteriza de EE.UU. recaud\u00f3 US$ 81.500 millones de los aranceles de Trump.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Departamento del Tesoro emitir\u00e1 reembolsos si la Corte Suprema confirma un fallo que sostiene que los aranceles \u201crec\u00edprocos\u201d del presidente Donald Trump fueron un exceso de poder, dijo este domingo el secretario del Tesoro, Scott Bessent. \u201cTendr\u00edamos que devolver alrededor de la mitad de los aranceles, lo que ser\u00eda terrible para el Tesoro\u201d, dijo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466227","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. reembolsar\u00e1 cerca de la mitad de los aranceles si la Corte Suprema falla contra Trump, dice Bessent - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. reembolsar\u00e1 cerca de la mitad de los aranceles si la Corte Suprema falla contra Trump, dice Bessent - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Departamento del Tesoro emitir\u00e1 reembolsos si la Corte Suprema confirma un fallo que sostiene que los aranceles \u201crec\u00edprocos\u201d del presidente Donald Trump fueron un exceso de poder, dijo este domingo el secretario del Tesoro, Scott Bessent. \u201cTendr\u00edamos que devolver alrededor de la mitad de los aranceles, lo que ser\u00eda terrible para el Tesoro\u201d, dijo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-07T16:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. reembolsar\u00e1 cerca de la mitad de los aranceles si la Corte Suprema falla contra Trump, dice Bessent\",\"datePublished\":\"2025-09-07T16:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/\"},\"wordCount\":624,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/\",\"name\":\"EE.UU. reembolsar\u00e1 cerca de la mitad de los aranceles si la Corte Suprema falla contra Trump, dice Bessent - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-07T16:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. reembolsar\u00e1 cerca de la mitad de los aranceles si la Corte Suprema falla contra Trump, dice Bessent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. reembolsar\u00e1 cerca de la mitad de los aranceles si la Corte Suprema falla contra Trump, dice Bessent - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. reembolsar\u00e1 cerca de la mitad de los aranceles si la Corte Suprema falla contra Trump, dice Bessent - Noticias","og_description":"El Departamento del Tesoro emitir\u00e1 reembolsos si la Corte Suprema confirma un fallo que sostiene que los aranceles \u201crec\u00edprocos\u201d del presidente Donald Trump fueron un exceso de poder, dijo este domingo el secretario del Tesoro, Scott Bessent. \u201cTendr\u00edamos que devolver alrededor de la mitad de los aranceles, lo que ser\u00eda terrible para el Tesoro\u201d, dijo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-07T16:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/"},"author":{"name":"","@id":""},"headline":"EE.UU. reembolsar\u00e1 cerca de la mitad de los aranceles si la Corte Suprema falla contra Trump, dice Bessent","datePublished":"2025-09-07T16:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/"},"wordCount":624,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/","name":"EE.UU. reembolsar\u00e1 cerca de la mitad de los aranceles si la Corte Suprema falla contra Trump, dice Bessent - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-07T16:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. reembolsar\u00e1 cerca de la mitad de los aranceles si la Corte Suprema falla contra Trump, dice Bessent"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. reembolsar\u00e1 cerca de la mitad de los aranceles si la Corte Suprema falla contra Trump, dice Bessent","url":"http:\/\/noticiasya.com\/laredo\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/09\/07\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-07T16:03:39Z","datePublished":"2025-09-07T16:03:39Z","dateModified":"2025-09-07T16:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. reembolsar\\u00e1 cerca de la mitad de los aranceles si la Corte Suprema falla contra Trump, dice Bessent\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/09\\\/07\\\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/09\\\/07\\\/ee-uu-reembolsara-mitad-aranceles-corte-falla-contra-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-07T16:03:39Z\",\"datePublished\":\"2025-09-07T16:03:39Z\",\"dateModified\":\"2025-09-07T16:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468400,"url":"https:\/\/noticiasya.com\/laredo\/2025\/11\/16\/cheques-us-2000-aranceles-trump-trax\/","url_meta":{"origin":1466227,"position":0},"title":"Secretario del Tesoro dice &#171;ya veremos&#187; sobre cheques de US$ 2.000 mientras la Corte Suprema eval\u00faa los aranceles de Trump","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"El secretario del Tesoro, Scott Bessent, dijo este domingo que la propuesta del presidente Donald Trump de emitir cheques de reembolso por aranceles de US$ 2.000 para la mayor\u00eda de los estadounidenses requerir\u00eda la aprobaci\u00f3n del Congreso.\u201cYa veremos. Necesitamos una ley para eso\u201d, dijo Bessent en \u201cSunday Morning Futures\u201d de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471495,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/20\/quien-recibira-reembolso-aranceles-trump-trax\/","url_meta":{"origin":1466227,"position":1},"title":"La pregunta de US$ 134.000 millones: \u00bfqui\u00e9n recibir\u00e1 un reembolso de aranceles?","author":"","date":"febrero 20, 2026","format":false,"excerpt":"La batalla acaba de comenzar para las 300.000 empresas que buscan que se les reembolsen US$ 134.000 millones en aranceles.Result\u00f3 que convencer a seis jueces de la Corte Suprema de que el presidente Donald Trump excedi\u00f3 su autoridad al imponer aranceles generalizados bajo poderes econ\u00f3micos de emergencia fue la parte\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471590,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/24\/aranceles-reembolso-corte-suprema-consumidores-eeuu-trax\/","url_meta":{"origin":1466227,"position":2},"title":"Has pagado por los aranceles, pero no recibir\u00e1s ning\u00fan reembolso","author":"","date":"febrero 24, 2026","format":false,"excerpt":"El Gobierno est\u00e1 obligado a reembolsar US$ 134.000 millones (y la cifra sigue aumentando) en ingresos recaudados por los amplios aranceles del presidente Donald Trump que la Corte Suprema declar\u00f3 ilegales la semana pasada.\u00bfCu\u00e1nto de esa cantidad recuperar\u00e1n los consumidores que pagaron los elevados aranceles a trav\u00e9s de precios m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466116,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/03\/trump-aranceles-reembolso-trax\/","url_meta":{"origin":1466227,"position":3},"title":"Si Trump pierde su demanda sobre aranceles, EE.UU. podr\u00eda tener que reembolsar a las empresas m\u00e1s de US$ 200.000 millones","author":"","date":"septiembre 3, 2025","format":false,"excerpt":"La mayor\u00eda de los aranceles generalizados que el presidente de EE.UU., Donald Trump, ha impuesto durante su segundo mandato enfrentan una \u00faltima prueba decisiva que determinar\u00e1 si puede seguir aplic\u00e1ndolos o si las empresas son elegibles para recibir reembolsos masivos.Ese giro potencialmente dram\u00e1tico en la saga de los aranceles se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470553,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/28\/decision-corte-suprema-aranceles-trump-trax\/","url_meta":{"origin":1466227,"position":4},"title":"\u00bfD\u00f3nde est\u00e1 la decisi\u00f3n de la Corte Suprema sobre los aranceles de Trump?","author":"","date":"enero 28, 2026","format":false,"excerpt":"Cuando la Corte Suprema accedi\u00f3 en septiembre a escuchar una disputa sobre los aranceles multimillonarios impuestos por el presidente Donald Trump a los productos extranjeros, atendi\u00f3 la petici\u00f3n del Gobierno de que el tiempo era crucial.Para Trump, el caso es una cuesti\u00f3n de \u201cVIDA O MUERTE para nuestro pa\u00eds\u201d, como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471556,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/23\/corte-suprema-trump-escape-aranceles-trax\/","url_meta":{"origin":1466227,"position":5},"title":"La Corte Suprema acaba de darle a Trump una v\u00eda de escape para los aranceles, pero \u00e9l no la va a aprovechar","author":"","date":"febrero 23, 2026","format":false,"excerpt":"La implementaci\u00f3n de aranceles sin precedentes por parte del presidente Donald Trump ha inyectado una enorme incertidumbre en la econom\u00eda global, ha afectado el crecimiento del empleo en Estados Unidos y ha aumentado los precios, de paso.El viernes, la Corte Suprema le dio a Trump una v\u00eda de escape de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1466227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1466227"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1466227\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1466227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1466227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1466227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}