{"id":1466237,"date":"2025-09-07T17:04:03","date_gmt":"2025-09-08T00:04:03","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/"},"modified":"2025-09-07T17:04:03","modified_gmt":"2025-09-08T00:04:03","slug":"iphone-air-evento-apple-septiembre-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/","title":{"rendered":"Un \u2018iPhone Air,\u2019 aumentos de precio e IA: Qu\u00e9 esperar del evento m\u00e1s grande del a\u00f1o de Apple"},"content":{"rendered":"<p>El iPhone necesita una renovaci\u00f3n y podr\u00eda verse el 9 de septiembre, cuando se espera que <a href=\"https:\/\/www.cnn.com\/2025\/08\/26\/tech\/apples-iphone-17-launch-september-9-what-to-expect\">Apple anuncie un modelo de iPhone<\/a> totalmente nuevo y m\u00e1s delgado, que podr\u00eda llamarse \u201ciPhone Air\u201d, junto con el iPhone 17 y nuevos modelos de Apple Watch en su evento anual principal.<\/p>\n<p>Ese tipo de revisi\u00f3n ser\u00eda el primer redise\u00f1o dr\u00e1stico del producto insignia de Apple desde 2017, cuando Apple lanz\u00f3 el iPhone X, el primer modelo sin el familiar bot\u00f3n de inicio y con la tecnolog\u00eda Face ID ahora omnipresente de Apple. Ese cambio sent\u00f3 las bases para las generaciones futuras de iPhone.<\/p>\n<p>Pero el iPhone Air, que, <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2025-09-05\/what-apple-is-planning-to-introduce-at-sept-9-awe-dropping-iphone-17-event?srnd=undefined\">seg\u00fan Bloomberg<\/a>, se anunciar\u00e1 en el evento de este a\u00f1o, podr\u00eda desempe\u00f1ar un papel diferente. En lugar de sentar las bases para el futuro del iPhone, un iPhone Air podr\u00eda a\u00f1adir m\u00e1s variedad a la l\u00ednea de iPhone para clientes que quieren algo diferente, dicen los analistas.<\/p>\n<p>Si bien las ventas de iPhone han sido s\u00f3lidas, como indic\u00f3 el <a href=\"https:\/\/www.cnn.com\/2025\/07\/31\/tech\/apple-earnings-iphone-china-ai\">informe de ganancias<\/a> m\u00e1s reciente de Apple en julio, los consumidores solo actualizan cuando sienten que las nuevas caracter\u00edsticas valen la pena, y eso est\u00e1 ocurriendo con menos frecuencia ahora, seg\u00fan la firma de investigaci\u00f3n de mercado Consumer Intelligence Research Partners.<\/p>\n<p>Y a diferencia de sus rivales de Android, Samsung y Google, que se han apoyado en la inteligencia artificial en el software de sus tel\u00e9fonos inteligentes, se espera que Apple Intelligence pase a un segundo plano durante el evento del martes, incluso mientras persisten las percepciones de que la empresa est\u00e1 rezagada en cuestiones de inteligencia artificial.<\/p>\n<p>Apple tambi\u00e9n podr\u00eda disipar las dudas sobre si los aranceles aumentar\u00e1n los precios del iPhone.<\/p>\n<p>Pero una pregunta m\u00e1s grande se cierne sobre todo esto: el producto de gran \u00e9xito de Apple, de 18 a\u00f1os, \u00bfpuede todav\u00eda entusiasmar a los consumidores?<\/p>\n<p>Apple no respondi\u00f3 de inmediato a la solicitud de comentarios de CNN.<\/p>\n<p>Cuando Google present\u00f3 la l\u00ednea Pixel 10 en agosto, adelant\u00e1ndose al anuncio del iPhone de Apple, su asistente Gemini fue el protagonista. Rick Osterloh, vicepresidente senior de plataformas y dispositivos de Google, comenz\u00f3 el evento de lanzamiento con una visi\u00f3n general de la visi\u00f3n de la empresa sobre Gemini, afirmando que el asistente digital puede \u201cdesbloquear mucha utilidad en tu tel\u00e9fono\u201d.<\/p>\n<p>Una de las caracter\u00edsticas nuevas distintivas del Pixel 10 es una herramienta <a href=\"https:\/\/www.cnn.com\/2025\/08\/20\/tech\/google-pixel-10-ai-features-magic-cue\">llamada Magic Cue<\/a>, que utiliza IA para analizar lo que est\u00e1s haciendo en tu tel\u00e9fono y sugerir la siguiente acci\u00f3n.<\/p>\n<p>Samsung, de manera similar, promocion\u00f3 las capacidades de IA en el Galaxy S25 \u2014su tel\u00e9fono insignia que compite con el iPhone\u2014 como un punto de venta importante cuando present\u00f3 el dispositivo en enero. Una de esas caracter\u00edsticas permite a los usuarios realizar una tarea de varios pasos, como buscar el calendario de un equipo deportivo y a\u00f1adirlo a su calendario, con un comando de voz.<\/p>\n<p>Pero los analistas dicen que Apple est\u00e1 muy rezagada en IA para adoptar ese enfoque. En cambio, se espera que se enfoque m\u00e1s en los avances de hardware que en la IA.<\/p>\n<p>Ted Mortonson, estratega de tecnolog\u00eda en Baird, dijo que los avances de IA de Apple probablemente a\u00fan no est\u00e9n listos, y agreg\u00f3 que la empresa est\u00e1 bajo presi\u00f3n para impresionar cuando entregue nuevas herramientas de IA o de lo contrario podr\u00eda arriesgarse a perder clientes frente a Samsung y Google.<\/p>\n<p>A principios de este a\u00f1o, Apple retras\u00f3 una actualizaci\u00f3n de alto perfil que habr\u00eda permitido a Siri actuar en todas las aplicaciones y responder preguntas sobre el contenido en la pantalla de tu tel\u00e9fono. La caracter\u00edstica habr\u00eda puesto a Siri al d\u00eda con agentes de IA m\u00e1s sofisticados como Gemini de Google y ChatGPT de OpenAI.<\/p>\n<p>Apple dijo que necesitaba m\u00e1s tiempo para llevar la tecnolog\u00eda al \u201calto est\u00e1ndar de calidad\u201d de la empresa.<\/p>\n<p>\u201cDando un paso atr\u00e1s, vemos la IA como una de las tecnolog\u00edas m\u00e1s profundas de nuestra vida\u201d, dijo el ceo Tim Cook en sus comentarios de apertura durante la llamada de ganancias de Apple en julio. \u201cLa estamos integrando en nuestros dispositivos y plataformas y en toda la empresa. Tambi\u00e9n estamos aumentando significativamente nuestras inversiones\u201d.<\/p>\n<p>Aun as\u00ed, la IA no est\u00e1 \u201cobligando a los usuarios a ir a las tiendas para actualizarse\u201d, dijo anteriormente a CNN por correo electr\u00f3nico Nabila Popal, directora s\u00e9nior del equipo de datos y an\u00e1lisis de International Data Corporation (IDC). Y entre un <a href=\"https:\/\/www.artificialintelligence-news.com\/wp-content\/uploads\/2025\/08\/ai_report_2025.pdf\">estudio del MIT<\/a> que indica que el 95 % de las organizaciones no est\u00e1n obteniendo ning\u00fan retorno de sus inversiones en IA y las ganancias moderadas de Nvidia, el fabricante de chips en el centro del auge de la IA, existe una creciente sensaci\u00f3n de que la fiebre del oro de la IA podr\u00eda estar sobrevalorada.<\/p>\n<p>Pero el iPhone sigue siendo uno de los tel\u00e9fonos inteligentes m\u00e1s ubicuos del mundo, representando el 15,7 % de la cuota global de tel\u00e9fonos inteligentes, justo por detr\u00e1s del l\u00edder del mercado Samsung, seg\u00fan la <a href=\"https:\/\/my.idc.com\/getdoc.jsp?containerId=prUS53684525\">IDC<\/a>.<\/p>\n<p>Es probable que Apple aproveche esa ventaja, optando por enfocarse en mejoras en la funcionalidad principal del iPhone, como la duraci\u00f3n de la bater\u00eda, la calidad de la c\u00e1mara y el dise\u00f1o. Y el precio ser\u00e1 una prioridad; tanto Wall Street como los consumidores estar\u00e1n atentos para ver si los aranceles han afectado el precio del nuevo iPhone.<\/p>\n<p>Analistas de Morgan Stanley y Loop Capital creen que podr\u00eda haber incrementos de precios.<br \/>La compa\u00f1\u00eda podr\u00eda eliminar una de las opciones de almacenamiento m\u00e1s bajas para el iPhone 17 Pro para impulsar a los consumidores hacia los modelos m\u00e1s caros, escribi\u00f3 un grupo de analistas de Morgan Stanley liderado por Erik Woodring en una nota de investigaci\u00f3n del 4 de septiembre. Esto podr\u00eda ayudar a Apple a compensar los precios de los mayores costos de los componentes, se\u00f1al\u00f3 el informe.<\/p>\n<p>\u201cNormalmente, no es una buena se\u00f1al para un evento de lanzamiento cuando el precio es el gran foco, porque entonces el producto en s\u00ed mismo podr\u00eda no ser tan destacado en comparaci\u00f3n con las generaciones anteriores\u201d, dijo Runar Bj\u00f8rhovde, analista de investigaci\u00f3n de la firma de investigaci\u00f3n de mercado Canalys.<\/p>\n<p>Pero los aranceles del presidente Donald Trump hacen de este lanzamiento una excepci\u00f3n, ya que muchos estar\u00e1n atentos para ver si Apple cambia sus precios en EE.UU. y otros mercados. \u201c\u00bfC\u00f3mo decide Apple jugar ese juego?\u201d, dijo Bj\u00f8rhovde. \u201cA Apple no le gusta cambiar los precios con el tiempo, as\u00ed que lo que se establece desde el D\u00eda 1 es normalmente un indicador clave de lo que veremos para el pr\u00f3ximo a\u00f1o\u201d.<\/p>\n<p>Apple ha tenido dificultades en los \u00faltimos a\u00f1os para encontrar un cuarto modelo de iPhone que resuene tan fuertemente como el est\u00e1ndar, Pro y Pro Max. Elimin\u00f3 el iPhone Mini de su l\u00ednea despu\u00e9s de solo dos generaciones a partir del iPhone 14, y ahora se espera que la compa\u00f1\u00eda reemplace el modelo Plus con este nuevo Air.<\/p>\n<p>Pero eso podr\u00eda implicar compromisos como una sola c\u00e1mara en lugar de las dos en el iPhone 16 est\u00e1ndar, seg\u00fan <a href=\"https:\/\/www.bloomberg.com\/news\/newsletters\/2025-03-16\/apple-iphone-17-air-foldable-iphone-details-ai-crisis-to-haunt-top-100-event-m8bl3a9c\">Bloomberg<\/a>.<\/p>\n<p>El tel\u00e9fono tambi\u00e9n podr\u00eda ser dif\u00edcil de vender por otras razones. Los consumidores han ajustado sus presupuestos y est\u00e1n conservando sus tel\u00e9fonos inteligentes por per\u00edodos de tiempo <a href=\"https:\/\/www.marketwatch.com\/story\/why-people-are-now-keeping-their-phones-for-over-3-years-according-to-verizons-ceo-b101d44c\">m\u00e1s largos<\/a>, por lo que un dise\u00f1o delgado podr\u00eda no ser suficiente para atraer a nuevos compradores. Adem\u00e1s, Samsung ya se ha adelantado a Apple con un nuevo tel\u00e9fono m\u00e1s delgado llamado Galaxy S25 Edge.<\/p>\n<p>Aun as\u00ed, Apple tiene una ventaja.<\/p>\n<p>\u201cLa versi\u00f3n Air del MacBook ha perdurado. La versi\u00f3n Air del iPad ha perdurado\u201d, dijo Dipanjan Chatterjee, vicepresidente y analista principal de la firma de investigaci\u00f3n de mercado Forrester. \u201cAs\u00ed que hay buenas razones para creer que la versi\u00f3n Air \u2014un iPhone m\u00e1s delgado y fino\u2014 lo har\u00e1\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El iPhone necesita una renovaci\u00f3n y podr\u00eda verse el 9 de septiembre, cuando se espera que Apple anuncie un modelo de iPhone totalmente nuevo y m\u00e1s delgado, que podr\u00eda llamarse \u201ciPhone Air\u201d, junto con el iPhone 17 y nuevos modelos de Apple Watch en su evento anual principal. Ese tipo de revisi\u00f3n ser\u00eda el primer [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466237","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un \u2018iPhone Air,\u2019 aumentos de precio e IA: Qu\u00e9 esperar del evento m\u00e1s grande del a\u00f1o de Apple - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un \u2018iPhone Air,\u2019 aumentos de precio e IA: Qu\u00e9 esperar del evento m\u00e1s grande del a\u00f1o de Apple - Noticias\" \/>\n<meta property=\"og:description\" content=\"El iPhone necesita una renovaci\u00f3n y podr\u00eda verse el 9 de septiembre, cuando se espera que Apple anuncie un modelo de iPhone totalmente nuevo y m\u00e1s delgado, que podr\u00eda llamarse \u201ciPhone Air\u201d, junto con el iPhone 17 y nuevos modelos de Apple Watch en su evento anual principal. Ese tipo de revisi\u00f3n ser\u00eda el primer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-08T00:04:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un \u2018iPhone Air,\u2019 aumentos de precio e IA: Qu\u00e9 esperar del evento m\u00e1s grande del a\u00f1o de Apple\",\"datePublished\":\"2025-09-08T00:04:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/\"},\"wordCount\":1425,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/\",\"name\":\"Un \u2018iPhone Air,\u2019 aumentos de precio e IA: Qu\u00e9 esperar del evento m\u00e1s grande del a\u00f1o de Apple - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-08T00:04:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un \u2018iPhone Air,\u2019 aumentos de precio e IA: Qu\u00e9 esperar del evento m\u00e1s grande del a\u00f1o de Apple\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un \u2018iPhone Air,\u2019 aumentos de precio e IA: Qu\u00e9 esperar del evento m\u00e1s grande del a\u00f1o de Apple - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un \u2018iPhone Air,\u2019 aumentos de precio e IA: Qu\u00e9 esperar del evento m\u00e1s grande del a\u00f1o de Apple - Noticias","og_description":"El iPhone necesita una renovaci\u00f3n y podr\u00eda verse el 9 de septiembre, cuando se espera que Apple anuncie un modelo de iPhone totalmente nuevo y m\u00e1s delgado, que podr\u00eda llamarse \u201ciPhone Air\u201d, junto con el iPhone 17 y nuevos modelos de Apple Watch en su evento anual principal. Ese tipo de revisi\u00f3n ser\u00eda el primer [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-08T00:04:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/"},"author":{"name":"","@id":""},"headline":"Un \u2018iPhone Air,\u2019 aumentos de precio e IA: Qu\u00e9 esperar del evento m\u00e1s grande del a\u00f1o de Apple","datePublished":"2025-09-08T00:04:03+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/"},"wordCount":1425,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/","name":"Un \u2018iPhone Air,\u2019 aumentos de precio e IA: Qu\u00e9 esperar del evento m\u00e1s grande del a\u00f1o de Apple - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-08T00:04:03+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un \u2018iPhone Air,\u2019 aumentos de precio e IA: Qu\u00e9 esperar del evento m\u00e1s grande del a\u00f1o de Apple"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un \u2018iPhone Air,\u2019 aumentos de precio e IA: Qu\u00e9 esperar del evento m\u00e1s grande del a\u00f1o de Apple","url":"http:\/\/noticiasya.com\/laredo\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/09\/07\/iphone-air-evento-apple-septiembre-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-08T00:04:03Z","datePublished":"2025-09-08T00:04:03Z","dateModified":"2025-09-08T00:04:03Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un \\u2018iPhone Air,\\u2019 aumentos de precio e IA: Qu\\u00e9 esperar del evento m\\u00e1s grande del a\\u00f1o de Apple\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/09\\\/07\\\/iphone-air-evento-apple-septiembre-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/09\\\/07\\\/iphone-air-evento-apple-septiembre-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-08T00:04:03Z\",\"datePublished\":\"2025-09-08T00:04:03Z\",\"dateModified\":\"2025-09-08T00:04:03Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466306,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/09\/evento-iphone-air-iphone-17-apple-watch-trax\/","url_meta":{"origin":1466237,"position":0},"title":"Todo lo que Apple present\u00f3 en su gran evento: iPhone Air, iPhone 17, nuevos modelos de Apple Watch y m\u00e1s","author":"","date":"septiembre 9, 2025","format":false,"excerpt":"Apple present\u00f3 este martes el primer redise\u00f1o importante del iPhone en a\u00f1os al confirmar el lanzamiento de un nuevo modelo m\u00e1s delgado, el iPhone Air. El CEO, Tim Cook, lo calific\u00f3 como \u201cel mayor salto en la historia del iPhone\u201d.Este fue uno de varios lanzamientos de productos durante el evento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466264,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/08\/nuevo-iphone-17-fecha-lanzamiento-precios-colores-orix\/","url_meta":{"origin":1466237,"position":1},"title":"Nuevo iPhone 17: qu\u00e9 esperar, fecha de lanzamiento, precios, colores y m\u00e1s","author":"","date":"septiembre 8, 2025","format":false,"excerpt":"Apple presentar\u00e1 este martes su nueva l\u00ednea de tel\u00e9fonos iPhone 17 en su evento anual de oto\u00f1o boreal. Hay gran expectativa sobre los cambios que incluir\u00e1 su dispositivo insignia tanto en sistema operativo como en dise\u00f1o.Este a\u00f1o, el eslogan es \u201cAwe-dropping\u201d que se traduce como \u201cimpresionante\u201d.Habr\u00eda un tel\u00e9fono nuevo, m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470565,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/28\/encuesta-criticas-iphone-air-trax\/","url_meta":{"origin":1466237,"position":2},"title":"Seg\u00fan una encuesta, los consumidores no est\u00e1n convencidos con la gran apuesta de Apple por un iPhone m\u00e1s delgado","author":"","date":"enero 28, 2026","format":false,"excerpt":"Apple apost\u00f3 fuerte el a\u00f1o pasado por un redise\u00f1o dr\u00e1stico de su iPhone, el mayor cambio en su smartphone insignia en casi una d\u00e9cada. Pero el iPhone Air, m\u00e1s delgado, no parece haber conectado con los compradores.Nuevos datos de investigaci\u00f3n de mercado indican que la adopci\u00f3n del iPhone Air est\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466330,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/10\/iphone-air-apple-telefonos-inteligentes-emocionantes-trax\/","url_meta":{"origin":1466237,"position":3},"title":"iPhone Air: el \u00faltimo intento de Apple por hacer que los tel\u00e9fonos inteligentes vuelvan a ser emocionantes","author":"","date":"septiembre 10, 2025","format":false,"excerpt":"Durante buena parte de la \u00faltima d\u00e9cada, las c\u00e1maras m\u00e1s n\u00edtidas, las pantallas m\u00e1s grandes y la mayor duraci\u00f3n de la bater\u00eda han definido las actualizaciones anuales de los tel\u00e9fonos inteligentes.Pero eso puede que ya no sea suficiente para deslumbrar a los consumidores, al menos en opini\u00f3n de Apple.La compa\u00f1\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465887,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/26\/que-esperar-lanzamiento-nuevo-iphone-9-de-septiembre-trax\/","url_meta":{"origin":1466237,"position":4},"title":"\u00bfQu\u00e9 esperar del lanzamiento del nuevo iPhone este 9 de septiembre?","author":"","date":"agosto 26, 2025","format":false,"excerpt":"Apple celebrar\u00e1 un evento el 9 de septiembre, seg\u00fan dijo la compa\u00f1\u00eda en una invitaci\u00f3n a la prensa el martes, donde probablemente anunciar\u00e1 el iPhone 17 y nuevos Apple Watch, entre otros posibles nuevos dispositivos.Apple rara vez comparte detalles sobre productos futuros antes de anunciarlos, pero la compa\u00f1\u00eda ha estado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452517,"url":"https:\/\/noticiasya.com\/laredo\/2024\/09\/07\/nuevo-iphone-que-esperar-del-evento-de-apple-del-lunes-trax\/","url_meta":{"origin":1466237,"position":5},"title":"Qu\u00e9 esperar del nuevo iPhone que se presentar\u00e1 en un evento de Apple del lunes","author":"","date":"septiembre 7, 2024","format":false,"excerpt":"(CNN) -- A principios de a\u00f1o, Apple entusiasm\u00f3 a sus fans con su sistema de inteligencia artificial \"Apple Intelligence\". Ahora ha llegado el momento de demostrar que funciona.La compa\u00f1\u00eda est\u00e1 lista para presentar la primera l\u00ednea de iPhones creados espec\u00edficamente para la inteligencia artificial generativa (que permite a los usuarios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1466237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1466237"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1466237\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1466237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1466237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1466237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}