{"id":1469015,"date":"2025-12-05T17:03:46","date_gmt":"2025-12-06T01:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/"},"modified":"2025-12-05T17:03:46","modified_gmt":"2025-12-06T01:03:46","slug":"congresista-adelita-grijalva-gas-pimienta-redada-ice-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/","title":{"rendered":"La congresista Adelita Grijalva dice que fue rociada con gas pimienta durante una redada de ICE en Arizona"},"content":{"rendered":"<p>La representante Adelita Grijalva dijo el viernes que fue rociada con gas pimienta y empujada durante una redada del Servicio Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Tucson, Arizona, una afirmaci\u00f3n que el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) refut\u00f3 r\u00e1pidamente.<\/p>\n<p>La dem\u00f3crata de Arizona dijo en un video en X que el incidente ocurri\u00f3 cerca de un restaurante que frecuenta y que se top\u00f3 con una escena de \u201cquiz\u00e1s 40 agentes de ICE, la mayor\u00eda enmascarados, en varios veh\u00edculos\u201d que hab\u00edan sido \u201cdetenidos\u201d en la calle por personas que, seg\u00fan ella, \u201cten\u00edan miedo de que se llevaran a personas sin el debido proceso\u201d.<\/p>\n<p>Grijalva dijo que \u201cfue rociada en la cara por un agente muy agresivo\u201d y \u201cempujada por otros\u201d, aunque asegur\u00f3 que no hab\u00eda sido agresiva. \u201cEstaba pidiendo aclaraciones, lo cual es mi derecho como miembro del Congreso\u201d, dijo.<\/p>\n<p>Tricia McLaughlin, portavoz del DHS, dijo en X en respuesta al video de la congresista que las afirmaciones \u201cno son ciertas\u201d.<\/p>\n<p>\u201cSi sus afirmaciones fueran ciertas, esto ser\u00eda un milagro m\u00e9dico. Pero no lo son. No fue rociada con gas pimienta. Estaba en las cercan\u00edas de alguien que <em>s\u00ed<\/em> fue rociado con gas pimienta mientras obstru\u00eda y agred\u00eda a las fuerzas del orden\u201d, dijo McLaughlin.<\/p>\n<p>\u201cDe hecho, dos agentes del orden resultaron gravemente heridos por esta multitud a la que se uni\u00f3 @Rep_Grijalva. Presentarse como \u2018Miembro del Congreso\u2019 no te da derecho a obstruir a las fuerzas del orden\u201d.<\/p>\n<p>Posteriormente, Grijalva public\u00f3 un video en X que muestra a funcionarios uniformados rociando a una multitud de personas, incluyendo lo que parecen ser manifestantes, Grijalva y su personal. Se puede ver a Grijalva diciendo: \u201cUstedes necesitan calmarse y salir de aqu\u00ed\u201d.<\/p>\n<p>La congresista dijo en el primer video que public\u00f3 que una vez que se present\u00f3 como miembro del Congreso, asumi\u00f3 que la situaci\u00f3n se calmar\u00eda, \u201cpero literalmente solo hab\u00eda una persona que intentaba hablarme en un tono civilizado, y todos los dem\u00e1s estaban siendo groseros e irrespetuosos\u201d.<\/p>\n<p>\u201cSolo puedo imaginar si me van a tratar as\u00ed, c\u00f3mo estar\u00e1n tratando a los dem\u00e1s\u201d, dijo.<\/p>\n<p>Grijalva denunci\u00f3 el manejo de la aplicaci\u00f3n de la ley migratoria por parte del Gobierno de Trump,<\/p>\n<p>\u201cCreo que este es uno de los problemas, el mayor problema que tenemos en esta comunidad es que tenemos a Trump que no respeta el debido proceso, el estado de derecho, la Constituci\u00f3n\u201d, dijo Grijalva en el video. \u201cLiteralmente est\u00e1n desapareciendo personas de las calles. Arrestaron a dos personas. No tenemos idea a d\u00f3nde se las llevan\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La representante Adelita Grijalva dijo el viernes que fue rociada con gas pimienta y empujada durante una redada del Servicio Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Tucson, Arizona, una afirmaci\u00f3n que el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) refut\u00f3 r\u00e1pidamente. La dem\u00f3crata de Arizona dijo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469015","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La congresista Adelita Grijalva dice que fue rociada con gas pimienta durante una redada de ICE en Arizona - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La congresista Adelita Grijalva dice que fue rociada con gas pimienta durante una redada de ICE en Arizona - Noticias\" \/>\n<meta property=\"og:description\" content=\"La representante Adelita Grijalva dijo el viernes que fue rociada con gas pimienta y empujada durante una redada del Servicio Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Tucson, Arizona, una afirmaci\u00f3n que el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) refut\u00f3 r\u00e1pidamente. La dem\u00f3crata de Arizona dijo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-06T01:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La congresista Adelita Grijalva dice que fue rociada con gas pimienta durante una redada de ICE en Arizona\",\"datePublished\":\"2025-12-06T01:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/\"},\"wordCount\":490,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/\",\"name\":\"La congresista Adelita Grijalva dice que fue rociada con gas pimienta durante una redada de ICE en Arizona - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-06T01:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La congresista Adelita Grijalva dice que fue rociada con gas pimienta durante una redada de ICE en Arizona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La congresista Adelita Grijalva dice que fue rociada con gas pimienta durante una redada de ICE en Arizona - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La congresista Adelita Grijalva dice que fue rociada con gas pimienta durante una redada de ICE en Arizona - Noticias","og_description":"La representante Adelita Grijalva dijo el viernes que fue rociada con gas pimienta y empujada durante una redada del Servicio Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Tucson, Arizona, una afirmaci\u00f3n que el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s) refut\u00f3 r\u00e1pidamente. La dem\u00f3crata de Arizona dijo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-06T01:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/"},"author":{"name":"","@id":""},"headline":"La congresista Adelita Grijalva dice que fue rociada con gas pimienta durante una redada de ICE en Arizona","datePublished":"2025-12-06T01:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/"},"wordCount":490,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/","name":"La congresista Adelita Grijalva dice que fue rociada con gas pimienta durante una redada de ICE en Arizona - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-06T01:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La congresista Adelita Grijalva dice que fue rociada con gas pimienta durante una redada de ICE en Arizona"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La congresista Adelita Grijalva dice que fue rociada con gas pimienta durante una redada de ICE en Arizona","url":"http:\/\/noticiasya.com\/laredo\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/12\/05\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-06T01:03:46Z","datePublished":"2025-12-06T01:03:46Z","dateModified":"2025-12-06T01:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La congresista Adelita Grijalva dice que fue rociada con gas pimienta durante una redada de ICE en Arizona\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/12\\\/05\\\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/12\\\/05\\\/congresista-adelita-grijalva-gas-pimienta-redada-ice-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-06T01:03:46Z\",\"datePublished\":\"2025-12-06T01:03:46Z\",\"dateModified\":\"2025-12-06T01:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1466776,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/24\/adelita-grijalva-gana-eleccion-arizona-archivos-epstein-trax\/","url_meta":{"origin":1469015,"position":0},"title":"Adelita Grijalva gana elecciones especiales en Arizona, una firma decisiva sobre los archivos de Epstein","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"La dem\u00f3crata Adelita Grijalva gan\u00f3 una elecci\u00f3n especial en el s\u00e9ptimo distrito electoral por Arizona, que entregar\u00e1 la firma decisiva para impulsar una votaci\u00f3n para publicar los archivos del caso de Jeffrey Epstein.La contienda se llev\u00f3 a cabo para determinar qui\u00e9n ocupar\u00eda el esca\u00f1o que dej\u00f3 vacante el difunto representante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466193,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/05\/gritos-llanto-tristeza-tres-horas-redada-inmigracion-nueva-york-orix\/","url_meta":{"origin":1469015,"position":1},"title":"Gritos, llanto, tristeza: as\u00ed fue la redada de inmigraci\u00f3n de tres horas en Nueva York que dej\u00f3 decenas de detenidos","author":"","date":"septiembre 5, 2025","format":false,"excerpt":"Eran alrededor de las 9 de la ma\u00f1ana del jueves. Como cualquier otro d\u00eda, decenas de personas trabajaban en la f\u00e1brica Nutrition Bar Confectioners, ubicada en Cato, Nueva York, el escenario m\u00e1s reciente de una redada de inmigraci\u00f3n. La normalidad se quebr\u00f3 cuando algunos empleados se asomaron por la ventana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467119,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/05\/dhs-agentes-chicago-embistio-vehiculo-policial-trax\/","url_meta":{"origin":1469015,"position":2},"title":"DHS dice que agentes en Chicago dispararon a conductora que &#171;embisti\u00f3 el veh\u00edculo de las fuerzas del orden&#187;","author":"","date":"octubre 5, 2025","format":false,"excerpt":"Agentes federales dispararon a una mujer despu\u00e9s de que embistiera un veh\u00edculo de las fuerzas del orden en Chicago, seg\u00fan el Departamento de Seguridad Nacional (DHS, por sus siglas en ingl\u00e9s), en medio de crecientes protestas contra el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465541,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/15\/hombre-muere-redada-inmigracion-ice-autopista-los-angeles-trax\/","url_meta":{"origin":1469015,"position":3},"title":"Muere un hombre que hu\u00eda de una redada de inmigraci\u00f3n tras correr hacia una autopista de Los \u00c1ngeles, seg\u00fan las autoridades","author":"","date":"agosto 15, 2025","format":false,"excerpt":"Un hombre que hu\u00eda mientras se desarrollaba una redada de inmigraci\u00f3n en un Home Depot en el sur de California muri\u00f3 cuando corri\u00f3 hacia una autopista mientras agentes federales ingresaban, dijeron funcionarios locales.La Red Nacional de Jornaleros identific\u00f3 al hombre como Roberto Carlos Montoya Vald\u00e9s, de 52 a\u00f1os y originario\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464505,"url":"https:\/\/noticiasya.com\/laredo\/2025\/07\/14\/que-sabemos-mexicano-muere-redada-ice-california-orix\/","url_meta":{"origin":1469015,"position":4},"title":"\u00bfQu\u00e9 pas\u00f3 con el trabajador agr\u00edcola que muri\u00f3 tras caer de un techo durante una redada de ICE en California? Esto sabemos","author":"","date":"julio 14, 2025","format":false,"excerpt":"Un trabajador agr\u00edcola de origen mexicano muri\u00f3 el domingo tras caer del techo de un invernadero durante una redada migratoria el jueves anterior en granjas agr\u00edcolas en Glass House Farms en Camarillo, California, a 80 km del centro de Los \u00c1ngeles.Se trata de Jaime Alanis, de 57 a\u00f1os, originario del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464670,"url":"https:\/\/noticiasya.com\/laredo\/2025\/07\/19\/ciudadano-estadounidense-veterano-ejercito-detenido-redada-inmigracion-trax\/","url_meta":{"origin":1469015,"position":5},"title":"Este veterano del Ej\u00e9rcito alistaba todo para el cumplea\u00f1os 3 de su hija. Pero fue detenido tras una redada de inmigraci\u00f3n","author":"","date":"julio 19, 2025","format":false,"excerpt":"George Retes, un veterano del Ej\u00e9rcito de 25 a\u00f1os y padre de dos hijos, llevaba semanas planeando la fiesta de cumplea\u00f1os de su hija de tres a\u00f1os sobre Minnie Mouse en el parque.Pensaba comprarle un castillo inflable, invitar a toda la familia y colmarla de regalos y golosinas. Ella estaba\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1469015"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469015\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1469015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1469015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1469015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}