{"id":1469022,"date":"2025-12-06T00:03:39","date_gmt":"2025-12-06T08:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/"},"modified":"2025-12-06T00:03:39","modified_gmt":"2025-12-06T08:03:39","slug":"crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/","title":{"rendered":"Crisis en la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. tras la salida de un veterano investigador del c\u00e1ncer"},"content":{"rendered":"<p>El comisionado de la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA, por sus siglas en ingl\u00e9s), Marty Makary, est\u00e1 bajo un renovado escrutinio por parte de los funcionarios de Trump.<\/p>\n<p>La agencia atraviesa un periodo de agitaci\u00f3n continua, incluida una serie de salidas de alto perfil que han generado preguntas en la administraci\u00f3n sobre la capacidad de Makary para liderar, seg\u00fan dos personas familiarizadas con las conversaciones.<\/p>\n<p>La inminente salida del Dr. Richard Pazdur, investigador veterano pionero en el enfoque de la FDA para los tratamientos contra el c\u00e1ncer, ha generado la mayor preocupaci\u00f3n, informaron fuentes de CNN.<\/p>\n<p>Pazdur planea jubilarse este mes, apenas unas semanas despu\u00e9s de aceptar el cargo de director de la divisi\u00f3n m\u00e1s grande de la FDA, encargada de la supervisi\u00f3n de medicamentos con receta, medicamentos de venta libre y productos b\u00e1sicos de farmacia.<\/p>\n<p>La salida de Pazdur se produce en medio de enfrentamientos m\u00e1s amplios con los altos mandos de la FDA sobre qui\u00e9n deber\u00eda dirigir los departamentos clave de la agencia y c\u00f3mo equilibrar las revisiones aceleradas de medicamentos con el control de calidad, seg\u00fan tres personas familiarizadas con la din\u00e1mica dentro de la agencia.<\/p>\n<p>El punto de quiebre de Pazdur se produjo cuando Makary lo presion\u00f3 para que reemplazara a los reguladores de medicamentos de carrera con personas seleccionadas por \u00e9l mismo, dijeron esas fuentes.<\/p>\n<p>Makary hasta ahora ha sido un aliado personal cercano del Secretario de Salud y Servicios Humanos de EE.UU. (HHS), Robert F. Kennedy Jr., quien se reuni\u00f3 con Pazdur durante una hora el mi\u00e9rcoles y se ha mostrado frustrado por la agitaci\u00f3n p\u00fablica, apuntan las fuentes.<\/p>\n<p>La salida de Pazdur ha generado una amplia preocupaci\u00f3n en toda la administraci\u00f3n y dentro de la industria farmac\u00e9utica, por la posibilidad de que pueda desestabilizar el proceso de revisi\u00f3n de medicamentos y erosionar la confianza en la FDA, considerada ampliamente como el regulador est\u00e1ndar de oro de medicamentos y vacunas del mundo.<\/p>\n<p>Bajo el liderazgo de Kennedy, numerosos funcionarios de carrera han sido destituidos del departamento de salud, lo que ha reestructurado las altas esferas de los reguladores y los legisladores.<\/p>\n<p>En algunos casos, esto ha llevado a cambios dr\u00e1sticos en las pol\u00edticas, incluyendo recomendaciones sobre vacunas infantiles.<\/p>\n<p>Mientras los funcionarios de la Casa Blanca lamentaban en privado otra salida de la FDA como una distracci\u00f3n vergonzosa, algunos de los contratados por Kennedy parecieron burlarse de la agitaci\u00f3n de esta semana en una reuni\u00f3n crucial para discutir si se deb\u00eda abandonar la vacunaci\u00f3n universal contra la hepatitis B para los reci\u00e9n nacidos.<\/p>\n<p>\u201cNo est\u00e1 sucediendo mucho en la Administraci\u00f3n de Alimentos y Medicamentos\u201d, dijo el Dr. Robert Malone, vicepresidente de la Comisi\u00f3n Asesora sobre Pr\u00e1cticas de Inmunizaci\u00f3n, <a href=\"https:\/\/www.cnn.com\/health\/live-news\/cdc-vaccine-meeting-hepatitis-b-12-04-25\">durante una reuni\u00f3n p\u00fablica<\/a> el jueves cuando present\u00f3 al reemplazo de Pazdur, la Dra. Tracy Beth Hoeg.<\/p>\n<p>\u201c\u00bfDesea compartir alg\u00fan evento reciente?\u201d, le pregunt\u00f3 Malone antes de que ella presentara los cambios en curso en el proceso de revisi\u00f3n de vacunas de la FDA.<\/p>\n<p>\u201cNo ha sucedido nada dram\u00e1tico ni lascivo ni nada por el estilo\u201d, pareci\u00f3 bromear Hoeg.<\/p>\n<p>Los asesores de los CDC <a href=\"https:\/\/www.cnn.com\/health\/live-news\/cdc-vaccine-meeting-hepatitis-b-12-05-25\">votaron el viernes<\/a> abandonar las vacunas contra la hepatitis B para los reci\u00e9n nacidos.<\/p>\n<p>Mientras tanto, Makary ten\u00eda previsto reunirse con funcionarios de la Casa Blanca el viernes. La reuni\u00f3n ya estaba prevista, pero, tras el anuncio de la salida de Pazdur, adquiri\u00f3 una nueva urgencia, seg\u00fan una persona al tanto de la situaci\u00f3n.<\/p>\n<p>Portavoces de la Casa Blanca y del HHS negaron el viernes que el trabajo de Makary estuviera en peligro, insistiendo en que los altos funcionarios a\u00fan ten\u00edan plena confianza en su liderazgo y en la agenda de la agencia.<\/p>\n<p>\u201cLa Casa Blanca mantiene plena confianza en Marty Makary y en todo el equipo del HHS y la FDA\u201d, afirm\u00f3 el portavoz de la Casa Blanca, Kush Desai, elogiando \u201cel flujo casi semanal de anuncios innovadores de la FDA\u201d.<\/p>\n<p>La salida de Pazdur es la \u00faltima de una serie de trastornos en la FDA este a\u00f1o.<\/p>\n<p>Peter Marks, el jefe de vacunas que lider\u00f3 la Operaci\u00f3n Warp Speed \u200b\u200bdurante el primer mandato de Donald Trump, dej\u00f3 el cargo en marzo y acus\u00f3 p\u00fablicamente al secretario del HHS, Kennedy, de <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2025%2F03%2F28%2Fhealth%2Ffda-vaccine-peter-marks-resigns&#038;data=05%7C02%7Csarah.owermohle%40cnn.com%7C1072106761284267c87108de342150fe%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C639005514864261856%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=sL459Ip7FZLkP5xo9HzvC%2Bl10tqybKGdb%2FidQmqqgAM%3D&#038;reserved=0\">obligarlo a dimitir<\/a>.<\/p>\n<p>Marks fue reemplazado por Vinay Prasad, un veterano cr\u00edtico de la FDA que <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2025%2F08%2F09%2Fpolitics%2Ffda-official-dr-vinay-prasad-returns-to-agency-after-loomer-ouster&#038;data=05%7C02%7Csarah.owermohle%40cnn.com%7C1072106761284267c87108de342150fe%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C639005514864279871%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=LlTjoX91ZYZoggWo85XmL1iGGqXYdBTTwLZJJZTPnFc%3D&#038;reserved=0\" rel=\"noopener noreferrer\" target=\"_blank\">abandon\u00f3 brevemente la agencia<\/a> este verano en medio de las cr\u00edticas de Laura Loomer, la \u201cejecutora de la lealtad\u201d de Trump, para regresar semanas despu\u00e9s.<\/p>\n<p>La agitaci\u00f3n constante en la FDA ha irritado a algunos funcionarios de la Casa Blanca en los \u00faltimos meses, quienes han visto las controversias de personal como una molestia innecesaria que significa una distraci\u00f3n de la agenda pol\u00edtica de la agencia.<\/p>\n<p>Esas preocupaciones alcanzaron su punto m\u00e1ximo en noviembre, a ra\u00edz de enfrentamientos internos entre Prasad y el entonces principal regulador de medicamentos, George Tidmarsh, quien posteriormente renunci\u00f3 abruptamente en medio de acusaciones sobre su participaci\u00f3n en un plan de extorsi\u00f3n.<\/p>\n<p>La Casa Blanca discuti\u00f3 brevemente en ese momento la posibilidad de dejar de lado a Makary, quien tambi\u00e9n hab\u00eda enfurecido a los funcionarios de Trump en ocasiones al no seguir los procesos de pol\u00edticas internas, aunque finalmente se negaron a seguir adelante, dijeron dos personas familiarizadas con el asunto.<\/p>\n<p>Makary r\u00e1pidamente se encontr\u00f3 en problemas poco despu\u00e9s de que una asesora cercana, Sanjula Jain-Nagpal, se presentara ante algunas partes interesadas de la FDA como la nueva jefa adjunta de gabinete del comisionado antes de que la Casa Blanca hubiera aprobado oficialmente la promoci\u00f3n.<\/p>\n<p>Los funcionarios de la Casa Blanca desistieron de su intento de despedirla despu\u00e9s de determinar que el episodio hab\u00eda sido un malentendido, aunque hasta ahora le han negado el ascenso.<\/p>\n<p>Pazdur inicialmente rechaz\u00f3 la oferta de reemplazar a Tidmarsh como director de medicamentos de la FDA, pero Makary lo convenci\u00f3 el mes pasado despu\u00e9s de una visita personal, seg\u00fan personas familiarizadas con el proceso.<\/p>\n<p>Pazdur insisti\u00f3 en dirigir la divisi\u00f3n sin interferencias pol\u00edticas, pero pronto se frustr\u00f3, seg\u00fan tres personas familiarizadas con su pensamiento. Tambi\u00e9n cuestion\u00f3 c\u00f3mo un <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2025%2F11%2F06%2Fpolitics%2Fweight-loss-drugs-medicare-deals&#038;data=05%7C02%7Csarah.owermohle%40cnn.com%7C1072106761284267c87108de342150fe%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C639005514864312750%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=IodkEyQEVIMJRtKQx2rvCdjAinRpjmVuddssuW%2FJntk%3D&#038;reserved=0\">proceso acelerado<\/a> de revisi\u00f3n de medicamentos mantendr\u00eda los est\u00e1ndares de seguridad.<\/p>\n<p>Un memorando de Prasad de la semana pasada que describe <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fwww.cnn.com%2F2025%2F11%2F29%2Fpolitics%2Fvaccine-approval-process-fda-official&#038;data=05%7C02%7Csarah.owermohle%40cnn.com%7C1072106761284267c87108de342150fe%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C639005514864331518%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=OmJSRszsJtjO1rmerjYd14JwV0w1caqkfF7i%2F%2BYJsFo%3D&#038;reserved=0\">nuevos requisitos para la aprobaci\u00f3n de vacunas<\/a> gener\u00f3 alarma entre algunos funcionarios de la administraci\u00f3n que fueron tomados por sorpresa por su amplia revisi\u00f3n, incluida su sugerencia de que la FDA podr\u00eda reevaluar las vacunas ya aprobadas.<\/p>\n<p>En su reuni\u00f3n de una hora con Kennedy el mi\u00e9rcoles, Pazdur expres\u00f3 su preocupaci\u00f3n de que el equipo de Makary estaba desmantelando el proceso de revisi\u00f3n de medicamentos, comentaron fuentes familiarizadas con su pensamiento.<\/p>\n<p>\u201cKennedy tuvo una conversaci\u00f3n con Pazdur para agradecerle su servicio y dedicaci\u00f3n en la FDA\u201d, seg\u00fan un portavoz del HHS.<\/p>\n<p>Algunos funcionarios y aliados de Trump desestimaron la sugerencia de que la salida de Pazdur servir\u00eda como un punto de inflexi\u00f3n, retrat\u00e1ndolo simplemente como otro funcionario de carrera descontento que no apoyaba la agenda de la administraci\u00f3n Trump.<\/p>\n<p>En cierto modo, la abrupta partida de Pazdur era \u201ctotalmente esperada\u201d, expres\u00f3 un exfuncionario.<\/p>\n<p>\u201cPredije que esto suceder\u00eda en seis meses\u201d, manifest\u00f3 la persona. \u201cMi \u00fanico error fue no pensar que suceder\u00eda en seis semanas\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El comisionado de la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA, por sus siglas en ingl\u00e9s), Marty Makary, est\u00e1 bajo un renovado escrutinio por parte de los funcionarios de Trump. La agencia atraviesa un periodo de agitaci\u00f3n continua, incluida una serie de salidas de alto perfil que han generado preguntas en la administraci\u00f3n sobre [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469022","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Crisis en la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. tras la salida de un veterano investigador del c\u00e1ncer - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crisis en la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. tras la salida de un veterano investigador del c\u00e1ncer - Noticias\" \/>\n<meta property=\"og:description\" content=\"El comisionado de la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA, por sus siglas en ingl\u00e9s), Marty Makary, est\u00e1 bajo un renovado escrutinio por parte de los funcionarios de Trump. La agencia atraviesa un periodo de agitaci\u00f3n continua, incluida una serie de salidas de alto perfil que han generado preguntas en la administraci\u00f3n sobre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-06T08:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Crisis en la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. tras la salida de un veterano investigador del c\u00e1ncer\",\"datePublished\":\"2025-12-06T08:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/\"},\"wordCount\":1318,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/\",\"name\":\"Crisis en la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. tras la salida de un veterano investigador del c\u00e1ncer - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-06T08:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crisis en la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. tras la salida de un veterano investigador del c\u00e1ncer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crisis en la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. tras la salida de un veterano investigador del c\u00e1ncer - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Crisis en la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. tras la salida de un veterano investigador del c\u00e1ncer - Noticias","og_description":"El comisionado de la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA, por sus siglas en ingl\u00e9s), Marty Makary, est\u00e1 bajo un renovado escrutinio por parte de los funcionarios de Trump. La agencia atraviesa un periodo de agitaci\u00f3n continua, incluida una serie de salidas de alto perfil que han generado preguntas en la administraci\u00f3n sobre [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-06T08:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/"},"author":{"name":"","@id":""},"headline":"Crisis en la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. tras la salida de un veterano investigador del c\u00e1ncer","datePublished":"2025-12-06T08:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/"},"wordCount":1318,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/","name":"Crisis en la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. tras la salida de un veterano investigador del c\u00e1ncer - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-06T08:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Crisis en la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. tras la salida de un veterano investigador del c\u00e1ncer"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Crisis en la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. tras la salida de un veterano investigador del c\u00e1ncer","url":"http:\/\/noticiasya.com\/laredo\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/12\/06\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-06T08:03:39Z","datePublished":"2025-12-06T08:03:39Z","dateModified":"2025-12-06T08:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Crisis en la Administraci\\u00f3n de Alimentos y Medicamentos de EE.UU. tras la salida de un veterano investigador del c\\u00e1ncer\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/12\\\/06\\\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/12\\\/06\\\/crisis-administracion-alimentos-medicamentos-eeuu-salida-investigador-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-06T08:03:39Z\",\"datePublished\":\"2025-12-06T08:03:39Z\",\"dateModified\":\"2025-12-06T08:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1461512,"url":"https:\/\/noticiasya.com\/laredo\/2025\/04\/22\/fda-eliminara-colorantes-alimentarios-petroleo-trax\/","url_meta":{"origin":1469022,"position":0},"title":"La FDA eliminar\u00e1 gradualmente los colorantes alimentarios a base de petr\u00f3leo; autorizar\u00e1 cuatro aditivos de color naturales","author":"","date":"abril 22, 2025","format":false,"excerpt":"La Administraci\u00f3n de Alimentos y Medicamentos (FDA, por sus siglas en ingl\u00e9s) de EE.UU. planea eliminar gradualmente el uso de colorantes sint\u00e9ticos a base de petr\u00f3leo en el suministro de alimentos del pa\u00eds debido a preocupaciones de salud, anunci\u00f3 este martes el comisionado Dr. Marty Makary.\u201cDurante los \u00faltimos 50 a\u00f1os,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456038,"url":"https:\/\/noticiasya.com\/laredo\/2024\/11\/23\/trump-puestos-clave-en-salud-publica-trax\/","url_meta":{"origin":1469022,"position":1},"title":"Trump designa puestos clave en salud p\u00fablica","author":"","date":"noviembre 23, 2024","format":false,"excerpt":"(CNN) -- El presidente electo, Donald Trump, anunci\u00f3 este viernes sus candidatos para los puestos de salud p\u00fablica m\u00e1s importantes de su pr\u00f3xima administraci\u00f3n.Trump nombr\u00f3 a la Dra. Janette Nesheiwat como directora general de Sanidad de EE.UU., al Dr. Marty Makary como comisionado de la Administraci\u00f3n de Alimentos y Medicamentos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473464,"url":"https:\/\/noticiasya.com\/laredo\/2026\/04\/24\/fda-psicodelicos-hongos-salud-mental-trax\/","url_meta":{"origin":1469022,"position":2},"title":"La FDA acelera la revisi\u00f3n de algunas drogas psicod\u00e9licas para la salud mental","author":"","date":"abril 24, 2026","format":false,"excerpt":"Algunas drogas psicod\u00e9licas, antes consideradas marginales, est\u00e1n cada vez m\u00e1s cerca de ser aprobadas para su uso como tratamientos de salud mental en Estados Unidos.La Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA, por sus siglas en ingl\u00e9s) otorg\u00f3 el viernes vales de prioridad nacional a tres compa\u00f1\u00edas que investigan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466811,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/25\/mifepristona-revision-fda-abortos-trax\/","url_meta":{"origin":1469022,"position":3},"title":"Agencias federales de EE.UU. investigan la seguridad de la mifepristona, f\u00e1rmaco utilizado para abortar","author":"","date":"septiembre 25, 2025","format":false,"excerpt":"La Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA, por sus siglas en ingl\u00e9s) revisar\u00e1 la seguridad y eficacia de la mifepristona, uno de los f\u00e1rmacos utilizados en la pr\u00e1ctica del aborto con medicamentos, para investigar c\u00f3mo puede dispensarse de forma segura, seg\u00fan el secretario de Salud y Servicios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462852,"url":"https:\/\/noticiasya.com\/laredo\/2025\/05\/27\/recomendacion-vacuna-covid-19-ninos-embarazadas-trax\/","url_meta":{"origin":1469022,"position":4},"title":"RFK Jr. afirma que la vacuna contra el covid-19 ya no se recomendar\u00e1 para ni\u00f1os sanos y mujeres embarazadas","author":"","date":"mayo 27, 2025","format":false,"excerpt":"El secretario del Departamento de Salud y Servicios Humanos de EE.UU., Robert F. Kennedy Jr., anunci\u00f3 el martes que la vacuna contra el covid-19 ya no figurar\u00e1 entre las vacunas recomendadas para mujeres embarazadas y ni\u00f1os sanos en el calendario de vacunaci\u00f3n de los Centros para el Control y la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466702,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/22\/trump-relacion-autismo-tylenol-acetaminofen-paracetamol-trax\/","url_meta":{"origin":1469022,"position":5},"title":"Trump relaciona el autismo con el consumo de paracetamol durante el embarazo, a pesar de la evidencia que demuestra seguridad","author":"","date":"septiembre 22, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump anunci\u00f3 el lunes que la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA, por sus siglas en ingl\u00e9s) notificar\u00e1 a los m\u00e9dicos que el uso de acetaminof\u00e9n (tambi\u00e9n denominado gen\u00e9ricamente como paracetamol) durante el embarazo \u201cpuede estar asociado con un riesgo muy elevado de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1469022"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469022\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1469022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1469022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1469022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}