{"id":1469035,"date":"2025-12-06T15:03:49","date_gmt":"2025-12-06T23:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/"},"modified":"2025-12-06T15:03:49","modified_gmt":"2025-12-06T23:03:49","slug":"mundial-2026-sorteo-calendario-grupos-muerte-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/","title":{"rendered":"Mundial 2026: el camino a la gloria, con grupos de la muerte, cruces pesados y un choque de gigantes que podr\u00eda llegar pronto"},"content":{"rendered":"<p>El Mundial 2026 comenz\u00f3 este viernes 5 de diciembre. Extraoficialmente, claro, porque el primer partido se jugar\u00e1 reci\u00e9n el 11 de junio, cuando M\u00e9xico y Sud\u00e1frica se enfrenten cara a cara en el m\u00edtico Estadio Azteca. Sin embargo, conocidos los rivales que tendr\u00e1 cada grupo, a excepci\u00f3n de los boletos que reci\u00e9n encontrar\u00e1n due\u00f1o en marzo, ya empieza a planificarse el camino que puede llevar a cada selecci\u00f3n a la gloria.<\/p>\n<p>Lo primero que deja el <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/05\/deportes\/grupos-mundial-fifa-2026-orix\">sorteo realizado en Washington <\/a>es que las tres selecciones anfitrionas la sacaron bastante \u201cbarata\u201d, por as\u00ed decirlo. El Tri tendr\u00e1 como rivales en el Grupo A a Sud\u00e1frica, Corea del Sur y una selecci\u00f3n europea que saldr\u00e1 del repechaje entre Dinamarca, Macedonia del Norte, Rep\u00fablica Checa e Irlanda. A priori, bastante accesible, sin un gigante europeo o potencia de \u00c1frica.<\/p>\n<p>Los aztecas saben que si ganan el grupo, ir\u00e1n en 16avos ante una selecci\u00f3n que termine tercera, y si finalizan en el segundo escal\u00f3n, enfrentar\u00e1n a la segunda del Grupo B, un camino que inspira confianza.<\/p>\n<p>Estados Unidos respir\u00f3 aliviado cuando vio caer en su Grupo D a Australia, la selecci\u00f3n que todos quer\u00edan del Bombo 2, y a Paraguay, que llega siendo un combinado nacional compacto, pero sin los grandes reflectores de los m\u00e1ximos candidatos. El europeo saldr\u00e1 de la llave entre Turqu\u00eda, Rumania, Eslovaquia y Kosovo, por lo que la puerta de salida a los 16avos est\u00e1 a la vista. Una vez en los cruces, si gana el grupo, enfrentar\u00e1 a una tercera, y si es escolta, se medir\u00e1 ante la segunda del Grupo G, que, si hay l\u00f3gica, no saldr\u00e1 de Egipto o Ir\u00e1n.<\/p>\n<p>Canad\u00e1 tiene en el Grupo B un panorama m\u00e1s te\u00f1ido de gris, especialmente si Italia gana su repechaje y acaba cayendo en esta zona. Tambi\u00e9n est\u00e1 Suiza, una selecci\u00f3n que, sin hacer demasiado ruido, siempre acaba pasando la fase de grupos. Qatar apunta a ser el objetivo a vencer para tener chance de acceder a los 16avos de final. Si no saca esos tres puntos, la clasificaci\u00f3n estar\u00e1 en riesgo.<\/p>\n<p>Es dif\u00edcil aventurar si existe un <a href=\"https:\/\/cnnespanol.cnn.com\/deportes\/live-news\/sorteo-grupos-mundial-2026-orix\">\u201cgrupo de la muerte\u201d <\/a>como tal, teniendo en cuenta que hasta saliendo tercero de grupo hay chance de acceder a la siguiente ronda.<\/p>\n<p>Sin embargo, no quedan dudas de que la combinaci\u00f3n Francia-Noruega-Senegal se roba todas las miradas. Los \u00faltimos subcampeones del mundo (y campeones en 2018) cruzar\u00e1n caminos con los escandinavos, que adem\u00e1s de la catarata de goles que promete Erling Haaland, tiene un equipo muy serio y bien trabajado, que gan\u00f3 todos los partidos que jug\u00f3 en las Eliminatorias y que mand\u00f3 a Italia al repechaje con dos goleadas en las valijas.<\/p>\n<p>La selecci\u00f3n africana es peligrosa, y junto con Ghana, son las dos candidatas del continente a pasar de ronda. A ellos se sumar\u00e1n Iraq, Bolivia o Surinam, que, en la previa, correr\u00e1n desde muy atr\u00e1s.<\/p>\n<p>La otra zona \u201croja\u201d es la L. Si Croacia repite lo hecho en 2018 (subcampe\u00f3n) y 2022 (semifinales) y Ghana vuelve a ser protagonista como ya es costumbre, el grupo de Inglaterra puede ponerse de patas para arriba. Panam\u00e1 llegar\u00e1 como \u201cCenicienta\u201d, es cierto, pero las otras tres selecciones pueden robarse puntos entre ellas y dejar un gran signo de pregunta.<\/p>\n<p>Sin numerolog\u00eda forzada ni c\u00e1balas de por medio, el campe\u00f3n del mundo recibi\u00f3 un gui\u00f1o en la fase de grupos, pero el futuro inmediato puede ponerlo en apuros. Argentina enfrentar\u00e1 a Austria, que, si bien gan\u00f3 su zona en la UEFA, no es de las principales potencias, y luego a Argelia y a la debutante Jordania. El pron\u00f3stico marca nueve puntos sobre nueve jugados, pero en 2022 esa misma calculadora se fue al bote de basura antes de los primeros 90 minutos. Aquella derrota ante Arabia Saudita ser\u00e1 la lecci\u00f3n a aprender para un grupo que, desde el cuerpo t\u00e9cnico hasta el plantel, repetir\u00e1 muchos nombres.<\/p>\n<p>La gran dificultad de ese Grupo J es el cruce de 16avos. Termine primera o segunda, la Albiceleste se cruzar\u00e1 con un rival del Grupo H, donde est\u00e1n Espa\u00f1a y Uruguay. La l\u00f3gica es que los europeos y Argentina terminen primeros y no se encuentren hasta la final (si llegan), pero si uno acaba como escolta y el otro como l\u00edder, se ver\u00e1n las caras no por levantar el trofeo dorado, sino por avanzar a octavos de final. Un choque de planetas demasiado pronto.<\/p>\n<p>En ese mismo Grupo H hay un gran asterisco, y tiene nombre y apellido: Arabia Saudita. Mejor dicho, la Arabia Saudita de Herv\u00e9 Renard. Si el nombre no suena demasiado, es porque sintonizaron el Mundial de Qatar un poco tarde. Los \u00e1rabes fueron los \u00fanicos que lograron derrotar a Argentina en la Copa del Mundo de 2022. Es m\u00e1s, esa derrota en el debut llev\u00f3 a la Albiceleste a cambiar un once titular que parec\u00eda que llegaba muy aceitado y que no volvi\u00f3 a repetirse nunca m\u00e1s. Si los verdes meten otro batacazo, esa zona puede terminar al rojo vivo.<\/p>\n<p>Y si de cruces se trata, conviene tener este otro anotado: el 29 de junio, en Monterrey, Pa\u00edses Bajos podr\u00eda enfrentarse a Brasil o Marruecos por un lugar entre los 16 mejores del Mundial. Es que los neerlandeses no debieran tener demasiadas complicaciones para ganar el Grupo F, con Jap\u00f3n (el rival de mayor cuidado), T\u00fanez y otro europeo que saldr\u00e1 del repechaje entre Ucrania, Suecia, Polonia y Albania.<\/p>\n<p>El mapa sit\u00faa al l\u00edder de esta zona con el segundo del Grupo C, donde el bolillero dej\u00f3 a Brasil y Marruecos, dos candidatos que, ya sea por presente o por jerarqu\u00eda hist\u00f3rica, est\u00e1n llamados a ser protagonistas. Estas dos selecciones se enfrentar\u00e1n en el debut, y la que pierda tendr\u00e1 casi todos los boletos comprados para viajar a M\u00e9xico a medirse con los naranjas. Cuidado, la selecci\u00f3n de Brasil est\u00e1 en un momento tan delicado que hasta Escocia se ilusiona con hacer ruido en ese grupo. Hait\u00ed correr\u00e1 desde muy atr\u00e1s.<\/p>\n<p>El sorteo de la Copa Mundial de la FIFA nos dej\u00f3 tambi\u00e9n un par de duelos interesantes en la primera ronda. Colombia tendr\u00e1 una gran oportunidad de medir fuerzas con la Portugal de Cristiano Ronaldo, Bruno Fern\u00e1ndez y compa\u00f1\u00eda. Los Cafeteros necesitan ganar esa zona, ya que si lo hacen, enfrentar\u00e1n a un tercero en 16avos y, potencialmente, al l\u00edder del grupo de Canad\u00e1 en octavos. Si son escoltas, ir\u00e1n ante Inglaterra, Croacia o Ghana (la que salga segunda) primero, y luego, siempre seg\u00fan la l\u00f3gica, a Espa\u00f1a.<\/p>\n<p>A pesar de las cr\u00edticas de la prensa ecuatoriana, Ecuador llega en un gran momento y ser\u00e1 muy interesante ver su duelo con Alemania. Costa de Marfil puede resultar un rival molesto, a pesar de no tener los nombres rutilantes de hace un par de d\u00e9cadas, pero la Tricolor hizo m\u00e9ritos suficientes para aspirar, de m\u00ednima, con un segundo puesto. All\u00ed se le vendr\u00e1n los problemas, ya que le tocar\u00eda en 16avos Francia o Noruega, si se respetan los papeles.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Mundial 2026 comenz\u00f3 este viernes 5 de diciembre. Extraoficialmente, claro, porque el primer partido se jugar\u00e1 reci\u00e9n el 11 de junio, cuando M\u00e9xico y Sud\u00e1frica se enfrenten cara a cara en el m\u00edtico Estadio Azteca. Sin embargo, conocidos los rivales que tendr\u00e1 cada grupo, a excepci\u00f3n de los boletos que reci\u00e9n encontrar\u00e1n due\u00f1o en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469035","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mundial 2026: el camino a la gloria, con grupos de la muerte, cruces pesados y un choque de gigantes que podr\u00eda llegar pronto - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mundial 2026: el camino a la gloria, con grupos de la muerte, cruces pesados y un choque de gigantes que podr\u00eda llegar pronto - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Mundial 2026 comenz\u00f3 este viernes 5 de diciembre. Extraoficialmente, claro, porque el primer partido se jugar\u00e1 reci\u00e9n el 11 de junio, cuando M\u00e9xico y Sud\u00e1frica se enfrenten cara a cara en el m\u00edtico Estadio Azteca. Sin embargo, conocidos los rivales que tendr\u00e1 cada grupo, a excepci\u00f3n de los boletos que reci\u00e9n encontrar\u00e1n due\u00f1o en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-06T23:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mundial 2026: el camino a la gloria, con grupos de la muerte, cruces pesados y un choque de gigantes que podr\u00eda llegar pronto\",\"datePublished\":\"2025-12-06T23:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/\"},\"wordCount\":1264,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/\",\"name\":\"Mundial 2026: el camino a la gloria, con grupos de la muerte, cruces pesados y un choque de gigantes que podr\u00eda llegar pronto - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-06T23:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mundial 2026: el camino a la gloria, con grupos de la muerte, cruces pesados y un choque de gigantes que podr\u00eda llegar pronto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mundial 2026: el camino a la gloria, con grupos de la muerte, cruces pesados y un choque de gigantes que podr\u00eda llegar pronto - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Mundial 2026: el camino a la gloria, con grupos de la muerte, cruces pesados y un choque de gigantes que podr\u00eda llegar pronto - Noticias","og_description":"El Mundial 2026 comenz\u00f3 este viernes 5 de diciembre. Extraoficialmente, claro, porque el primer partido se jugar\u00e1 reci\u00e9n el 11 de junio, cuando M\u00e9xico y Sud\u00e1frica se enfrenten cara a cara en el m\u00edtico Estadio Azteca. Sin embargo, conocidos los rivales que tendr\u00e1 cada grupo, a excepci\u00f3n de los boletos que reci\u00e9n encontrar\u00e1n due\u00f1o en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/","og_site_name":"Noticias","article_published_time":"2025-12-06T23:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/"},"author":{"name":"","@id":""},"headline":"Mundial 2026: el camino a la gloria, con grupos de la muerte, cruces pesados y un choque de gigantes que podr\u00eda llegar pronto","datePublished":"2025-12-06T23:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/"},"wordCount":1264,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/","url":"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/","name":"Mundial 2026: el camino a la gloria, con grupos de la muerte, cruces pesados y un choque de gigantes que podr\u00eda llegar pronto - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-06T23:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mundial 2026: el camino a la gloria, con grupos de la muerte, cruces pesados y un choque de gigantes que podr\u00eda llegar pronto"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mundial 2026: el camino a la gloria, con grupos de la muerte, cruces pesados y un choque de gigantes que podr\u00eda llegar pronto","url":"http:\/\/noticiasya.com\/laredo\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/12\/06\/mundial-2026-sorteo-calendario-grupos-muerte-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-06T23:03:49Z","datePublished":"2025-12-06T23:03:49Z","dateModified":"2025-12-06T23:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mundial 2026: el camino a la gloria, con grupos de la muerte, cruces pesados y un choque de gigantes que podr\\u00eda llegar pronto\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/12\\\/06\\\/mundial-2026-sorteo-calendario-grupos-muerte-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/12\\\/06\\\/mundial-2026-sorteo-calendario-grupos-muerte-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-06T23:03:49Z\",\"datePublished\":\"2025-12-06T23:03:49Z\",\"dateModified\":\"2025-12-06T23:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469128,"url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/09\/mundial-2026-camino-seleccion-colombia-orix\/","url_meta":{"origin":1469035,"position":0},"title":"El camino de Colombia para el Mundial 2026: mano a mano con Cristiano Ronaldo y varios gigantes a la vista","author":"","date":"diciembre 9, 2025","format":false,"excerpt":"Colombia ya conoce su hoja de ruta para la Copa Mundial de la FIFA 2026. El camino puede parecer amable en principio en la fase de grupos, pero el menor traspi\u00e9 la puede situar en el horizonte de varios gigantes que llegan a la m\u00e1xima cita del f\u00fatbol como candidatos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466341,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/10\/bolivia-repechaje-mundial-2026-rivales-fechas-orix\/","url_meta":{"origin":1469035,"position":1},"title":"Bolivia en el repechaje al Mundial 2026: cu\u00e1ndo sabr\u00e1 sus rivales, c\u00f3mo se elegir\u00e1n y fechas clave","author":"","date":"septiembre 10, 2025","format":false,"excerpt":"Las Eliminatorias Sudamericanas para el Mundial de 2026 dejaron una gran sorpresa en la \u00faltima jornada: Bolivia venci\u00f3 a Brasil en los 4.100 metros de altura de El Alto y, como Venezuela fue goleada en casa ante Colombia, se meti\u00f3 en el repechaje intercontinental, que reci\u00e9n se disputar\u00e1 en marzo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468863,"url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/01\/mundial-2026-calendario-completo-sorteo-orix\/","url_meta":{"origin":1469035,"position":2},"title":"La FIFA anunci\u00f3 cu\u00e1ndo y c\u00f3mo dar\u00e1 a conocer el calendario del Mundial 2026 con sedes y horarios confirmados","author":"","date":"diciembre 1, 2025","format":false,"excerpt":"La ansiedad es total. A cuatro d\u00edas de que se d\u00e9 a conocer el sorteo del Mundial 2026, la FIFA anunci\u00f3 cu\u00e1ndo y de qu\u00e9 manera se determinar\u00e1n las sedes y los horarios de cada uno de los 104 partidos que tendr\u00e1 la primera Copa del Mundo de 48 selecciones.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467134,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/05\/mundial-sub-20-cruces-octavos-orix\/","url_meta":{"origin":1469035,"position":3},"title":"Mundial Sub-20: as\u00ed quedaron los cruces de octavos de final, con M\u00e9xico, Argentina y Colombia protagonistas","author":"","date":"octubre 5, 2025","format":false,"excerpt":"El Mundial Sub-20 entr\u00f3 en etapa de definiciones con el cierre de la fase de grupos, una etapa que tuvo la sorpresiva eliminaci\u00f3n de Brasil en el Grupo C, con apenas un empate y dos derrotas.Con la \u00faltima ronda de partidos disputada este domingo ya qued\u00f3 el cuadro de octavos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469096,"url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/08\/mundial-2026-camino-seleccion-mexico-orix\/","url_meta":{"origin":1469035,"position":4},"title":"Mundial 2026: el camino de M\u00e9xico, con un grupo accesible pero Inglaterra en el horizonte","author":"","date":"diciembre 8, 2025","format":false,"excerpt":"Respira M\u00e9xico. Los millones de ciudadanos que sintonizaron el sorteo del Mundial 2026 estar\u00e1n aliviados, sabiendo que ning\u00fan gigante ni firme candidato duerme en el mismo Grupo A que el Tri.Ser organizador ayud\u00f3, claro. La selecci\u00f3n azteca ocupa el 15\u00b0 lugar del ranking FIFA, por lo que, t\u00e9cnicamente, habr\u00eda sido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471780,"url":"https:\/\/noticiasya.com\/laredo\/2026\/03\/02\/100-dias-mundial-2026-guia-orix\/","url_meta":{"origin":1469035,"position":5},"title":"Faltan 100 d\u00edas para el Mundial 2026: gu\u00eda de lo que sabemos y lo que falta conocer","author":"","date":"marzo 2, 2026","format":false,"excerpt":"La cuenta regresiva para la Copa Mundial de la FIFA 2026 ha comenzado. El reloj marca este lunes 100 d\u00edas para que la pelota comience a rodar en el escenario m\u00e1s importante del mundo a nivel selecciones. Hay mucho del torneo que ya conocemos, pero a\u00fan faltan unas cuantas piezas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1469035"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469035\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1469035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1469035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1469035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}