{"id":1469087,"date":"2025-12-08T15:03:45","date_gmt":"2025-12-08T23:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/"},"modified":"2025-12-08T15:03:45","modified_gmt":"2025-12-08T23:03:45","slug":"que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/","title":{"rendered":"\u00bfQu\u00e9 es una oferta p\u00fablica de adquisici\u00f3n hostil, como la que lanz\u00f3 Paramount sobre Warner Bros. Discovery?"},"content":{"rendered":"<p>Paramount Skydance ha desatado una <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/08\/economia\/paramount-lanza-oferta-publica-adquisicion-warner-wbd-trax\">oferta p\u00fablica de adquisici\u00f3n hostil por Warner Bros. Discovery<\/a> (WBD), desafiando el megacuerdo de US$ 72.000 millones que WBD anunci\u00f3 el pasado viernes con Netflix. Al dirigirse directamente a los accionistas, Paramount Skydance present\u00f3 una agresiva oferta en efectivo que, seg\u00fan la compa\u00f1\u00eda, supera en valor a la propuesta de Netflix.<\/p>\n<p>Una adquisici\u00f3n hostil se produce cuando una empresa realiza una oferta no solicitada para comprar las acciones de otra empresa. Esta medida suele ir expl\u00edcitamente en contra de los deseos de la direcci\u00f3n de la empresa objetivo.<\/p>\n<p>Eso es exactamente lo que Paramount pretende hacer. \u201cEstamos ofreciendo a los accionistas  US$ 17.600 millones m\u00e1s en efectivo que el acuerdo que tienen actualmente con Netflix\u201d, declar\u00f3 el lunes el director ejecutivo de Paramount, <a href=\"https:\/\/www.cnn.com\/2025\/10\/23\/media\/ellison-wbd-trump-warner-bros-discovery-bid\">David Ellison<\/a>, en una entrevista con la CNBC. \u201cY creemos que cuando vean lo que incluye nuestra oferta, votar\u00e1n a favor\u201d.<\/p>\n<p>Ellison afirm\u00f3 que los accionistas de WBD \u201cmerecen la oportunidad de considerar nuestra oferta superior en efectivo por sus acciones en toda la empresa\u201d, y a\u00f1adi\u00f3 que cree que ofrece \u201cun valor superior y un camino m\u00e1s seguro y r\u00e1pido hacia la finalizaci\u00f3n. Creemos que la junta directiva de WBD est\u00e1 persiguiendo una propuesta inferior\u201d. WBD es la empresa matriz de CNN.<\/p>\n<p>Las acciones m\u00e1s recientes de Ellison reflejan las de <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/02\/05\/eeuu\/vivieron-adquisicion-twitter-elon-musk-consejos-gobierno-trax\">Elon Musk<\/a>, quien inicialmente realiz\u00f3 una oferta no solicitada de US$ 43.000 millones para adquirir una participaci\u00f3n mayoritaria en lo que entonces se conoc\u00eda como Twitter, en 2022. La junta directiva de Twitter no rechaz\u00f3 formalmente la oferta. M\u00e1s bien, adopt\u00f3<a href=\"https:\/\/www.cnn.com\/2022\/04\/18\/tech\/elon-musk-twitter-board-next-steps\"> una t\u00e1ctica defensiva dise\u00f1ada para encarecer la compra de la empresa de redes sociales<\/a> por parte de Musk. Tras una larga batalla, Musk adquiri\u00f3 Twitter por US$ 44.000 millones y convirti\u00f3 la empresa en privada, renombr\u00e1ndola X.<\/p>\n<p>Hay otros ejemplos de ofertas p\u00fablicas de adquisici\u00f3n hostiles que han tenido \u00e9xito, como la adquisici\u00f3n de Anheuser-Busch por parte de InBev en 2008, as\u00ed como la adquisici\u00f3n de Cadbury por parte de Kraft Foods en 2010. Pero esta t\u00e1ctica no siempre funciona.<\/p>\n<p>Existen dos formas principales en que una empresa puede llevar a cabo una adquisici\u00f3n hostil de otra empresa.<\/p>\n<p>La primera consiste en dirigirse directamente a los accionistas con el fin de asegurarse una participaci\u00f3n mayoritaria en las acciones de la empresa objetivo. Para ello, el oferente ofrece a los accionistas una prima superior al precio actual de cotizaci\u00f3n de las acciones. Si los accionistas venden al menos el 50 % del total de las acciones de la empresa objetivo, el oferente obtiene una participaci\u00f3n mayoritaria, que puede utilizar para ayudar a nombrar nuevos miembros del consejo de administraci\u00f3n que aprueben la fusi\u00f3n. Ese es el enfoque que parece estar adoptando Paramount.<\/p>\n<p>La otra forma en que una empresa inicia una lucha por el control accionario consiste en apelar directamente a los accionistas de la empresa objetivo. Pero en lugar de comprar sus acciones, el postor intenta persuadir a los accionistas para que voten a favor de sustituir a los miembros del consejo de administraci\u00f3n que aprobar\u00edan la adquisici\u00f3n.<\/p>\n<p>Pero una empresa objetivo tiene diversas formas de defenderse para evitar una oferta p\u00fablica de adquisici\u00f3n hostil. Un ejemplo famoso es el intento de Carl Icahn de adquirir Clorox en 2011. Su oferta p\u00fablica de adquisici\u00f3n hostil fracas\u00f3 porque el consejo de administraci\u00f3n de Clorox adopt\u00f3 una estrategia conocida como \u201cp\u00edldora venenosa\u201d, por la que los accionistas existentes tienen la oportunidad de comprar m\u00e1s acciones con un importante descuento. Si tiene \u00e9xito, esta estrategia reduce la participaci\u00f3n del oferente en la empresa objetivo y encarece la adquisici\u00f3n de una participaci\u00f3n mayoritaria por parte del oferente.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Paramount Skydance ha desatado una oferta p\u00fablica de adquisici\u00f3n hostil por Warner Bros. Discovery (WBD), desafiando el megacuerdo de US$ 72.000 millones que WBD anunci\u00f3 el pasado viernes con Netflix. Al dirigirse directamente a los accionistas, Paramount Skydance present\u00f3 una agresiva oferta en efectivo que, seg\u00fan la compa\u00f1\u00eda, supera en valor a la propuesta de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469087","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 es una oferta p\u00fablica de adquisici\u00f3n hostil, como la que lanz\u00f3 Paramount sobre Warner Bros. Discovery? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es una oferta p\u00fablica de adquisici\u00f3n hostil, como la que lanz\u00f3 Paramount sobre Warner Bros. Discovery? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Paramount Skydance ha desatado una oferta p\u00fablica de adquisici\u00f3n hostil por Warner Bros. Discovery (WBD), desafiando el megacuerdo de US$ 72.000 millones que WBD anunci\u00f3 el pasado viernes con Netflix. Al dirigirse directamente a los accionistas, Paramount Skydance present\u00f3 una agresiva oferta en efectivo que, seg\u00fan la compa\u00f1\u00eda, supera en valor a la propuesta de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-08T23:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 es una oferta p\u00fablica de adquisici\u00f3n hostil, como la que lanz\u00f3 Paramount sobre Warner Bros. Discovery?\",\"datePublished\":\"2025-12-08T23:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/\"},\"wordCount\":673,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/\",\"name\":\"\u00bfQu\u00e9 es una oferta p\u00fablica de adquisici\u00f3n hostil, como la que lanz\u00f3 Paramount sobre Warner Bros. Discovery? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-08T23:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es una oferta p\u00fablica de adquisici\u00f3n hostil, como la que lanz\u00f3 Paramount sobre Warner Bros. Discovery?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es una oferta p\u00fablica de adquisici\u00f3n hostil, como la que lanz\u00f3 Paramount sobre Warner Bros. Discovery? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es una oferta p\u00fablica de adquisici\u00f3n hostil, como la que lanz\u00f3 Paramount sobre Warner Bros. Discovery? - Noticias","og_description":"Paramount Skydance ha desatado una oferta p\u00fablica de adquisici\u00f3n hostil por Warner Bros. Discovery (WBD), desafiando el megacuerdo de US$ 72.000 millones que WBD anunci\u00f3 el pasado viernes con Netflix. Al dirigirse directamente a los accionistas, Paramount Skydance present\u00f3 una agresiva oferta en efectivo que, seg\u00fan la compa\u00f1\u00eda, supera en valor a la propuesta de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-08T23:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 es una oferta p\u00fablica de adquisici\u00f3n hostil, como la que lanz\u00f3 Paramount sobre Warner Bros. Discovery?","datePublished":"2025-12-08T23:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/"},"wordCount":673,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/","name":"\u00bfQu\u00e9 es una oferta p\u00fablica de adquisici\u00f3n hostil, como la que lanz\u00f3 Paramount sobre Warner Bros. Discovery? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-08T23:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es una oferta p\u00fablica de adquisici\u00f3n hostil, como la que lanz\u00f3 Paramount sobre Warner Bros. Discovery?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 es una oferta p\u00fablica de adquisici\u00f3n hostil, como la que lanz\u00f3 Paramount sobre Warner Bros. Discovery?","url":"http:\/\/noticiasya.com\/laredo\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/12\/08\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-08T23:03:45Z","datePublished":"2025-12-08T23:03:45Z","dateModified":"2025-12-08T23:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 es una oferta p\\u00fablica de adquisici\\u00f3n hostil, como la que lanz\\u00f3 Paramount sobre Warner Bros. Discovery?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/12\\\/08\\\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/12\\\/08\\\/que-es-una-oferta-publica-hostil-paramount-warner-bros-discovery-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-08T23:03:45Z\",\"datePublished\":\"2025-12-08T23:03:45Z\",\"dateModified\":\"2025-12-08T23:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469074,"url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/08\/paramount-lanza-oferta-publica-adquisicion-warner-wbd-trax\/","url_meta":{"origin":1469087,"position":0},"title":"Paramount lanza una oferta p\u00fablica de adquisici\u00f3n hostil sobre Warner Bros. Discovery","author":"","date":"diciembre 8, 2025","format":false,"excerpt":"Paramount se ha dirigido directamente a los accionistas de Warner Bros. Discovery con una oferta en efectivo por la empresa que, seg\u00fan afirma, es m\u00e1s valiosa que el acuerdo de Netflix anunciado el viernes.Se esperaba ampliamente que Paramount fuera el favorito para Warner Bros. Pero WBD \u2014que es la empresa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469860,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/07\/junta-directiva-warner-bros-discovery-rechaza-paramount-trax\/","url_meta":{"origin":1469087,"position":1},"title":"La junta directiva de Warner Bros. Discovery rechaza la renovada oferta de adquisici\u00f3n hostil de Paramount","author":"","date":"enero 7, 2026","format":false,"excerpt":"Una vez m\u00e1s, Warner Bros. Discovery ha elegido a Netflix como su pretendiente preferido frente a Paramount.La junta directiva de WBD inform\u00f3 este mi\u00e9rcoles a los accionistas que la oferta revisada del mes pasado de Paramount todav\u00eda no es tan atractiva como el acuerdo existente con Netflix, a pesar de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469148,"url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/10\/paramount-oferta-wbd-trax\/","url_meta":{"origin":1469087,"position":2},"title":"\u00bfPor qu\u00e9 la oferta de Paramount por Warner Bros. Discovery es hist\u00f3rica?","author":"","date":"diciembre 10, 2025","format":false,"excerpt":"Paramount y Netflix libran una intensa disputa por Warner Bros. Discovery (WBD).De un lado est\u00e1 Netflix, el pretendiente al que la junta directiva de WBD dio el visto bueno, tras anunciar la semana pasada un acuerdo por US$ 72.000 millones. Del otro lado est\u00e1 Paramount, el pretendiente al que la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470014,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/12\/paramount-demanda-warner-bros-discovery-netflix-trax\/","url_meta":{"origin":1469087,"position":3},"title":"Paramount presenta una demanda contra Warner Bros. Discovery y amenaza con una batalla por el control de la compa\u00f1\u00eda","author":"","date":"enero 12, 2026","format":false,"excerpt":"Paramount decidi\u00f3 llevar a los tribunales su intento de adquirir Warner Bros. Discovery, la empresa matriz de CNN.El lunes, el CEO de Paramount, David Ellison, anunci\u00f3 una demanda ante el tribunal de equidad de Delaware, donde habitualmente se resuelven las disputas corporativas entre accionistas, en su intento de compra hostil\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470256,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/20\/netflix-oferta-warner-bros-discovery-efectivo-trax\/","url_meta":{"origin":1469087,"position":4},"title":"Netflix revisa su oferta por Warner Bros. Discovery. Ahora, es todo en efectivo","author":"","date":"enero 20, 2026","format":false,"excerpt":"En la lucha por el futuro de Warner Bros. Discovery, Netflix dice que est\u00e1 dispuesto a pagar todo en efectivo por Warner Bros. y HBO, en lugar de una combinaci\u00f3n de efectivo y acciones.Netflix y Warner Bros. Discovery \u2014WBD para abreviar\u2014 anunciaron el plan modificado este martes por la ma\u00f1ana,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471723,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/27\/david-ellison-paramount-hollywood-trax\/","url_meta":{"origin":1469087,"position":5},"title":"C\u00f3mo David Ellison, el CEO de Paramount, luch\u00f3 para dominar Hollywood\u2026 y gan\u00f3","author":"","date":"febrero 27, 2026","format":false,"excerpt":"Hace menos de un a\u00f1o, David Ellison dirig\u00eda una peque\u00f1a productora. Ahora, est\u00e1 a punto de convertirse en el rey de Hollywood.El director ejecutivo de Paramount Skydance sali\u00f3 victorioso el jueves por la noche en una puja por Warner Bros. Discovery. Era un premio que Paramount necesitaba desesperadamente para sobrevivir,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1469087"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469087\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1469087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1469087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1469087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}