{"id":1469116,"date":"2025-12-09T09:03:39","date_gmt":"2025-12-09T17:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/"},"modified":"2025-12-09T09:03:39","modified_gmt":"2025-12-09T17:03:39","slug":"ninos-australia-redes-sociales-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/","title":{"rendered":"Millones de ni\u00f1os australianos acaban de perder el acceso a las redes sociales. \u00bfQu\u00e9 est\u00e1 pasando? \u00bfFuncionar\u00e1?"},"content":{"rendered":"<p>Ni\u00f1os de toda Australia se despertar\u00e1n el mi\u00e9rcoles sin acceso a sus cuentas de redes sociales debido a una prohibici\u00f3n que es pionera en el mundo, dise\u00f1ada para proteger a los menores de 16 a\u00f1os de algoritmos adictivos, depredadores en l\u00ednea y acosadores digitales.<\/p>\n<p>Ning\u00fan otro pa\u00eds ha tomado medidas tan dr\u00e1sticas, y legisladores de todo el mundo siguen de cerca la implementaci\u00f3n de esta estricta legislaci\u00f3n.<\/p>\n<p>La mayor\u00eda de las 10 plataformas prohibidas (Instagram, Facebook, Threads, Snapchat, YouTube, TikTok, Kick, Reddit, Twitch y X) afirman que cumplir\u00e1n con la prohibici\u00f3n y para eso utilizar\u00e1n la tecnolog\u00eda de verificaci\u00f3n de edad para identificar a los menores de 16 a\u00f1os y suspender sus cuentas, pero dijeron que no creen que esto mejore la seguridad de los ni\u00f1os.<\/p>\n<p>El primer ministro de Australia, Anthony Albanese, ya promociona la prohibici\u00f3n como un \u00e9xito debido a que las familias est\u00e1n hablando sobre el uso de las redes sociales. Se espera que algunos ni\u00f1os y sus padres ignoren la medida y no habr\u00e1 consecuencias en ninguno de los casos. \u201cHemos dicho muy claramente que esto no ser\u00e1 perfecto\u2026 pero es lo correcto para que la sociedad exprese su opini\u00f3n, su juicio, sobre lo que es apropiado\u201d, declar\u00f3 Albanese a la cadena p\u00fablica ABC el domingo.<\/p>\n<p>Seg\u00fan la ley, las plataformas deben demostrar que han tomado \u201cmedidas razonables\u201d para desactivar las cuentas utilizadas por menores de 16 a\u00f1os y evitar la apertura de nuevas cuentas. As\u00ed podr\u00e1n evitar multas de hasta 49,5 millones de d\u00f3lares australianos (US$ 32 millones).<\/p>\n<p>Las cuentas de los usuarios de <strong>Snapchat<\/strong> ser\u00e1n suspendidas durante tres a\u00f1os o hasta que cumplan 16 a\u00f1os.<\/p>\n<p>Las cuentas de <strong>YouTube<\/strong> ser\u00e1n desconectadas autom\u00e1ticamente el 10 de diciembre. Sus canales ya no ser\u00e1n visibles. Sin embargo, sus datos se guardar\u00e1n para que puedan reactivar sus cuentas al cumplir 16 a\u00f1os. Con todo, los menores podr\u00e1n seguir viendo YouTube sin iniciar sesi\u00f3n.<\/p>\n<p><strong>TikTok<\/strong> afirma que todas las cuentas de menores de 16 a\u00f1os se desactivar\u00e1n el 10 de diciembre. Indica que no importa el correo electr\u00f3nico ni el nombre de la cuenta: su tecnolog\u00eda de verificaci\u00f3n de edad determinar\u00e1 qui\u00e9n la usa. El contenido publicado previamente por j\u00f3venes usuarios ya no ser\u00e1 visible. La plataforma tambi\u00e9n llama a los padres que crean que sus hijos pueden haber mentido sobre su edad al abrir cuentas a que lo denuncien.<\/p>\n<p><strong>Twitch <\/strong>afirma que los menores de 16 a\u00f1os en Australia no podr\u00e1n crear nuevas cuentas en la popular plataforma de streaming en vivo a partir del 10 de diciembre, pero las cuentas actuales de menores de 16 a\u00f1os no se desactivar\u00e1n hasta el 9 de enero. La compa\u00f1\u00eda no respondi\u00f3 a una solicitud para explicar el porqu\u00e9 del retraso.<\/p>\n<p><strong>Meta<\/strong> comenz\u00f3 a eliminar cuentas de adolescentes menores de 16 a\u00f1os en Instagram, Facebook y Threads el 4 de diciembre. Se invit\u00f3 a los usuarios a descargar su contenido, que estar\u00e1 disponible si desean reactivar su cuenta al cumplir los 16 a\u00f1os.<\/p>\n<p><strong>Reddit <\/strong>anunci\u00f3 que suspender\u00e1 las cuentas de los usuarios menores de 16 a\u00f1os e impedir\u00e1 la creaci\u00f3n de nuevas cuentas.<\/p>\n<p><strong>X<\/strong> no ha respondido a las preguntas sobre c\u00f3mo cumplir\u00e1 con la prohibici\u00f3n, pero la compa\u00f1\u00eda se opone firmemente a la legislaci\u00f3n por considerarla una violaci\u00f3n de la libertad de expresi\u00f3n.<\/p>\n<p><strong>Kick<\/strong>, un servicio de transmisi\u00f3n en vivo similar a Twitch, no ha respondido a una solicitud de comentarios de CNN.<\/p>\n<p>Junto con la lista de sitios prohibidos, se incluye una lista de plataformas que a\u00fan no se consideran parte de la prohibici\u00f3n. Estas son Discord, GitHub, Google Classroom, LEGO Play, Messenger, Pinterest, Roblox, Steam y Steam Chat, WhatsApp y YouTube Kids.<\/p>\n<p>La decisi\u00f3n de excluir a Roblox fue considerada por muchos australianos como desconcertante, dados los recientes informes que alegan que varios ni\u00f1os han sido v\u00edctimas de depredadores sexuales en sus juegos.<\/p>\n<p>La Comisionada de Seguridad Electr\u00f3nica, Julie Inman-Grant, declar\u00f3 que las conversaciones con Roblox comenzaron en junio y acordaron introducir nuevos controles que se implementar\u00e1n este mes en Australia, Nueva Zelanda y los Pa\u00edses Bajos, y en enero en el resto del mundo.<\/p>\n<p>Los usuarios deber\u00e1n verificar su edad para habilitar las funciones de chat, y solo podr\u00e1n chatear con personas de su misma edad.<\/p>\n<p>Las plataformas prohibidas ya ten\u00edan una idea bastante precisa de qui\u00e9n usaba sus servicios a partir de la fecha de nacimiento que los usuarios ingresaban al abrir una cuenta, pero la nueva ley les exige verificar activamente su edad.<\/p>\n<p>Esto ha generado objeciones por parte de algunos usuarios adultos, quienes temen que se les solicite verificar su edad. El Ensayo de Tecnolog\u00eda de Verificaci\u00f3n de Edad, realizado a principios de este a\u00f1o, convenci\u00f3 al Gobierno de que las verificaciones de edad pod\u00edan realizarse sin comprometer la privacidad.<\/p>\n<p>Las plataformas verifican las edades mediante <em>selfies<\/em> en video en vivo, direcciones de correo electr\u00f3nico o documentos oficiales. Seg\u00fan Yoti, una empresa de verificaci\u00f3n de edad cuyos clientes incluyen a Meta, la mayor\u00eda de los usuarios eligen una <em>selfie<\/em> en video que utiliza puntos de datos faciales para estimar la edad.<\/p>\n<p>Algunos ni\u00f1os buscan plataformas alternativas que ofrezcan servicios similares que no est\u00e9n prohibidos.<\/p>\n<p>Yope, una plataforma para compartir fotos, afirm\u00f3 haber atra\u00eddo a 100.000 nuevos usuarios australianos gracias al boca a boca ante la inminente prohibici\u00f3n. Lemon8, una plataforma similar a TikTok, propiedad de ByteDance, tambi\u00e9n se ha promocionado entre los adolescentes como alternativa.<\/p>\n<p>Ambas plataformas fueron notificadas por el Comisionado de Seguridad Electr\u00f3nica. Lemon8 afirma que cumplir\u00e1 con las nuevas leyes australianas, mientras que Yope declar\u00f3 a CNN que la prohibici\u00f3n no le aplica porque no permite la mensajer\u00eda con desconocidos.<\/p>\n<p>El comisionado de Seguridad Electr\u00f3nica afirma que la lista de sitios prohibidos est\u00e1 evolucionando y que podr\u00edan a\u00f1adirse nuevos a medida que ganen popularidad u ofrezcan nuevos servicios.<\/p>\n<p>La naturaleza cambiante de la lista y el incentivo para que otros operadores atiendan a millones de adolescentes que buscan alternativas ha generado cr\u00edticas, alegando que el gobierno ha creado un juego de \u201cgolpea al topo\u201d que posiblemente nunca ganar\u00e1.<\/p>\n<p>Los consejeros juveniles y los grupos de apoyo temen que los ni\u00f1os que dependen de las redes sociales para su inclusi\u00f3n terminen en espacios digitales sin regular, donde hay a\u00fan menos protecciones, y est\u00e1n observando ad\u00f3nde van.<\/p>\n<p>Parte de la motivaci\u00f3n para la prohibici\u00f3n fue que los ni\u00f1os desconectaran y se conectaran m\u00e1s con el mundo real, algo que las autoridades planean medir.<\/p>\n<p>\u201cEstudiaremos todos los aspectos, desde si los ni\u00f1os duermen m\u00e1s, si interact\u00faan m\u00e1s, si toman menos antidepresivos, si leen m\u00e1s libros, si salen a hacer deporte\u201d, declar\u00f3 la Comisionada de Seguridad Electr\u00f3nica, Inman-Grant, en el Di\u00e1logo de S\u00eddney la semana pasada.<\/p>\n<p>Pero a\u00f1adi\u00f3 que tambi\u00e9n estar\u00e1n monitoreando las consecuencias no deseadas. \u201c\u00bfSe dirigen a zonas m\u00e1s oscuras de la web y cu\u00e1l es el resultado?\u201d, se pregunt\u00f3.<\/p>\n<p>Seis expertos del Laboratorio de Redes Sociales de la Universidad de Stanford trabajar\u00e1n con la Comisionada de Seguridad Electr\u00f3nica para recopilar los datos, y todo el proceso ser\u00e1 revisado por un Grupo Asesor Acad\u00e9mico independiente compuesto por 11 acad\u00e9micos de Estados Unidos, el Reino Unido y Australia.<\/p>\n<p>La Universidad de Stanford afirm\u00f3 que su enfoque, m\u00e9todos y hallazgos se publicar\u00e1n para su an\u00e1lisis por parte de investigadores, el p\u00fablico y los responsables pol\u00edticos de todo el mundo.<\/p>\n<p>\u201cEsperamos que la evidencia generada pueda respaldar e informar directamente la toma de decisiones de otros pa\u00edses en su b\u00fasqueda de promover la seguridad en l\u00ednea de los ni\u00f1os en sus jurisdicciones\u201d, afirm\u00f3 la universidad en un comunicado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ni\u00f1os de toda Australia se despertar\u00e1n el mi\u00e9rcoles sin acceso a sus cuentas de redes sociales debido a una prohibici\u00f3n que es pionera en el mundo, dise\u00f1ada para proteger a los menores de 16 a\u00f1os de algoritmos adictivos, depredadores en l\u00ednea y acosadores digitales. Ning\u00fan otro pa\u00eds ha tomado medidas tan dr\u00e1sticas, y legisladores de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469116","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Millones de ni\u00f1os australianos acaban de perder el acceso a las redes sociales. \u00bfQu\u00e9 est\u00e1 pasando? \u00bfFuncionar\u00e1? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Millones de ni\u00f1os australianos acaban de perder el acceso a las redes sociales. \u00bfQu\u00e9 est\u00e1 pasando? \u00bfFuncionar\u00e1? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Ni\u00f1os de toda Australia se despertar\u00e1n el mi\u00e9rcoles sin acceso a sus cuentas de redes sociales debido a una prohibici\u00f3n que es pionera en el mundo, dise\u00f1ada para proteger a los menores de 16 a\u00f1os de algoritmos adictivos, depredadores en l\u00ednea y acosadores digitales. Ning\u00fan otro pa\u00eds ha tomado medidas tan dr\u00e1sticas, y legisladores de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-09T17:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Millones de ni\u00f1os australianos acaban de perder el acceso a las redes sociales. \u00bfQu\u00e9 est\u00e1 pasando? \u00bfFuncionar\u00e1?\",\"datePublished\":\"2025-12-09T17:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/\"},\"wordCount\":1385,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/\",\"name\":\"Millones de ni\u00f1os australianos acaban de perder el acceso a las redes sociales. \u00bfQu\u00e9 est\u00e1 pasando? \u00bfFuncionar\u00e1? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-09T17:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Millones de ni\u00f1os australianos acaban de perder el acceso a las redes sociales. \u00bfQu\u00e9 est\u00e1 pasando? \u00bfFuncionar\u00e1?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Millones de ni\u00f1os australianos acaban de perder el acceso a las redes sociales. \u00bfQu\u00e9 est\u00e1 pasando? \u00bfFuncionar\u00e1? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Millones de ni\u00f1os australianos acaban de perder el acceso a las redes sociales. \u00bfQu\u00e9 est\u00e1 pasando? \u00bfFuncionar\u00e1? - Noticias","og_description":"Ni\u00f1os de toda Australia se despertar\u00e1n el mi\u00e9rcoles sin acceso a sus cuentas de redes sociales debido a una prohibici\u00f3n que es pionera en el mundo, dise\u00f1ada para proteger a los menores de 16 a\u00f1os de algoritmos adictivos, depredadores en l\u00ednea y acosadores digitales. Ning\u00fan otro pa\u00eds ha tomado medidas tan dr\u00e1sticas, y legisladores de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-09T17:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/"},"author":{"name":"","@id":""},"headline":"Millones de ni\u00f1os australianos acaban de perder el acceso a las redes sociales. \u00bfQu\u00e9 est\u00e1 pasando? \u00bfFuncionar\u00e1?","datePublished":"2025-12-09T17:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/"},"wordCount":1385,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/","name":"Millones de ni\u00f1os australianos acaban de perder el acceso a las redes sociales. \u00bfQu\u00e9 est\u00e1 pasando? \u00bfFuncionar\u00e1? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-09T17:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Millones de ni\u00f1os australianos acaban de perder el acceso a las redes sociales. \u00bfQu\u00e9 est\u00e1 pasando? \u00bfFuncionar\u00e1?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Millones de ni\u00f1os australianos acaban de perder el acceso a las redes sociales. \u00bfQu\u00e9 est\u00e1 pasando? \u00bfFuncionar\u00e1?","url":"http:\/\/noticiasya.com\/laredo\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/12\/09\/ninos-australia-redes-sociales-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-09T17:03:39Z","datePublished":"2025-12-09T17:03:39Z","dateModified":"2025-12-09T17:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Millones de ni\\u00f1os australianos acaban de perder el acceso a las redes sociales. \\u00bfQu\\u00e9 est\\u00e1 pasando? \\u00bfFuncionar\\u00e1?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/12\\\/09\\\/ninos-australia-redes-sociales-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/12\\\/09\\\/ninos-australia-redes-sociales-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-09T17:03:39Z\",\"datePublished\":\"2025-12-09T17:03:39Z\",\"dateModified\":\"2025-12-09T17:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469175,"url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/11\/australia-prohibicion-redes-sociales-ninos-trax\/","url_meta":{"origin":1469116,"position":0},"title":"&#171;\u00bfQu\u00e9 es lo peor que podr\u00eda pasar?&#187; Primer ministro de Australia del Sur, sobre la prohibici\u00f3n de redes sociales a menores","author":"","date":"diciembre 11, 2025","format":false,"excerpt":"El primer ministro de Australia del Sur, Peter Malinauskas, dijo a Jake Tapper de CNN que la primera prohibici\u00f3n de redes sociales del mundo en su pa\u00eds para ni\u00f1os menores de 16 a\u00f1os tiene como objetivo protegerlos de algoritmos adictivos y pregunt\u00f3: \u201c\u00bfQu\u00e9 es lo peor que puede pasar aqu\u00ed\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470486,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/26\/macron-francia-prohibicion-redes-sociales-ninos-trax\/","url_meta":{"origin":1469116,"position":1},"title":"&#171;El cerebro de nuestros ni\u00f1os no est\u00e1 en venta&#187;: Macron quiere acelerar prohibici\u00f3n de redes sociales para menores de 15 a\u00f1os","author":"","date":"enero 26, 2026","format":false,"excerpt":"El presidente de Francia, Emmanuel Macron, afirm\u00f3 que quiere que su Gobierno agilice el proceso legal para garantizar que la prohibici\u00f3n del uso de redes sociales para menores de 15 a\u00f1os est\u00e9 vigente antes del inicio del pr\u00f3ximo curso escolar en septiembre.\u201cEl cerebro de nuestros ni\u00f1os y adolescentes no est\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455986,"url":"https:\/\/noticiasya.com\/laredo\/2024\/11\/20\/australia-ley-limitar-uso-redes-sociales-menores-16-trax\/","url_meta":{"origin":1469116,"position":2},"title":"Australia presenta proyecto de ley para limitar el uso de redes sociales en menores de 16 a\u00f1os. Las empresas tecnol\u00f3gicas se enfrentan a enormes multas","author":"","date":"noviembre 20, 2024","format":false,"excerpt":"Brisbane, Australia (CNN) \u2013\u2013 El Gobierno de Australia amenaza con multas multimillonarias para las empresas de redes sociales que violen una propuesta de prohibici\u00f3n de que los ni\u00f1os menores de 16 a\u00f1os usen sus servicios.La ministra de Comunicaciones, Michelle Rowland, present\u00f3 este jueves en el Parlamento una enmienda a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469134,"url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/10\/australia-ansiedad-adolescentes-redes-sociales-trax\/","url_meta":{"origin":1469116,"position":3},"title":"Australia acaba de aliviar su ansiedad por los adolescentes en las redes sociales\u2026 \u00bfo no?","author":"","date":"diciembre 10, 2025","format":false,"excerpt":"Para los padres y activistas que han argumentado durante mucho tiempo que la navegaci\u00f3n vertical incesante est\u00e1 da\u00f1ando las mentes j\u00f3venes, el inicio de la primera prohibici\u00f3n de redes sociales del mundo en Australia para menores de 16 a\u00f1os es solo el comienzo.Wayne Holdsworth, el padre de Mac, quien se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447352,"url":"https:\/\/noticiasya.com\/laredo\/2024\/03\/25\/gobernador-florida-ley-acceso-ninos-redes-sociales-trax\/","url_meta":{"origin":1469116,"position":4},"title":"El gobernador Ron DeSantis firma ley en Florida que restringe el acceso de los ni\u00f1os a las redes sociales","author":"","date":"marzo 25, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El gobernador de Florida, el republicano Ron DeSantis, firm\u00f3 este lunes un proyecto de ley que proh\u00edbe a los ni\u00f1os menores de 14 a\u00f1os tener sus propias cuentas de redes sociales, seg\u00fan un comunicado de prensa de su oficina.Los j\u00f3venes de 14 y 15 a\u00f1os podr\u00e1n tener cuentas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469130,"url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/09\/australia-prohibe-adolescentes-redes-sociales-trax\/","url_meta":{"origin":1469116,"position":5},"title":"Australia proh\u00edbe a los adolescentes usar redes sociales. \u00bfPodr\u00eda suceder en Estados Unidos?","author":"","date":"diciembre 9, 2025","format":false,"excerpt":"La primera prohibici\u00f3n global del uso de las principales plataformas de redes sociales para menores de 16 a\u00f1os entrar\u00e1 en vigor en Australia el mi\u00e9rcoles. Reguladores, padres y adolescentes de todo el mundo est\u00e1n observando de cerca para ver c\u00f3mo se desarrolla.La ley llega despu\u00e9s de a\u00f1os de preocupaciones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1469116"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469116\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1469116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1469116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1469116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}