{"id":1469673,"date":"2025-12-30T15:03:44","date_gmt":"2025-12-30T23:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/"},"modified":"2025-12-30T15:03:44","modified_gmt":"2025-12-30T23:03:44","slug":"mclaren-norris-f1-marc-marquez-motogp-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/","title":{"rendered":"Un 2025 donde McLaren y Norris desbancaron a Verstappen y donde Marc M\u00e1rquez igual\u00f3 a Valentino Rossi"},"content":{"rendered":"<p>El brit\u00e1nico Lando Norris, al mando de un poderoso McLaren, logr\u00f3 conseguir en este 2025 lo que hasta hace un par de a\u00f1os parec\u00eda muy lejano en la F\u00f3rmula 1: terminar con la hegemon\u00eda de Max Verstappen.<\/p>\n<p>Norris conquist\u00f3 su ansiado primer t\u00edtulo en la m\u00e1xima categor\u00eda del automovilismo en un cerrado final, en el que compiti\u00f3 con Verstappen (Red Bull) y Oscar Piastri (su comp\u00f1aero en McLaren).<\/p>\n<p>Norris lo conquist\u00f3 en la \u00faltima competencia de la temporada, que se celebr\u00f3 en Abu Dhabi, con un tercer puesto que le asegur\u00f3 la coronaci\u00f3n a pesar del triunfo de Verstappen y el segundo lugar de Piastri.<\/p>\n<p>Debieron pasar 152 grandes premios, 16 pole positions y 11 victorias para que Lando Norris conquiste su ansiado primer t\u00edtulo en la F\u00f3rmula 1.<\/p>\n<p>El brit\u00e1nico se convirti\u00f3 en el campe\u00f3n n\u00famero 35 de la F\u00f3rmula 1 con 26 a\u00f1os y 24 d\u00edas de edad, en una temporada donde demostr\u00f3 su indudable talento, pero tambi\u00e9n errores propios (y otros de la escuder\u00eda) que le hicieron demorar la merecida coronaci\u00f3n, que finalmente se dio por solo dos puntos sobre Verstappen, ganador de los \u00faltimos cuatro Mundiales de Pilotos.<\/p>\n<p>En el motociclismo, Marc M\u00e1rquez volvi\u00f3 a ser el rey del MotoGP, al conquistar en Jap\u00f3n su s\u00e9ptimo t\u00edtulo.<\/p>\n<p>El espa\u00f1ol regres\u00f3 a lo m\u00e1s alto despu\u00e9s de los duros momentos que experiment\u00f3 con su salud y que lo tuvieron muy cerca del retiro.<\/p>\n<p>M\u00e1rquez volvi\u00f3 a reinar en el MotoGP tras dejar Honda por Ducati, marca insignia del motociclismo, con la cual fue imparable.<\/p>\n<p>El piloto espa\u00f1ol fue una flecha roja en la temporada ganando 11 carreras largas y 14 competiciones de sprint, que le permitieron volver a lo m\u00e1s alto tras tortuosos momentos que incluyeron un accidente, una fractura y cuatro operaciones.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El brit\u00e1nico Lando Norris, al mando de un poderoso McLaren, logr\u00f3 conseguir en este 2025 lo que hasta hace un par de a\u00f1os parec\u00eda muy lejano en la F\u00f3rmula 1: terminar con la hegemon\u00eda de Max Verstappen. Norris conquist\u00f3 su ansiado primer t\u00edtulo en la m\u00e1xima categor\u00eda del automovilismo en un cerrado final, en el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469673","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un 2025 donde McLaren y Norris desbancaron a Verstappen y donde Marc M\u00e1rquez igual\u00f3 a Valentino Rossi - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un 2025 donde McLaren y Norris desbancaron a Verstappen y donde Marc M\u00e1rquez igual\u00f3 a Valentino Rossi - Noticias\" \/>\n<meta property=\"og:description\" content=\"El brit\u00e1nico Lando Norris, al mando de un poderoso McLaren, logr\u00f3 conseguir en este 2025 lo que hasta hace un par de a\u00f1os parec\u00eda muy lejano en la F\u00f3rmula 1: terminar con la hegemon\u00eda de Max Verstappen. Norris conquist\u00f3 su ansiado primer t\u00edtulo en la m\u00e1xima categor\u00eda del automovilismo en un cerrado final, en el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-30T23:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un 2025 donde McLaren y Norris desbancaron a Verstappen y donde Marc M\u00e1rquez igual\u00f3 a Valentino Rossi\",\"datePublished\":\"2025-12-30T23:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/\"},\"wordCount\":348,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/\",\"name\":\"Un 2025 donde McLaren y Norris desbancaron a Verstappen y donde Marc M\u00e1rquez igual\u00f3 a Valentino Rossi - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-30T23:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un 2025 donde McLaren y Norris desbancaron a Verstappen y donde Marc M\u00e1rquez igual\u00f3 a Valentino Rossi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un 2025 donde McLaren y Norris desbancaron a Verstappen y donde Marc M\u00e1rquez igual\u00f3 a Valentino Rossi - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Un 2025 donde McLaren y Norris desbancaron a Verstappen y donde Marc M\u00e1rquez igual\u00f3 a Valentino Rossi - Noticias","og_description":"El brit\u00e1nico Lando Norris, al mando de un poderoso McLaren, logr\u00f3 conseguir en este 2025 lo que hasta hace un par de a\u00f1os parec\u00eda muy lejano en la F\u00f3rmula 1: terminar con la hegemon\u00eda de Max Verstappen. Norris conquist\u00f3 su ansiado primer t\u00edtulo en la m\u00e1xima categor\u00eda del automovilismo en un cerrado final, en el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/","og_site_name":"Noticias","article_published_time":"2025-12-30T23:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/"},"author":{"name":"","@id":""},"headline":"Un 2025 donde McLaren y Norris desbancaron a Verstappen y donde Marc M\u00e1rquez igual\u00f3 a Valentino Rossi","datePublished":"2025-12-30T23:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/"},"wordCount":348,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/","url":"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/","name":"Un 2025 donde McLaren y Norris desbancaron a Verstappen y donde Marc M\u00e1rquez igual\u00f3 a Valentino Rossi - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-30T23:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un 2025 donde McLaren y Norris desbancaron a Verstappen y donde Marc M\u00e1rquez igual\u00f3 a Valentino Rossi"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un 2025 donde McLaren y Norris desbancaron a Verstappen y donde Marc M\u00e1rquez igual\u00f3 a Valentino Rossi","url":"http:\/\/noticiasya.com\/laredo\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2025\/12\/30\/mclaren-norris-f1-marc-marquez-motogp-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-30T23:03:44Z","datePublished":"2025-12-30T23:03:44Z","dateModified":"2025-12-30T23:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un 2025 donde McLaren y Norris desbancaron a Verstappen y donde Marc M\\u00e1rquez igual\\u00f3 a Valentino Rossi\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/12\\\/30\\\/mclaren-norris-f1-marc-marquez-motogp-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2025\\\/12\\\/30\\\/mclaren-norris-f1-marc-marquez-motogp-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-30T23:03:44Z\",\"datePublished\":\"2025-12-30T23:03:44Z\",\"dateModified\":\"2025-12-30T23:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1468672,"url":"https:\/\/noticiasya.com\/laredo\/2025\/11\/24\/formula-uno-norris-piastri-verstappen-orix\/","url_meta":{"origin":1469673,"position":0},"title":"La F\u00f3rmula 1 puede decidirse en Qatar: Norris est\u00e1 cerca de ser campe\u00f3n, pero Piastri y Verstappen llegan con vida","author":"","date":"noviembre 24, 2025","format":false,"excerpt":"La F\u00f3rmula 1 est\u00e1 viviendo uno de los momentos m\u00e1s tensos y dram\u00e1ticos de los \u00faltimos a\u00f1os. El Gran Premio de Las Vegas desat\u00f3 el caos absoluto. Los dos McLaren fueron descalificados por infracciones t\u00e9cnicas y el campeonato dio un giro inesperado justo cuando la temporada entra en su punto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469049,"url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/07\/lando-norris-campeon-mundial-formula-uno-efe\/","url_meta":{"origin":1469673,"position":1},"title":"Lando Norris, nuevo campe\u00f3n del mundo de F\u00f3rmula Uno","author":"","date":"diciembre 7, 2025","format":false,"excerpt":"El ingl\u00e9s Lando Norris (McLaren) se proclam\u00f3 este domingo nuevo campe\u00f3n del mundo de F\u00f3rmula Uno, al acabar tercero el Gran Premio de Abu Dabi, el \u00faltimo del a\u00f1o, que gan\u00f3, en el circuito de Yas Marina, el cu\u00e1druple campe\u00f3n mundial neerland\u00e9s Max Verstappen (Red Bull).Norris, de 26 a\u00f1os, se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448907,"url":"https:\/\/noticiasya.com\/laredo\/2024\/05\/05\/lando-norris-gana-gran-premio-de-miami-primera-victoria-en-formula-1-trax\/","url_meta":{"origin":1469673,"position":2},"title":"Lando Norris sorprende y gana el Gran Premio de Miami, su primera victoria en F\u00f3rmula 1","author":"","date":"mayo 5, 2024","format":false,"excerpt":"(CNN) -- Lando Norris sorprendi\u00f3 a los competidores y gan\u00f3 el Gran Premio de Miami mientras las celebridades acudieron en masa a Florida para la tercera edici\u00f3n de la carrera este domingo. El piloto de McLaren termin\u00f3 7,6 segundos por delante de Max Verstappen de Red Bull en segundo lugar.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468130,"url":"https:\/\/noticiasya.com\/laredo\/2025\/11\/07\/franco-colapinto-alpine-2026-brasil-gp-orix\/","url_meta":{"origin":1469673,"position":3},"title":"F\u00f3rmula 1: Franco Colapinto se mantiene con Alpine para 2026, mientras el t\u00edtulo de pilotos se empieza a definir en Brasil","author":"","date":"noviembre 7, 2025","format":false,"excerpt":"El piloto argentino Franco Colapinto renov\u00f3 contrato con la escuder\u00eda Alpine y competir\u00e1 en el Campeonato Mundial de la F\u00f3rmula 1 de 2026.El anuncio se realiz\u00f3 en el Aut\u00f3dromo Jos\u00e9 Carlos Pace, conocido como Interlagos y sede del Gran Premio de Sao Paulo, la vig\u00e9sima primera carrera de la temporada.Colapinto,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468843,"url":"https:\/\/noticiasya.com\/laredo\/2025\/11\/30\/verstappen-gp-qatar-mclaren-norris-piastri-f1-orix\/","url_meta":{"origin":1469673,"position":4},"title":"McLaren arruina su fin de semana y deja m\u00e1s vivo que nunca a Verstappen: sorpresivo tercer puesto de Sainz en el GP de Qatar","author":"","date":"noviembre 30, 2025","format":false,"excerpt":"Siete vueltas. Eso fue todo lo que dur\u00f3 la carrera en el GP de Qatar este fin de semana, gracias a una estrategia casi de principiantes de McLaren con las paradas en boxes, que le facilit\u00f3 todo al tetracampe\u00f3n del mundo Max Verstappen, que ahora tiene claras chances de quedarse\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473758,"url":"https:\/\/noticiasya.com\/laredo\/2026\/05\/03\/antonelli-gran-premio-miami-f1-orix\/","url_meta":{"origin":1469673,"position":5},"title":"Antonelli gana el Gran Premio de Miami de la F1: Colapinto igual\u00f3 su mejor resultado y Checo P\u00e9rez tuvo una mala tarde","author":"","date":"mayo 3, 2026","format":false,"excerpt":"La F\u00f3rmula 1 regres\u00f3 a la actividad con una gran carrera en Miami. En lo que fue apenas el cuarto Gran Premio de la temporada (suspendidos los de Medio Oriente por la guerra entre Estados Unidos e Israel con Ir\u00e1n), Mercedes demostr\u00f3 que, a pesar de las mejoras que otras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1469673"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469673\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1469673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1469673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1469673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}