{"id":1469871,"date":"2026-01-07T10:03:48","date_gmt":"2026-01-07T18:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/"},"modified":"2026-01-07T10:03:48","modified_gmt":"2026-01-07T18:03:48","slug":"caracas-noche-calle-seguridad-maduro-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/","title":{"rendered":"Apenas cae el sol, las calles de Caracas se vac\u00edan: as\u00ed cambi\u00f3 la rutina nocturna de los venezolanos tras el ataque de EE.UU"},"content":{"rendered":"<p>Cuando apenas han pasado cinco d\u00edas <a href=\"https:\/\/cnnespanol.cnn.com\/mundo\/live-news\/noticias-maduro-detenido-venezuela-hoy-orix\">del ataque <\/a>de Estados Unidos a Caracas y la captura de Nicol\u00e1s Maduro, los venezolanos intentan recuperar cierto grado de normalidad. Pero hay algo que refleja la tensi\u00f3n latente: aunque durante el d\u00eda la circulaci\u00f3n va recuperando el ritmo usual, en la noche el panorama es bien diferente.<\/p>\n<p>Un conductor de Ridery, una aplicaci\u00f3n para servicios de traslado, dijo a CNN que una vez que oscurece disminuye dr\u00e1sticamente el n\u00famero de conductores en l\u00ednea ofreciendo el servicio. \u201cEst\u00e1 todo muy solitario y es mejor evitar contratiempos\u201d, detalla el ciudadano, que que no quiso ser identificado por temor a represalias.<\/p>\n<p>En el este de Caracas, un local de hamburguesas y perros calientes que usualmente abre hasta las 10:00 pm informa que trabajar\u00e1n hasta las 06:00 pm \u201cmientras se estabiliza la situaci\u00f3n\u201d, explica un empleado a cargo de la caja.<\/p>\n<p>Las calles caraque\u00f1as se vac\u00edan al bajar el sol. La gente no sale de sus casas. Los bares y restaurantes est\u00e1n cerrados o vac\u00edos. No hay transe\u00fantes paseando a sus perros, ni caminando. No se ven muchos autos particulares circulando. Un escenario muy diferente al de una semana atr\u00e1s, cuando los venezolanos celebraban el a\u00f1o nuevo y las calles estaban inundadas de gente.<\/p>\n<p>En cambio, ahora, el silencio y la oscuridad solo se ven interrumpidos por la fuerte presencia de personal de seguridad armado. No son militares, sino polic\u00edas y miembros de la contrainteligencia. Algo similar a lo que ocurri\u00f3 luego de las cuestionadas elecciones presidenciales de 2024.<\/p>\n<p>Hay patrullajes permanentes, hombres encapuchados, vestidos de negro, con armas larga recorren las calles en largas caravanas de veh\u00edculos. Transitan lento, vigilando lo que pasa en la ciudad, aunque es casi nulo el movimiento civil.<\/p>\n<p>Las pocas personas que circulan son interrogadas por estas fuerzas de seguridad sobre los motivos por los que est\u00e1n en la calle. Tambi\u00e9n se ven polic\u00edas y civiles armados a las afueras de los supermercados desde que ocurrieron los ataques de EE.UU. en la madrugada del s\u00e1bado.<\/p>\n<p>La situaci\u00f3n se extiende hacia las afueras de la capital. Anoche, frente a la plaza Altamira, en el municipio de Chacao, al este de Caracas, se pod\u00eda observar un contingente de entre 40 o 50 miembros de la Polic\u00eda Nacional Bolivariana (PNB), apostados con autos y motos.<\/p>\n<p>En la urbanizaci\u00f3n las Mercedes hab\u00eda otro contingente de la PNB apostado en una de las entradas.<\/p>\n<p>As\u00ed, mientras crece la incertidumbre de lo que pasar\u00e1 de aqu\u00ed en m\u00e1s en Venezuela, la aparente normalidad del d\u00eda contrasta con el rotundo cambio de la rutina nocturna de los ciudadanos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando apenas han pasado cinco d\u00edas del ataque de Estados Unidos a Caracas y la captura de Nicol\u00e1s Maduro, los venezolanos intentan recuperar cierto grado de normalidad. Pero hay algo que refleja la tensi\u00f3n latente: aunque durante el d\u00eda la circulaci\u00f3n va recuperando el ritmo usual, en la noche el panorama es bien diferente. Un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469871","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Apenas cae el sol, las calles de Caracas se vac\u00edan: as\u00ed cambi\u00f3 la rutina nocturna de los venezolanos tras el ataque de EE.UU - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apenas cae el sol, las calles de Caracas se vac\u00edan: as\u00ed cambi\u00f3 la rutina nocturna de los venezolanos tras el ataque de EE.UU - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cuando apenas han pasado cinco d\u00edas del ataque de Estados Unidos a Caracas y la captura de Nicol\u00e1s Maduro, los venezolanos intentan recuperar cierto grado de normalidad. Pero hay algo que refleja la tensi\u00f3n latente: aunque durante el d\u00eda la circulaci\u00f3n va recuperando el ritmo usual, en la noche el panorama es bien diferente. Un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-07T18:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Apenas cae el sol, las calles de Caracas se vac\u00edan: as\u00ed cambi\u00f3 la rutina nocturna de los venezolanos tras el ataque de EE.UU\",\"datePublished\":\"2026-01-07T18:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/\"},\"wordCount\":498,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/\",\"name\":\"Apenas cae el sol, las calles de Caracas se vac\u00edan: as\u00ed cambi\u00f3 la rutina nocturna de los venezolanos tras el ataque de EE.UU - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-07T18:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apenas cae el sol, las calles de Caracas se vac\u00edan: as\u00ed cambi\u00f3 la rutina nocturna de los venezolanos tras el ataque de EE.UU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apenas cae el sol, las calles de Caracas se vac\u00edan: as\u00ed cambi\u00f3 la rutina nocturna de los venezolanos tras el ataque de EE.UU - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Apenas cae el sol, las calles de Caracas se vac\u00edan: as\u00ed cambi\u00f3 la rutina nocturna de los venezolanos tras el ataque de EE.UU - Noticias","og_description":"Cuando apenas han pasado cinco d\u00edas del ataque de Estados Unidos a Caracas y la captura de Nicol\u00e1s Maduro, los venezolanos intentan recuperar cierto grado de normalidad. Pero hay algo que refleja la tensi\u00f3n latente: aunque durante el d\u00eda la circulaci\u00f3n va recuperando el ritmo usual, en la noche el panorama es bien diferente. Un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/","og_site_name":"Noticias","article_published_time":"2026-01-07T18:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/"},"author":{"name":"","@id":""},"headline":"Apenas cae el sol, las calles de Caracas se vac\u00edan: as\u00ed cambi\u00f3 la rutina nocturna de los venezolanos tras el ataque de EE.UU","datePublished":"2026-01-07T18:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/"},"wordCount":498,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/","url":"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/","name":"Apenas cae el sol, las calles de Caracas se vac\u00edan: as\u00ed cambi\u00f3 la rutina nocturna de los venezolanos tras el ataque de EE.UU - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-07T18:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Apenas cae el sol, las calles de Caracas se vac\u00edan: as\u00ed cambi\u00f3 la rutina nocturna de los venezolanos tras el ataque de EE.UU"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Apenas cae el sol, las calles de Caracas se vac\u00edan: as\u00ed cambi\u00f3 la rutina nocturna de los venezolanos tras el ataque de EE.UU","url":"http:\/\/noticiasya.com\/laredo\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/01\/07\/caracas-noche-calle-seguridad-maduro-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-07T18:03:48Z","datePublished":"2026-01-07T18:03:48Z","dateModified":"2026-01-07T18:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Apenas cae el sol, las calles de Caracas se vac\\u00edan: as\\u00ed cambi\\u00f3 la rutina nocturna de los venezolanos tras el ataque de EE.UU\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/07\\\/caracas-noche-calle-seguridad-maduro-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/07\\\/caracas-noche-calle-seguridad-maduro-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-07T18:03:48Z\",\"datePublished\":\"2026-01-07T18:03:48Z\",\"dateModified\":\"2026-01-07T18:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469843,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/06\/caracas-venezolanos-normalidad-temor-represion-orix\/","url_meta":{"origin":1469871,"position":0},"title":"D\u00edas despu\u00e9s del ataque de EE.UU., venezolanos se debaten entre el nerviosismo, el miedo a la represi\u00f3n y la normalidad","author":"","date":"enero 6, 2026","format":false,"excerpt":"Los venezolanos buscan recuperar cierta normalidad tras la captura del presidente Nicol\u00e1s Maduro por parte de Estados Unidos, mientras las autoridades del pa\u00eds reprimen cualquier muestra de apoyo al derrocamiento del l\u00edder.El lunes, cuando Delcy Rodr\u00edguez asumi\u00f3 como presidenta encargada de Venezuela, grupos de derechos humanos advirtieron sobre una creciente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466165,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/04\/venezolanos-calma-esperanza-tension-eeuu-orix\/","url_meta":{"origin":1469871,"position":1},"title":"En medio de las tensiones con EE.UU., los venezolanos mantienen la calma y siguen adelante mientras susurran esperanzas","author":"","date":"septiembre 4, 2025","format":false,"excerpt":"El trabajo comienza temprano para los pescadores de Chichiriviche de la Costa, un remoto pueblo en la costa caribe\u00f1a de Venezuela, a unas dos horas de carretera sin asfaltar desde la capital, Caracas.El jueves, Eduard Ulloa, de 47 a\u00f1os, lleg\u00f3 a la orilla antes de las seis de la ma\u00f1ana,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465812,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/24\/venezolanos-caracas-unirse-milicia-trax\/","url_meta":{"origin":1469871,"position":2},"title":"Venezolanos se re\u00fanen en Caracas para unirse a la milicia tras el llamado de Maduro a movilizarse ante amenazas de EE.UU.","author":"","date":"agosto 24, 2025","format":false,"excerpt":"Multitudes se convocaron Caracas el s\u00e1bado para inscribirse en la milicia venezolana despu\u00e9s de que el presidente Nicol\u00e1s Maduro hiciera un llamado a reforzar la defensa ante amenazas de Estados Unidos.CNN observ\u00f3 a los inscritos formar largas filas en la Plaza Bol\u00edvar, ubicada en el coraz\u00f3n de Caracas, para entregar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468845,"url":"https:\/\/noticiasya.com\/laredo\/2025\/11\/30\/acusan-homicidio-ataques-caribe-trax\/","url_meta":{"origin":1469871,"position":3},"title":"Venezuela acusa a EE.UU. de &#171;homicidio&#187; tras reconocer que ciudadanos murieron en ataques en el Caribe","author":"","date":"noviembre 30, 2025","format":false,"excerpt":"Venezuela acus\u00f3 a EE.UU. de \u201chomicidio\u201d, despu\u00e9s de reconocer p\u00fablicamente por primera vez que algunos de sus ciudadanos se encontraban entre los muertos por ataques estadounidenses contra supuestas embarcaciones de drogas en el Caribe.\u201cNo hay una guerra declarada [entre EE.UU. y Venezuela], por lo tanto, esto no puede clasificarse como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468409,"url":"https:\/\/noticiasya.com\/laredo\/2025\/11\/16\/venezolanos-deportados-eeuu-avion-caracas-trax\/","url_meta":{"origin":1469871,"position":4},"title":"M\u00e1s de 290 venezolanos deportados de EE.UU. llegaron a Caracas en vuelo de repatriaci\u00f3n","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"Un vuelo con 298 ciudadanos venezolanos que fueron deportados de Estados Unidos lleg\u00f3 a Caracas el viernes, inform\u00f3 el Ministerio del Interior, Justicia y Paz de Venezuela.A su llegada desde El Paso al Aeropuerto Internacional de Maiquet\u00eda Sim\u00f3n Bol\u00edvar, los deportados fueron recibidos por autoridades de seguridad ciudadana que siguieron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470164,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/16\/venezolanos-reunion-trump-machado-celebracion-dudas-orix\/","url_meta":{"origin":1469871,"position":5},"title":"Dentro y fuera del pa\u00eds, muchos venezolanos celebran la reuni\u00f3n Machado-Trump. Otros tienen dudas: &#171;Necesitamos ver cambios&#187;","author":"","date":"enero 16, 2026","format":false,"excerpt":"Sonriente y entre muestras de afecto de algunos simpatizantes que la esperaban en Washington, la l\u00edder opositora venezolana Mar\u00eda Corina Machado asegur\u00f3 que ten\u00eda el apoyo del presidente de Estados Unidos, Donald Trump, despu\u00e9s de la reuni\u00f3n que mantuvieron el jueves en la Casa Blanca.\u201cSepan que contamos con el presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1469871"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469871\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1469871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1469871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1469871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}