{"id":1469908,"date":"2026-01-08T15:03:45","date_gmt":"2026-01-08T23:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/"},"modified":"2026-01-08T15:03:45","modified_gmt":"2026-01-08T23:03:45","slug":"quien-son-presos-politicos-liberados-venezuela-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/","title":{"rendered":"Qui\u00e9n es qui\u00e9n entre los presos pol\u00edticos liberados en Venezuela"},"content":{"rendered":"<p>El Gobierno de la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, anunci\u00f3 este jueves la <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/08\/venezuela\/liberara-numero-importante-presos-politicos-venezolanos-extranjeros-asamblea-nacional-orix\">excarcelaci\u00f3n de \u201cun n\u00famero importante\u201d de presos pol\u00edticos<\/a>, tanto venezolanos como extranjeros, cinco d\u00edas despu\u00e9s de la captura de Nicol\u00e1s Maduro y su esposa, Cilia Flores, en un operativo militar de Estados Unidos.<\/p>\n<p>El anuncio lo hizo el presidente de la Asamblea Nacional de Venezuela, Jorge Rodr\u00edguez, y lo describi\u00f3 como una medida dirigida a \u201ccolaborar en el esfuerzo\u201d de la \u201cuni\u00f3n nacional\u201d en el pa\u00eds. Aunque no especific\u00f3 cu\u00e1ntos ni exactamente qui\u00e9nes ser\u00edan liberados.<\/p>\n<p>\u201cEl Gobierno bolivariano ha decidido la puesta en libertad de un n\u00famero importante de personas venezolanas y extranjeras, y estos procesos de excarcelaci\u00f3n est\u00e1n ocurriendo desde este mismo momento\u201d, coment\u00f3 Rodr\u00edguez en un mensaje en video transmitido por el canal p\u00fablico TeleSur.<\/p>\n<p>La ONG Foro Penal contabilizaba que hab\u00eda 806 presos pol\u00edticos en las c\u00e1rceles venezolanas <a href=\"https:\/\/foropenal.com\/\">hasta el 5 de enero de 2026<\/a>; entre ellos extranjeros o con doble nacionalidad.<\/p>\n<p>Tras la operaci\u00f3n militar en la que fuerzas estadounidenses capturaron al presidente de Venezuela, Nicol\u00e1s Maduro, y lo llevaron a Nueva York para ser juzgado por presunto narcotr\u00e1fico \u2014cargos que Maduro rechaza\u2014 funcionarios de Estados Unidos han solicitado al gobierno encargado, entre otras cosas, la liberaci\u00f3n de los presos pol\u00edticos, <a href=\"https:\/\/www.cnn.com\/2026\/01\/08\/americas\/venezuela-to-release-prisoners-in-peace-gesture-latam-intl\">seg\u00fan una fuente cercana a un informe del Gobierno de Donald Trump presentado esta semana a legisladores.<\/a><\/p>\n<p>Los primeros excarcelados confirmados en Venezuela son cinco ciudadanos espa\u00f1oles, al menos tres de los cuales hab\u00edan sido detenidos tras la crisis poselectoral de 2024. El ministro de Asuntos Exteriores espa\u00f1ol, Jos\u00e9 Manuel Albares, confirm\u00f3 en su cuenta de X que los cinco ya estaba volando de vuelta a Espa\u00f1a.<\/p>\n<p>\u201cVuelan ya hacia Espa\u00f1a los 5 compatriotas liberados hoy en Venezuela. Pronto estar\u00e1n en casa con sus seres queridos. He hablado con ellos para transmitirles mi alegr\u00eda por su liberaci\u00f3n\u201d, dijo Albares.<\/p>\n<p>A continuaci\u00f3n, un breve perfil de los presos pol\u00edticos cuya liberaci\u00f3n ha sido confirmada.<\/p>\n<p>Roc\u00edo del Carmen San Miguel Sosa es una abogada venezolana-espa\u00f1ola de 58 a\u00f1os, especialista en Derecho y Pol\u00edtica Internacional y mag\u00edster del IAEDEN. Es una<a href=\"https:\/\/cnnespanol.cnn.com\/2024\/02\/14\/rocio-san-miguel-activista-detenida-venezuela-orix\"> reconocida analista <\/a>en temas de seguridad, defensa y derechos humanos en Venezuela.<\/p>\n<p>Hasta el momento de su detenci\u00f3n, se desempe\u00f1aba como presidenta de la asociaci\u00f3n civil Control Ciudadano, dedicada al seguimiento de la Fuerza Armada Nacional Bolivariana. Ocup\u00f3 cargos en distintos organismos del Estado y fue docente en instituciones militares. En 2018, un caso suyo ante la Corte Interamericana de Derechos Humanos sent\u00f3 jurisprudencia sobre derechos humanos y participaci\u00f3n pol\u00edtica.<\/p>\n<p>San Miguel hab\u00eda sido detenida en febrero de 2024 acusada de presunta conspiraci\u00f3n \u2014cargo rechazado por su defensa\u2014, y ahora liberada tras permanecer recluida en el Helicoide. Funcionarios de Estados Unidos hab\u00edan <a href=\"https:\/\/www.cnn.com\/2024\/02\/13\/americas\/white-bracelet-venezuela-arrest-rocio-san-miguel-intl\">expresado su preocupaci\u00f3n por su caso.<\/a><\/p>\n<p>Andr\u00e9s Mart\u00ednez y Jos\u00e9 Mar\u00eda Basoa, ambos nacidos en el Pa\u00eds Vasco, al norte de Espa\u00f1a, fueron detenidos en septiembre de 2024 en Puerto Ayacucho, estado Amazonas,<a href=\"https:\/\/foropenal.com\/wp-content\/uploads\/2025\/03\/EXTRANJEROS-1_compressed-1.pdf\"> seg\u00fan la organizaci\u00f3n Foro Penal.<\/a><\/p>\n<p>Mart\u00ednez y Basoa fueron acusados por el Gobierno de Venezuela de estar <a href=\"https:\/\/pre.efe.com\/mundo\/2024-09-14\/venezuela-espanoles-supuesto-plan-contra-maduro\/\">implicados <\/a>en una supuesta operaci\u00f3n que, seg\u00fan el ministro del Interior, Diosdado Cabello, ten\u00eda como objetivo llevar a cabo actos \u201cterroristas\u201d. Entre ellos llevar a Venezuela \u201cun grupo de mercenarios\u201d para asesinar al presidente Nicol\u00e1s Maduro, y de tener v\u00ednculos con el Centro Nacional de Inteligencia (CNI), lo que fue desmentido por el Gobierno de Espa\u00f1a,<a href=\"https:\/\/foropenal.com\/reporte-especial-sobre-presos-politicos-con-nacionalidad-extranjera-en-venezuela\/\"> seg\u00fan Foto Penal.<\/a><\/p>\n<p>Los j\u00f3venes espa\u00f1oles, de 32 y 35 a\u00f1os al momento de ser detenidos, viajaban de vacaciones por Sudam\u00e9rica desde finales de agosto de 2024 y fueron vistos por \u00faltima vez el 2 de septiembre en In\u00edrida, Colombia, rumbo a Puerto Ayacucho, Venezuela, antes de ser detenidos por las autoridades venezolanas, seg\u00fan Foro Penal. Su familia denunci\u00f3 su desaparici\u00f3n.<\/p>\n<p>Su arresto se <a href=\"https:\/\/pre.efe.com\/mundo\/2024-09-14\/venezuela-espanoles-supuesto-plan-contra-maduro\/\">produjo <\/a>en un contexto de creciente tensi\u00f3n entre Venezuela y Espa\u00f1a, tras la llegada a Madrid del l\u00edder opositor Edmundo Gonz\u00e1lez Urrutia, luego de que la oposici\u00f3n denunciara fraude electoral y afirmara que \u00e9l hab\u00eda resultado vencedor en los comicios.<\/p>\n<p>Miguel Moreno Dapena, de 34 a\u00f1os, es un periodista de las Islas Canarias que fue <a href=\"https:\/\/efe.com\/canarias\/2026-01-08\/venezuela-libera-al-periodista-canario-miguel-moreno\/\">detenido <\/a>en junio de 2025 cuando la Armada de Venezuela intercept\u00f3 el barco de exploraci\u00f3n marina N35, en el que viajaba y trabajaba buscando pecios de barcos hundidos de la Segunda Guerra Mundial.<\/p>\n<p>Las autoridades venezolanas sostuvieron que la embarcaci\u00f3n mostraba un comportamiento \u201cmuy sospechoso\u201d en la zona econ\u00f3mica exclusiva del pa\u00eds, lo que motiv\u00f3 su arresto y posterior detenci\u00f3n en Venezuela.<\/p>\n<p>De acuerdo con la<a href=\"https:\/\/foropenal.com\/cidh-otorga-medidas-cautelares-a-favor-de-nueve-personas-extranjeras-privadas-de-su-libertad-en-venezuela\/\"> Corte Interamericana de Derechos Humanos (CIDH),<\/a> la madre de Moreno Dapena dijo que su hijo le cont\u00f3 durante una breve comunicaci\u00f3n en julio de 2025 que hab\u00eda sido acusados de \u201cterrorismo\u201d e \u201cinvasi\u00f3n de zonas de seguridad de Venezuela\u201d<\/p>\n<p>Moreno, que pas\u00f3 m\u00e1s de 200 d\u00edas detenido en el pa\u00eds sudamericano, trabaj\u00f3 en medios como La Provincia, Expansi\u00f3n y Sport antes de cerrar su etapa como periodista.<\/p>\n<p>Ernesto Gorbe Cardona es un valenciano de 52 a\u00f1os. CNN est\u00e1 intentando obtener m\u00e1s informaci\u00f3n sobre su caso.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, anunci\u00f3 este jueves la excarcelaci\u00f3n de \u201cun n\u00famero importante\u201d de presos pol\u00edticos, tanto venezolanos como extranjeros, cinco d\u00edas despu\u00e9s de la captura de Nicol\u00e1s Maduro y su esposa, Cilia Flores, en un operativo militar de Estados Unidos. El anuncio lo hizo el presidente de la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1469908","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qui\u00e9n es qui\u00e9n entre los presos pol\u00edticos liberados en Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qui\u00e9n es qui\u00e9n entre los presos pol\u00edticos liberados en Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno de la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, anunci\u00f3 este jueves la excarcelaci\u00f3n de \u201cun n\u00famero importante\u201d de presos pol\u00edticos, tanto venezolanos como extranjeros, cinco d\u00edas despu\u00e9s de la captura de Nicol\u00e1s Maduro y su esposa, Cilia Flores, en un operativo militar de Estados Unidos. El anuncio lo hizo el presidente de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-08T23:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Qui\u00e9n es qui\u00e9n entre los presos pol\u00edticos liberados en Venezuela\",\"datePublished\":\"2026-01-08T23:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/\"},\"wordCount\":932,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/\",\"name\":\"Qui\u00e9n es qui\u00e9n entre los presos pol\u00edticos liberados en Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-08T23:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qui\u00e9n es qui\u00e9n entre los presos pol\u00edticos liberados en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qui\u00e9n es qui\u00e9n entre los presos pol\u00edticos liberados en Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Qui\u00e9n es qui\u00e9n entre los presos pol\u00edticos liberados en Venezuela - Noticias","og_description":"El Gobierno de la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, anunci\u00f3 este jueves la excarcelaci\u00f3n de \u201cun n\u00famero importante\u201d de presos pol\u00edticos, tanto venezolanos como extranjeros, cinco d\u00edas despu\u00e9s de la captura de Nicol\u00e1s Maduro y su esposa, Cilia Flores, en un operativo militar de Estados Unidos. El anuncio lo hizo el presidente de la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/","og_site_name":"Noticias","article_published_time":"2026-01-08T23:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/"},"author":{"name":"","@id":""},"headline":"Qui\u00e9n es qui\u00e9n entre los presos pol\u00edticos liberados en Venezuela","datePublished":"2026-01-08T23:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/"},"wordCount":932,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/","url":"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/","name":"Qui\u00e9n es qui\u00e9n entre los presos pol\u00edticos liberados en Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-08T23:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Qui\u00e9n es qui\u00e9n entre los presos pol\u00edticos liberados en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Qui\u00e9n es qui\u00e9n entre los presos pol\u00edticos liberados en Venezuela","url":"http:\/\/noticiasya.com\/laredo\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/01\/08\/quien-son-presos-politicos-liberados-venezuela-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-08T23:03:45Z","datePublished":"2026-01-08T23:03:45Z","dateModified":"2026-01-08T23:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Qui\\u00e9n es qui\\u00e9n entre los presos pol\\u00edticos liberados en Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/08\\\/quien-son-presos-politicos-liberados-venezuela-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/08\\\/quien-son-presos-politicos-liberados-venezuela-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-08T23:03:45Z\",\"datePublished\":\"2026-01-08T23:03:45Z\",\"dateModified\":\"2026-01-08T23:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469903,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/08\/liberara-numero-importante-presos-politicos-venezolanos-extranjeros-asamblea-nacional-orix\/","url_meta":{"origin":1469908,"position":0},"title":"Venezuela liberar\u00e1 a &#171;un n\u00famero importante&#187; de presos pol\u00edticos venezolanos y extranjeros, dice la Asamblea Nacional","author":"","date":"enero 8, 2026","format":false,"excerpt":"Jorge Rodr\u00edguez, presidente de la Asamblea Nacional de Venezuela, dijo este jueves que el Gobierno del pa\u00eds decidi\u00f3 poner en libertad a \u201cun n\u00famero importante\u201d de presos pol\u00edticos, tanto venezolanos como extranjeros, con el fin de \u201ccolaborar en el esfuerzo\u201d de la \u201cuni\u00f3n nacional\u201d.\u201cEl Gobierno bolivariano ha decidido la puesta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470463,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/25\/nuevas-excarcelaciones-presos-politicos-orix\/","url_meta":{"origin":1469908,"position":1},"title":"Foro Penal reporta al menos 80 nuevas excarcelaciones de presos pol\u00edticos en Venezuela","author":"","date":"enero 25, 2026","format":false,"excerpt":"La organizaci\u00f3n no gubernamental Foro Penal dijo que al menos 80 presos pol\u00edticos fueron liberados este domingo en Venezuela, mientras trabaja por confirmar las identidades de los involucrados.\u201cAl menos 80 presos pol\u00edticos que estamos verificando han sido excarcelados el d\u00eda de hoy en todo el pa\u00eds. Probablemente se producen m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469960,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/10\/confirman-excarcelados-presos-politicos-venezuela-orix\/","url_meta":{"origin":1469908,"position":2},"title":"Confirman otros tres excarcelados y ya son doce los detenidos pol\u00edticos que dejaron la prisi\u00f3n en Venezuela","author":"","date":"enero 10, 2026","format":false,"excerpt":"El director presidente de la organizaci\u00f3n sin fines de lucro Foro Penal, Alfredo Romero, dijo este s\u00e1bado que hasta ahora han confirmado la excarcelaci\u00f3n de doce presos pol\u00edticos desde el anuncio del jueves por parte del presidente de la Asamblea Nacional, Jorge Rodr\u00edguez, quien asegur\u00f3 que Venezuela liberar\u00eda \u201cun n\u00famero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470377,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/22\/excarcelacion-presos-politicos-proceso-orix\/","url_meta":{"origin":1469908,"position":3},"title":"Venezuela anunci\u00f3 excarcelaci\u00f3n de &#171;un n\u00famero significativo&#187; de presos pol\u00edticos. \u00bfCu\u00e1ntos han salido?","author":"","date":"enero 22, 2026","format":false,"excerpt":"Pasaron dos semanas desde que el Gobierno de Venezuela anunci\u00f3 un proceso de excarcelaciones \u201csignificativas\u201d en el pa\u00eds, aunque el conteo de las organizaciones locales que verifican el proceso indica que el n\u00famero de presos pol\u00edticos que salieron de prisi\u00f3n desde esa fecha no llega al 15 % del total,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470009,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/12\/excarcelaciones-presos-politicos-repaso-orix\/","url_meta":{"origin":1469908,"position":4},"title":"\u00bfQu\u00e9 sabemos de las excarcelaciones de presos pol\u00edticos en Venezuela?","author":"","date":"enero 12, 2026","format":false,"excerpt":"Desde que el Gobierno de Venezuela anunci\u00f3 la semana pasada que pondr\u00eda en libertad a \u201cun n\u00famero importante\u201d de presos pol\u00edticos, el proceso ha avanzado muy por debajo de las expectativas de cientos de familias que esperan por sus parientes. A su vez, las autoridades no han difundido una lista\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469992,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/11\/excarcelaciones-venezuela-gobierno-reporta-muerte-policia-detenido-orix\/","url_meta":{"origin":1469908,"position":5},"title":"En medio de las excarcelaciones anunciadas por Venezuela, el Gobierno reporta la muerte de un pol\u00edcia detenido","author":"","date":"enero 11, 2026","format":false,"excerpt":"El Ministerio P\u00fablico de Venezuela inform\u00f3 este domingo que el 10 de enero de 2026 muri\u00f3 un ciudadano que se encontraba preso desde el 11 de diciembre de 2025, d\u00edas despu\u00e9s de que el presidente de la Asamblea Nacional anunciara la excarcelaci\u00f3n de \u201cun n\u00famero importante\u201d de detenidos.A trav\u00e9s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1469908"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1469908\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1469908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1469908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1469908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}