{"id":1470170,"date":"2026-01-16T16:04:01","date_gmt":"2026-01-17T00:04:01","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/"},"modified":"2026-01-16T16:04:01","modified_gmt":"2026-01-17T00:04:01","slug":"chatgpt-anuncios-usuarios-conversaciones-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/","title":{"rendered":"ChatGPT informa que mostrar\u00e1 anuncios a los usuarios basados en sus conversaciones"},"content":{"rendered":"<p>ChatGPT pronto podr\u00eda mostrar anuncios de productos que cree que a las personas les gustar\u00eda comprar.<\/p>\n<p>OpenAI<a href=\"https:\/\/openai.com\/index\/our-approach-to-advertising-and-expanding-access\/\"> inform\u00f3 este viernes <\/a>que probar\u00e1 anuncios en su versi\u00f3n gratuita para usuarios adultos registrados en EE.UU. Tambi\u00e9n est\u00e1 lanzando una suscripci\u00f3n \u201cGo\u201d de US $8 al mes que incluye algunas capacidades mejoradas, como mayor memoria y m\u00e1s oportunidades de creaci\u00f3n de im\u00e1genes, un precio inferior al de sus suscripciones \u201cPlus\u201d (US $20\/mes) y Pro (US $200\/mes). Los suscriptores de \u201cGo\u201d tambi\u00e9n ver\u00e1n anuncios, mientras que los clientes de Plus, Pro y de OpenAI para empresas no los tendr\u00e1n.<\/p>\n<p>El CEO de OpenAI, Sam Altman, previamente ha expresado reservas sobre introducir anuncios en ChatGPT. Pero la medida llega mientras OpenAI intenta con urgencia encontrar formas de aumentar sus ingresos para poder costear los US $1,4 billones que se ha comprometido a gastar en infraestructura de IA en los pr\u00f3ximos ocho a\u00f1os. Altman dijo en noviembre que la compa\u00f1\u00eda esperaba terminar 2025 con alrededor de US $20 mil millones en ingresos anuales.<\/p>\n<p>El a\u00f1o pasado, la empresa<a href=\"https:\/\/www.cnn.com\/2025\/10\/14\/tech\/walmart-openai-chatgpt-shopping-partnership\"> lanz\u00f3 una herramienta llamada \u201cInstant Checkout\u201d<\/a> que permite a los usuarios comprar art\u00edculos de minoristas como Walmart y Etsy directamente a trav\u00e9s de ChatGPT. OpenAI tambi\u00e9n introdujo herramientas de salud y aprendizaje, entre otras, ya que busca hacer de ChatGPT una parte m\u00e1s esencial de la vida cotidiana de los usuarios y, potencialmente, darles una raz\u00f3n para actualizar a una suscripci\u00f3n paga.<\/p>\n<p>La publicidad podr\u00eda resultar una estrategia lucrativa para OpenAI, ya que usar la informaci\u00f3n de las conversaciones de las personas con ChatGPT podr\u00eda llevar a anuncios altamente personalizados. Por ejemplo, si un usuario pide ayuda a ChatGPT para planificar un viaje, podr\u00eda mostrar anuncios de hoteles o entretenimiento en la zona.<\/p>\n<p>Como parte de la prueba, los anuncios aparecer\u00e1n en la parte inferior de la respuesta de ChatGPT a la consulta del usuario y estar\u00e1n etiquetados como \u201cpatrocinados\u201d. OpenAI dijo que los anuncios no dictar\u00e1n las respuestas que ChatGPT brinda, y a\u00f1adi\u00f3 que los usuarios \u201cnecesitan confiar en que las respuestas de ChatGPT est\u00e1n impulsadas por lo que es objetivamente \u00fatil\u201d.<\/p>\n<p>La empresa tambi\u00e9n afirm\u00f3 que no vender\u00e1 los datos ni las conversaciones de los usuarios a los anunciantes y que los usuarios podr\u00e1n desactivar la personalizaci\u00f3n de anuncios basada en sus chats. OpenAI no planea publicitar en conversaciones sobre \u201ctemas regulados\u201d, incluyendo salud, salud mental o pol\u00edtica.<\/p>\n<p>\u201cDadas las capacidades de la IA, estamos emocionados de desarrollar con el tiempo nuevas experiencias que la gente encuentre m\u00e1s \u00fatiles y relevantes que cualquier otro anuncio\u201d, dijo OpenAI en una publicaci\u00f3n de blog. \u201cPronto podr\u00edas ver un anuncio y ser capaz de preguntar directamente lo que necesitas para tomar una decisi\u00f3n de compra\u201d.<\/p>\n<p>Altman dijo en una entrevista de 2024 que \u201codia\u201d los anuncios y calific\u00f3 la idea de combinar anuncios con IA como \u201cparticularmente inquietante\u201d, aunque a\u00f1adi\u00f3 que \u201cno digo que OpenAI nunca considerar\u00eda los anuncios\u201d. El a\u00f1o pasado, dijo que no estaba \u201ctotalmente en contra\u201d de a\u00f1adir anuncios a ChatGPT, pero que habr\u00eda que \u201ctener mucho cuidado para hacerlo bien\u201d.<\/p>\n<p>Insertar anuncios en las conversaciones de los chatbots podr\u00eda ser pol\u00e9mico, dadas las conversaciones a veces personales e \u00edntimas de los usuarios. Y la medida aumentar\u00e1 la presi\u00f3n sobre OpenAI para asegurar que no recomiende productos que puedan ser potencialmente peligrosos o da\u00f1inos, especialmente despu\u00e9s de que la empresa se ha <a href=\"https:\/\/www.cnn.com\/2025\/11\/06\/us\/openai-chatgpt-suicide-lawsuit-invs-vis\">enfrentado a demandas<\/a> que alegan que ChatGPT alent\u00f3 a suicidios de usuarios.<\/p>\n<p>OpenAI dijo que no mostrar\u00e1 anuncios a usuarios que se hayan identificado como menores de 18 a\u00f1os o que crea que lo son. (La empresa utiliza IA para estimar la edad de los usuarios seg\u00fan sus conversaciones y h\u00e1bitos de uso).<\/p>\n<p>Es probable que los anuncios sean una parte cada vez mayor de las experiencias con IA de los usuarios en diversas plataformas. En diciembre, Meta comenz\u00f3 a usar informaci\u00f3n de las interacciones de los usuarios con su chatbot de IA para dirigirles anuncios m\u00e1s personalizados.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ChatGPT pronto podr\u00eda mostrar anuncios de productos que cree que a las personas les gustar\u00eda comprar. OpenAI inform\u00f3 este viernes que probar\u00e1 anuncios en su versi\u00f3n gratuita para usuarios adultos registrados en EE.UU. Tambi\u00e9n est\u00e1 lanzando una suscripci\u00f3n \u201cGo\u201d de US $8 al mes que incluye algunas capacidades mejoradas, como mayor memoria y m\u00e1s oportunidades [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470170","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ChatGPT informa que mostrar\u00e1 anuncios a los usuarios basados en sus conversaciones - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ChatGPT informa que mostrar\u00e1 anuncios a los usuarios basados en sus conversaciones - Noticias\" \/>\n<meta property=\"og:description\" content=\"ChatGPT pronto podr\u00eda mostrar anuncios de productos que cree que a las personas les gustar\u00eda comprar. OpenAI inform\u00f3 este viernes que probar\u00e1 anuncios en su versi\u00f3n gratuita para usuarios adultos registrados en EE.UU. Tambi\u00e9n est\u00e1 lanzando una suscripci\u00f3n \u201cGo\u201d de US $8 al mes que incluye algunas capacidades mejoradas, como mayor memoria y m\u00e1s oportunidades [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-17T00:04:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"ChatGPT informa que mostrar\u00e1 anuncios a los usuarios basados en sus conversaciones\",\"datePublished\":\"2026-01-17T00:04:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/\"},\"wordCount\":730,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/\",\"name\":\"ChatGPT informa que mostrar\u00e1 anuncios a los usuarios basados en sus conversaciones - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-17T00:04:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ChatGPT informa que mostrar\u00e1 anuncios a los usuarios basados en sus conversaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ChatGPT informa que mostrar\u00e1 anuncios a los usuarios basados en sus conversaciones - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/","og_locale":"es_ES","og_type":"article","og_title":"ChatGPT informa que mostrar\u00e1 anuncios a los usuarios basados en sus conversaciones - Noticias","og_description":"ChatGPT pronto podr\u00eda mostrar anuncios de productos que cree que a las personas les gustar\u00eda comprar. OpenAI inform\u00f3 este viernes que probar\u00e1 anuncios en su versi\u00f3n gratuita para usuarios adultos registrados en EE.UU. Tambi\u00e9n est\u00e1 lanzando una suscripci\u00f3n \u201cGo\u201d de US $8 al mes que incluye algunas capacidades mejoradas, como mayor memoria y m\u00e1s oportunidades [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-17T00:04:01+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/"},"author":{"name":"","@id":""},"headline":"ChatGPT informa que mostrar\u00e1 anuncios a los usuarios basados en sus conversaciones","datePublished":"2026-01-17T00:04:01+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/"},"wordCount":730,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/","name":"ChatGPT informa que mostrar\u00e1 anuncios a los usuarios basados en sus conversaciones - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-17T00:04:01+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"ChatGPT informa que mostrar\u00e1 anuncios a los usuarios basados en sus conversaciones"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"ChatGPT informa que mostrar\u00e1 anuncios a los usuarios basados en sus conversaciones","url":"http:\/\/noticiasya.com\/laredo\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/01\/16\/chatgpt-anuncios-usuarios-conversaciones-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-17T00:04:01Z","datePublished":"2026-01-17T00:04:01Z","dateModified":"2026-01-17T00:04:01Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"ChatGPT informa que mostrar\\u00e1 anuncios a los usuarios basados en sus conversaciones\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/16\\\/chatgpt-anuncios-usuarios-conversaciones-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/16\\\/chatgpt-anuncios-usuarios-conversaciones-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-17T00:04:01Z\",\"datePublished\":\"2026-01-17T00:04:01Z\",\"dateModified\":\"2026-01-17T00:04:01Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1464634,"url":"https:\/\/noticiasya.com\/laredo\/2025\/07\/17\/chatgpt-actualizacion-openai-trax\/","url_meta":{"origin":1470170,"position":0},"title":"ChatGPT ahora puede &#171;pensar&#187; y &#171;actuar&#187; por ti tras una nueva actualizaci\u00f3n","author":"","date":"julio 17, 2025","format":false,"excerpt":"OpenAI anunci\u00f3 el jueves una nueva funci\u00f3n para ChatGPT que permite al popular chatbot ejecutar acciones en nombre del usuario. Esto forma parte de un esfuerzo de toda la industria para cambiar la forma en que las personas hacen las cosas en internet: los gigantes tecnol\u00f3gicos esperan que, en lugar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449484,"url":"https:\/\/noticiasya.com\/laredo\/2024\/05\/15\/openai-modelo-inteligencia-artificial-gpt-4o-trax\/","url_meta":{"origin":1470170,"position":1},"title":"OpenAI presenta su nuevo modelo de Inteligencia Artificial, GPT-4o","author":"","date":"mayo 15, 2024","format":false,"excerpt":"Nueva York (CNN) -- OpenAI anunci\u00f3 este lunes su \u00faltimo modelo de lenguaje de gran inteligencia artificial que, seg\u00fan afirma, har\u00e1 que ChatGPT sea m\u00e1s inteligente y f\u00e1cil de usar.El nuevo modelo, llamado GPT-4o, es una actualizaci\u00f3n del anterior modelo GPT-4 de la compa\u00f1\u00eda, que se lanz\u00f3 hace poco m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472574,"url":"https:\/\/noticiasya.com\/laredo\/2026\/03\/26\/openai-videos-ia-demasiado-cara-trax\/","url_meta":{"origin":1470170,"position":2},"title":"OpenAI pens\u00f3 que podr\u00eda adue\u00f1arse de los videos de IA. La realidad fue demasiado cara","author":"","date":"marzo 26, 2026","format":false,"excerpt":"Tras seis meses y millones de d\u00f3lares tirados a la basura, OpenAI pone fin a lo que en su d\u00eda denomin\u00f3 \u201cel motor de imaginaci\u00f3n m\u00e1s potente jam\u00e1s construido\u201d.Parece que ha habido dos errores clave en la saga de Sora:OpenAI no comprend\u00eda c\u00f3mo interact\u00faan los consumidores con los videos en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452548,"url":"https:\/\/noticiasya.com\/laredo\/2024\/09\/09\/apple-keynote-presentacion-iphone-16-cupertino-a-que-hora-y-como-ver-vivo-orix\/","url_meta":{"origin":1470170,"position":3},"title":"Apple Keynote de presentaci\u00f3n del iPhone 16: qu\u00e9 esperar, a qu\u00e9 hora y c\u00f3mo ver en vivo","author":"","date":"septiembre 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Apple llevar\u00e1 a cabo su pr\u00f3ximo gran evento, en el que se espera el lanzamiento del iPhone 16 y otra novedades, este lunes 9 de septiembre. El lema en esta ocasi\u00f3n ser\u00e1 \"It's Glowtime\".Aunque es una tradici\u00f3n que Apple realice una conferencia para presentar nuevas tecnolog\u00edas e\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466090,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/02\/chatgpt-controles-parentales-proximo-mes-trax\/","url_meta":{"origin":1470170,"position":4},"title":"OpenAI dice que ChatGPT tendr\u00e1 controles parentales &#171;en el pr\u00f3ximo mes&#187;","author":"","date":"septiembre 2, 2025","format":false,"excerpt":"La empresa matriz de ChatGPT, OpenAI, anunci\u00f3 que planea lanzar controles parentales para su popular asistente de inteligencia artificial \u201cen el pr\u00f3ximo mes\u201d, tras denuncias de que este y otros chatbots habr\u00edan contribuido a casos de autolesiones o suicidios entre adolescentes.Los controles incluir\u00e1n la opci\u00f3n de que los padres vinculen\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465896,"url":"https:\/\/noticiasya.com\/laredo\/2025\/08\/27\/openai-chatgpt-demanda-suicidio-adolescente-trax\/","url_meta":{"origin":1470170,"position":5},"title":"Padres de un joven de 16 a\u00f1os que se suicid\u00f3 demandan a OpenAI, alegando que ChatGPT lo orient\u00f3","author":"","date":"agosto 27, 2025","format":false,"excerpt":"Los padres de Adam Raine, de 16 a\u00f1os, demandaron a OpenAI y al CEO, Sam Altman, alegando que ChatGPT contribuy\u00f3 al suicidio de su hijo, incluso aconsej\u00e1ndole sobre m\u00e9todos y ofreci\u00e9ndose a escribir el primer borrador de su nota de suicidio.En poco m\u00e1s de seis meses que utiliz\u00f3 ChatGPT, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1470170"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470170\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1470170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1470170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1470170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}