{"id":1470173,"date":"2026-01-16T18:03:43","date_gmt":"2026-01-17T02:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/"},"modified":"2026-01-16T18:03:43","modified_gmt":"2026-01-17T02:03:43","slug":"rechazan-trump-afirmo-tylenol-estudios-autismo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/","title":{"rendered":"Muchas mujeres y m\u00e9dicos rechazan lo que Trump afirm\u00f3 sobre el Tylenol, mientras estudios descartan un v\u00ednculo con el autismo"},"content":{"rendered":"<p>Cuando el presidente de EE.UU., Donald Trump, afirm\u00f3 el a\u00f1o pasado que tomar <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/22\/eeuu\/trump-relacion-autismo-tylenol-acetaminofen-paracetamol-trax\">Tylenol durante el embarazo puede estar relacionado con un mayor riesgo de autismo<\/a>, la consulta del ginecobstetra Nathaniel DeNicola recibi\u00f3 una oleada de preguntas y confusi\u00f3n, pero solo durante unos d\u00edas.<\/p>\n<p>\u201cLuego, despu\u00e9s de una semana, el tema dej\u00f3 de ser relevante\u201d, dijo DeNicola, radicado en Newport Beach, California, quien ayud\u00f3 a redactar las gu\u00edas del <a href=\"https:\/\/www.acog.org\/clinical\/clinical-guidance\/practice-advisory\/articles\/2025\/09\/acetaminophen-use-in-pregnancy-and-neurodevelopmental-outcomes\">Colegio Estadounidense de Obstetras y Ginec\u00f3logos<\/a> sobre el uso de paracetamol en el embarazo.<\/p>\n<p>En ese momento, la comunidad m\u00e9dica cient\u00edfica \u201cfue tan r\u00e1pida en su respuesta y tan contundente en su afirmaci\u00f3n sobre la utilidad y seguridad del Tylenol durante el embarazo seg\u00fan sea necesario, que no creo que haya habido confusi\u00f3n duradera, al menos entre quienes escuchan a los expertos m\u00e9dicos\u201d, dijo DeNicola.<\/p>\n<p>\u201cCreo que las pacientes, correctamente, acuden a sus m\u00e9dicos\u201d, agreg\u00f3. \u201cEl p\u00fablico parece haber seguido la orientaci\u00f3n de los expertos, confiando en su voz al respecto\u201d.<\/p>\n<p>La m\u00e9dica especialista en medicina materno-fetal de Chicago, Lynn Yee, dijo que menos de sus pacientes parecen preocupadas ahora por el Tylenol que en el oto\u00f1o.<\/p>\n<p>\u201cEn septiembre, octubre y noviembre, hubo bastante preocupaci\u00f3n y atenci\u00f3n p\u00fablica sobre este tema, y ahora, en enero, siento que la situaci\u00f3n est\u00e1 cambiando y que tengo menos pacientes pregunt\u00e1ndome sobre Tylenol o paracetamol\u201d, dijo Yee, jefa de medicina materno-fetal en el Departamento de Obstetricia y Ginecolog\u00eda de la Facultad de Medicina Feinberg de la Universidad Northwestern.<\/p>\n<p>\u201cRealmente me siento orgullosa de nuestras organizaciones profesionales como el Colegio Estadounidense de Obstetras y Ginec\u00f3logos y la Sociedad de Medicina Materno-Fetal. Han hecho mucho trabajo de concienciaci\u00f3n sobre la seguridad del paracetamol y el \u2018consulte a su m\u00e9dico\u2019\u201d, dijo. \u201cTodas estas organizaciones confiables han hecho un trabajo encomiable para difundir los mensajes correctos, y quiz\u00e1 est\u00e9 funcionando\u201d.<\/p>\n<p>Los expertos insisten en que el autismo tiene muchas <a href=\"https:\/\/www.niehs.nih.gov\/health\/topics\/conditions\/autism\">causas potenciales<\/a> \u2014incluyendo la gen\u00e9tica, la edad avanzada de los padres y la exposici\u00f3n prenatal a la contaminaci\u00f3n del aire o ciertos pesticidas\u2014 y que la ciencia que lo vincula con el paracetamol est\u00e1 lejos de estar resuelta.<\/p>\n<p>En una gu\u00eda publicada luego de las afirmaciones de Trump en septiembre, el Colegio Estadounidense de Obstetras y Ginec\u00f3logos reafirm\u00f3 que \u201cel paracetamol sigue siendo el analg\u00e9sico y antipir\u00e9tico de elecci\u00f3n durante el embarazo. El uso juicioso de la dosis m\u00e1s baja efectiva durante el periodo m\u00e1s corto necesario, en consulta con un obstetra-ginec\u00f3logo u otro profesional del cuidado obst\u00e9trico, sigue siendo consistente con la mejor pr\u00e1ctica\u201d.<\/p>\n<p>El paracetamol, tambi\u00e9n conocido como acetaminof\u00e9n y vendido bajo la marca Tylenol, es ampliamente considerado como la \u00fanica opci\u00f3n segura de venta libre para tratar el dolor o la fiebre durante el embarazo. Otros medicamentos comunes, como el<a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Furldefense.com%2Fv3%2F__https%3A%2F%2Fwww.ncbi.nlm.nih.gov%2Fbooks%2FNBK582759%2F__%3B!!Dq0X2DkFhyF93HkjWTBQKhk!TBk4QjdVPn6_OnGtJz0Nge9INaAOrTVhWaieOuwb0Vt-ubO_pj2_WK8Vj5IkK4U4b0y5l1zWgLWdAUL-AV764jzZASg9h1Wm%24&#038;data=05%7C02%7Cjacqueline.howard%40cnn.com%7Cb349c5040e89417b19c608de5477e74a%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C639041071156900127%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=7sjplo6p06wtI%2F679UUSEPSabCo65EBWYpKKGpCJwJs%3D&#038;reserved=0\"> ibuprofeno<\/a> o la <a href=\"https:\/\/nam11.safelinks.protection.outlook.com\/?url=https%3A%2F%2Furldefense.com%2Fv3%2F__https%3A%2F%2Fwww.mayoclinic.org%2Fhealthy-lifestyle%2Fpregnancy-week-by-week%2Fexpert-answers%2Faspirin-during-pregnancy%2Ffaq-20058167__%3B!!Dq0X2DkFhyF93HkjWTBQKhk!TBk4QjdVPn6_OnGtJz0Nge9INaAOrTVhWaieOuwb0Vt-ubO_pj2_WK8Vj5IkK4U4b0y5l1zWgLWdAUL-AV764jzZARJwKQNS%24&#038;data=05%7C02%7Cjacqueline.howard%40cnn.com%7Cb349c5040e89417b19c608de5477e74a%7C0eb48825e8714459bc72d0ecd68f1f39%7C0%7C0%7C639041071156926301%7CUnknown%7CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%3D%3D%7C0%7C%7C%7C&#038;sdata=xw%2B%2FiOOfrzSJUFvY%2FFPRpAQD1EtWdDfVOoccb0QOuaI%3D&#038;reserved=0\">aspirina en dosis regular<\/a>, pueden aumentar el riesgo de complicaciones graves en el embarazo.<\/p>\n<p>En muchos casos, los m\u00e9dicos pueden recomendar Tylenol para tratar el dolor o la fiebre. Dejar una fiebre sin tratar puede ser peligroso tanto para el feto como para la madre, advierten los expertos, aumentando el riesgo de aborto espont\u00e1neo, defectos cong\u00e9nitos, hipertensi\u00f3n y trastornos del neurodesarrollo.<\/p>\n<p>\u201cLas fiebres no tratadas pueden tener impactos a corto y largo plazo en el neurodesarrollo fetal\u201d, dijo Yee. \u201cEs realmente importante tratar la fiebre, porque sabemos que una fiebre no tratada durante el embarazo es perjudicial tanto para la madre como para el beb\u00e9. \u2026 Y no tenemos mejores alternativas seguras para reducir la fiebre durante el embarazo\u201d.<\/p>\n<p>Se estima que alrededor del <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/25369643\/\">65 % de las mujeres embarazadas<\/a> usan paracetamol en alg\u00fan momento del embarazo.<\/p>\n<p>La Casa Blanca public\u00f3 una <a href=\"https:\/\/www.whitehouse.gov\/articles\/2025\/09\/fact-evidence-suggests-link-between-acetaminophen-autism\/\">hoja informativa en septiembre<\/a> en la que hac\u00eda referencia a varios estudios que suger\u00edan que el uso de paracetamol durante el embarazo, especialmente en etapas tard\u00edas, puede causar efectos neurol\u00f3gicos a largo plazo en los ni\u00f1os, como autismo o trastorno por d\u00e9ficit de atenci\u00f3n e hiperactividad (TDAH).<\/p>\n<p>En ese momento, la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. <a href=\"https:\/\/www.fda.gov\/media\/188843\/download?attachment\">emiti\u00f3 una carta a los m\u00e9dicos <\/a>indicando que \u201clos profesionales de la salud deber\u00edan considerar minimizar el uso de paracetamol durante el embarazo para fiebres leves de rutina\u201d y que en los \u00faltimos a\u00f1os, \u201cse ha acumulado evidencia que sugiere que el uso de paracetamol por mujeres embarazadas podr\u00eda estar asociado con un mayor riesgo de trastornos neurol\u00f3gicos como autismo y TDAH en los ni\u00f1os\u201d.<\/p>\n<p>Uno de los art\u00edculos a los que hizo referencia el Gobierno de Trump fue un an\u00e1lisis de 46 estudios previos. Esa revisi\u00f3n, publicada en agosto en la revista <a href=\"https:\/\/link.springer.com\/article\/10.1186\/s12940-025-01208-0\">BMC Environmental Health<\/a>, encontr\u00f3 evidencia de un v\u00ednculo entre la exposici\u00f3n al paracetamol durante el embarazo y una mayor incidencia de trastornos del neurodesarrollo.<\/p>\n<p>\u201cEsta asociaci\u00f3n es m\u00e1s fuerte cuando el paracetamol se toma durante cuatro semanas o m\u00e1s\u201d, dijo la autora principal del estudio, <a href=\"https:\/\/hsph.harvard.edu\/profile\/andrea-baccarelli\/\">Andrea Baccarelli<\/a>, decana de la Facultad de Salud P\u00fablica T.H. Chan de Harvard y profesora de salud ambiental, en un comunicado en septiembre.<\/p>\n<p><a href=\"https:\/\/hsph.harvard.edu\/news\/using-acetaminophen-during-pregnancy-may-increase-childrens-autism-and-adhd-risk\/\">Baccarelli dijo que hab\u00eda discutido su investigaci\u00f3n<\/a> con el secretario de Salud y Servicios Humanos de EE.UU., Robert F. Kennedy Jr., en las semanas previas al anuncio de la Casa Blanca.<\/p>\n<p>\u201cAl mismo tiempo, como el \u00fanico medicamento aprobado para la reducci\u00f3n del dolor y la fiebre durante el embarazo, el paracetamol sigue siendo una herramienta importante para las pacientes embarazadas y sus m\u00e9dicos. La fiebre alta puede representar riesgos tanto para la madre como para el feto, incluyendo defectos del tubo neural y parto prematuro\u201d, afirm\u00f3.<\/p>\n<p>\u201cDespu\u00e9s de evaluar la evidencia, mis colegas y yo recomendamos un enfoque equilibrado basado en el principio de precauci\u00f3n: las pacientes que necesiten reducir la fiebre o el dolor durante el embarazo deben tomar la dosis efectiva m\u00e1s baja de paracetamol, durante el menor tiempo posible, tras consultar con su m\u00e9dico sobre su c\u00e1lculo individual de riesgo-beneficio\u201d.<\/p>\n<p>Ahora, nuevas investigaciones est\u00e1n sum\u00e1ndose al debate.<\/p>\n<p>Un art\u00edculo publicado este viernes no encontr\u00f3 indicios de que los ni\u00f1os nacidos de madres que usaron paracetamol durante el embarazo tengan una mayor probabilidad de autismo.<\/p>\n<p>La investigaci\u00f3n, publicada en <a href=\"https:\/\/www.thelancet.com\/journals\/lanogw\/article\/PIIS3050-5038(25)00211-0\/fulltext\">The Lancet Obstetrics, Gynaecology &#038; Women\u2019s Health<\/a>, revis\u00f3 43 estudios publicados sobre la exposici\u00f3n prenatal al paracetamol y posibles v\u00ednculos con el neurodesarrollo infantil, incluyendo datos de m\u00e1s de 300.000 embarazos. De esos estudios, 17 fueron incluidos en un metaan\u00e1lisis.<\/p>\n<p>\u201cExaminamos varios resultados, incluyendo autismo, TDAH y discapacidad intelectual\u201d, dijo la autora principal, Asma Khalil, obstetra consultora y especialista en medicina fetal en el Hospital St. George\u2019s de Londres, en una conferencia de prensa.<\/p>\n<p>Los investigadores no encontraron evidencia de que el uso de paracetamol durante el embarazo aumente el riesgo de autismo, trastorno por d\u00e9ficit de atenci\u00f3n e hiperactividad o discapacidad intelectual entre los ni\u00f1os.<\/p>\n<p>El Departamento de Salud y Servicios Humanos de EE.UU. dijo en un comunicado que el nuevo art\u00edculo no resuelve las dudas sobre los posibles riesgos del Tylenol y que excluye la mayor\u00eda de los estudios sobre el tema.<\/p>\n<p>En respuesta, Khalil dijo en un correo electr\u00f3nico que el art\u00edculo de revisi\u00f3n \u201cno excluye la evidencia\u201d, sino que evalu\u00f3 sistem\u00e1ticamente todos los estudios y dio mayor peso a aquellos \u201cmejor capacitados para abordar los factores de sesgo y confusi\u00f3n\u201d.<\/p>\n<p>\u201cSi bien reconocemos que incluso los efectos peque\u00f1os pueden ser importantes a nivel poblacional, la orientaci\u00f3n de salud p\u00fablica debe basarse en la evidencia m\u00e1s s\u00f3lida disponible, no en se\u00f1ales impulsadas por el sesgo o la confusi\u00f3n por indicaci\u00f3n\u201d, escribi\u00f3. \u201cEsta revisi\u00f3n ofrece tranquilidad en lugar de alarma, y respalda la gu\u00eda cl\u00ednica actual de que el paracetamol sigue siendo el tratamiento de primera l\u00ednea apropiado para el dolor y la fiebre en el embarazo cuando se utiliza seg\u00fan lo recomendado\u201d.<\/p>\n<p>Algunos de los estudios en el nuevo an\u00e1lisis incluyeron datos sobre hermanos, en los cuales la madre podr\u00eda haber usado paracetamol durante el embarazo de uno de los hijos, pero no del otro.<\/p>\n<p>\u201cLos meta-an\u00e1lisis de comparaci\u00f3n entre hermanos representan la principal evidencia, ya que tienen en cuenta factores familiares y gen\u00e9ticos compartidos\u201d, escribieron los investigadores en su art\u00edculo.<\/p>\n<p>Priorizar estos estudios con hermanos fue una fortaleza de la nueva investigaci\u00f3n, dijo Steven Kapp, profesor titular de psicolog\u00eda en la Universidad de Portsmouth que no particip\u00f3 en el nuevo estudio, en una declaraci\u00f3n distribuida por el Science Media Centre, con sede en el Reino Unido.<\/p>\n<p>\u201cSu rigor cient\u00edfico incluy\u00f3 tomar en cuenta factores de confusi\u00f3n como tener un hermano con la condici\u00f3n, ya que estas neurodivergencias son hereditarias. Los padres de ni\u00f1os con discapacidad podr\u00edan tener m\u00e1s probabilidades de tomar paracetamol debido a dolores relacionados con el estr\u00e9s de la crianza o sus propias condiciones cr\u00f3nicas\u201d, dijo Kapp.<\/p>\n<p>\u201cEl control entre hermanos en estos estudios demuestra que el medicamento no causa la discapacidad del hijo. Como investigador y defensor neurodivergente, creo que una implicaci\u00f3n es que la sociedad debe dejar de buscar explicaciones falsas para la prevenci\u00f3n de discapacidades del desarrollo\u201d, afirm\u00f3. \u201cEn cambio, deber\u00edamos centrarnos m\u00e1s en hacer del mundo un lugar mejor para las personas con discapacidad\u201d.<\/p>\n<p>DeNicola, quien tampoco particip\u00f3 en la investigaci\u00f3n, tambi\u00e9n elogi\u00f3 el trabajo, pero a\u00f1adi\u00f3 que \u201chasta la fecha solo ha habido tres estudios con hermanos\u201d, como se indica en el art\u00edculo.<\/p>\n<p>\u201cEntonces, \u00bfresponden tres estudios cualquier pregunta dada? Esa es una limitaci\u00f3n razonable. Siempre querr\u00edas tener m\u00e1s informaci\u00f3n\u201d, dijo. \u201cPero considerando que los tres estudios dicen exactamente lo mismo, realizados con m\u00e9todos superiores, al menos proporciona la tranquilidad hasta la fecha de que debemos usar el beneficio terap\u00e9utico del Tylenol sin ning\u00fan riesgo infundado\u201d.<\/p>\n<p>En su art\u00edculo de agosto, Baccarelli y sus colegas escribieron que \u201clos an\u00e1lisis de comparaci\u00f3n entre hermanos tienen limitaciones significativas que afectan su interpretaci\u00f3n\u201d y que \u201caunque los estudios de comparaci\u00f3n entre hermanos eliminan el impacto de los factores familiares compartidos que act\u00faan como confusores, tambi\u00e9n eliminan posibles mediadores que son compartidos en las familias e interact\u00faan con el paracetamol, lo que potencialmente introduce sesgos\u201d.<\/p>\n<p>Algunos posibles mediadores que pueden agruparse dentro de las familias, se\u00f1alaron, incluyen alteraciones en el sistema hormonal del cuerpo o un aumento del estr\u00e9s oxidativo.<\/p>\n<p>No obstante, Khalil describi\u00f3 la comparaci\u00f3n entre hermanos como uno de los mejores dise\u00f1os de estudio para tener en cuenta los factores compartidos que pueden influir en el riesgo de autismo.<\/p>\n<p>\u201cProbablemente este sea el mejor dise\u00f1o para ayudar a tener en cuenta factores gen\u00e9ticos compartidos o el entorno familiar compartido \u2014que estos dos ni\u00f1os est\u00e1n expuestos al mismo entorno, o a caracter\u00edsticas de crianza a largo plazo, antecedentes socioecon\u00f3micos, antecedentes educativos\u2014 y muchos de los otros estudios incluidos o publicados en la literatura no consideraban completamente esto\u201d, dijo.<\/p>\n<p>Khalil dijo que la nueva investigaci\u00f3n se realiz\u00f3 porque ella y sus colegas se toparon con mujeres embarazadas que estaban preocupadas por la seguridad del paracetamol debido a lo que Trump dijo el a\u00f1o pasado.<\/p>\n<p>Ese temor entre las pacientes en ese momento fue \u201csin duda mi experiencia\u201d, dijo Khalil.<\/p>\n<p>Grupos m\u00e9dicos nacionales e internacionales \u201crespondieron bastante r\u00e1pido emitiendo declaraciones para intentar tranquilizar a las mujeres embarazadas\u201d, record\u00f3. \u201cY dejaron claro el mensaje a las mujeres embarazadas de que es seguro usar paracetamol cuando se necesita, en la dosis adecuada y por la duraci\u00f3n adecuada\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando el presidente de EE.UU., Donald Trump, afirm\u00f3 el a\u00f1o pasado que tomar Tylenol durante el embarazo puede estar relacionado con un mayor riesgo de autismo, la consulta del ginecobstetra Nathaniel DeNicola recibi\u00f3 una oleada de preguntas y confusi\u00f3n, pero solo durante unos d\u00edas. \u201cLuego, despu\u00e9s de una semana, el tema dej\u00f3 de ser relevante\u201d, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470173","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muchas mujeres y m\u00e9dicos rechazan lo que Trump afirm\u00f3 sobre el Tylenol, mientras estudios descartan un v\u00ednculo con el autismo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muchas mujeres y m\u00e9dicos rechazan lo que Trump afirm\u00f3 sobre el Tylenol, mientras estudios descartan un v\u00ednculo con el autismo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cuando el presidente de EE.UU., Donald Trump, afirm\u00f3 el a\u00f1o pasado que tomar Tylenol durante el embarazo puede estar relacionado con un mayor riesgo de autismo, la consulta del ginecobstetra Nathaniel DeNicola recibi\u00f3 una oleada de preguntas y confusi\u00f3n, pero solo durante unos d\u00edas. \u201cLuego, despu\u00e9s de una semana, el tema dej\u00f3 de ser relevante\u201d, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-17T02:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Muchas mujeres y m\u00e9dicos rechazan lo que Trump afirm\u00f3 sobre el Tylenol, mientras estudios descartan un v\u00ednculo con el autismo\",\"datePublished\":\"2026-01-17T02:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/\"},\"wordCount\":2044,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/\",\"name\":\"Muchas mujeres y m\u00e9dicos rechazan lo que Trump afirm\u00f3 sobre el Tylenol, mientras estudios descartan un v\u00ednculo con el autismo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-17T02:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muchas mujeres y m\u00e9dicos rechazan lo que Trump afirm\u00f3 sobre el Tylenol, mientras estudios descartan un v\u00ednculo con el autismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muchas mujeres y m\u00e9dicos rechazan lo que Trump afirm\u00f3 sobre el Tylenol, mientras estudios descartan un v\u00ednculo con el autismo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Muchas mujeres y m\u00e9dicos rechazan lo que Trump afirm\u00f3 sobre el Tylenol, mientras estudios descartan un v\u00ednculo con el autismo - Noticias","og_description":"Cuando el presidente de EE.UU., Donald Trump, afirm\u00f3 el a\u00f1o pasado que tomar Tylenol durante el embarazo puede estar relacionado con un mayor riesgo de autismo, la consulta del ginecobstetra Nathaniel DeNicola recibi\u00f3 una oleada de preguntas y confusi\u00f3n, pero solo durante unos d\u00edas. \u201cLuego, despu\u00e9s de una semana, el tema dej\u00f3 de ser relevante\u201d, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-17T02:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/"},"author":{"name":"","@id":""},"headline":"Muchas mujeres y m\u00e9dicos rechazan lo que Trump afirm\u00f3 sobre el Tylenol, mientras estudios descartan un v\u00ednculo con el autismo","datePublished":"2026-01-17T02:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/"},"wordCount":2044,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/","name":"Muchas mujeres y m\u00e9dicos rechazan lo que Trump afirm\u00f3 sobre el Tylenol, mientras estudios descartan un v\u00ednculo con el autismo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-17T02:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Muchas mujeres y m\u00e9dicos rechazan lo que Trump afirm\u00f3 sobre el Tylenol, mientras estudios descartan un v\u00ednculo con el autismo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Muchas mujeres y m\u00e9dicos rechazan lo que Trump afirm\u00f3 sobre el Tylenol, mientras estudios descartan un v\u00ednculo con el autismo","url":"http:\/\/noticiasya.com\/laredo\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/01\/16\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-17T02:03:43Z","datePublished":"2026-01-17T02:03:43Z","dateModified":"2026-01-17T02:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Muchas mujeres y m\\u00e9dicos rechazan lo que Trump afirm\\u00f3 sobre el Tylenol, mientras estudios descartan un v\\u00ednculo con el autismo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/16\\\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/16\\\/rechazan-trump-afirmo-tylenol-estudios-autismo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-17T02:03:43Z\",\"datePublished\":\"2026-01-17T02:03:43Z\",\"dateModified\":\"2026-01-17T02:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466410,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/12\/tylenol-kennedy-jr-no-vinculo-autismo-trax\/","url_meta":{"origin":1470173,"position":0},"title":"CEO del fabricante de Tylenol dice, en reuni\u00f3n con Kennedy Jr., que no existe un v\u00ednculo claro con el autismo, informa el WSJ","author":"","date":"septiembre 12, 2025","format":false,"excerpt":"El CEO y director de la farmac\u00e9utica Kenvue, fabricante del analg\u00e9sico Tylenol, se reuni\u00f3 en privado esta semana con el secretario del Departamento de Salud y Servicios Humanos de EE.UU. (HHS, por sus siglas en ingl\u00e9s), Robert F. Kennedy Jr., para intentar disuadirlo de incluir el medicamento como posible causa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473181,"url":"https:\/\/noticiasya.com\/laredo\/2026\/04\/14\/tylenol-embarazo-relacion-autismo-estudio-danes-reux\/","url_meta":{"origin":1470173,"position":1},"title":"El Tylenol en el embarazo no est\u00e1 vinculado con el autismo, dice un estudio dan\u00e9s","author":"","date":"abril 14, 2026","format":false,"excerpt":"El uso de Tylenol por parte de mujeres durante el embarazo no se asocia con autismo en sus hijos, seg\u00fan los resultados de un estudio nacional realizado en Dinamarca y publicado este lunes.Entre m\u00e1s de 1,5 millones de ni\u00f1os nacidos entre 1997 y 2022, incluidos 31.098 expuestos al Tylenol en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466702,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/22\/trump-relacion-autismo-tylenol-acetaminofen-paracetamol-trax\/","url_meta":{"origin":1470173,"position":2},"title":"Trump relaciona el autismo con el consumo de paracetamol durante el embarazo, a pesar de la evidencia que demuestra seguridad","author":"","date":"septiembre 22, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump anunci\u00f3 el lunes que la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA, por sus siglas en ingl\u00e9s) notificar\u00e1 a los m\u00e9dicos que el uso de acetaminof\u00e9n (tambi\u00e9n denominado gen\u00e9ricamente como paracetamol) durante el embarazo \u201cpuede estar asociado con un riesgo muy elevado de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467552,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/20\/fabricante-tylenol-rechaza-posible-cambio-etiqueta-trax\/","url_meta":{"origin":1470173,"position":3},"title":"El fabricante de Tylenol rechaza posible cambio de etiqueta que vincule el uso del analg\u00e9sico en el embarazo con el autismo","author":"","date":"octubre 20, 2025","format":false,"excerpt":"Kenvue, la compa\u00f1\u00eda estadounidense que fabrica Tylenol, dice que la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos no deber\u00eda realizar los cambios propuestos en la etiqueta de seguridad del producto para reflejar la investigaci\u00f3n sobre una posible conexi\u00f3n entre su uso en el embarazo y los diagn\u00f3sticos de autismo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466708,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/23\/embarazadas-acetaminofen-tylenol-riesgos-rax\/","url_meta":{"origin":1470173,"position":4},"title":"Lo que las embarazadas deben saber sobre el acetaminof\u00e9n","author":"","date":"septiembre 23, 2025","format":false,"excerpt":"Las mujeres embarazadas no deben tener miedo de tomar Tylenol, afirman los expertos, que refutan la tesis no comprobada de la administraci\u00f3n Trump de que puede causar autismo. En una rueda de prensa este lunes, el presidente Donald Trump repiti\u00f3 una advertencia general: \u201cSi est\u00e1 embarazada, no tome Tylenol. Cuando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466693,"url":"https:\/\/noticiasya.com\/laredo\/2025\/09\/22\/trump-autismo-analgesico-vitaminas-trax\/","url_meta":{"origin":1470173,"position":5},"title":"Trump anticipa &#171;asombroso&#187; anuncio sobre autismo en el que se espera aborde analg\u00e9sico y vitaminas","author":"","date":"septiembre 22, 2025","format":false,"excerpt":"El discurso del presidente de EE.UU., Donald Trump, en el funeral de Charlie Kirk este domingo dio un giro para adelantar un anuncio que planea hacer el lunes desde la Oficina Oval sobre el autismo.\u201cCreo que les parecer\u00e1 asombroso\u201d, dijo. \u201cCreo que encontramos una respuesta al autismo\u201d.Aunque no ofreci\u00f3 detalles,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1470173"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470173\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1470173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1470173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1470173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}