{"id":1470205,"date":"2026-01-18T03:03:40","date_gmt":"2026-01-18T11:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/"},"modified":"2026-01-18T03:03:40","modified_gmt":"2026-01-18T11:03:40","slug":"dunk-egg-knight-seven-kingdoms-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/","title":{"rendered":"Qui\u00e9nes son Ser Duncan el Alto y Egg de &#171;A Knight of the Seven Kingdoms&#187; y c\u00f3mo conecta con &#171;Game of Thrones&#187;"},"content":{"rendered":"<p>\u00bfUna serie de \u201c<a href=\"https:\/\/cnnespanol.cnn.com\/2019\/04\/11\/por-que-es-tan-popular-game-of-thrones-guia-para-quienes-no-la-han-visto#:~:text=Aun%20as%C3%AD%2C%20la%20atenci%C3%B3n%20no,es%20una%20unidad%20de%20WarnerMedia.\">Game of Thrones<\/a>\u201d sin dragones? Cuesta imaginarlo, pero esa es la premisa de la nueva serie del universo fant\u00e1stico creado por el escritor George R. R. Martin, \u201cA Knight of Seven Kingdoms\u201d, que se estrena este domingo en la plataforma HBO Max.<\/p>\n<p>La historia se desarrolla 90 a\u00f1os antes de los acontecimientos vistos en \u201cGame of Thrones\u201d (2011-2019), en una \u00e9poca en la que no quedan dragones vivos en el continente de Westeros tras la guerra por el trono entre integrantes de la familia Targaryen, tal como se cuenta en la serie \u201c<a href=\"https:\/\/cnnespanol.cnn.com\/2022\/08\/20\/en-que-esta-basado-house-of-the-dragon-orix\">House of the Dragon<\/a>\u201d.<\/p>\n<p>La serie, titulada en Latinoam\u00e9rica \u201cEl caballero de los siete reinos\u201d, est\u00e1 basada en la novela corta \u201cThe Hedge Knight\u201d, publicada en 1998 por George R. R. Martin. Esta obra forma parte de una serie de novelas cortas conocida como \u201cTales of Dunk and Egg\u201d, que cuenta con otros dos t\u00edtulos publicados: \u201cThe Sworn Sword\u201d (2003) y \u201cThe Mystery Knight\u201d (2010).<\/p>\n<p>El plan de HBO Max es que cada temporada de la serie adapte un libro distinto de la saga \u201cTales of Dunk and Egg\u201d, por lo que hay material para versionar dos novelas m\u00e1s. Y, seg\u00fan el sitio web <a href=\"https:\/\/lossietereinos.com\/confirmado-george-r-r-martin-tiene-ideas-de-10-o-12-historias-mas-de-dunk-y-egg-segun-el-showrunner-de-el-caballero-de-los-siete-reinos\/\">Los siete reinos<\/a>, especializado en la obra de George R. R. Martin, el autor tiene ideas para <a href=\"https:\/\/lossietereinos.com\/que-sabemos-del-cuarto-cuento-de-dunk-y-egg-las-lobas-de-invernalia\/\">escribir 10 o 12 historias<\/a> m\u00e1s de estos personajes.<\/p>\n<p>La historia de la nueva serie se centra en un caballero errante llamado Ser Duncan el Alto (Peter Claffey) y su joven escudero apodado Egg (Dexter Sol Ansell), quien recibe este mote por lucir sin pelo su cabeza, como si fuese un huevo. Cada temporada se enfocar\u00e1 en una nueva aventura de ambos personajes, quienes ser\u00e1n testigos de muchos acontecimientos importantes de la historia de Westeros.<\/p>\n<p>Ser Duncan el Alto, tambi\u00e9n conocido como Dunk, es un caballero errante, lo que indica que no sirve a ning\u00fan se\u00f1or de una gran familia en Westeros. Recorre el continente compitiendo en torneos y, si la suerte le sonr\u00ede, acepta trabajos al servicio de un pr\u00edncipe. Vive su vida bajo el c\u00f3digo de honor de la caballer\u00eda.<\/p>\n<p>Nacido en Pozo de pulgas, el barrio m\u00e1s grande y pobre de la ciudad de King\u2019s Landing, Ser Duncan sirvi\u00f3 como escudero al caballero Ser Arlan de Pennytree, quien lo educ\u00f3 y lo jurament\u00f3 como caballero a los 16 a\u00f1os. La serie muestra la evoluci\u00f3n de Ser Duncan como caballero errante, su encuentro con quien ser\u00eda su escudero, el joven Egg y su participaci\u00f3n en el torno de Ashford.<\/p>\n<p>Egg, tal es su apodo, es el joven escudero de Ser Duncan. En las novelas se le describe como \u201csabio para su edad, seguro de s\u00ed mismo y astuto\u201d. Su identidad es un secreto que vale la pena dejar como misterio a los espectadores. George R. R. Martin <a href=\"https:\/\/awoiaf.westeros.org\/index.php\/Dunk_and_Egg\">ha dicho<\/a> que desea escribir historias que abarquen la vida completa de Dunk y Egg.<\/p>\n<p>Sin revelar <em>spoilers<\/em> de la trama, \u201cA Knight of the Seven Kingdoms\u201d conecta con \u201cGame of Thrones\u201d al ofrecer antecedentes cruciales, explorando la historia de la Casa Targaryen 90 a\u00f1os antes de los acontecimientos vistos en la serie original.<\/p>\n<p>La serie muestra a los antepasados de personajes protagonistas en \u201cGame of Thrones\u201d. Y, en especial, es probable que conozcamos a las versiones j\u00f3venes de dos personajes importantes: el <a href=\"https:\/\/gameofthrones.fandom.com\/wiki\/Aemon\">maestre Aemon<\/a>, maestre de la <a href=\"https:\/\/gameofthrones.fandom.com\/wiki\/Night%27s_Watch\">Guardia Nocturna<\/a>, que protege a Westeros de los Salvajes y, luego, de los Caminantes Blancos; y <a href=\"https:\/\/awoiaf.westeros.org\/index.php\/Brynden_Rivers\">Bloodraven<\/a>, quien habr\u00eda de convertirse en el <a href=\"https:\/\/www.20minutos.es\/cinemania\/series\/quien-es-cuervo-tres-ojos-casa-dragon-cambiado-actor-5556611\/\">Cuervo de Tres Ojos<\/a> en \u201cGame of Thrones\u201d.<\/p>\n<p>Uno de los libros de \u201cTales of Dunk and Egg\u201d mostrar\u00e1 una de las rebeliones Backfyre (fuego oscuro), fundamentales en la historia de Westeros y una de las muchas guerras civiles que los Targaryen enfrentaron durante sus reinados.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfUna serie de \u201cGame of Thrones\u201d sin dragones? Cuesta imaginarlo, pero esa es la premisa de la nueva serie del universo fant\u00e1stico creado por el escritor George R. R. Martin, \u201cA Knight of Seven Kingdoms\u201d, que se estrena este domingo en la plataforma HBO Max. La historia se desarrolla 90 a\u00f1os antes de los acontecimientos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470205","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qui\u00e9nes son Ser Duncan el Alto y Egg de &quot;A Knight of the Seven Kingdoms&quot; y c\u00f3mo conecta con &quot;Game of Thrones&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qui\u00e9nes son Ser Duncan el Alto y Egg de &quot;A Knight of the Seven Kingdoms&quot; y c\u00f3mo conecta con &quot;Game of Thrones&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"\u00bfUna serie de \u201cGame of Thrones\u201d sin dragones? Cuesta imaginarlo, pero esa es la premisa de la nueva serie del universo fant\u00e1stico creado por el escritor George R. R. Martin, \u201cA Knight of Seven Kingdoms\u201d, que se estrena este domingo en la plataforma HBO Max. La historia se desarrolla 90 a\u00f1os antes de los acontecimientos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-18T11:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Qui\u00e9nes son Ser Duncan el Alto y Egg de &#171;A Knight of the Seven Kingdoms&#187; y c\u00f3mo conecta con &#171;Game of Thrones&#187;\",\"datePublished\":\"2026-01-18T11:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/\"},\"wordCount\":678,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/\",\"name\":\"Qui\u00e9nes son Ser Duncan el Alto y Egg de \\\"A Knight of the Seven Kingdoms\\\" y c\u00f3mo conecta con \\\"Game of Thrones\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-18T11:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qui\u00e9nes son Ser Duncan el Alto y Egg de &#171;A Knight of the Seven Kingdoms&#187; y c\u00f3mo conecta con &#171;Game of Thrones&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qui\u00e9nes son Ser Duncan el Alto y Egg de \"A Knight of the Seven Kingdoms\" y c\u00f3mo conecta con \"Game of Thrones\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Qui\u00e9nes son Ser Duncan el Alto y Egg de \"A Knight of the Seven Kingdoms\" y c\u00f3mo conecta con \"Game of Thrones\" - Noticias","og_description":"\u00bfUna serie de \u201cGame of Thrones\u201d sin dragones? Cuesta imaginarlo, pero esa es la premisa de la nueva serie del universo fant\u00e1stico creado por el escritor George R. R. Martin, \u201cA Knight of Seven Kingdoms\u201d, que se estrena este domingo en la plataforma HBO Max. La historia se desarrolla 90 a\u00f1os antes de los acontecimientos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/","og_site_name":"Noticias","article_published_time":"2026-01-18T11:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/"},"author":{"name":"","@id":""},"headline":"Qui\u00e9nes son Ser Duncan el Alto y Egg de &#171;A Knight of the Seven Kingdoms&#187; y c\u00f3mo conecta con &#171;Game of Thrones&#187;","datePublished":"2026-01-18T11:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/"},"wordCount":678,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/","url":"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/","name":"Qui\u00e9nes son Ser Duncan el Alto y Egg de \"A Knight of the Seven Kingdoms\" y c\u00f3mo conecta con \"Game of Thrones\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-18T11:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Qui\u00e9nes son Ser Duncan el Alto y Egg de &#171;A Knight of the Seven Kingdoms&#187; y c\u00f3mo conecta con &#171;Game of Thrones&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Qui\u00e9nes son Ser Duncan el Alto y Egg de &#171;A Knight of the Seven Kingdoms&#187; y c\u00f3mo conecta con &#171;Game of Thrones&#187;","url":"http:\/\/noticiasya.com\/laredo\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/01\/18\/dunk-egg-knight-seven-kingdoms-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-18T11:03:40Z","datePublished":"2026-01-18T11:03:40Z","dateModified":"2026-01-18T11:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Qui\\u00e9nes son Ser Duncan el Alto y Egg de &#171;A Knight of the Seven Kingdoms&#187; y c\\u00f3mo conecta con &#171;Game of Thrones&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/18\\\/dunk-egg-knight-seven-kingdoms-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/18\\\/dunk-egg-knight-seven-kingdoms-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-18T11:03:40Z\",\"datePublished\":\"2026-01-18T11:03:40Z\",\"dateModified\":\"2026-01-18T11:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470189,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/17\/knight-seven-kingdoms-estreno-episodios-game-thrones-orix\/","url_meta":{"origin":1470205,"position":0},"title":"&#171;A Knight of the Seven Kingdoms&#187;: fecha de estreno y episodios de la nueva serie de &#171;Game of Thrones&#187;","author":"","date":"enero 17, 2026","format":false,"excerpt":"El universo televisivo de \u201cGame of Thrones\u201d no tiene descanso. A la serie \u201cHouse of the Dragon\u201d lanzada en 2022 se suma ahora \u201cA Knight of the Seven Kingdoms\u201d (\u201cEl caballero de los siete reinos\u201d), que se estrena en HBO Max este domingo en EE.UU. y Latinoam\u00e9rica y este lunes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470255,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/20\/caballero-siete-reinos-episodio-1-orix\/","url_meta":{"origin":1470205,"position":1},"title":"&#171;El caballero de los siete reinos&#187; apuesta por el humor en su primer episodio","author":"","date":"enero 20, 2026","format":false,"excerpt":"El primer episodio de la serie \u201cEl caballero de los siete reinos\u201d, estrenado el domingo, dej\u00f3 claras sus diferencias con \u201cGame of Thrones\u201d al proponer una historia que provilegiar\u00e1 el humor y coraz\u00f3n por encima de la violencia.A diferencia de las series \u201cGame of Thrones\u201d y \u201cHouse of the Dragons\u201d\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471530,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/22\/peliculas-series-juego-de-tronos-futuro-orix\/","url_meta":{"origin":1470205,"position":2},"title":"\u00bfQu\u00e9 pel\u00edculas y series del universo de &#171;Juego de Tronos&#187; saldr\u00e1n en el futuro? Estas son las temporadas y obras confirmadas","author":"","date":"febrero 22, 2026","format":false,"excerpt":"Tras la criticada temporada final de \u201cJuego de tronos\u201d en 2019, el \u00e9xito de la serie \u201cEl caballero de los siete reinos\u201d, cuyo final de temporada se emite este domingo en HBO, ha resucitado el inter\u00e9s por la saga de fantas\u00eda creada por George R. R. Martin.La saga \u201cA song\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470225,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/19\/5-cosas-19-enero-2026-orix\/","url_meta":{"origin":1470205,"position":3},"title":"Las 5 cosas que debes saber este 19 de enero","author":"","date":"enero 19, 2026","format":false,"excerpt":"Unos 1.500 soldados se alistan para un posible despliegue en Minnesota. Trump le dice a Noruega que ya no se siente obligado a \u201cpensar \u00fanicamente en la paz\u201d en una carta sobre el Nobel y Groenlandia. La evaluaci\u00f3n de Mike Pence sobre Delcy Rodr\u00edguez. Esto es lo que debes saber\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473490,"url":"https:\/\/noticiasya.com\/laredo\/2026\/04\/24\/reino-montanoso-narnia-game-of-thrones-irlanda-del-norte-trax\/","url_meta":{"origin":1470205,"position":4},"title":"El antiguo reino monta\u00f1oso donde la fantas\u00eda de &#171;Narnia&#187; y &#171;Game of Thrones&#187; cobra vida","author":"","date":"abril 24, 2026","format":false,"excerpt":"Los densos bosques, los r\u00edos serpenteantes y los picos de granito de las monta\u00f1as Mourne de Irlanda del Norte han vivido muchas vidas y asumido muchos nombres.Son Westeros en \u201cGame of Thrones\u201d. Son \u201cKrypton\u201d en la precuela de Superman.Tambi\u00e9n son Transilvania en \u201cDracula Untold\u201d, Sherwood en la pr\u00f3xima \u201cThe Death\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457606,"url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/17\/blake-lively-justin-baldoni-khaleesi-game-of-thrones-trax\/","url_meta":{"origin":1470205,"position":5},"title":"Blake Lively se habr\u00eda referido a s\u00ed misma como &#171;Khaleesi&#187; de &#171;Game of Thrones&#187; en un mensaje de texto para Justin Baldoni","author":"","date":"enero 17, 2025","format":false,"excerpt":"Parece que \u201cGame of Thrones\u201d ahora forma parte de la batalla legal entre Blake Lively y Justin Baldoni.Baldoni demand\u00f3 a Lively, su coprotagonista en \u201cIt Ends With Us\u201d, y a su esposo Ryan Reynolds, alegando que la pareja de Hollywood intent\u00f3 \u201cdestruirlo\u201d despu\u00e9s de que Lively lo acusara de acoso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1470205"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470205\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1470205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1470205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1470205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}