{"id":1470218,"date":"2026-01-18T18:03:38","date_gmt":"2026-01-19T02:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/"},"modified":"2026-01-18T18:03:38","modified_gmt":"2026-01-19T02:03:38","slug":"presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/","title":{"rendered":"Presidente de Guatemala declara el estado de sitio tras ola de violencia de las pandillas"},"content":{"rendered":"<p>El presidente de Guatemala, Bernardo Ar\u00e9valo de Le\u00f3n, decret\u00f3 este domingo el estado de sitio durante 30 d\u00edas en todo el pa\u00eds despu\u00e9s de una oleada de violencia por parte de las pandillas con ataques a las fuerzas de seguridad y motines en las c\u00e1rceles.<\/p>\n<p>La decisi\u00f3n, divulgada por el gobernante en cadena nacional, tiene lugar despu\u00e9s de que este domingo fueron <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/18\/latinoamerica\/pandillas-matan-siete-policias-guatemala-trax\">asesinados ocho agentes <\/a>de la Polic\u00eda Nacional Civil, atacados en distintos puntos de la capital del pa\u00eds, presuntamente en un ataque coordinado por pandilleros.<\/p>\n<p>El estado de sitio permite a las autoridades la detenci\u00f3n de cualquier persona sin necesidad de mandamiento judicial y est\u00e1 dise\u00f1ado para garantizar la seguridad contra el terrorismo o actividades rebeldes. Adem\u00e1s, proh\u00edbe las reuniones o manifestaciones.<\/p>\n<p>El mandatario subray\u00f3 durante su mensaje a la naci\u00f3n que \u201cno permitiremos que la violencia y la intimidaci\u00f3n dicten el rumbo de Guatemala\u201d.<\/p>\n<p>De acuerdo al presidente, la estrategia \u201ccontra los criminales est\u00e1 teniendo \u00e9xito\u201d y por ello \u201cest\u00e1n desesperados\u201d.<\/p>\n<p>En el mismo contexto, seg\u00fan Ar\u00e9valo de Leon, los grupos criminales decidieron amotinarse el s\u00e1bado en varias c\u00e1rceles y \u201cen represalia a los exitosos operativos\u201d este domingo para retomar el control de las prisiones, los pandilleros atacaron a las fuerzas de seguridad.<\/p>\n<p>\u201cQuiero decirlo alto y claro que no negociamos con criminales ni toleramos acciones terroristas\u201d, a\u00f1adi\u00f3.<\/p>\n<p>El mandatario recalc\u00f3 que la declaraci\u00f3n del estado de sitio no alterar\u00e1 las \u201cvida cotidiana\u201d de la poblaci\u00f3n ni la \u201cmovilidad de la poblaci\u00f3n\u201d, m\u00e1s all\u00e1 de la suspensi\u00f3n de la jornada educativa programada para este lunes en el \u00e1mbito privado y p\u00fablico.<\/p>\n<p>Ar\u00e9valo de Le\u00f3n puntualiz\u00f3 adem\u00e1s que \u201csabemos quienes est\u00e1n detr\u00e1s: grupos que se benefician de la corrupci\u00f3n que crecen en las sombras\u201d, que \u201cresisten y buscan infundir terror\u201d porque \u201ceste a\u00f1o Guatemala recuperar\u00e1 su sistema de justicia\u201d, en referencia al cambio de fiscal general programado para mayo, adem\u00e1s de la renovaci\u00f3n de la Corte de Constitucionalidad, m\u00e1ximo tribunal del pa\u00eds.<\/p>\n<p>Los ataques de los presuntos pandilleros contra la Polic\u00eda Nacional Civil dejaron ocho agentes asesinados, adem\u00e1s de un presunto sicario tambi\u00e9n fallecido.<\/p>\n<p>Los atentados se registraron en diversos puntos de la Ciudad de Guatemala y mantienen en alerta a la poblaci\u00f3n y a las fuerzas de seguridad.<\/p>\n<p>Con respecto a los motines, las fuerzas de seguridad retomaron este domingo el control de la c\u00e1rcel de m\u00e1xima seguridad denominada \u2018Renovaci\u00f3n I\u2019, en el sur del pa\u00eds, tras la revuelta registrada el s\u00e1bado.<\/p>\n<p>La Polic\u00eda Nacional Civil indic\u00f3 que se \u201cneutraliz\u00f3\u201d al l\u00edder de la pandilla denominada Barrio 18, Aldo Ochoa, uno de los promotores del mot\u00edn, quien demandaba su traslado a otra prisi\u00f3n adem\u00e1s de diversas comodidades como aire acondicionado y comida a domicilio.<\/p>\n<p>En el segundo semestre de 2025, las pandillas \u2018Barrio 18\u2019 y \u2018Mara Salvatrucha\u2019 mantuvieron una f\u00e9rrea pugna con el Gobierno de Guatemala por el control de las prisiones, luego de que el pasado 31 de julio sus l\u00edderes fueran trasladados a la c\u00e1rcel de m\u00e1xima seguridad \u2018Renovaci\u00f3n I\u2019 para ser aislados, lo que ha provocado constantes motines desde entonces en los centros penitenciarios.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Guatemala, Bernardo Ar\u00e9valo de Le\u00f3n, decret\u00f3 este domingo el estado de sitio durante 30 d\u00edas en todo el pa\u00eds despu\u00e9s de una oleada de violencia por parte de las pandillas con ataques a las fuerzas de seguridad y motines en las c\u00e1rceles. La decisi\u00f3n, divulgada por el gobernante en cadena nacional, tiene [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470218","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Presidente de Guatemala declara el estado de sitio tras ola de violencia de las pandillas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presidente de Guatemala declara el estado de sitio tras ola de violencia de las pandillas - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Guatemala, Bernardo Ar\u00e9valo de Le\u00f3n, decret\u00f3 este domingo el estado de sitio durante 30 d\u00edas en todo el pa\u00eds despu\u00e9s de una oleada de violencia por parte de las pandillas con ataques a las fuerzas de seguridad y motines en las c\u00e1rceles. La decisi\u00f3n, divulgada por el gobernante en cadena nacional, tiene [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-19T02:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Presidente de Guatemala declara el estado de sitio tras ola de violencia de las pandillas\",\"datePublished\":\"2026-01-19T02:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/\"},\"wordCount\":593,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/\",\"name\":\"Presidente de Guatemala declara el estado de sitio tras ola de violencia de las pandillas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-19T02:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presidente de Guatemala declara el estado de sitio tras ola de violencia de las pandillas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presidente de Guatemala declara el estado de sitio tras ola de violencia de las pandillas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/","og_locale":"es_ES","og_type":"article","og_title":"Presidente de Guatemala declara el estado de sitio tras ola de violencia de las pandillas - Noticias","og_description":"El presidente de Guatemala, Bernardo Ar\u00e9valo de Le\u00f3n, decret\u00f3 este domingo el estado de sitio durante 30 d\u00edas en todo el pa\u00eds despu\u00e9s de una oleada de violencia por parte de las pandillas con ataques a las fuerzas de seguridad y motines en las c\u00e1rceles. La decisi\u00f3n, divulgada por el gobernante en cadena nacional, tiene [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/","og_site_name":"Noticias","article_published_time":"2026-01-19T02:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/"},"author":{"name":"","@id":""},"headline":"Presidente de Guatemala declara el estado de sitio tras ola de violencia de las pandillas","datePublished":"2026-01-19T02:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/"},"wordCount":593,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/","url":"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/","name":"Presidente de Guatemala declara el estado de sitio tras ola de violencia de las pandillas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-19T02:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Presidente de Guatemala declara el estado de sitio tras ola de violencia de las pandillas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Presidente de Guatemala declara el estado de sitio tras ola de violencia de las pandillas","url":"http:\/\/noticiasya.com\/laredo\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/01\/18\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-19T02:03:38Z","datePublished":"2026-01-19T02:03:38Z","dateModified":"2026-01-19T02:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Presidente de Guatemala declara el estado de sitio tras ola de violencia de las pandillas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/18\\\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/18\\\/presidente-guatemala-declara-estado-sitio-ola-violencia-pandillas-efe\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-19T02:03:38Z\",\"datePublished\":\"2026-01-19T02:03:38Z\",\"dateModified\":\"2026-01-19T02:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470235,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/19\/guatemala-motines-policias-asesinados-que-esta-pasando-orix\/","url_meta":{"origin":1470218,"position":0},"title":"\u00bfQu\u00e9 est\u00e1 pasando en Guatemala? Motines, polic\u00edas asesinados y estado de sitio","author":"","date":"enero 19, 2026","format":false,"excerpt":"Guatemala vivi\u00f3 este fin de semana una de las mayores crisis durante el Gobierno de Bernardo Ar\u00e9valo. Al menos ocho polic\u00edas murieron y varios m\u00e1s resultaron heridos en ataques atribuidos por las autoridades a las pandillas, tras motines en diferentes prisiones que tuvieron que ser controladas por las fuerzas del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471286,"url":"https:\/\/noticiasya.com\/laredo\/2026\/02\/16\/guatemala-estado-sitio-miedo-crimen-migrar-opcion-orix\/","url_meta":{"origin":1470218,"position":1},"title":"El estado de sitio termina en Guatemala pero el miedo al crimen sigue. Para algunos, emigrar a El Salvador es una opci\u00f3n","author":"","date":"febrero 16, 2026","format":false,"excerpt":"El estado de sitio declarado hace 30 d\u00edas en Guatemala, luego de ataques del crimen organizado contra las fuerzas de seguridad, termin\u00f3 este lunes pero los patrullajes y operativos conjuntos entre la Polic\u00eda y el Ej\u00e9rcito van a continuar en el pa\u00eds centroamericano. A partir de este martes, entrar\u00e1 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470213,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/18\/pandillas-matan-siete-policias-guatemala-trax\/","url_meta":{"origin":1470218,"position":2},"title":"Pandillas matan a siete polic\u00edas en Guatemala en represalia por operativo tras motines en c\u00e1rceles","author":"","date":"enero 18, 2026","format":false,"excerpt":"Siete polic\u00edas murieron en Guatemala en medio de un repunte de la violencia de pandillas que se origin\u00f3 luego de producirse motines en tres c\u00e1rceles, inform\u00f3 el ministro del Interior, Marco Antonio Villeda.Las autoridades retomaron la ma\u00f1ana del domingo el control de una prisi\u00f3n, despu\u00e9s de que hab\u00eda sido tomada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470313,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/20\/bernardo-arevalo-fiscalia-detenidos-violencia-guatemala-impunidad-entrevista-orix\/","url_meta":{"origin":1470218,"position":3},"title":"Ar\u00e9valo dice a CNN que la Fiscal\u00eda ha imputado delitos menores a detenidos por violencia en Guatemala: &#171;Reparten impunidad&#187;","author":"","date":"enero 20, 2026","format":false,"excerpt":"El presidente de Guatemala, Bernardo Ar\u00e9valo, dijo este martes en una entrevista con CNN que la Fiscal\u00eda no present\u00f3 los cargos que corresponder\u00edan contra dos personas detenidas por su presunta participaci\u00f3n en la reciente ola de violencia en el pa\u00eds centroamericano, desatada luego de que las autoridades retomaran el control\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470264,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/20\/barrio-18-mara-salvatrucha-pandillas-guatemala-orix\/","url_meta":{"origin":1470218,"position":4},"title":"\u00bfQu\u00e9 son y c\u00f3mo operan Barrio 18 y la Mara Salvatrucha, las dos pandillas con mayor presencia en Guatemala?","author":"","date":"enero 20, 2026","format":false,"excerpt":"Guatemala vive el segundo de los 30 d\u00edas de estado de sitio declarados por el presidente Bernardo Ar\u00e9valo tras el asesinato de nueve polic\u00edas. Desde hace varios a\u00f1os, el pa\u00eds centroamericano es escenario de las operaciones criminales de dos principales pandillas, la Mara Salvatrucha (MS-13) y Barrio 18, que a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457199,"url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/03\/fuerzas-guatemaltecas-salvadorenas-haiti-pandillas-trax\/","url_meta":{"origin":1470218,"position":5},"title":"Fuerzas guatemaltecas y salvadore\u00f1as llegan a Hait\u00ed para unirse a la lucha contra las pandillas violentas","author":"","date":"enero 3, 2025","format":false,"excerpt":"Un grupo de fuerzas de seguridad de Guatemala y El Salvador lleg\u00f3 a Hait\u00ed este viernes para reforzar una misi\u00f3n multinacional encargada de abordar la violencia desenfrenada de las pandillas en el pa\u00eds, anunci\u00f3 la Polic\u00eda Nacional de Hait\u00ed.Los 75 soldados guatemaltecos y ocho salvadore\u00f1os fueron recibidos en la pista\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1470218"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470218\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1470218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1470218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1470218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}