{"id":1470229,"date":"2026-01-19T08:03:49","date_gmt":"2026-01-19T16:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/"},"modified":"2026-01-19T08:03:49","modified_gmt":"2026-01-19T16:03:49","slug":"bunker-secreto-casa-blanca-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/","title":{"rendered":"As\u00ed son los planes para reconstruir el b\u00fanker &#171;ultrasecreto&#187; debajo del ala este de la Casa Blanca"},"content":{"rendered":"<p>El presidente de Estados Unidos orden\u00f3 la construcci\u00f3n secreta de una instalaci\u00f3n subterr\u00e1nea segura en la Casa Blanca y construy\u00f3 una nueva extensi\u00f3n del ala este encima.<\/p>\n<p>Corr\u00eda el a\u00f1o 1941, y Franklin D. Roosevelt hab\u00eda sido alentado a construir un refugio antia\u00e9reo en la Casa Blanca tras el ataque a Pearl Harbor.<\/p>\n<p>En aquel momento, \u201cno se hizo ning\u00fan reconocimiento p\u00fablico de que se estuviera construyendo un refugio antia\u00e9reo, solo el ala este\u201d, seg\u00fan Bill Seale, historiador de la Asociaci\u00f3n Hist\u00f3rica de la Casa Blanca.<\/p>\n<p>M\u00e1s de 80 a\u00f1os despu\u00e9s, el ala este est\u00e1 de nuevo en construcci\u00f3n en preparaci\u00f3n para el nuevo y extenso sal\u00f3n de baile del presidente Donald Trump, y las hist\u00f3ricas, aunque anticuadas, instalaciones subterr\u00e1neas han sido desmanteladas. Y, una vez m\u00e1s, existe mucho secretismo en torno a los planes para reconstruir el b\u00fanker.<\/p>\n<p>Se sabe poco p\u00fablicamente sobre la construcci\u00f3n que se lleva a cabo en lo que una vez fue un b\u00fanker secreto similar a un submarino, que inclu\u00eda el Centro de Operaciones de Emergencia Presidencial (PEOC, por sus siglas en ingl\u00e9s) y la infraestructura subterr\u00e1nea que lo rodea. El espacio se ha utilizado para todo, desde ver una pel\u00edcula de parodia que la administraci\u00f3n Nixon consider\u00f3 pornogr\u00e1fica y que se buscaba matar, hasta planificar el viaje clandestino del expresidente Joe Biden a Ucrania. El entonces vicepresidente Dick Cheney fue evacuado al espacio momentos antes del ataque al Pent\u00e1gono el 11 de septiembre de 2001.<\/p>\n<p>Seg\u00fan una fuente con conocimiento del asunto, es probable que el espacio est\u00e9 siendo redise\u00f1ado y reemplazado con nueva tecnolog\u00eda para contrarrestar las amenazas en constante evoluci\u00f3n.<\/p>\n<p>Pero ha habido muy poco reconocimiento de la existencia del proyecto.<\/p>\n<p>Durante una reuni\u00f3n reciente de la Comisi\u00f3n Nacional de Planificaci\u00f3n de la Capital, donde se habl\u00f3 sobre el sal\u00f3n de baile, el director de gesti\u00f3n y administraci\u00f3n de la Casa Blanca, Joshua Fisher, afirm\u00f3 en t\u00e9rminos generales que el proyecto general del sal\u00f3n de baile \u201cmejorar\u00e1 la funcionalidad cr\u00edtica para la misi\u00f3n\u201d, \u201cimplementar\u00e1 las mejoras de seguridad necesarias\u201d y \u201cofrecer\u00e1 una infraestructura resiliente y adaptable, alineada con las necesidades futuras de la misi\u00f3n\u201d.<\/p>\n<p>Se le pregunt\u00f3 a Fisher por qu\u00e9 el proyecto romp\u00eda con los precedentes al iniciar el proceso de demolici\u00f3n sin la aprobaci\u00f3n de la comisi\u00f3n, e indic\u00f3 que la motivaci\u00f3n fue el trabajo \u201calto secreto\u201d que se realizaba bajo tierra.<\/p>\n<p>\u201cHay algunos aspectos de este proyecto que, francamente, son de alto secreto y en los que estamos trabajando actualmente. Esto no nos impide modificar la estructura sobre el nivel del suelo, pero ese trabajo deb\u00eda tenerse en cuenta al realizar este proyecto, que no formaba parte del proceso del NCPC\u201d, declar\u00f3.<\/p>\n<p>La Casa Blanca declin\u00f3 la solicitud de comentarios de CNN. Sin embargo, en una presentaci\u00f3n judicial la semana pasada para un caso que busca detener la construcci\u00f3n del ala este, la Casa Blanca defendi\u00f3 el proceso, argumentando que detener la construcci\u00f3n subterr\u00e1nea \u201cpondr\u00eda en peligro la seguridad nacional y, por lo tanto, perjudicar\u00eda el inter\u00e9s p\u00fablico\u201d. A\u00f1adi\u00f3 que el razonamiento para ello se describi\u00f3 en una \u201cdeclaraci\u00f3n clasificada\u201d adjunta al caso.<\/p>\n<p>Esto es lo que sabemos sobre lo que hab\u00eda antes y lo que est\u00e1 sucediendo ahora.<\/p>\n<p>Aunque la construcci\u00f3n de Roosevelt se concibi\u00f3 inicialmente como un refugio antia\u00e9reo, las instalaciones subterr\u00e1neas bajo el ala este evolucionaron con el tiempo para cumplir m\u00faltiples funciones.<\/p>\n<p>Quienes acced\u00edan por el ala este descend\u00edan varios niveles y luego atravesaban una enorme puerta tipo b\u00f3veda protegida para acceder a un b\u00fanker aut\u00f3nomo de techo bajo que inclu\u00eda camas, alimentos no perecederos, agua y otros suministros, adem\u00e1s de comunicaciones seguras con el exterior, seg\u00fan una fuente que estuvo en el espacio y no estaba autorizada a declarar oficialmente.<\/p>\n<p>El espacio subterr\u00e1neo tambi\u00e9n inclu\u00eda el PEOC, una instalaci\u00f3n centralizada de comando y control para el presidente y su personal, fortificada para resistir una posible explosi\u00f3n nuclear u otro ataque de gran magnitud.<\/p>\n<p>El PEOC funciona en conjunto con la Sala de Situaci\u00f3n, seg\u00fan Jonathan Wackrow, exagente del Servicio Secreto de EE. UU. y colaborador de CNN.<\/p>\n<p>\u201cLa Sala de Situaciones es un centro de vigilancia mucho m\u00e1s espec\u00edfico que transmite informaci\u00f3n al PEOC. Sin embargo, al ser un complejo ubicado en el Ala Oeste, es seguro hasta cierto punto, pero no es una instalaci\u00f3n reforzada\u201d, dijo.<\/p>\n<p>\u201cEl PEOC se utiliza durante emergencias. No es un lugar al que acuda todo el mundo\u201d, a\u00f1adi\u00f3. \u201cLa Sala de Situaciones es utilizada por casi todo el gobierno, las 24 horas del d\u00eda\u201d.<\/p>\n<p>El PEOC ha sido representado en la gran pantalla con distintos grados de precisi\u00f3n; m\u00e1s recientemente, en el thriller de 2025 \u201cUna Casa de Dinamita\u201d, junto con \u201cLa Ca\u00edda del Olimpo\u201d de 2013, que retrat\u00f3 un ataque terrorista a la Casa Blanca.<\/p>\n<p>Este espacio, que parec\u00eda una tumba, fue visitado por Roosevelt solo una vez, seg\u00fan Seale, el historiador. En los a\u00f1os siguientes, \u201cla inspecci\u00f3n del refugio antia\u00e9reo se convirti\u00f3 en una costumbre el primer d\u00eda para todos los presidentes entrantes, hasta los \u00faltimos veinte a\u00f1os, cuando la relevancia del refugio disminuy\u00f3\u201d, escribi\u00f3 en 2011.<\/p>\n<p>Una segunda fuente familiarizada con el espacio, que prefiri\u00f3 el anonimato para hablar libremente, describi\u00f3 el complejo subterr\u00e1neo como \u201cun submarino muy complejo construido en la d\u00e9cada de 1940: una unidad aut\u00f3noma, con sistemas de energ\u00eda y agua de reserva independientes y filtraci\u00f3n de aire independiente\u201d.<\/p>\n<p>\u201cPero toda la infraestructura es de la d\u00e9cada de 1940\u201d, a\u00f1adieron.<\/p>\n<p>El complejo tambi\u00e9n contaba con una ruta de evacuaci\u00f3n segura, seg\u00fan la primera fuente, a trav\u00e9s de la cual se pod\u00eda trasladar al presidente de los terrenos de la Casa Blanca a otro lugar.<\/p>\n<p>La demolici\u00f3n del ala este comenz\u00f3 en octubre, y las excavadoras que desmantelaron la Columnata Este y el espacio de oficinas hist\u00f3ricamente ocupado por las primeras damas se llevaron consigo la anticuada instalaci\u00f3n subterr\u00e1nea.<\/p>\n<p>\u201cCon un alto grado de certeza, dir\u00eda que todas las estructuras subterr\u00e1neas\u201d, incluyendo el Centro de Operaciones de Emergencia Presidencial (PEOC), los servicios de calefacci\u00f3n y aire acondicionado, y las instalaciones subterr\u00e1neas de la Oficina Militar de la Casa Blanca y la Divisi\u00f3n Uniformada del Servicio Secreto de EE. UU., \u201cparecen haber desaparecido\u201d, dijo la segunda fuente.<\/p>\n<p>Para cualquiera que est\u00e9 preocupado por la seguridad presidencial en ausencia del b\u00fanker, dicha fuente indic\u00f3 que existen numerosas redundancias para mantener al presidente a salvo en caso de emergencia.<\/p>\n<p>Si bien es improbable que los planes se hagan p\u00fablicos pronto, los detalles podr\u00edan revelarse con el tiempo: El PEOC jug\u00f3 un papel importante el 11 de septiembre de 2001, y algunas im\u00e1genes del interior del centro ese d\u00eda se publicaron mediante una solicitud amparada en la Ley de Libertad de Informaci\u00f3n en 2015.<\/p>\n<p>Trump ha sugerido que el ej\u00e9rcito estadounidense est\u00e1 muy involucrado en la construcci\u00f3n del sal\u00f3n de baile, y es probable que el proyecto est\u00e9 siendo ejecutado por una combinaci\u00f3n de oficiales militares; el Servicio Secreto; la Oficina Ejecutiva del Presidente; la contratista Clark Construction, con amplia experiencia en la construcci\u00f3n de instalaciones de alta seguridad; y Shalom Baranes Architects, el grupo que lider\u00f3 la construcci\u00f3n del sal\u00f3n de baile y que tambi\u00e9n dirigi\u00f3 el proyecto de reconstrucci\u00f3n y fortificaci\u00f3n del Pent\u00e1gono tras el atentado del 11-S.<\/p>\n<p>Wackrow, ahora ejecutivo de gesti\u00f3n de riesgos, predijo que cualquier instalaci\u00f3n que reemplace el espacio subterr\u00e1neo podr\u00e1 anticipar y responder a amenazas emergentes, incluyendo amenazas cin\u00e9ticas como una explosi\u00f3n nuclear o un accidente a\u00e9reo; instrumentos qu\u00edmicos o biol\u00f3gicos; o pulsos electromagn\u00e9ticos, entre otras posibles preocupaciones, y hacerlo sin revelar detalles a posibles adversarios.<\/p>\n<p>\u201cHay que pensar en una instalaci\u00f3n que pueda construirse en secreto, altamente clasificada, que pueda soportar el entorno de amenazas estatales actual y futuro\u201d, afirm\u00f3.<\/p>\n<p>Lo que ser\u00e1 pr\u00e1cticamente imposible: conocer el costo de esta parte de la construcci\u00f3n. Trump ha ofrecido un precio cada vez mayor para el proyecto del sal\u00f3n de baile, que comenz\u00f3 en 200 millones de d\u00f3lares y ahora asciende a 400 millones, pero eso no incluye lo que ocurrir\u00e1 bajo tierra. Trump ha dejado claro que el sal\u00f3n de baile ser\u00e1 financiado por donantes privados, pero cualquier infraestructura de seguridad subterr\u00e1nea ser\u00e1 financiada en \u00faltima instancia por los contribuyentes estadounidenses.<\/p>\n<p>\u201cSi pensamos en mitigar las amenazas actuales y futuras, en realidad nos referimos a tecnolog\u00edas emergentes, infraestructura emergente, cosas que podr\u00edan no estar disponibles comercialmente. Nunca sabremos con certeza cu\u00e1nto cuesta\u201d, dijo Wackrow.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Estados Unidos orden\u00f3 la construcci\u00f3n secreta de una instalaci\u00f3n subterr\u00e1nea segura en la Casa Blanca y construy\u00f3 una nueva extensi\u00f3n del ala este encima. Corr\u00eda el a\u00f1o 1941, y Franklin D. Roosevelt hab\u00eda sido alentado a construir un refugio antia\u00e9reo en la Casa Blanca tras el ataque a Pearl Harbor. En aquel [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470229","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>As\u00ed son los planes para reconstruir el b\u00fanker &quot;ultrasecreto&quot; debajo del ala este de la Casa Blanca - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As\u00ed son los planes para reconstruir el b\u00fanker &quot;ultrasecreto&quot; debajo del ala este de la Casa Blanca - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Estados Unidos orden\u00f3 la construcci\u00f3n secreta de una instalaci\u00f3n subterr\u00e1nea segura en la Casa Blanca y construy\u00f3 una nueva extensi\u00f3n del ala este encima. Corr\u00eda el a\u00f1o 1941, y Franklin D. Roosevelt hab\u00eda sido alentado a construir un refugio antia\u00e9reo en la Casa Blanca tras el ataque a Pearl Harbor. En aquel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-19T16:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"As\u00ed son los planes para reconstruir el b\u00fanker &#171;ultrasecreto&#187; debajo del ala este de la Casa Blanca\",\"datePublished\":\"2026-01-19T16:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/\"},\"wordCount\":1562,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/\",\"name\":\"As\u00ed son los planes para reconstruir el b\u00fanker \\\"ultrasecreto\\\" debajo del ala este de la Casa Blanca - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-19T16:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As\u00ed son los planes para reconstruir el b\u00fanker &#171;ultrasecreto&#187; debajo del ala este de la Casa Blanca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As\u00ed son los planes para reconstruir el b\u00fanker \"ultrasecreto\" debajo del ala este de la Casa Blanca - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/","og_locale":"es_ES","og_type":"article","og_title":"As\u00ed son los planes para reconstruir el b\u00fanker \"ultrasecreto\" debajo del ala este de la Casa Blanca - Noticias","og_description":"El presidente de Estados Unidos orden\u00f3 la construcci\u00f3n secreta de una instalaci\u00f3n subterr\u00e1nea segura en la Casa Blanca y construy\u00f3 una nueva extensi\u00f3n del ala este encima. Corr\u00eda el a\u00f1o 1941, y Franklin D. Roosevelt hab\u00eda sido alentado a construir un refugio antia\u00e9reo en la Casa Blanca tras el ataque a Pearl Harbor. En aquel [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-19T16:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/"},"author":{"name":"","@id":""},"headline":"As\u00ed son los planes para reconstruir el b\u00fanker &#171;ultrasecreto&#187; debajo del ala este de la Casa Blanca","datePublished":"2026-01-19T16:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/"},"wordCount":1562,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/","name":"As\u00ed son los planes para reconstruir el b\u00fanker \"ultrasecreto\" debajo del ala este de la Casa Blanca - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-19T16:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"As\u00ed son los planes para reconstruir el b\u00fanker &#171;ultrasecreto&#187; debajo del ala este de la Casa Blanca"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"As\u00ed son los planes para reconstruir el b\u00fanker &#171;ultrasecreto&#187; debajo del ala este de la Casa Blanca","url":"http:\/\/noticiasya.com\/laredo\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/01\/19\/bunker-secreto-casa-blanca-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-19T16:03:49Z","datePublished":"2026-01-19T16:03:49Z","dateModified":"2026-01-19T16:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"As\\u00ed son los planes para reconstruir el b\\u00fanker &#171;ultrasecreto&#187; debajo del ala este de la Casa Blanca\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/19\\\/bunker-secreto-casa-blanca-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/19\\\/bunker-secreto-casa-blanca-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-19T16:03:49Z\",\"datePublished\":\"2026-01-19T16:03:49Z\",\"dateModified\":\"2026-01-19T16:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467613,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/21\/casa-blanca-historia-renovaciones-ala-este-trax\/","url_meta":{"origin":1470229,"position":0},"title":"La nueva ala este de la Casa Blanca: cuando el Caesars Palace se encuentra con el Palacio de Versalles","author":"","date":"octubre 21, 2025","format":false,"excerpt":"El sal\u00f3n de baile que el presidente Donald Trump quiere construir y por lo que est\u00e1 demoliendo parte del ala este de la Casa Blanca es una mezcla entre el Caesars Palace y el Palacio de Versalles, que es el mismo gusto que Trump ha impregnado a edificios durante d\u00e9cadas.Costar\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467685,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/23\/fotografias-ala-este-casa-blanca-demolida-trax\/","url_meta":{"origin":1470229,"position":1},"title":"Fotograf\u00edas muestran c\u00f3mo qued\u00f3 el Ala Este de la Casa Blanca tras ser demolida","author":"","date":"octubre 23, 2025","format":false,"excerpt":"La totalidad del Ala Este de la Casa Blanca parece haber sido derribada, seg\u00fan muestran fotos publicadas este jueves, mientras el presidente Donald Trump avanza r\u00e1pidamente con los planes de construir un nuevo y enorme sal\u00f3n de baile.Las im\u00e1genes de Associated Press muestran que los trabajos de demolici\u00f3n llegan casi\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467625,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/22\/grupo-preservacion-historica-pide-pausar-demolicion-ala-este-casa-blanca-trax\/","url_meta":{"origin":1470229,"position":2},"title":"Grupo de preservaci\u00f3n hist\u00f3rica pide pausar demolici\u00f3n del Ala Este de Casa Blanca mientras Trump edifica su sal\u00f3n de baile","author":"","date":"octubre 22, 2025","format":false,"excerpt":"Uno de los principales grupos de preservaci\u00f3n hist\u00f3rica de EE.UU. inst\u00f3 este martes a la administraci\u00f3n Trump a pausar la demolici\u00f3n del Ala Este de la Casa Blanca, que desde inicios de esta semana llevan a cabo las excavadoras para dar paso al sal\u00f3n de baile planeado por el presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467656,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/23\/trump-ignora-preocupaciones-demolicion-ala-este-trax\/","url_meta":{"origin":1470229,"position":3},"title":"Trump ignora preocupaciones por demolici\u00f3n del Ala Este y visualiza un sal\u00f3n de baile m\u00e1s grande que el inicialmente planeado","author":"","date":"octubre 23, 2025","format":false,"excerpt":"El presidente Donald Trump ha procedido con enorme libertad a medida que construye su nuevo y enorme sal\u00f3n de baile, ignorando las preocupaciones planteadas por los conservacionistas y hasta ahora sin intentar buscar la aprobaci\u00f3n de la comisi\u00f3n que supervisa la construcci\u00f3n de edificios federales para derribar la totalidad del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467751,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/26\/ala-este-casa-blanca-demolida-lo-perdido-trax\/","url_meta":{"origin":1470229,"position":4},"title":"El Ala Este de la Casa Blanca ya est\u00e1 demolida. Esto es lo que se perdi\u00f3","author":"","date":"octubre 26, 2025","format":false,"excerpt":"Entre los escombros y la indignaci\u00f3n que conmemoran el lugar donde alguna vez estuvo el Ala Este de la Casa Blanca, el presidente Donald Trump y su equipo intentan salir adelante. La indignaci\u00f3n p\u00fablica ha ido en aumento por la demolici\u00f3n repentina para dar paso al extenso y dorado sal\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467648,"url":"https:\/\/noticiasya.com\/laredo\/2025\/10\/22\/demolicion-ala-este-casa-blanca-trump-salon-baile-trax\/","url_meta":{"origin":1470229,"position":5},"title":"Por qu\u00e9 la repentina demolici\u00f3n del Ala Este de la Casa Blanca por parte de Trump es extraordinaria y arriesgada","author":"","date":"octubre 22, 2025","format":false,"excerpt":"Cuando el presidente Donald Trump reflexion\u00f3 la semana pasada sobre la inminente construcci\u00f3n de su sal\u00f3n de baile en la Casa Blanca, el veterano promotor inmobiliario estaba pr\u00e1cticamente emocionado por la falta de tr\u00e1mites burocr\u00e1ticos. Se\u00f1al\u00f3 que sus proyectos en Nueva York a menudo tardaban a\u00f1os en comenzar.\u201cMe dijeron, \u2018Se\u00f1or,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1470229"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470229\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1470229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1470229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1470229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}