{"id":1470231,"date":"2026-01-19T09:03:55","date_gmt":"2026-01-19T17:03:55","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/"},"modified":"2026-01-19T09:03:55","modified_gmt":"2026-01-19T17:03:55","slug":"nfl-buffalo-bills-despiden-entrenador-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/","title":{"rendered":"Los Buffalo Bills despiden a su entrenador, Sean McDermott"},"content":{"rendered":"<p>Agreguemos a los Buffalo Bills como otro equipo de la NFL que ahora est\u00e1 en busca de un entrenador.<\/p>\n<p>Los Bills despidieron a Sean McDermott tras nueve temporadas al mando. La decisi\u00f3n se tom\u00f3 despu\u00e9s de que los Bills perdieran en tiempo extra ante los Denver Broncos, en la ronda divisional, el s\u00e1bado.<\/p>\n<p>Tras la destituci\u00f3n de McDermott, 10 equipos tendr\u00e1n un nuevo entrenador en jefe la pr\u00f3xima temporada. Nueve de estos cambios se debieron a despidos, mientras que Mike Tomlin opt\u00f3 por dimitir como entrenador en jefe de los Pittsburgh Steelers, la semana pasada. Los Giants y los Falcons han cubierto sus vacantes con John Harbaugh y Kevin Stefanski, respectivamente.<\/p>\n<p>\u201cSean ha hecho un trabajo admirable al frente de nuestro equipo de f\u00fatbol americano durante las \u00faltimas nueve temporadas\u201d, declar\u00f3 el due\u00f1o de los Bills, Terry Pegula. \u201cPero creo que necesitamos una nueva estructura de liderazgo para brindar a esta organizaci\u00f3n la mejor oportunidad de llevar a nuestro equipo al siguiente nivel\u201d.<\/p>\n<p>McDermott, quien fue contratado por los Bills el 11 de enero de 2017, llev\u00f3 a Buffalo a los <em>playoffs <\/em>ocho veces y gan\u00f3 cinco t\u00edtulos de la divisi\u00f3n Este de la AFC.<\/p>\n<p>A pesar del \u00e9xito del equipo con McDermott, los Bills no lograron avanzar al Super Bowl bajo su liderazgo, ya que quedaron 8-8 en los <em>playoffs<\/em>.<\/p>\n<p>Antes de la contrataci\u00f3n de McDermott, los Bills no hab\u00edan podido llegar a los <em>playoffs <\/em>desde la temporada de 1999.<\/p>\n<p>\u201cSean ayud\u00f3 a cambiar la mentalidad de esta organizaci\u00f3n y fue fundamental para que los Bills se convirtieran en un equipo que siempre participa en los <em>playoffs<\/em>\u201d, dijo Pegula. \u201cRespeto todo el trabajo, la lealtad y la atenci\u00f3n al detalle que demostr\u00f3 por este equipo y la comunidad\u201d.<\/p>\n<p>Los Bills dijeron este lunes que Brandon Beane liderar\u00e1 la b\u00fasqueda del pr\u00f3ximo entrenador en jefe del equipo.<\/p>\n<p>\u201cDe ahora en adelante, Brandon Beane se desempe\u00f1ar\u00e1 como presidente de Operaciones de F\u00fatbol Americano\/gerente general de los Buffalo Bills\u201d, dijo Pegula. \u201cBrandon supervisar\u00e1 todas las facetas de nuestras operaciones de f\u00fatbol americano, incluyendo la supervisi\u00f3n de nuestro cuerpo t\u00e9cnico. Tengo plena fe en el excepcional estilo de liderazgo de Brandon y he sido testigo de \u00e9l, y conf\u00edo en su capacidad para liderar nuestra organizaci\u00f3n\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agreguemos a los Buffalo Bills como otro equipo de la NFL que ahora est\u00e1 en busca de un entrenador. Los Bills despidieron a Sean McDermott tras nueve temporadas al mando. La decisi\u00f3n se tom\u00f3 despu\u00e9s de que los Bills perdieran en tiempo extra ante los Denver Broncos, en la ronda divisional, el s\u00e1bado. Tras la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470231","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los Buffalo Bills despiden a su entrenador, Sean McDermott - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los Buffalo Bills despiden a su entrenador, Sean McDermott - Noticias\" \/>\n<meta property=\"og:description\" content=\"Agreguemos a los Buffalo Bills como otro equipo de la NFL que ahora est\u00e1 en busca de un entrenador. Los Bills despidieron a Sean McDermott tras nueve temporadas al mando. La decisi\u00f3n se tom\u00f3 despu\u00e9s de que los Bills perdieran en tiempo extra ante los Denver Broncos, en la ronda divisional, el s\u00e1bado. Tras la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-19T17:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los Buffalo Bills despiden a su entrenador, Sean McDermott\",\"datePublished\":\"2026-01-19T17:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/\"},\"wordCount\":419,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/\",\"name\":\"Los Buffalo Bills despiden a su entrenador, Sean McDermott - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-19T17:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los Buffalo Bills despiden a su entrenador, Sean McDermott\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los Buffalo Bills despiden a su entrenador, Sean McDermott - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los Buffalo Bills despiden a su entrenador, Sean McDermott - Noticias","og_description":"Agreguemos a los Buffalo Bills como otro equipo de la NFL que ahora est\u00e1 en busca de un entrenador. Los Bills despidieron a Sean McDermott tras nueve temporadas al mando. La decisi\u00f3n se tom\u00f3 despu\u00e9s de que los Bills perdieran en tiempo extra ante los Denver Broncos, en la ronda divisional, el s\u00e1bado. Tras la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-19T17:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/"},"author":{"name":"","@id":""},"headline":"Los Buffalo Bills despiden a su entrenador, Sean McDermott","datePublished":"2026-01-19T17:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/"},"wordCount":419,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/","name":"Los Buffalo Bills despiden a su entrenador, Sean McDermott - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-19T17:03:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los Buffalo Bills despiden a su entrenador, Sean McDermott"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los Buffalo Bills despiden a su entrenador, Sean McDermott","url":"http:\/\/noticiasya.com\/laredo\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/01\/19\/nfl-buffalo-bills-despiden-entrenador-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-19T17:03:55Z","datePublished":"2026-01-19T17:03:55Z","dateModified":"2026-01-19T17:03:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los Buffalo Bills despiden a su entrenador, Sean McDermott\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/19\\\/nfl-buffalo-bills-despiden-entrenador-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/19\\\/nfl-buffalo-bills-despiden-entrenador-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-19T17:03:55Z\",\"datePublished\":\"2026-01-19T17:03:55Z\",\"dateModified\":\"2026-01-19T17:03:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470050,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/13\/mike-tomlin-renuncia-entrenador-steelers-trax\/","url_meta":{"origin":1470231,"position":0},"title":"Mike Tomlin renuncia como entrenador en jefe de los Steelers de Pittsburgh tras 19 temporadas","author":"","date":"enero 13, 2026","format":false,"excerpt":"La era de Mike Tomlin lleg\u00f3 a su fin en Pittsburgh.Tras 19 temporadas como entrenador en jefe de los Steelers, Tomlin tom\u00f3 la decisi\u00f3n de dejar el cargo.\u201cDespu\u00e9s de mucha reflexi\u00f3n, he decidido dejar el cargo de entrenador en jefe de los Pittsburgh Steelers\u201d, dijo Tomlin en un comunicado.\u201cLa organizaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470242,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/19\/super-bowl-lx-finales-de-conferencia-nfl\/","url_meta":{"origin":1470231,"position":1},"title":"Solo queda una parada antes del Super Bowl LX, las Finales de Conferencia est\u00e1n servidas en la NFL","author":"","date":"enero 19, 2026","format":false,"excerpt":"Los duelos divisionales de la NFL nos dejaron algunas sorpresas, mantuvieron a ciertos favoritos en sus puestos de \u201cprivilegio\u201d y arrojaron una que otra decepci\u00f3n. El Super Bowl LX est\u00e1 cada vez m\u00e1s cerca y solo falta una parada de cara a la gran final del 8 de febrero; las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469848,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/06\/nfl-john-harbaugh-despido-baltimore-ravens-trax\/","url_meta":{"origin":1470231,"position":2},"title":"NFL: Tras el fracaso de no llegar a los playoffs, se termin\u00f3 la era de John Harbaugh en los Baltimore Ravens","author":"","date":"enero 6, 2026","format":false,"excerpt":"Tras 18 temporadas en Baltimore, John Harbaugh deja el cargo de entrenador en jefe, anunci\u00f3 el equipo el martes.\u201cEsta fue una decisi\u00f3n incre\u00edblemente dif\u00edcil, dados los tremendos 18 a\u00f1os que hemos pasado juntos y el profundo respeto que siento por John como entrenador y, sobre todo, como una gran persona\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445434,"url":"https:\/\/noticiasya.com\/laredo\/2024\/02\/14\/travis-kelce-dice-que-su-empujon-al-entrenador-de-los-chiefs-andy-reid-fue-definitivamente-inaceptable\/","url_meta":{"origin":1470231,"position":3},"title":"Travis Kelce dice que su empuj\u00f3n al entrenador de los Chiefs, Andy Reid, fue &#171;definitivamente inaceptable&#187;","author":"","date":"febrero 14, 2024","format":false,"excerpt":"(CNN) -- Travis Kelce, jugador de los Chiefs de Kansas City, dijo este mi\u00e9rcoles que su empuj\u00f3n al entrenador en jefe del equipo, Andy Reid, durante el Super Bowl LVIII fue \"definitivamente inaceptable\".En declaraciones en su podcast 'New Heights' junto a su hermano Jason, Kelce explic\u00f3 la situaci\u00f3n, admitiendo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445436,"url":"https:\/\/noticiasya.com\/laredo\/2024\/02\/14\/travis-kelce-dice-que-su-empujon-al-entrenador-de-los-chiefs-andy-reid-fue-definitivamente-inaceptable-2\/","url_meta":{"origin":1470231,"position":4},"title":"Travis Kelce dice que su empuj\u00f3n al entrenador de los Chiefs, Andy Reid, fue &#171;definitivamente inaceptable&#187;","author":"","date":"febrero 14, 2024","format":false,"excerpt":"(CNN) -- Travis Kelce, jugador de los Chiefs de Kansas City, dijo este mi\u00e9rcoles que su empuj\u00f3n al entrenador en jefe del equipo, Andy Reid, durante el Super Bowl LVIII fue \"definitivamente inaceptable\".En declaraciones en su podcast 'New Heights' junto a su hermano Jason, Kelce explic\u00f3 la situaci\u00f3n, admitiendo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457910,"url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/27\/los-chiefs-y-eagles-reservan-sus-viajes-al-super-bowl-trax\/","url_meta":{"origin":1470231,"position":5},"title":"Los Chiefs y los Eagles reservan pasajes al super bowl","author":"","date":"enero 27, 2025","format":false,"excerpt":"El enfrentamiento del Super Bowl ya est\u00e1 oficialmente decidido: los Philadelphia Eagles y los Kansas City Chiefs se enfrentar\u00e1n una vez m\u00e1s por el premio m\u00e1s grande de la NFL en el Super Bowl LIX en dos semanas en Nueva Orleans.El gran juego est\u00e1 programado para comenzar a las 6:30\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1470231"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470231\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1470231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1470231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1470231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}