{"id":1470303,"date":"2026-01-20T15:03:53","date_gmt":"2026-01-20T23:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/"},"modified":"2026-01-20T15:03:53","modified_gmt":"2026-01-20T23:03:53","slug":"descarrilamiento-tren-cataluna-espana-muertos-heridos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/","title":{"rendered":"Al menos 1 muerto y 20 heridos tras el descarrilamiento de un tren en Catalu\u00f1a"},"content":{"rendered":"<p>Al menos una persona muri\u00f3 y 20 resultaron heridas este martes a causa del descarrilamiento de un tren de cercan\u00edas en Catalu\u00f1a, en el noroeste de Espa\u00f1a, confirm\u00f3 a CNN un portavoz de la Generalitat.<\/p>\n<p>El accidente involucr\u00f3 a un convoy de la l\u00ednea R4 del servicio de cercan\u00edas (llamado Rodalies en Catalu\u00f1a), que circulaba entre los municipios de Gelida y Sant Sadurn\u00ed d\u2019Anoia, donde un muro de contenci\u00f3n cay\u00f3 sobre la zona de v\u00edas e impact\u00f3 contra el tren, seg\u00fan Protecci\u00f3n Civil de la Generalitat. El incidente se produjo alrededor de las 22:00 horas (tiempo local, 16:00 ET), de acuerdo con un comunicado del servicio de cercan\u00edas.<\/p>\n<p>Cercan\u00edas es un servicio ferroviario de transporte p\u00fablico que conecta \u00e1reas metropolitanas con localidades cercanas y es utilizado a diario por miles de pasajeros.<\/p>\n<p>El tel\u00e9fono de emergencias 112 recibi\u00f3 28 llamadas relacionadas con el suceso. Para atender la situaci\u00f3n, se activaron 20 ambulancias del Sistema de Emergencias M\u00e9dicas (SEM) y 38 dotaciones de los Bomberos de la Generalitat de Catalu\u00f1a.<\/p>\n<p>Los Bomberos de la Generalitat informaron que establecieron una zona de seguridad y procedieron a apuntalar tanto el muro de contenci\u00f3n como el tren para estabilizar la escena. Asimismo, evacuaron a los heridos fuera de la denominada \u201czona caliente\u201d para ser atendidos por los servicios de emergencia locales. Las autoridades dijeron que fue necesario \u201cexcarcelar\u201d a una persona que permanec\u00eda atrapada en el interior del convoy.<\/p>\n<p>Seg\u00fan Rodalies, varias personas fueron atendidas con heridas de distinta consideraci\u00f3n, entre ellas el maquinista del tren, asistido por los Servicios de Emergencias. La Consejera de Interior y Seguridad, Nuria Parl\u00f3n, y la Consejera de Territorio, Silvia Paneque, se desplazan al lugar de los hechos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos una persona muri\u00f3 y 20 resultaron heridas este martes a causa del descarrilamiento de un tren de cercan\u00edas en Catalu\u00f1a, en el noroeste de Espa\u00f1a, confirm\u00f3 a CNN un portavoz de la Generalitat. El accidente involucr\u00f3 a un convoy de la l\u00ednea R4 del servicio de cercan\u00edas (llamado Rodalies en Catalu\u00f1a), que circulaba [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470303","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al menos 1 muerto y 20 heridos tras el descarrilamiento de un tren en Catalu\u00f1a - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al menos 1 muerto y 20 heridos tras el descarrilamiento de un tren en Catalu\u00f1a - Noticias\" \/>\n<meta property=\"og:description\" content=\"Al menos una persona muri\u00f3 y 20 resultaron heridas este martes a causa del descarrilamiento de un tren de cercan\u00edas en Catalu\u00f1a, en el noroeste de Espa\u00f1a, confirm\u00f3 a CNN un portavoz de la Generalitat. El accidente involucr\u00f3 a un convoy de la l\u00ednea R4 del servicio de cercan\u00edas (llamado Rodalies en Catalu\u00f1a), que circulaba [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-20T23:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Al menos 1 muerto y 20 heridos tras el descarrilamiento de un tren en Catalu\u00f1a\",\"datePublished\":\"2026-01-20T23:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/\"},\"wordCount\":326,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/\",\"name\":\"Al menos 1 muerto y 20 heridos tras el descarrilamiento de un tren en Catalu\u00f1a - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-20T23:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al menos 1 muerto y 20 heridos tras el descarrilamiento de un tren en Catalu\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al menos 1 muerto y 20 heridos tras el descarrilamiento de un tren en Catalu\u00f1a - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Al menos 1 muerto y 20 heridos tras el descarrilamiento de un tren en Catalu\u00f1a - Noticias","og_description":"Al menos una persona muri\u00f3 y 20 resultaron heridas este martes a causa del descarrilamiento de un tren de cercan\u00edas en Catalu\u00f1a, en el noroeste de Espa\u00f1a, confirm\u00f3 a CNN un portavoz de la Generalitat. El accidente involucr\u00f3 a un convoy de la l\u00ednea R4 del servicio de cercan\u00edas (llamado Rodalies en Catalu\u00f1a), que circulaba [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/","og_site_name":"Noticias","article_published_time":"2026-01-20T23:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/"},"author":{"name":"","@id":""},"headline":"Al menos 1 muerto y 20 heridos tras el descarrilamiento de un tren en Catalu\u00f1a","datePublished":"2026-01-20T23:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/"},"wordCount":326,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/","url":"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/","name":"Al menos 1 muerto y 20 heridos tras el descarrilamiento de un tren en Catalu\u00f1a - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-20T23:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Al menos 1 muerto y 20 heridos tras el descarrilamiento de un tren en Catalu\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Al menos 1 muerto y 20 heridos tras el descarrilamiento de un tren en Catalu\u00f1a","url":"http:\/\/noticiasya.com\/laredo\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/01\/20\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-20T23:03:53Z","datePublished":"2026-01-20T23:03:53Z","dateModified":"2026-01-20T23:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Al menos 1 muerto y 20 heridos tras el descarrilamiento de un tren en Catalu\\u00f1a\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/20\\\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/20\\\/descarrilamiento-tren-cataluna-espana-muertos-heridos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-20T23:03:53Z\",\"datePublished\":\"2026-01-20T23:03:53Z\",\"dateModified\":\"2026-01-20T23:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470214,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/18\/accidente-descarrilamiento-trenes-alta-velocidad-muertos-espana-orix\/","url_meta":{"origin":1470303,"position":0},"title":"Descarrilamiento de dos trenes de alta velocidad deja al menos 5 muertos y m\u00e1s de 20 heridos en el sur de Espa\u00f1a","author":"","date":"enero 18, 2026","format":false,"excerpt":"El descarrilamiento de dos trenes de alta velocidad ha dejado al menos cinco muertos y 25 heridos graves en el t\u00e9rmino municipal de Adamuz, cerca de C\u00f3rdoba, en el sur de Espa\u00f1a, seg\u00fan inform\u00f3 el servicio de emergencias de la Junta de Andaluc\u00eda.El accidente ocurri\u00f3 cuando un tren de alta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468238,"url":"https:\/\/noticiasya.com\/laredo\/2025\/11\/11\/descarrilamiento-tren-sarmiento-buenos-aires-orix\/","url_meta":{"origin":1470303,"position":1},"title":"20 personas resultan heridas tras el descarrilamiento de un tren en la ciudad de Buenos Aires","author":"","date":"noviembre 11, 2025","format":false,"excerpt":"El descarrilamiento de un tren en la zona de Liniers de la ciudad de Buenos Aires caus\u00f3 heridas a 20 personas este martes, inform\u00f3 el Sistema de Atenci\u00f3n de Emergencia M\u00e9dica (SAME) de la capital de Argentina.Del total de lesionados, 11 fueron atendidos en el lugar y los nueve restantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448613,"url":"https:\/\/noticiasya.com\/laredo\/2024\/04\/27\/evacuaciones-tren-descarrilamiento-nueva-mexico-gas-propano-trax\/","url_meta":{"origin":1470303,"position":2},"title":"Siguen las evacuaciones tras descarrilamiento de tren cerca de la frontera del estado de Nuevo M\u00e9xico; algunos vagones transportaban propano","author":"","date":"abril 27, 2024","format":false,"excerpt":"(CNN) -- Se emitieron \u00f3rdenes de evacuaci\u00f3n y permanecen vigentes para los residentes dentro de un radio de 3 km del principal descarrilamiento e incendio del tren a lo largo de la frontera del estado de Nuevo M\u00e9xico con Arizona, seg\u00fan una actualizaci\u00f3n de BNSF Railway.El Departamento de Bomberos y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469650,"url":"https:\/\/noticiasya.com\/laredo\/2025\/12\/29\/tren-interoceanico-accidente-oaxaca-orix\/","url_meta":{"origin":1470303,"position":3},"title":"Descarrilamiento del Tren Interoce\u00e1nico en M\u00e9xico: \u00bfqu\u00e9 se sabe hasta ahora sobre las v\u00edctimas y las causas?","author":"","date":"diciembre 29, 2025","format":false,"excerpt":"El Tren Interoce\u00e1nico, un proyecto ferroviario clave del Gobierno de M\u00e9xico que recorre el Istmo de Tehuantepec en el sur del pa\u00eds, descarril\u00f3 este domingo en el centro del estado de Oaxaca, dejando al menos 13 muertos y m\u00e1s de un centenar de heridos, seg\u00fan la Secretar\u00eda de Marina (Semar).Tras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470319,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/21\/5-cosas-21-enero-orix\/","url_meta":{"origin":1470303,"position":4},"title":"Las 5 cosas que debes saber este 21 de enero","author":"","date":"enero 21, 2026","format":false,"excerpt":"Trump quiere que Machado se \u201cinvolucre\u201d en Venezuela. Ya son 92 los criminales que M\u00e9xico env\u00eda a EE.UU. en un a\u00f1o. Una peligrosa tormenta invernal azotar\u00e1 EE.UU. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo\ud83c\udf99\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1434087,"url":"https:\/\/noticiasya.com\/laredo\/2022\/10\/25\/suspende-rtd-servicio-en-segmento-de-linea-r\/","url_meta":{"origin":1470303,"position":5},"title":"Suspende RTD servicio en segmento de l\u00ednea R","author":"agomez","date":"octubre 25, 2022","format":false,"excerpt":"El descarrilamiento de un tren y la escasez de personal son las principales causas.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/laredo\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1470303"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470303\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1470303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1470303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1470303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}