{"id":1470346,"date":"2026-01-21T16:03:40","date_gmt":"2026-01-22T00:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/"},"modified":"2026-01-21T16:03:40","modified_gmt":"2026-01-22T00:03:40","slug":"trump-davos-insensible-declaraciones-ricos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/laredo\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/","title":{"rendered":"Trump se regodea en Davos sobre c\u00f3mo hacer a los ricos a\u00fan m\u00e1s ricos"},"content":{"rendered":"<p>Despu\u00e9s de que se anunciara que <a href=\"https:\/\/www.cnn.com\/2026\/01\/21\/politics\/gavin-newsom-trump-davos\">el gobernador de California, Gavin Newsom<\/a>, compartir\u00eda sus opiniones sobre el <a href=\"https:\/\/www.cnn.com\/politics\/president-donald-trump-47\">presidente Donald Trump<\/a> en el <a href=\"https:\/\/www.cnn.com\/politics\/live-news\/trump-administration-news-01-21-26?t=1769031980358\">Foro Econ\u00f3mico Mundial en Suiza<\/a> esta semana, la influencer MAGA Katie Miller se burl\u00f3 del dem\u00f3crata por su presencia en el evento frecuentado por empresarios adinerados.<\/p>\n<p>\u201cPor supuesto que Gavin Newsom va a Davos\u201d, public\u00f3 Miller, quien est\u00e1 casada con el principal asesor de la Casa Blanca, Stephen Miller, <a href=\"https:\/\/x.com\/KatieMiller\/status\/2013251954961453199\">el lunes en X<\/a>. \u201cNada dice tanto EE.UU. Primero como compadecerse ante la multitud de la \u00e9lite mundial\u201d.<\/p>\n<p>Pero lo que ha ocurrido en los \u00faltimos d\u00edas no ha reforzado exactamente su punto de la manera en que ella podr\u00eda haber imaginado.<\/p>\n<p>Newsom ha pasado su tiempo instando a las \u00e9lites en Davos a enfrentarse con m\u00e1s fuerza a Trump. Y es Trump quien ha estado code\u00e1ndose con los ricos y sin ning\u00fan pudor al hablar sobre sus lazos con personas adineradas y sus gestiones para hacerlas a\u00fan m\u00e1s ricas.<\/p>\n<p>Incluso mientras los estadounidenses luchan con lo que en su mayor\u00eda consideran una econom\u00eda estancada, el presidente pareci\u00f3 regodearse el mi\u00e9rcoles de lo buenas que han sido sus pol\u00edticas para los ricos.<\/p>\n<p>Hizo una serie de comentarios de este tipo durante una recepci\u00f3n con directores ejecutivos.<\/p>\n<p>\u201cAs\u00ed que creo que en cuanto a sus inversiones, est\u00e1n en muy buena forma\u201d, dijo Trump al p\u00fablico. \u201cYa ni siquiera le pregunto a nadie c\u00f3mo le va ahora. Es como si todos estuvieran ganando mucho dinero\u201d.<\/p>\n<p>Trump dijo que suele ir felicitando a los l\u00edderes empresariales.<\/p>\n<p>\u201cEllos dicen, \u00bfpor qu\u00e9?\u201d, cont\u00f3 Trump. \u201cYo dije, \u2018\u00bfhas duplicado tu patrimonio neto desde que soy presidente, verdad?\u2019 \u00c9l dijo, \u2018s\u00ed, incluso m\u00e1s que eso.\u2019 Ellos dir\u00edan, \u2018a\u00fan m\u00e1s. Nos va incluso mejor que eso.\u2019 Y les hemos dado una plataforma donde pueden poner su genio a trabajar\u201d.<\/p>\n<p>En otro momento del mismo evento, Trump se\u00f1al\u00f3 su gran proyecto de ley de agenda interna \u2014que a menudo llamaba la \u201cGran Hermosa Ley\u201d\u2014 que se aprob\u00f3 el a\u00f1o pasado y una deducci\u00f3n fiscal clave que otorg\u00f3 a los due\u00f1os de negocios.<\/p>\n<p>Luego, Trump improvis\u00f3 sobre c\u00f3mo, en su primer mandato, un amigo adinerado compr\u00f3 un avi\u00f3n que ni siquiera us\u00f3 porque quer\u00eda aprovechar esa deducci\u00f3n.<\/p>\n<p>\u201cSiempre dije, eso es lo que hizo mi primer mandato tan exitoso\u201d, dijo Trump. \u201cPorque, quiero decir, la gente estaba comprando cosas que\u2026 Tengo un amigo que compr\u00f3 un avi\u00f3n, nunca lo us\u00f3. Simplemente lo compr\u00f3. Dijo, \u2018recib\u00ed una\u2026 lo deduje\u2019\u201d.<\/p>\n<p>\u201cDe hecho, ser\u00eda un gran avi\u00f3n para comprar, porque nunca lo us\u00f3\u201d, continu\u00f3 Trump.<\/p>\n<p>Una cosa es presumir de tus lazos con los ricos y de c\u00f3mo reducen su carga fiscal en tiempos buenos, cuando una econom\u00eda fuerte eleva a todos. Pero uno de los mayores problemas con la econom\u00eda actual es su \u201c<a href=\"https:\/\/www.cnn.com\/2025\/12\/31\/economy\/k-shaped-consumers-left-behind-2026\">forma de K<\/a>\u201d, es decir, que es excelente para los ricos pero no tanto para el resto del pa\u00eds.<\/p>\n<p>De hecho, el reciente <a href=\"https:\/\/www.cnn.com\/2026\/01\/18\/economy\/wealth-political-inequality-billionaires-wef\">informe anual sobre desigualdad<\/a> de Oxfam de este mes mostr\u00f3 que la riqueza de los multimillonarios creci\u00f3 tres veces m\u00e1s r\u00e1pido el a\u00f1o pasado que el promedio de los cinco a\u00f1os anteriores.<\/p>\n<p>Y la publicaci\u00f3n de Miller se\u00f1ala los riesgos pol\u00edticos aqu\u00ed.<\/p>\n<p>Incluso cuando aproximadamente 7 de cada 10 estadounidenses consideraron la econom\u00eda como \u201cpobre\u201d en la nueva encuesta de CNN de la semana pasada, ah\u00ed estaba Trump en una reuni\u00f3n de \u00e9lites hablando de lo bueno que ha sido para la parte alta de esa econom\u00eda en forma de K. Eso es bastante insensible.<\/p>\n<p>Y no es ni mucho menos el \u00fanico ejemplo de un comentario poco recomendable que podr\u00eda molestar a los estadounidenses preocupados por sus bolsillos. En medio de los problemas econ\u00f3micos, Trump y su gabinete \u2014que, no casualmente, est\u00e1 <a href=\"https:\/\/www.cnn.com\/2025\/04\/24\/politics\/donald-trump-cabinet-policy-ethics\">lleno de multimillonarios<\/a>\u2014 han hecho una serie de comentarios de este tipo.<\/p>\n<p>Los comentarios de Trump llegaron apenas un d\u00eda despu\u00e9s de que el secretario del Tesoro, Scott Bessent, hablara sobre la idea del Gobierno de <a href=\"https:\/\/www.cnn.com\/2026\/01\/07\/economy\/trump-institutional-investors-homebuying\">prohibir que los inversores institucionales compren viviendas unifamiliares.<\/a><\/p>\n<p>Algunos estadounidenses creen que los grandes inversores institucionales han elevado los costos de la vivienda. Bessent trat\u00f3 de asegurar que esta medida no perjudicar\u00eda a los inversores \u201cpeque\u00f1os\u201d. Pero su definici\u00f3n de inversores \u201cpeque\u00f1os\u201d levant\u00f3 algunas cejas. \u201cAlguien, tal vez tus padres para su jubilaci\u00f3n\u201d, le dijo Bessent a Maria Bartiromo de Fox Business Network, \u201ccompraron cinco, diez, doce casas. As\u00ed que no queremos sacar a los peque\u00f1os propietarios. Solo queremos sacar a todos los dem\u00e1s\u201d.<\/p>\n<p>Solo un jubilado promedio, due\u00f1o de entre cinco y una docena de casas.<\/p>\n<p>Newsom promocion\u00f3 el video de Bessent, preguntando: \u201c\u00bfpodr\u00eda este hombre arrogante estar m\u00e1s desconectado de la realidad?\u201d <a href=\"https:\/\/x.com\/edwardlawrence\/status\/2013916326801068099\">Bessent respondi\u00f3<\/a> el mi\u00e9rcoles que el gobernador dem\u00f3crata \u201cpuede ser el \u00fanico californiano que sabe menos de econom\u00eda que Kamala Harris\u201d.<\/p>\n<p>Y en el transcurso del \u00faltimo a\u00f1o, el Gobierno ha hecho <a href=\"https:\/\/www.cnn.com\/2026\/01\/15\/politics\/trump-rollins-austerity-affordability-inflation\">una serie de comentarios inc\u00f3modos<\/a> sobre c\u00f3mo los estadounidenses podr\u00edan sortear las dificultades econ\u00f3micas. Trump habl\u00f3 de simplemente comprar menos mu\u00f1ecas y l\u00e1pices.<\/p>\n<p>M\u00e1s recientemente, la secretaria de Agricultura Brooke Rollins, dijo que los estadounidenses pueden permitirse una comida de US$ 3 de calidad que incluya \u201cun trozo de br\u00f3coli\u201d.<\/p>\n<p>Se prev\u00e9 que las elecciones de 2026 se enfoquen ampliamente en la econom\u00eda, y el equipo de Trump le est\u00e1 dando a los dem\u00f3cratas mucho material para presentarlos como desconectados de la realidad.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de que se anunciara que el gobernador de California, Gavin Newsom, compartir\u00eda sus opiniones sobre el presidente Donald Trump en el Foro Econ\u00f3mico Mundial en Suiza esta semana, la influencer MAGA Katie Miller se burl\u00f3 del dem\u00f3crata por su presencia en el evento frecuentado por empresarios adinerados. \u201cPor supuesto que Gavin Newsom va a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470346","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trump se regodea en Davos sobre c\u00f3mo hacer a los ricos a\u00fan m\u00e1s ricos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump se regodea en Davos sobre c\u00f3mo hacer a los ricos a\u00fan m\u00e1s ricos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de que se anunciara que el gobernador de California, Gavin Newsom, compartir\u00eda sus opiniones sobre el presidente Donald Trump en el Foro Econ\u00f3mico Mundial en Suiza esta semana, la influencer MAGA Katie Miller se burl\u00f3 del dem\u00f3crata por su presencia en el evento frecuentado por empresarios adinerados. \u201cPor supuesto que Gavin Newsom va a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-22T00:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Trump se regodea en Davos sobre c\u00f3mo hacer a los ricos a\u00fan m\u00e1s ricos\",\"datePublished\":\"2026-01-22T00:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/\"},\"wordCount\":990,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/\",\"name\":\"Trump se regodea en Davos sobre c\u00f3mo hacer a los ricos a\u00fan m\u00e1s ricos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-01-22T00:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump se regodea en Davos sobre c\u00f3mo hacer a los ricos a\u00fan m\u00e1s ricos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trump se regodea en Davos sobre c\u00f3mo hacer a los ricos a\u00fan m\u00e1s ricos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Trump se regodea en Davos sobre c\u00f3mo hacer a los ricos a\u00fan m\u00e1s ricos - Noticias","og_description":"Despu\u00e9s de que se anunciara que el gobernador de California, Gavin Newsom, compartir\u00eda sus opiniones sobre el presidente Donald Trump en el Foro Econ\u00f3mico Mundial en Suiza esta semana, la influencer MAGA Katie Miller se burl\u00f3 del dem\u00f3crata por su presencia en el evento frecuentado por empresarios adinerados. \u201cPor supuesto que Gavin Newsom va a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/","og_site_name":"Noticias","article_published_time":"2026-01-22T00:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/"},"author":{"name":"","@id":""},"headline":"Trump se regodea en Davos sobre c\u00f3mo hacer a los ricos a\u00fan m\u00e1s ricos","datePublished":"2026-01-22T00:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/"},"wordCount":990,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/","url":"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/","name":"Trump se regodea en Davos sobre c\u00f3mo hacer a los ricos a\u00fan m\u00e1s ricos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-01-22T00:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Trump se regodea en Davos sobre c\u00f3mo hacer a los ricos a\u00fan m\u00e1s ricos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Trump se regodea en Davos sobre c\u00f3mo hacer a los ricos a\u00fan m\u00e1s ricos","url":"http:\/\/noticiasya.com\/laredo\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/laredo\/2026\/01\/21\/trump-davos-insensible-declaraciones-ricos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-01-22T00:03:40Z","datePublished":"2026-01-22T00:03:40Z","dateModified":"2026-01-22T00:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Trump se regodea en Davos sobre c\\u00f3mo hacer a los ricos a\\u00fan m\\u00e1s ricos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/21\\\/trump-davos-insensible-declaraciones-ricos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/laredo\\\/2026\\\/01\\\/21\\\/trump-davos-insensible-declaraciones-ricos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-01-22T00:03:40Z\",\"datePublished\":\"2026-01-22T00:03:40Z\",\"dateModified\":\"2026-01-22T00:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470357,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/21\/trump-anuncia-marco-acuerdo-groenlandia-davos-orix\/","url_meta":{"origin":1470346,"position":0},"title":"Trump anuncia un &#171;marco de acuerdo&#187; sobre Groenlandia tras reuni\u00f3n con el jefe de la OTAN en Davos","author":"","date":"enero 21, 2026","format":false,"excerpt":"En el marco del Foro Econ\u00f3mico Mundial, el presidente de Estados Unidos, Donald Trump, asegur\u00f3 este mi\u00e9rcoles haber alcanzado un \u201cmarco de acuerdo futuro\u201d sobre Groenlandia tras una reuni\u00f3n clave con el secretario general de la OTAN, Mark Rutte.Como resultado inmediato de este acercamiento, el mandatario estadounidense se\u00f1al\u00f3 que ya\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470314,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/20\/analisis-anfitriones-davos-aborrezcan-trump-trax\/","url_meta":{"origin":1470346,"position":1},"title":"Puede que los anfitriones de Davos aborrezcan a Trump, pero vale la pena escucharlo","author":"","date":"enero 20, 2026","format":false,"excerpt":"Dean Acheson, el venerado diplom\u00e1tico estadounidense, describi\u00f3 su papel como arquitecto del mundo posterior a la Segunda Guerra Mundial en unas memorias de gran \u00e9xito tituladas \u201cPresente en la creaci\u00f3n\u201d.La audiencia del presidente Donald Trump en la ciudad alpina suiza de Davos este mi\u00e9rcoles puede preguntarse si est\u00e1n presentes en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470220,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/18\/multimillonarios-probabilidades-cargos-publicos-desigualdad-trax\/","url_meta":{"origin":1470346,"position":2},"title":"Los multimillonarios tienen 4.000 veces m\u00e1s probabilidades de ocupar cargos p\u00fablicos","author":"","date":"enero 18, 2026","format":false,"excerpt":"Las personas m\u00e1s ricas del planeta tienen muchas m\u00e1s probabilidades de estar en el poder pol\u00edtico que el resto, seg\u00fan el informe anual sobre desigualdad de Oxfam.Unos 74 de los 2.027 multimillonarios del mundo ocuparon cargos ejecutivos o legislativos en 2023, lo que les da una probabilidad del 3,6 %\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470298,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/20\/lentes-sol-emmanuel-macron-davos-orix\/","url_meta":{"origin":1470346,"position":3},"title":"\u00bfPor qu\u00e9 llevaba lentes de sol el presidente de Francia, Emmanuel Macron, durante su discurso en Davos?","author":"","date":"enero 20, 2026","format":false,"excerpt":"Cuando el presidente de Francia, Emmanuel Macron, habl\u00f3 a la audiencia del Foro Econ\u00f3mico Mundial (WEF, por sus siglas en ingl\u00e9s) en Davos este martes, varias personas se hicieron la misma pregunta: \u201c\u00bfPor qu\u00e9 llevaba lentes de sol?\u201dEl l\u00edder franc\u00e9s luci\u00f3 un par de gafas de sol estilo aviador con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470368,"url":"https:\/\/noticiasya.com\/laredo\/2026\/01\/22\/mark-rutte-otan-principal-confidente-trump-trax\/","url_meta":{"origin":1470346,"position":4},"title":"Mark Rutte, de la OTAN, emerge como el principal confidente de Trump tras dram\u00e1tico cambio de postura en Davos","author":"","date":"enero 22, 2026","format":false,"excerpt":"Hace apenas unos d\u00edas, los l\u00edderes europeos se apresuraban a responder a la ret\u00f3rica cada vez m\u00e1s agresiva del presidente de EE.UU., Donald Trump, sobre tomar el control de Groenlandia, y se preparaban para una avalancha de insultos cuando el mandatario llegara a hablar en su propio territorio del Viejo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457813,"url":"https:\/\/noticiasya.com\/laredo\/2025\/01\/23\/trump-paz-rusia-ucrania-foro-economico-davos-trax\/","url_meta":{"origin":1470346,"position":5},"title":"Trump dice que los esfuerzos de paz entre Rusia y Ucrania &#171;est\u00e1n en marcha&#187;","author":"","date":"enero 23, 2025","format":false,"excerpt":"El presidente Donald Trump dijo el jueves que los esfuerzos de paz entre Rusia y Ucrania est\u00e1n en marcha mientras hablaba virtualmente en el Foro Econ\u00f3mico Mundial.\u201cNuestros esfuerzos para asegurar un acuerdo de paz entre Rusia y Ucrania ahora est\u00e1n en marcha\u201d, dijo Trump mientras hablaba virtualmente en el foro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/laredo\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/comments?post=1470346"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/posts\/1470346\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/media?parent=1470346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/categories?post=1470346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/laredo\/wp-json\/wp\/v2\/tags?post=1470346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}